{"id":97886,"date":"2021-05-28T08:57:17","date_gmt":"2021-05-28T11:57:17","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=97886"},"modified":"2021-05-28T08:57:17","modified_gmt":"2021-05-28T11:57:17","slug":"respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/","title":{"rendered":"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-97888\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1-600x375.png\" alt=\"\" width=\"755\" height=\"472\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1-1200x751.png 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1-768x481.png 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1-1536x961.png 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1-2048x1281.png 2048w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><br \/>\nInspirar e expirar \u00e9 um ato autom\u00e1tico e involunt\u00e1rio, mas a<strong> devida aten\u00e7\u00e3o \u00e0 pr\u00e1tica da respira\u00e7\u00e3o pode ser um fator determinante para a sa\u00fade de qualquer pessoa<\/strong>. &#8220;O ideal \u00e9 que todos possam aprender a respirar corretamente, principalmente quando estamos saud\u00e1veis. Os exerc\u00edcios respirat\u00f3rios ajudam na preven\u00e7\u00e3o de doen\u00e7as, infec\u00e7\u00f5es pulmonares e, principalmente, nas sequelas p\u00f3s-Covid-19&#8221;, orienta Gabriel Coutinho, fisioterapeuta cardiorrespirat\u00f3rio do Centro de Extens\u00e3o em Sa\u00fade da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), da Secretaria da Sa\u00fade do Estado (Sesa).<\/p>\n<p>Para o especialista, \u00e9 importante<strong> promover a respira\u00e7\u00e3o consciente<\/strong>, uma vez que as c\u00e9lulas corporais necessitam de oxig\u00eanio e precisam limpar o di\u00f3xido de carbono. Neste processo, chamado de hematose, os pulm\u00f5es s\u00e3o os \u00f3rg\u00e3os respons\u00e1veis pela troca gasosa.<\/p>\n<p>&#8220;Quando respiramos adequadamente, melhoramos nossa ventila\u00e7\u00e3o pulmonar, aumentamos o volume de ar nos pulm\u00f5es, mobilizamos as secre\u00e7\u00f5es das vias a\u00e9reas respirat\u00f3rias, facilitando a hematose e, consequentemente, levando oxig\u00eanio para todo o organismo&#8221;, destaca Coutinho.<\/p>\n<p>Para isso,<strong> \u00e9 preciso treinar exerc\u00edcios respirat\u00f3rios<\/strong>, na inspira\u00e7\u00e3o pelo nariz, que \u00e9 uma barreira imunol\u00f3gica. &#8220;Encher os pulm\u00f5es, n\u00e3o apenas o t\u00f3rax, mas tamb\u00e9m o abd\u00f4men, pois nas bases pulmonares t\u00eam muito mais alv\u00e9olos e capilares sangu\u00edneos que ir\u00e3o aumentar a troca gasosa&#8221;, pondera o fisioterapeuta. &#8220;Para finalizar com a respira\u00e7\u00e3o, podemos fazer expira\u00e7\u00e3o pela boca. A respira\u00e7\u00e3o abdominal tamb\u00e9m ajuda no alongamento do diafragma, principal m\u00fasculo da respira\u00e7\u00e3o&#8221;, acrescenta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-97887\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE-02-600x1492.png\" alt=\"\" width=\"755\" height=\"1878\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE-02-600x1492.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE-02-1200x2985.png 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE-02-768x1910.png 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE-02-618x1536.png 618w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE-02-823x2048.png 823w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/p>\n<h3>Preven\u00e7\u00e3o<\/h3>\n<p>Quando a respira\u00e7\u00e3o ocorre de forma adequada, a capacidade funcional pulmonar \u00e9 melhorada, o que previne complica\u00e7\u00f5es por doen\u00e7as, como a Covid-19. &#8220;Exerc\u00edcios respirat\u00f3rios s\u00e3o preventivos e tamb\u00e9m podem ajudar durante e ap\u00f3s o contato com o v\u00edrus. Para a Covid-19, \u00e9 comum aparecer dispneia (desconforto respirat\u00f3rio), hipoxemia (baixa concentra\u00e7\u00e3o de oxig\u00eanio no sangue), insufici\u00eancia respirat\u00f3ria, choque e insufici\u00eancia de m\u00faltiplos \u00f3rg\u00e3os&#8221;, destaca.<\/p>\n<h3>Benef\u00edcios \u00e0 sa\u00fade mental<\/h3>\n<p><strong>A respira\u00e7\u00e3o tamb\u00e9m tem rela\u00e7\u00e3o com o estado emocional<\/strong>. Desse modo, se o que sentimos reflete no ritmo respirat\u00f3rio, como uma respira\u00e7\u00e3o mais acelerada num momento de tens\u00e3o, \u00e9 poss\u00edvel tamb\u00e9m controlar inspira\u00e7\u00e3o e expira\u00e7\u00e3o para induzir a calma. &#8220;A respira\u00e7\u00e3o promove relaxamento muscular, melhora a concentra\u00e7\u00e3o, diminui o estresse, ansiedade e depress\u00e3o, melhora o equil\u00edbrio, a autoestima, a imagem corporal e autoconceito&#8221;, indica.<\/p>\n<h3>Dicas nas redes sociais<\/h3>\n<p>O <a href=\"https:\/\/youtu.be\/svLvCqZCvVY\" target=\"_blank\" rel=\"noopener noreferrer\">canal do Youtub<\/a>e e o perfil do <a href=\"https:\/\/instagram.com\/espceara\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram da ESP\/CE<\/a> disponibilizam semanalmente uma s\u00e9rie de dicas e exerc\u00edcios para aprimorar a respira\u00e7\u00e3o. Os v\u00eddeos podem ser tamb\u00e9m acessados na busca pelo termo #VemRespirar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inspirar e expirar \u00e9 um ato autom\u00e1tico e involunt\u00e1rio, mas a devida aten\u00e7\u00e3o \u00e0 pr\u00e1tica da respira\u00e7\u00e3o pode ser um fator determinante para a sa\u00fade de qualquer pessoa. &#8220;O ideal \u00e9 que todos possam aprender a respirar corretamente, principalmente quando estamos saud\u00e1veis. Os exerc\u00edcios respirat\u00f3rios ajudam na preven\u00e7\u00e3o de doen\u00e7as, infec\u00e7\u00f5es pulmonares e, principalmente, nas [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":97888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[2165,2406,135],"class_list":["post-97886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-escola-publica-de-saude","tag-respiracao","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Inspirar e expirar \u00e9 um ato autom\u00e1tico e involunt\u00e1rio, mas a devida aten\u00e7\u00e3o \u00e0 pr\u00e1tica da respira\u00e7\u00e3o pode ser um fator determinante para a sa\u00fade de qualquer pessoa. &#8220;O ideal \u00e9 que todos possam aprender a respirar corretamente, principalmente quando estamos saud\u00e1veis. Os exerc\u00edcios respirat\u00f3rios ajudam na preven\u00e7\u00e3o de doen\u00e7as, infec\u00e7\u00f5es pulmonares e, principalmente, nas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-28T11:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3230\" \/>\n\t<meta property=\"og:image:height\" content=\"2021\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas\",\"datePublished\":\"2021-05-28T11:57:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\"},\"wordCount\":501,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png\",\"keywords\":[\"escola p\u00fablica de sa\u00fade\",\"respira\u00e7\u00e3o\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\",\"name\":\"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png\",\"datePublished\":\"2021-05-28T11:57:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png\",\"width\":3230,\"height\":2021},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/","og_locale":"pt_BR","og_type":"article","og_title":"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Inspirar e expirar \u00e9 um ato autom\u00e1tico e involunt\u00e1rio, mas a devida aten\u00e7\u00e3o \u00e0 pr\u00e1tica da respira\u00e7\u00e3o pode ser um fator determinante para a sa\u00fade de qualquer pessoa. &#8220;O ideal \u00e9 que todos possam aprender a respirar corretamente, principalmente quando estamos saud\u00e1veis. Os exerc\u00edcios respirat\u00f3rios ajudam na preven\u00e7\u00e3o de doen\u00e7as, infec\u00e7\u00f5es pulmonares e, principalmente, nas [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-05-28T11:57:17+00:00","og_image":[{"width":3230,"height":2021,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/"},"author":{"name":"","@id":""},"headline":"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas","datePublished":"2021-05-28T11:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/"},"wordCount":501,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png","keywords":["escola p\u00fablica de sa\u00fade","respira\u00e7\u00e3o","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/","name":"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png","datePublished":"2021-05-28T11:57:17+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/05\/BANNER_MANCHETE2_Prancheta_1.png","width":3230,"height":2021},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/05\/28\/respirar-corretamente-melhora-a-capacidade-funcional-dos-pulmoes-e-traz-beneficios-a-saude-confira-dicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Respirar corretamente melhora a capacidade funcional dos pulm\u00f5es e traz benef\u00edcios \u00e0 sa\u00fade; confira dicas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/97886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=97886"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/97886\/revisions"}],"predecessor-version":[{"id":97889,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/97886\/revisions\/97889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/97888"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=97886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=97886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=97886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}