{"id":97032,"date":"2021-04-30T14:01:34","date_gmt":"2021-04-30T17:01:34","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=97032"},"modified":"2021-04-30T14:07:09","modified_gmt":"2021-04-30T17:07:09","slug":"novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/","title":{"rendered":"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-97034\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-2-600x277.jpg\" alt=\"\" width=\"775\" height=\"357\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-2-600x277.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-2-1200x553.jpg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-2-768x354.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-2-1536x708.jpg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-2.jpg 2048w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\n<em>Al\u00e9m de ampliar o n\u00edvel de especializa\u00e7\u00e3o dos profissionais e expandir a sua atua\u00e7\u00e3o, a Escola poder\u00e1 desenvolver pesquisas e inova\u00e7\u00e3o em prol do sistema p\u00fablico de sa\u00fade<\/em><\/p>\n<p>A Assembleia Legislativa aprovou, na manh\u00e3 de quinta-feira (29), mensagem encaminhada pelo Governo do Cear\u00e1 que prev\u00ea as <strong>novas atribui\u00e7\u00f5es da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong>, vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa). O texto modificou a Lei N\u00ba 12.140, de 22 de julho de 1993, sobre a cria\u00e7\u00e3o da ESP\/CE, que <strong>passa a ser reconhecida como Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o (ICT)<\/strong>.<\/p>\n<p>A nova legisla\u00e7\u00e3o torna a ESP\/CE um <strong>Centro de Intelig\u00eancia em Sa\u00fade P\u00fablica<\/strong>. Com isso, al\u00e9m de ampliar o n\u00edvel de especializa\u00e7\u00e3o dos profissionais e expandir a sua atua\u00e7\u00e3o, <strong>a Escola poder\u00e1 desenvolver pesquisas e inova\u00e7\u00e3o em prol do sistema p\u00fablico de sa\u00fade<\/strong>. Desse modo, a ESP est\u00e1 autorizada a captar receitas provenientes de suas atividades na qualidade de ICT p\u00fablica, melhorar a ambi\u00eancia administrativa e promover <em>startups<\/em> e outros empreendimentos em \u00e1reas de interesse no \u00e2mbito do Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<p>\u201cSendo um ICT, al\u00e9m de ser uma escola de sa\u00fade, a institui\u00e7\u00e3o passa a incorporar uma pol\u00edtica de inova\u00e7\u00e3o clara, transparente, que vai dar for\u00e7a, incentivar e criar um ambiente favor\u00e1vel \u00e0 incorpora\u00e7\u00e3o de projetos inovadores para o setor sa\u00fade\u201d, destaca o superintendente da ESP\/CE, Marcelo Alcantara, salientado a necessidade de parcerias com outras institui\u00e7\u00f5es, sejam de ensino ou fomento \u00e0 pesquisa, e com a iniciativa privada.<\/p>\n<p>A medida \u00e9 considerada, inclusive,<strong> estrat\u00e9gica para o enfrentamento da pandemia de Covid-19<\/strong>, que j\u00e1 tem como exemplo o desenvolvimento do <strong>capacete de respira\u00e7\u00e3o assistida Elmo<\/strong>. Desenvolvido pela ESP\/CE como uma das institui\u00e7\u00f5es integrantes de uma for\u00e7a-tarefa p\u00fablico-privada, o dispositivo \u00e9 um exemplo nacional de inova\u00e7\u00e3o em sa\u00fade, criado por pesquisadores cearenses, e j\u00e1 utilizado em diversos estados do Brasil. O Elmo auxilia na recupera\u00e7\u00e3o de pacientes acometidos por insufici\u00eancia respirat\u00f3ria,<strong> evitando a intuba\u00e7\u00e3o de 60% das pessoas submetidas ao tratamento<\/strong>.<\/p>\n<p>Para a assessora t\u00e9cnica da ESP\/CE, Alice Pequeno, a caracteriza\u00e7\u00e3o legal como ICT \u00e9 um marco para o avan\u00e7o da sa\u00fade p\u00fablica no Cear\u00e1. \u201cEssa transforma\u00e7\u00e3o est\u00e1 alinhada \u00e0 <strong>Plataforma de Moderniza\u00e7\u00e3o da Sa\u00fade da Sesa<\/strong>. \u00c9 muito importante que no momento que a nossa Escola vai se transformar num instituto de ci\u00eancia e tecnologia, que sejam potencializadas as a\u00e7\u00f5es de ensino, extens\u00e3o, pesquisa, inova\u00e7\u00e3o em ci\u00eancia e tecnologia para a gera\u00e7\u00e3o de novos produtos em sa\u00fade p\u00fablica que venham ajudar no enfrentamento dos problemas do nosso estado e do nosso pa\u00eds\u201d, destaca.<\/p>\n<h3>A Escola<\/h3>\n<p>Autarquia vinculada \u00e0 Sesa, a Escola de Sa\u00fade P\u00fablica do Cear\u00e1 foi fundada em 22 de julho de 1993 com o objetivo de promover a forma\u00e7\u00e3o e educa\u00e7\u00e3o permanente, pesquisa e extens\u00e3o na \u00e1rea da sa\u00fade, integrando ensino-servi\u00e7o-comunidade \u00e0s suas pr\u00e1ticas.<\/p>\n<p>Nesse per\u00edodo, a ESP tem constru\u00eddo s\u00f3lidas parcerias e redes colaborativas para o atendimento das necessidades sociais do <strong>Sistema \u00danico de Sa\u00fade<\/strong>. Sua atua\u00e7\u00e3o engloba um trabalho pioneiro junto a programas de resid\u00eancias em sa\u00fade, educa\u00e7\u00e3o profissional em sa\u00fade, cursos e projetos nas \u00e1reas da gest\u00e3o, aten\u00e7\u00e3o, vigil\u00e2ncia e extens\u00e3o em sa\u00fade.<\/p>\n<p>Durante a pandemia, a ESP\/CE se destacou tamb\u00e9m por diversas iniciativas, como o desenvolvimento do capacete Elmo e do<strong> aplicativo iSUS<\/strong>, voltado para atender os profissionais de sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00e9m de ampliar o n\u00edvel de especializa\u00e7\u00e3o dos profissionais e expandir a sua atua\u00e7\u00e3o, a Escola poder\u00e1 desenvolver pesquisas e inova\u00e7\u00e3o em prol do sistema p\u00fablico de sa\u00fade A Assembleia Legislativa aprovou, na manh\u00e3 de quinta-feira (29), mensagem encaminhada pelo Governo do Cear\u00e1 que prev\u00ea as novas atribui\u00e7\u00f5es da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":97033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,2165,1031,2353,1357],"class_list":["post-97032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-escola-publica-de-saude","tag-inovacao","tag-instituicao-cientifica","tag-tecnologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Al\u00e9m de ampliar o n\u00edvel de especializa\u00e7\u00e3o dos profissionais e expandir a sua atua\u00e7\u00e3o, a Escola poder\u00e1 desenvolver pesquisas e inova\u00e7\u00e3o em prol do sistema p\u00fablico de sa\u00fade A Assembleia Legislativa aprovou, na manh\u00e3 de quinta-feira (29), mensagem encaminhada pelo Governo do Cear\u00e1 que prev\u00ea as novas atribui\u00e7\u00f5es da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T17:01:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T17:07:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"944\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o\",\"datePublished\":\"2021-04-30T17:01:34+00:00\",\"dateModified\":\"2021-04-30T17:07:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\"},\"wordCount\":646,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg\",\"keywords\":[\"Cear\u00e1\",\"escola p\u00fablica de sa\u00fade\",\"inova\u00e7\u00e3o\",\"Institui\u00e7\u00e3o Cient\u00edfica\",\"Tecnologia\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\",\"name\":\"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg\",\"datePublished\":\"2021-04-30T17:01:34+00:00\",\"dateModified\":\"2021-04-30T17:07:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg\",\"width\":2048,\"height\":944},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Al\u00e9m de ampliar o n\u00edvel de especializa\u00e7\u00e3o dos profissionais e expandir a sua atua\u00e7\u00e3o, a Escola poder\u00e1 desenvolver pesquisas e inova\u00e7\u00e3o em prol do sistema p\u00fablico de sa\u00fade A Assembleia Legislativa aprovou, na manh\u00e3 de quinta-feira (29), mensagem encaminhada pelo Governo do Cear\u00e1 que prev\u00ea as novas atribui\u00e7\u00f5es da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-04-30T17:01:34+00:00","article_modified_time":"2021-04-30T17:07:09+00:00","og_image":[{"width":2048,"height":944,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/"},"author":{"name":"","@id":""},"headline":"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o","datePublished":"2021-04-30T17:01:34+00:00","dateModified":"2021-04-30T17:07:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/"},"wordCount":646,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg","keywords":["Cear\u00e1","escola p\u00fablica de sa\u00fade","inova\u00e7\u00e3o","Institui\u00e7\u00e3o Cient\u00edfica","Tecnologia"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/","name":"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg","datePublished":"2021-04-30T17:01:34+00:00","dateModified":"2021-04-30T17:07:09+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/04\/20210222_135044-2048x944-1.jpg","width":2048,"height":944},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/04\/30\/novas-atribuicoes-transformam-esp-ce-em-instituicao-cientifica-tecnologica-e-de-inovacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Novas atribui\u00e7\u00f5es transformam ESP\/CE em Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/97032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=97032"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/97032\/revisions"}],"predecessor-version":[{"id":97038,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/97032\/revisions\/97038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/97033"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=97032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=97032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=97032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}