{"id":9684,"date":"2017-09-26T12:15:25","date_gmt":"2017-09-26T15:15:25","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/"},"modified":"2019-01-09T13:14:11","modified_gmt":"2019-01-09T16:14:11","slug":"acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/","title":{"rendered":"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC"},"content":{"rendered":"<p>O cuidado, no Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, n\u00e3o \u00e9 destinado somente ao paciente internado ou ao paciente em acompanhamento ambulatorial. Assim como os cuidadores de idosos com dem\u00eancia e Alzheimer, que participam mensalmente do grupo multidisciplinar de apoio e orienta\u00e7\u00e3o, o hospital tamb\u00e9m disponibiliza atendimento para os acompanhantes.<\/p>\n<p>\u00c9 o Grupo de Apoio aos Acompanhantes, roda de conversa realizada pelo Servi\u00e7o de Psicologia que busca proporcionar momentos de descontra\u00e7\u00e3o e de escuta dos acompanhantes que ficam no hospital junto aos pacientes. As manh\u00e3s de quinta-feira, sempre no hor\u00e1rio de 8h \u00e0s 10h, s\u00e3o dedicadas a um momento de conversas, escuta, relaxamento, express\u00e3o dos sentimentos, din\u00e2micas, entre outras atividades.\u00a0 Carola Jorge Riffel, psic\u00f3loga do HGCC, conta que o grupo come\u00e7ou pequeno, com uma participa\u00e7\u00e3o n\u00e3o muito efetiva, mas que atualmente os pr\u00f3prios acompanhantes buscam pelo encontro, demonstrando mais interesse. \u201cCome\u00e7amos com uma participa\u00e7\u00e3o pequena e hoje eles participam mais, j\u00e1 gostam de participar porque antes n\u00e3o compreendiam bem a proposta. Hoje eles entendem que \u00e9 um espa\u00e7o promovido pelo hospital para eles se expressarem\u201d, explica.<\/p>\n<p>Na manh\u00e3 de quinta-feira, 21, foi a primeira vez que a Dona F\u00e1tima Maria Siqueira de Sousa participou do encontro. Ela est\u00e1 acompanhando o esposo desde o dia 19 de agosto. Nunca tinha participado do encontro, mas saiu feliz e dizendo que estava se sentindo em casa pelo apoio recebido. \u201cAl\u00e9m de ver meu marido melhorar a cada dia, o hospital ainda se preocupa em saber nossa opini\u00e3o, ouvir os acompanhantes\u201d, declara a participante. Quem participou pela \u00faltima vez foi a Dona Odete Viana Moreira, que estava acompanhando o cunhado, que teve alta no final do dia. Ela aproveitou o momento para compartilhar a boa not\u00edcia e tamb\u00e9m agradecer. \u201cO momento \u00e9 construtivo e ajuda a passar o tempo aqui no hospital\u201d, conta a acompanhante.<\/p>\n<p>Os acompanhantes passam muito tempo no hospital. Da\u00ed a necessidade de estender o cuidado al\u00e9m do paciente. \u201cOs acompanhantes, de alguma maneira, tamb\u00e9m vivenciam o ambiente hospitalar como um todo. Por isso \u00e9 importante tentar ouvi-los, conhecer os sentimentos, as emo\u00e7\u00f5es, as preocupa\u00e7\u00f5es por estarem muito tempo na unidade\u201d, esclarece Carola Riffel. Para que o papel do acompanhante seja desempenhado bem, eles precisam se sentir participante do processo. Precisam tamb\u00e9m se sentirem apoiados para tamb\u00e9m apoiar. \u201cSe eles est\u00e3o bem, certamente v\u00e3o desempenhar melhor o cuidado. Se eles est\u00e3o cansados, estressados, isso tamb\u00e9m vai implicar no tratamento, na maneira como eles desempenham suas fun\u00e7\u00f5es junto aos pacientes\u201d, \u00e9 o que constata Ana Cristina Coelho, psic\u00f3loga que passou integrar o grupo.<\/p>\n<p>Os assuntos mais abordados, de acordo com as psic\u00f3logas participantes retratam a preocupa\u00e7\u00e3o com os pacientes, a alta hospitalar e sobre o tratamento. Assuntos do cotidiano tamb\u00e9m s\u00e3o abordados, como a vida fora do hospital. Destacam tamb\u00e9m a import\u00e2ncia do apoio m\u00fatuo entre eles, entre os pacientes. \u201cUma das formas de chegar at\u00e9 o paciente \u00e9 por meio do cuidador. Se o cuidador est\u00e1 bem, ele consegue cuidar bem do paciente. Muitas vezes \u00e9 dif\u00edcil para eles se desligarem dos problemas de fora e poder focar no paciente. Realizamos v\u00e1rias atividades para eles se colocarem no lugar do paciente para entenderem que s\u00e3o importantes no cuidado\u201d destaca Sara Bastos, psic\u00f3loga que tamb\u00e9m participa dos encontros . No \u00faltimo encontro, 12 acompanhantes estiveram presentes para compartilhar suas hist\u00f3rias em mais uma a\u00e7\u00e3o de atendimento humanizado do Hospital Geral Dr. C\u00e9sar Cals.<\/p>\n<p><span style=\"font-size: 10px\"><em><strong>Foto:<\/strong> Assessoria de Comunica\u00e7\u00e3o do HGCC<\/em><\/span><\/p>\n<p><strong>Assessoria de Comunica\u00e7\u00e3o do HGCC<\/strong><br \/>\nWescley Jorge<br \/>\n<a href=\"mailto:ascom@hgcc.ce.gov.br\">ascom@hgcc.ce.gov.br<\/a> \/ 85 3101.5323<br \/>\nFacebook.com\/HospitalGeralCesarCals<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cuidado, no Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, n\u00e3o \u00e9 destinado somente ao paciente internado ou ao paciente em acompanhamento ambulatorial. Assim como os cuidadores de idosos com dem\u00eancia e Alzheimer, que participam mensalmente do grupo multidisciplinar de apoio e orienta\u00e7\u00e3o, o hospital tamb\u00e9m disponibiliza atendimento [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[501],"tags":[],"class_list":["post-9684","post","type-post","status-publish","format-standard","hentry","category-hgcc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O cuidado, no Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, n\u00e3o \u00e9 destinado somente ao paciente internado ou ao paciente em acompanhamento ambulatorial. Assim como os cuidadores de idosos com dem\u00eancia e Alzheimer, que participam mensalmente do grupo multidisciplinar de apoio e orienta\u00e7\u00e3o, o hospital tamb\u00e9m disponibiliza atendimento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-26T15:15:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-09T16:14:11+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC\",\"datePublished\":\"2017-09-26T15:15:25+00:00\",\"dateModified\":\"2019-01-09T16:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\"},\"wordCount\":642,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Hospital Geral Dr. C\u00e9sar Cals (HGCC)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\",\"name\":\"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2017-09-26T15:15:25+00:00\",\"dateModified\":\"2019-01-09T16:14:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/","og_locale":"pt_BR","og_type":"article","og_title":"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O cuidado, no Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, n\u00e3o \u00e9 destinado somente ao paciente internado ou ao paciente em acompanhamento ambulatorial. Assim como os cuidadores de idosos com dem\u00eancia e Alzheimer, que participam mensalmente do grupo multidisciplinar de apoio e orienta\u00e7\u00e3o, o hospital tamb\u00e9m disponibiliza atendimento [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2017-09-26T15:15:25+00:00","article_modified_time":"2019-01-09T16:14:11+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC","datePublished":"2017-09-26T15:15:25+00:00","dateModified":"2019-01-09T16:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/"},"wordCount":642,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Hospital Geral Dr. C\u00e9sar Cals (HGCC)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/","name":"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2017-09-26T15:15:25+00:00","dateModified":"2019-01-09T16:14:11+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2017\/09\/26\/acompanhantes-recebem-atencao-psicologica-no-hospital-cesar-cals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Acompanhantes recebem aten\u00e7\u00e3o psicol\u00f3gica no HGCC"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=9684"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9684\/revisions"}],"predecessor-version":[{"id":76474,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/9684\/revisions\/76474"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=9684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=9684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=9684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}