{"id":95067,"date":"2021-03-10T14:02:18","date_gmt":"2021-03-10T17:02:18","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=95067"},"modified":"2021-03-10T14:08:21","modified_gmt":"2021-03-10T17:08:21","slug":"novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/","title":{"rendered":"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10)"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-medium wp-image-135538\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6344-1-600x400.jpg\" alt=\"\" width=\"100%\" height=\"230\" \/><\/p>\n<p style=\"text-align: center\"><em>Distribui\u00e7\u00e3o das novas doses come\u00e7a imediatamente nesta quarta-feira (10) para agilizar o processo de imuniza\u00e7\u00e3o contra a Covid-19 em todo o Estado<\/em><\/p>\n<p>Avi\u00e3o com <strong>109.800 mil doses da vacina CoronaVac\/Butantan<\/strong> chegou ao Aeroporto Internacional de Fortaleza \u2013 Pinto Martins no fim da manh\u00e3 desta\u00a0<span id=\"OBJ_PREFIX_DWT129_com_zimbra_date\" class=\"Object\" role=\"link\">quarta<\/span>-feira (10). As novas doses correspondem <strong>ao oitavo lote de imunizantes que o Cear\u00e1 recebeu para a campanha de vacina\u00e7\u00e3o dos cearenses contra a Covid-19<\/strong>.<\/p>\n<p>Em publica\u00e7\u00e3o nas redes sociais, o governador Camilo Santana comentou sobre o ritmo de produ\u00e7\u00e3o e distribui\u00e7\u00e3o das vacinas em todo Pa\u00eds, e reafirmou que tem buscado alternativas para acelerar a imuniza\u00e7\u00e3o da popula\u00e7\u00e3o. \u201cPor isso, temos conversado periodicamente com o Minist\u00e9rio da Sa\u00fade, Fiocruz e Butantan, para cobrarmos mais agilidade nesse processo, al\u00e9m de estarmos em contato com outros laborat\u00f3rios para viabilizarmos a compra direta de imunizantes\u201d.<\/p>\n<p>De acordo com a Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), o Estado recebeu, at\u00e9 agora, <strong>805 mil doses de vacinas contra a Covid-19<\/strong>. Desse total, s\u00e3o 652 mil da CoronaVac, desenvolvida pela farmac\u00eautica Sinovac em parceria com o Instituto Butantan, e 153 mil da Oxford\/AstraZeneca, do laborat\u00f3rio AstraZeneca e da Universidade de Oxford, produzida no Brasil pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz).<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-135539 aligncenter\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/03\/quadro-materia-lotes-vacina_2-600x280.png\" alt=\"\" width=\"100%\" height=\"230\" \/><\/p>\n<h3>Distribui\u00e7\u00e3o<\/h3>\n<p>As doses ser\u00e3o distribu\u00eddas \u00e0 Capital e aos munic\u00edpios do Interior imediatamente nesta quarta-feira (10), seguindo o plano de log\u00edstica elaborado pelo Governo do Estado, operacionalizado pela Sesa. Com seis rotas de distribui\u00e7\u00e3o a\u00e9rea e duas terrestres, a estrat\u00e9gia tem o objetivo de garantir a conserva\u00e7\u00e3o e agilidade no envio dos imunizantes para as 22 \u00c1reas Descentralizadas de Sa\u00fade (ADS), respons\u00e1veis por articular a entrega do material junto \u00e0 secretaria de sa\u00fade de cada munic\u00edpio cearense.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-135540\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400.jpg\" alt=\"\" width=\"100%\" height=\"230\" \/><\/p>\n<p><strong>Os imunizantes ser\u00e3o destinados para aplica\u00e7\u00e3o da primeira e da segunda dose em profissionais da sa\u00fade e idosos a partir de 75 anos, grupo que est\u00e1 na primeira fase do Plano Nacional de Imuniza\u00e7\u00e3o (PNI)<\/strong>, coordenado pelo Minist\u00e9rio da Sa\u00fade.<\/p>\n<h3>Vacin\u00f4metro<\/h3>\n<p>Em todo o Cear\u00e1, 508.274 mil doses de vacinas contra a Covid-19 foram aplicadas at\u00e9 ter\u00e7a-feira (9). Um total de 369.231 mil cearenses receberam a primeira dose e 139.043 mil j\u00e1 foram imunizados com o refor\u00e7o. Parte do estoque de CoronaVac est\u00e1 reservado para a aplica\u00e7\u00e3o de segunda dose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Distribui\u00e7\u00e3o das novas doses come\u00e7a imediatamente nesta quarta-feira (10) para agilizar o processo de imuniza\u00e7\u00e3o contra a Covid-19 em todo o Estado Avi\u00e3o com 109.800 mil doses da vacina CoronaVac\/Butantan chegou ao Aeroporto Internacional de Fortaleza \u2013 Pinto Martins no fim da manh\u00e3 desta\u00a0quarta-feira (10). As novas doses correspondem ao oitavo lote de imunizantes que [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":95068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[133,2145,1515,135,954],"class_list":["post-95067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-ceara","tag-coronavac","tag-covid-19","tag-saude","tag-vacina"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10) - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10) - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Distribui\u00e7\u00e3o das novas doses come\u00e7a imediatamente nesta quarta-feira (10) para agilizar o processo de imuniza\u00e7\u00e3o contra a Covid-19 em todo o Estado Avi\u00e3o com 109.800 mil doses da vacina CoronaVac\/Butantan chegou ao Aeroporto Internacional de Fortaleza \u2013 Pinto Martins no fim da manh\u00e3 desta\u00a0quarta-feira (10). As novas doses correspondem ao oitavo lote de imunizantes que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-10T17:02:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-10T17:08:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10)\",\"datePublished\":\"2021-03-10T17:02:18+00:00\",\"dateModified\":\"2021-03-10T17:08:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\"},\"wordCount\":410,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg\",\"keywords\":[\"Cear\u00e1\",\"coronavac\",\"covid-19\",\"sa\u00fade\",\"vacina\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\",\"name\":\"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10) - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg\",\"datePublished\":\"2021-03-10T17:02:18+00:00\",\"dateModified\":\"2021-03-10T17:08:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10) - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10) - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Distribui\u00e7\u00e3o das novas doses come\u00e7a imediatamente nesta quarta-feira (10) para agilizar o processo de imuniza\u00e7\u00e3o contra a Covid-19 em todo o Estado Avi\u00e3o com 109.800 mil doses da vacina CoronaVac\/Butantan chegou ao Aeroporto Internacional de Fortaleza \u2013 Pinto Martins no fim da manh\u00e3 desta\u00a0quarta-feira (10). As novas doses correspondem ao oitavo lote de imunizantes que [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-03-10T17:02:18+00:00","article_modified_time":"2021-03-10T17:08:21+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/"},"author":{"name":"","@id":""},"headline":"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10)","datePublished":"2021-03-10T17:02:18+00:00","dateModified":"2021-03-10T17:08:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/"},"wordCount":410,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg","keywords":["Cear\u00e1","coronavac","covid-19","sa\u00fade","vacina"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/","name":"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10) - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg","datePublished":"2021-03-10T17:02:18+00:00","dateModified":"2021-03-10T17:08:21+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/03\/210310_LOTE-8-CORONAVAC_TF6422-600x400-1.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/03\/10\/novo-lote-com-109-800-doses-da-coronavac-chega-ao-ceara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Novo lote com 109.800 doses da CoronaVac chega ao Cear\u00e1; distribui\u00e7\u00e3o come\u00e7a j\u00e1 nesta quarta (10)"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/95067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=95067"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/95067\/revisions"}],"predecessor-version":[{"id":95076,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/95067\/revisions\/95076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/95068"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=95067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=95067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=95067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}