{"id":94129,"date":"2021-02-15T19:09:40","date_gmt":"2021-02-15T22:09:40","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=94129"},"modified":"2021-02-16T11:05:28","modified_gmt":"2021-02-16T14:05:28","slug":"carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/","title":{"rendered":"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4393.jpg\" \/><\/p>\n<p>Cumprindo o\u00a0<a href=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/02\/do20210210p02.pdf\">decreto especial para o per\u00edodo de Carnaval<\/a>, com o objetivo de preven\u00e7\u00e3o contra a dissemina\u00e7\u00e3o da Covid-19 no Estado, o Governo do Cear\u00e1 divulga o balan\u00e7o dos dias 12,13 e\u00a0<span id=\"OBJ_PREFIX_DWT67_com_zimbra_date\" class=\"Object\" role=\"link\">14 de fevereiro<\/span>. Nesse per\u00edodo, equipes da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Vigil\u00e2ncia Sanit\u00e1ria e da Pol\u00edcia Militar, fiscalizaram 1.387 estabelecimentos em todo o Cear\u00e1. Como resultado, dois com\u00e9rcios foram interditados, houve 12 autua\u00e7\u00f5es e 439 foram fechados temporariamente por descumprimento do decreto.<\/p>\n<h3>Fortaleza<\/h3>\n<p>No mesmo per\u00edodo, a Ag\u00eancia de Fiscaliza\u00e7\u00e3o de Fortaleza (Agefis), com o apoio da Inspetoria de Prote\u00e7\u00e3o Ambiental (Ipam), da Guarda Municipal de Fortaleza (GMFor), da Autarquia Municipal de Tr\u00e2nsito e Cidadania (AMC) e da Batalh\u00e3o de Pol\u00edcia de Meio Ambiente (BPMA), realizou 51 fiscaliza\u00e7\u00f5es na Capital cearense, resultando em 13 autua\u00e7\u00f5es, 13 notifica\u00e7\u00f5es e 19 estabelecimentos foram interditados em descumprimento aos decretos municipal e estadual de enfrentamento \u00e0 Covid-19. Al\u00e9m disso, houve apreens\u00e3o de cinco \u201cpared\u00f5es\u201d de som.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-133693 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<h3>Medidas de preven\u00e7\u00e3o<\/h3>\n<p>O governador Camilo Santana refor\u00e7ou a necessidade de aplicar as medidas de preven\u00e7\u00e3o. \u201cNesse momento precisamos colocar em pr\u00e1tica a\u00e7\u00f5es de restri\u00e7\u00e3o e de isolamento social, por isso\u00a0<a href=\"https:\/\/www.ceara.gov.br\/2021\/02\/10\/governo-do-ceara-anuncia-decreto-especial-para-o-periodo-de-carnaval\/\">fizemos decretos \u2013 o atual e o de Carnaval, v\u00e1lido de 12 a 17 de fevereiro<\/a> \u2013 para evitar as aglomera\u00e7\u00f5es e minimizar o efeito na economia do Estado. Nos preocupamos com o emprego, mas a prioridade \u00e9 a vida das pessoas\u201d, aponta.<\/p>\n<p>Camilo Santana tamb\u00e9m relembrou que foi recomendado aos munic\u00edpios com tradi\u00e7\u00e3o tur\u00edstica o uso de barreiras sanit\u00e1rias e medidas mais restritivas nesse per\u00edodo, de acordo com a situa\u00e7\u00e3o de cada um. \u201cPara isso, est\u00e1 havendo refor\u00e7o de policiamento nesses locais para apoiar o cumprimento dessas medidas\u201d, ressalta o governador do Cear\u00e1.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-133686 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/02\/Agefis-13012021-11.jpeg\" alt=\"\" width=\"1280\" height=\"960\" \/><\/p>\n<h3>Festas clandestinas<\/h3>\n<p>\u201cA popula\u00e7\u00e3o mais jovem, que \u00e9 vista frequentando festas clandestinas, eventos que se caracterizam como super disseminadores de Covid-19, pois s\u00e3o ambientes em que as pessoas est\u00e3o sem usar m\u00e1scara, em sua grande maioria, e de uma forma aglomerada, \u00e9 a mesma faixa et\u00e1ria de perfis mais jovens que, no \u00faltimo m\u00eas, registrou um aumento de casos da doen\u00e7a. Mesmo assintom\u00e1tica, uma pessoa dentro de um ambiente como esse pode transmitir a doen\u00e7a, ent\u00e3o o ideal \u00e9 n\u00e3o participar de nenhum tipo de evento como esse\u201d, alerta Jane Cris Cunha, t\u00e9cnica da Vigil\u00e2ncia Sanit\u00e1ria do Estado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-133685 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2021\/02\/IMG-20210215-WA0034.jpg\" alt=\"\" width=\"1280\" height=\"960\" \/><\/p>\n<h3>Detran<\/h3>\n<p>O balan\u00e7o do Departamento Estadual de Tr\u00e2nsito (Detran) de 12 a 14 de fevereiro mostra que foram abordados 1.577 ve\u00edculos, com 415 infra\u00e7\u00f5es lavradas. Foram flagrados 17 ve\u00edculos em faixas de areia e em orla mar\u00edtima, 71 motociclistas conduzindo sem o uso do capacete, e 27 condutores n\u00e3o habilitados. Os trabalhos contam com o apoio da Batalh\u00e3o de Pol\u00edcia de Tr\u00e2nsito Urbano e Rodovi\u00e1rio Estadual (BPRE) e est\u00e3o presentes em diversos pontos da Capital, Regi\u00e3o Metropolitana e Interior, atendendo ao decreto N\u00ba 33.928, do Governo do Estado, sobre medidas de preven\u00e7\u00e3o \u00e0 dissemina\u00e7\u00e3o da Covid-19 no Cear\u00e1 durante o per\u00edodo que seria o Carnaval.<\/p>\n<p>As opera\u00e7\u00f5es se d\u00e3o em 16 em pontos de sa\u00eddas de Fortaleza, 60 no Interior e mais 106 em praias da Regi\u00e3o Metropolitana, Litoral Leste e Litoral Oeste do Cear\u00e1. O efetivo conta com um total de 230 agentes do Detran-CE, al\u00e9m de 60 viaturas, 15 reboques e 50 etil\u00f4metros (aparelho que determina a concentra\u00e7\u00e3o de bebida alco\u00f3lica, analisando o ar exalado dos pulm\u00f5es de uma pessoa).<\/p>\n<h3>Ou\u00e7a<\/h3>\n<p>O governador Camilo Santana refor\u00e7ou a necessidade de aplicar as medidas de preven\u00e7\u00e3o.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/15.02-CAMILO-1-PREVINE.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/15.02-CAMILO-1-PREVINE.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>A coordenadora estadual da Vigil\u00e2ncia Sanit\u00e1ria, Jane Cris Cunha, alerta que ainda n\u00e3o \u00e9 poss\u00edvel haver aglomera\u00e7\u00e3o neste momento da pandemia<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/15.02-JANE-2-AGLOMERA.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/15.02-JANE-2-AGLOMERA.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>Mesmo com esse comportamento da popula\u00e7\u00e3o, Jane Cris\u00a0 destaca uma maior conscientiza\u00e7\u00e3o popular.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/15.02-JANE-3-CONSCIENCIA.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/15.02-JANE-3-CONSCIENCIA.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Cumprindo o\u00a0decreto especial para o per\u00edodo de Carnaval, com o objetivo de preven\u00e7\u00e3o contra a dissemina\u00e7\u00e3o da Covid-19 no Estado, o Governo do Cear\u00e1 divulga o balan\u00e7o dos dias 12,13 e\u00a014 de fevereiro. Nesse per\u00edodo, equipes da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Vigil\u00e2ncia Sanit\u00e1ria e da Pol\u00edcia Militar, fiscalizaram 1.387 estabelecimentos [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":94130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[161,1515,1732,667,135],"class_list":["post-94129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-carnaval","tag-covid-19","tag-fiscalizacao","tag-governo-do-ceara","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Cumprindo o\u00a0decreto especial para o per\u00edodo de Carnaval, com o objetivo de preven\u00e7\u00e3o contra a dissemina\u00e7\u00e3o da Covid-19 no Estado, o Governo do Cear\u00e1 divulga o balan\u00e7o dos dias 12,13 e\u00a014 de fevereiro. Nesse per\u00edodo, equipes da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Vigil\u00e2ncia Sanit\u00e1ria e da Pol\u00edcia Militar, fiscalizaram 1.387 estabelecimentos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-15T22:09:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T14:05:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana\",\"datePublished\":\"2021-02-15T22:09:40+00:00\",\"dateModified\":\"2021-02-16T14:05:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\"},\"wordCount\":709,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg\",\"keywords\":[\"Carnaval\",\"covid-19\",\"Fiscaliza\u00e7\u00e3o\",\"Governo do Cear\u00e1\",\"sa\u00fade\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\",\"name\":\"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg\",\"datePublished\":\"2021-02-15T22:09:40+00:00\",\"dateModified\":\"2021-02-16T14:05:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/","og_locale":"pt_BR","og_type":"article","og_title":"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Cumprindo o\u00a0decreto especial para o per\u00edodo de Carnaval, com o objetivo de preven\u00e7\u00e3o contra a dissemina\u00e7\u00e3o da Covid-19 no Estado, o Governo do Cear\u00e1 divulga o balan\u00e7o dos dias 12,13 e\u00a014 de fevereiro. Nesse per\u00edodo, equipes da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Vigil\u00e2ncia Sanit\u00e1ria e da Pol\u00edcia Militar, fiscalizaram 1.387 estabelecimentos [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-02-15T22:09:40+00:00","article_modified_time":"2021-02-16T14:05:28+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/"},"author":{"name":"","@id":""},"headline":"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana","datePublished":"2021-02-15T22:09:40+00:00","dateModified":"2021-02-16T14:05:28+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/"},"wordCount":709,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg","keywords":["Carnaval","covid-19","Fiscaliza\u00e7\u00e3o","Governo do Cear\u00e1","sa\u00fade"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/","name":"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg","datePublished":"2021-02-15T22:09:40+00:00","dateModified":"2021-02-16T14:05:28+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210215_VIG-SANIT_SABIAGUABA_TF4525-1536x1024-1.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/15\/carnaval-1-387-estabelecimentos-fiscalizados-durante-o-fim-de-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Carnaval: 1.387 estabelecimentos fiscalizados durante o fim de semana"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/94129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=94129"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/94129\/revisions"}],"predecessor-version":[{"id":94145,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/94129\/revisions\/94145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/94130"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=94129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=94129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=94129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}