{"id":93626,"date":"2021-02-07T09:31:58","date_gmt":"2021-02-07T12:31:58","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=93626"},"modified":"2021-02-08T09:33:43","modified_gmt":"2021-02-08T12:33:43","slug":"ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/","title":{"rendered":"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-93630\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1-600x400.jpeg\" alt=\"\" width=\"755\" height=\"503\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1-600x400.jpeg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1-1200x800.jpeg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1-768x512.jpeg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg 1280w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><em>Imunizante vai refor\u00e7ar a aplica\u00e7\u00e3o da primeira e segunda doses nos profissionais de sa\u00fade<\/em><\/p>\n<p>Desembarcou no Cear\u00e1 na noite deste s\u00e1bado (6) a quarta carga trazendo <strong>imunizantes contra a Covid-19<\/strong>. O avi\u00e3o pousou no Aeroporto Internacional de Fortaleza pouco antes das 22h45. Nele, estavam <strong>mais 115 mil doses da vacina CoronaVac<\/strong>. Com esta remessa, o Cear\u00e1 chega a 449.900 doses recebidas desde o in\u00edcio da campanha de vacina\u00e7\u00e3o, somadas as entregas anteriores de CoronaVac (262.400) e AstraZeneca (72.500).<\/p>\n<p>Em postagem nas redes sociais, o governador Camilo Santana falou sobre o desembarque. \u201cRecebemos h\u00e1 pouco em nosso aeroporto o quarto lote de vacinas contra a Covid. Foram 115 mil doses da CoronaVac\/Butantan, que refor\u00e7ar\u00e3o a campanha de imuniza\u00e7\u00e3o em todo o Cear\u00e1\u201d, afirmou o chefe do Executivo estadual. \u201cCerca de 160 mil cearenses foram vacinados at\u00e9 o momento, e nossa meta \u00e9 acelerar o processo de vacina\u00e7\u00e3o em todo o Estado. Seguimos firmes nessa luta\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-93631\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210206_CHEGADA-CORONAVAC_TF3533-1536x1024-1-600x400.jpg\" alt=\"\" width=\"755\" height=\"503\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210206_CHEGADA-CORONAVAC_TF3533-1536x1024-1-600x400.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210206_CHEGADA-CORONAVAC_TF3533-1536x1024-1-1200x800.jpg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210206_CHEGADA-CORONAVAC_TF3533-1536x1024-1-768x512.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/210206_CHEGADA-CORONAVAC_TF3533-1536x1024-1.jpg 1536w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/p>\n<p>Nesta segunda-feira (8), o novo lote come\u00e7a a ser <strong>distribu\u00eddo para os munic\u00edpios<\/strong> e deve refor\u00e7ar a quantidade de vacinas para primeira e segunda doses dos profissionais de sa\u00fade. \u201cVamos intensificar a campanha de vacina\u00e7\u00e3o no nosso Estado. Inclusive, neste s\u00e1bado, j\u00e1 foram abertos outros pontos de vacina\u00e7\u00e3o em Fortaleza\u201d, ressaltou Camilo Santana. \u201cContinuamos fazendo todos os esfor\u00e7os necess\u00e1rios para agilizar ao m\u00e1ximo essa imuniza\u00e7\u00e3o dos nossos irm\u00e3os e irm\u00e3s cearenses, principalmente aqueles que est\u00e3o nos grupos mais vulner\u00e1veis\u201d.<\/p>\n<h3>Refor\u00e7o<\/h3>\n<p>Na \u00faltima sexta-feira (5), em transmiss\u00e3o ao vivo nas redes sociais, o governador Camilo Santana e o prefeito de Fortaleza, Jos\u00e9 Sarto, anunciaram <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/06\/capital-vai-ganhar-novas-medidas-para-ampliar-vacinacao\/\" target=\"_blank\" rel=\"noopener noreferrer\">novas medidas para o enfrentamento da pandemia e o processo de imuniza\u00e7\u00e3o<\/a>. Entre elas est\u00e3o o aumento dos postos de vacina\u00e7\u00e3o com seis drive-thrus, que visam a atender \u00e0queles com mais de 75 anos, al\u00e9m da parceria com t\u00e1xis e aplicativos de mobilidade para o transporte de quem n\u00e3o tem carro e a garantia da circula\u00e7\u00e3o de 200 \u00f4nibus a mais, em hor\u00e1rios de pico,\u00a0na Capital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imunizante vai refor\u00e7ar a aplica\u00e7\u00e3o da primeira e segunda doses nos profissionais de sa\u00fade Desembarcou no Cear\u00e1 na noite deste s\u00e1bado (6) a quarta carga trazendo imunizantes contra a Covid-19. O avi\u00e3o pousou no Aeroporto Internacional de Fortaleza pouco antes das 22h45. Nele, estavam mais 115 mil doses da vacina CoronaVac. Com esta remessa, o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":93630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[],"class_list":["post-93626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Imunizante vai refor\u00e7ar a aplica\u00e7\u00e3o da primeira e segunda doses nos profissionais de sa\u00fade Desembarcou no Cear\u00e1 na noite deste s\u00e1bado (6) a quarta carga trazendo imunizantes contra a Covid-19. O avi\u00e3o pousou no Aeroporto Internacional de Fortaleza pouco antes das 22h45. Nele, estavam mais 115 mil doses da vacina CoronaVac. Com esta remessa, o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-07T12:31:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T12:33:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas\",\"datePublished\":\"2021-02-07T12:31:58+00:00\",\"dateModified\":\"2021-02-08T12:33:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\"},\"wordCount\":362,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg\",\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\",\"name\":\"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg\",\"datePublished\":\"2021-02-07T12:31:58+00:00\",\"dateModified\":\"2021-02-08T12:33:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/","og_locale":"pt_BR","og_type":"article","og_title":"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Imunizante vai refor\u00e7ar a aplica\u00e7\u00e3o da primeira e segunda doses nos profissionais de sa\u00fade Desembarcou no Cear\u00e1 na noite deste s\u00e1bado (6) a quarta carga trazendo imunizantes contra a Covid-19. O avi\u00e3o pousou no Aeroporto Internacional de Fortaleza pouco antes das 22h45. Nele, estavam mais 115 mil doses da vacina CoronaVac. Com esta remessa, o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-02-07T12:31:58+00:00","article_modified_time":"2021-02-08T12:33:43+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas","datePublished":"2021-02-07T12:31:58+00:00","dateModified":"2021-02-08T12:33:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/"},"wordCount":362,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg","articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/","name":"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg","datePublished":"2021-02-07T12:31:58+00:00","dateModified":"2021-02-08T12:33:43+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/02\/WhatsApp-Image-2021-02-07-at-05.54.55-1-1.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/02\/07\/ceara-recebe-115-mil-doses-da-vacina-coronavac-com-nova-remessa-estado-soma-449-900-imunizantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Cear\u00e1 recebe 115 mil doses da CoronaVac; com nova remessa, Estado soma 449.900 vacinas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/93626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=93626"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/93626\/revisions"}],"predecessor-version":[{"id":93633,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/93626\/revisions\/93633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/93630"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=93626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=93626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=93626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}