{"id":93080,"date":"2021-01-27T08:42:16","date_gmt":"2021-01-27T11:42:16","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=93080"},"modified":"2021-01-27T10:22:50","modified_gmt":"2021-01-27T13:22:50","slug":"hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/","title":{"rendered":"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-93082 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png\" alt=\"\" width=\"774\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png 774w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1-768x481.png 768w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><br \/>\n<em>Hospital de Sa\u00fade Mental oferece o &#8216;Programa Qualidade de Vida&#8217; no Trabalho desde setembro de 2020<\/em><\/p>\n<p>In\u00edcio do ano \u00e9 momento de planejar, renovar as energias e as esperan\u00e7as para o novo per\u00edodo que se inicia. \u00c9 quando, geralmente, se pensa em viver com mais qualidade e equil\u00edbrio emocional. Com a pandemia de Covid-19, o medo, a inseguran\u00e7a, a ansiedade e o estresse estiveram mais presentes na rotina da popula\u00e7\u00e3o \u2014 <strong>principalmente na de quem trabalha na linha de frente no combate \u00e0 doen\u00e7a<\/strong>. Por isso, o Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM) e o Hospital Geral Dr. Waldemar Alc\u00e2ntara (HGWA), vinculados \u00e0 Secretaria da Sa\u00fade do Cear\u00e1, <strong>implantaram ou refor\u00e7aram projetos de acompanhamento mental e emocional de servidores<\/strong>.<\/p>\n<p>No HSM, o <em>Programa Qualidade de Vida no Trabalho<\/em>, em vigor desde setembro de 2020, j\u00e1 atendeu cerca de 170 profissionais, entre eles t\u00e9cnicos de enfermagem, enfermeiros, al\u00e9m de colaboradores do Centro de Nutri\u00e7\u00e3o e da Higieniza\u00e7\u00e3o Hospitalar. Diversas a\u00e7\u00f5es t\u00eam sido realizadas para promover o equil\u00edbrio na rela\u00e7\u00e3o entre os n\u00edveis de satisfa\u00e7\u00e3o e de desempenho dos servidores. Neste momento, as atividades, uma iniciativa do servi\u00e7o de Psicologia do hospital, est\u00e3o acontecendo individualmente, seguindo protocolos de seguran\u00e7a.<\/p>\n<p>De acordo com a psic\u00f3loga Clarisse Missi\u00ea, coordenadora do programa, um bom ambiente de trabalho e benef\u00edcios satisfat\u00f3rios garantem uma rela\u00e7\u00e3o de confian\u00e7a entre o profissional e a institui\u00e7\u00e3o. \u201cEntendemos que o colaborador valorizado e satisfeito ter\u00e1 melhores condi\u00e7\u00f5es f\u00edsicas e emocionais para prestar um servi\u00e7o de humaniza\u00e7\u00e3o e excel\u00eancia aos pacientes\u201d, afirma.<\/p>\n<p>O <em>Programa Qualidade de Vida no Trabalho<\/em> busca atender todos os 617 profissionais do HSM, incluindo setores de apoio e administrativo. Nos primeiros encontros realizados, os servidores da Enfermagem foram convidados para uma atividade terap\u00eautica em grupos pequenos, realizada no jardim do hospital. \u201cAs interven\u00e7\u00f5es v\u00e3o acontecendo de modo abrangente, seguindo o crit\u00e9rio de demanda mais emergente\u201d, explica Clarisse.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-93083 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-11.png\" alt=\"\" width=\"774\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-11.png 774w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-11-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-11-768x481.png 768w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><br \/>\n<em>Grupo de medita\u00e7\u00e3o ensina t\u00e9cnicas de relaxamento e ioga para profissionais do HSM<\/em><\/p>\n<p>Al\u00e9m do atendimento psicol\u00f3gico, terapias hol\u00edsticas e integrativas, acupuntura, musicoterapia e atividades l\u00fadicas integram as atividades da iniciativa. O psic\u00f3logo e coordenador do N\u00facleo de Atendimento ao Cliente do HSM, Everton Barbosa, tamb\u00e9m est\u00e1 colaborando com o projeto, por meio de um grupo de medita\u00e7\u00e3o, onde ele ensina t\u00e9cnicas de relaxamento e ioga.<\/p>\n<p>A t\u00e9cnica de enfermagem Maria de F\u00e1tima Silveira, de 26 anos, ficou bastante entusiasmada com as atividades que est\u00e3o sendo propostas pelo programa. \u201cAcredito que, para cuidarmos melhor dos nossos pacientes, precisamos estar equilibrados e, para isso, \u00e9 importante recebermos apoio e incentivo no ambiente de trabalho. Iniciativa maravilhosa que vem me ajudando a ficar bem comigo mesma\u201d.<\/p>\n<h3>Plant\u00e3o Psicol\u00f3gico do HGWA<\/h3>\n<p>No HGWA, desde outubro de 2019, o setor de Psicologia da unidade oferece o <em>Plant\u00e3o Psicol\u00f3gico<\/em>, projeto que abre espa\u00e7o para colaboradores buscarem ajuda sempre que sentirem necessidade.<\/p>\n<p>Segundo a psic\u00f3loga respons\u00e1vel pelo setor, Flora Corr\u00eaa Guimar\u00e3es, os profissionais que atuam na linha de frente est\u00e3o entre os grupos que podem estar mais suscet\u00edveis a sofrer os impactos f\u00edsicos e psicol\u00f3gicos da pandemia. Ela explica que o suporte engloba desde o acolhimento at\u00e9 o atendimento de urg\u00eancia emocional.<\/p>\n<h3 class=\"destacado\">\u201cO servi\u00e7o permite que o funcion\u00e1rio tenha um espa\u00e7o de escuta dentro da pr\u00f3pria unidade que trabalha para expressar suas ang\u00fastias, ajudando ele a se estruturar melhor, a fim de que consiga criar estrat\u00e9gias para lidar com o momento em que est\u00e1 vivendo\u201d<\/h3>\n<p>At\u00e9 o momento, o <em>Plant\u00e3o Psicol\u00f3gico<\/em> j\u00e1 registrou mais de 100 atendimentos presenciais e beneficiou 65 colaboradores. Somente em 2020, 68 atendimentos foram realizados.<\/p>\n<p>O servi\u00e7o est\u00e1 dispon\u00edvel todas as segundas-feiras, das 14h \u00e0s 18h, no consult\u00f3rio 01 do ambulat\u00f3rio do HGWA. \u201cO <em>Plant\u00e3o Psicol\u00f3gico<\/em> atende por demanda espont\u00e2nea. N\u00e3o precisa fazer agendamento ou nenhum tipo de marca\u00e7\u00e3o pr\u00e9via. Qualquer funcion\u00e1rio do hospital que sentir necessidade e tiver passando por algum sofrimento emocional, pode procurar o servi\u00e7o no dia e no hor\u00e1rio de seu funcionamento\u201d, afirma Guimar\u00e3es.<\/p>\n<p>O formato do <em>Plant\u00e3o Psicol\u00f3gico<\/em> \u00e9 de um atendimento e at\u00e9 tr\u00eas retornos. Ao t\u00e9rmino, \u00e9 avaliada a necessidade de encaminhamento para outros servi\u00e7os de sa\u00fade mental. \u201c\u00c9 de extrema import\u00e2ncia uma unidade de sa\u00fade se preocupar com essa quest\u00e3o e ter o entendimento de que as demandas psicol\u00f3gicas de seus colaboradores precisam e devem ser cuidadas tanto quanto a de seus pacientes\u201d, continua a psic\u00f3loga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hospital de Sa\u00fade Mental oferece o &#8216;Programa Qualidade de Vida&#8217; no Trabalho desde setembro de 2020 In\u00edcio do ano \u00e9 momento de planejar, renovar as energias e as esperan\u00e7as para o novo per\u00edodo que se inicia. \u00c9 quando, geralmente, se pensa em viver com mais qualidade e equil\u00edbrio emocional. Com a pandemia de Covid-19, o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":93082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[133,1515,1629,2148,135,82],"class_list":["post-93080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-ceara","tag-covid-19","tag-pandemia","tag-plantao-psicologico","tag-saude","tag-saude-mental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Hospital de Sa\u00fade Mental oferece o &#8216;Programa Qualidade de Vida&#8217; no Trabalho desde setembro de 2020 In\u00edcio do ano \u00e9 momento de planejar, renovar as energias e as esperan\u00e7as para o novo per\u00edodo que se inicia. \u00c9 quando, geralmente, se pensa em viver com mais qualidade e equil\u00edbrio emocional. Com a pandemia de Covid-19, o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T11:42:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T13:22:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"774\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia\",\"datePublished\":\"2021-01-27T11:42:16+00:00\",\"dateModified\":\"2021-01-27T13:22:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\"},\"wordCount\":804,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png\",\"keywords\":[\"Cear\u00e1\",\"covid-19\",\"Pandemia\",\"plant\u00e3o psicol\u00f3gico\",\"sa\u00fade\",\"sa\u00fade mental\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\",\"name\":\"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png\",\"datePublished\":\"2021-01-27T11:42:16+00:00\",\"dateModified\":\"2021-01-27T13:22:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png\",\"width\":774,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Hospital de Sa\u00fade Mental oferece o &#8216;Programa Qualidade de Vida&#8217; no Trabalho desde setembro de 2020 In\u00edcio do ano \u00e9 momento de planejar, renovar as energias e as esperan\u00e7as para o novo per\u00edodo que se inicia. \u00c9 quando, geralmente, se pensa em viver com mais qualidade e equil\u00edbrio emocional. Com a pandemia de Covid-19, o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-01-27T11:42:16+00:00","article_modified_time":"2021-01-27T13:22:50+00:00","og_image":[{"width":774,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia","datePublished":"2021-01-27T11:42:16+00:00","dateModified":"2021-01-27T13:22:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/"},"wordCount":804,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png","keywords":["Cear\u00e1","covid-19","Pandemia","plant\u00e3o psicol\u00f3gico","sa\u00fade","sa\u00fade mental"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/","name":"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png","datePublished":"2021-01-27T11:42:16+00:00","dateModified":"2021-01-27T13:22:50+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/image-2-1.png","width":774,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/27\/hospitais-estaduais-acompanham-saude-mental-de-profissionais-durante-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Hospitais estaduais acompanham sa\u00fade mental de profissionais durante pandemia"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/93080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=93080"}],"version-history":[{"count":13,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/93080\/revisions"}],"predecessor-version":[{"id":93101,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/93080\/revisions\/93101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/93082"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=93080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=93080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=93080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}