{"id":92276,"date":"2021-01-11T09:16:12","date_gmt":"2021-01-11T12:16:12","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=92276"},"modified":"2021-01-11T16:33:33","modified_gmt":"2021-01-11T19:33:33","slug":"secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/","title":{"rendered":"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-92277 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png\" alt=\"\" width=\"756\" height=\"486\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png 756w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE-600x386.png 600w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/><\/p>\n<p>A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) orienta as secretarias do 184 munic\u00edpios cearenses que v\u00e3o realizar a vacina\u00e7\u00e3o contra a Covid-19 a fazer um novo cadastro dos vacinadores das unidades de sa\u00fade no Sistema de Cadastro de Permiss\u00e3o de Acesso (SCPA) que ir\u00e1 possibilitar o acesso e digita\u00e7\u00e3o dos dados (registro de vacinados) no M\u00f3dulo Covid-19 do Sistema de Informa\u00e7\u00e3o do Programa Nacional de Imuniza\u00e7\u00e3o (SIPNI), desenvolvido pelo Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>Nesse primeiro momento, os respons\u00e1veis pelo Sistema de Cadastro de Permiss\u00e3o de Acesso das \u00c1reas Descentralizadas de Sa\u00fade (ADS) do Estado j\u00e1 realizaram a solicita\u00e7\u00e3o em n\u00edvel estadual (gestor m\u00e1ster), mediante o sistema SCPA, e encontram-se devidamente habilitados para acessar ao SIPNI \u2013 M\u00f3dulo Covid-19. Com isto, os operadores (vacinadores\/respons\u00e1veis pela digita\u00e7\u00e3o) ter\u00e3o at\u00e9 quarta-feira, 13 de janeiro, para realizarem o cadastro no SCPA e solicitarem acesso ao Novo SIPNI. Ap\u00f3s o Minist\u00e9rio da Sa\u00fade disponibilizar o novo SIPNI, esses operadores devidamente cadastrados no SCPA ser\u00e3o vinculados \u00e0s suas respectivas unidades de sa\u00fade para digitar os dados (registro de vacinados) no M\u00f3dulo Covid-19.<\/p>\n<p>Na pr\u00e1tica, a Sesa busca mobilizar os munic\u00edpios a estarem com acessos atualizados para a nova ferramenta do Minist\u00e9rio da Sa\u00fade, o M\u00f3dulo Covid-19, que funcionar\u00e1 como um banco de dados geral dos brasileiros vacinados.\u00a0\u201c\u00c9 importante essa prepara\u00e7\u00e3o agora para quando a vacina chegar no Estado, as unidades de sa\u00fade come\u00e7arem a vacina\u00e7\u00e3o. Onde todos os registros ser\u00e3o realizados atrav\u00e9s do M\u00f3dulo Covid-19 no SIPNI\u201d, destaca Ricristhi Gon\u00e7alves, Coordenadora de Vigil\u00e2ncia e Preven\u00e7\u00e3o a Sa\u00fade da Sesa.<\/p>\n<p>O registro das pessoas que ser\u00e3o vacinadas contra a Covid-19 vai ser colocado no Novo SIPNI, programa elaborado pelo Minist\u00e9rio da Sa\u00fade.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-92296 \" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/banner_sipni_ms-1200x604.jpg\" alt=\"\" width=\"760\" height=\"379\" \/><\/p>\n<p>Os profissionais de sa\u00fade que v\u00e3o participar da campanha de Vacina\u00e7\u00e3o contra a Covid-19 dever\u00e3o estar vinculados \u00e0s respectivas Unidades de Sa\u00fade que realizar\u00e3o a vacina\u00e7\u00e3o, para permitir a imediata utiliza\u00e7\u00e3o no sistema. O Minist\u00e9rio da Sa\u00fade lembra que todos os profissionais que j\u00e1 s\u00e3o cadastrados no e-SUS AB e no SIPNI atual, dever\u00e3o realizar novo cadastro no SCPA.<\/p>\n<p>\u201cTodos os estabelecimentos de sa\u00fade que v\u00e3o realizar a vacina\u00e7\u00e3o, t\u00eam que registrar seus dados. Isso \u00e9 feito atrav\u00e9s do Plano Nacional de Imuniza\u00e7\u00e3o. \u00c9 de suma import\u00e2ncia que todos os munic\u00edpios estejam com o cadastro dos seus vacinadores em dia\u201d, refor\u00e7a Ricristhi Gon\u00e7alves.<\/p>\n<p><a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/06\/tutorial_scpa_210111.pdf\">Clique aqui<\/a> e confira o tutorial do SIPNI<\/p>\n<p><strong>Link SCPA usu\u00e1rio:<\/strong> <a href=\"https:\/\/scpaweb-usuario.saude.gov.br\/datasus-scpaweb-usuario\/\">https:\/\/scpaweb-usuario.saude.gov.br\/datasus-scpaweb-usuario\/<\/a><\/p>\n<p><a href=\"https:\/\/www.conasems.org.br\/wp-content\/uploads\/2021\/01\/SCPA_Acesso-ao-novo-SIPNI_Producao.pdf\">Acesse aqui o Manual para o cadastro no SCPA<\/a><\/p>\n<h3>Cadastro Nacional de Estabelecimentos de Sa\u00fade &#8211; CNES<\/h3>\n<p>Considerando a Portaria n\u00ba 1833 de 4 de novembro de 2018, que define o cadastramento dos estabelecimentos de sa\u00fade que realizam servi\u00e7os de vacina\u00e7\u00e3o no Cadastro Nacional de Estabelecimento de Sa\u00fade (CNES), dos 184 munic\u00edpios do Cear\u00e1, 141 j\u00e1 realizaram o cadastro e os outros 43 munic\u00edpios encontram-se com o procedimento em andamento. Al\u00e9m do cadastro das centrais de abastecimento municipais, as unidades de sa\u00fade que possuem salas de vacina dever\u00e3o enquadrar o &#8220;Servi\u00e7o 174 \u2013 Imuniza\u00e7\u00e3o&#8221; e a &#8220;Classifica\u00e7\u00e3o 001 \u2013 Indiv\u00edduos em Geral&#8221;.<\/p>\n<p>Ressalta-se que este procedimento \u00e9 uma forma de iniciar o processo de introdu\u00e7\u00e3o da vacina contra a Covid-19 com total rastreabilidade dos imunobiol\u00f3gicos adquiridos e distribu\u00eddos pela Coordena\u00e7\u00e3o Geral do Programa Nacional de Imuniza\u00e7\u00f5es. Portanto, \u00e9 de suma import\u00e2ncia que todos os munic\u00edpios estejam com o cadastro dos seus profissionais de sa\u00fade em dia.<\/p>\n<h3>Ou\u00e7a<\/h3>\n<p>O secret\u00e1rio da Sa\u00fade, Dr. Cabeto, destaca que o Cear\u00e1 est\u00e1 preparado para iniciar a vacina\u00e7\u00e3o dos cearenses, iniciando pelos grupos de risco.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/11.01-CABETO-1-VACINA.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/11.01-CABETO-1-VACINA.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>A coordenadora de Vigil\u00e2ncia e Preven\u00e7\u00e3o a Sa\u00fade da Sesa, Ricristhi Gon\u00e7alves, atenta para a import\u00e2ncia do cadastramento, para um melhor andamento do processo de vacina\u00e7\u00e3o.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/11.01-RICHRISTHI-2-CADASTRO.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/11.01-RICHRISTHI-2-CADASTRO.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) orienta as secretarias do 184 munic\u00edpios cearenses que v\u00e3o realizar a vacina\u00e7\u00e3o contra a Covid-19 a fazer um novo cadastro dos vacinadores das unidades de sa\u00fade no Sistema de Cadastro de Permiss\u00e3o de Acesso (SCPA) que ir\u00e1 possibilitar o acesso e digita\u00e7\u00e3o dos dados (registro de vacinados) no [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":92277,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1515,933,149,2116],"class_list":["post-92276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-covid-19","tag-imunizacao","tag-vacinacao","tag-vacinadores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) orienta as secretarias do 184 munic\u00edpios cearenses que v\u00e3o realizar a vacina\u00e7\u00e3o contra a Covid-19 a fazer um novo cadastro dos vacinadores das unidades de sa\u00fade no Sistema de Cadastro de Permiss\u00e3o de Acesso (SCPA) que ir\u00e1 possibilitar o acesso e digita\u00e7\u00e3o dos dados (registro de vacinados) no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-11T12:16:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-11T19:33:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19\",\"datePublished\":\"2021-01-11T12:16:12+00:00\",\"dateModified\":\"2021-01-11T19:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\"},\"wordCount\":732,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png\",\"keywords\":[\"covid-19\",\"imuniza\u00e7\u00e3o\",\"Vacina\u00e7\u00e3o\",\"vacinadores\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\",\"name\":\"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png\",\"datePublished\":\"2021-01-11T12:16:12+00:00\",\"dateModified\":\"2021-01-11T19:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png\",\"width\":756,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) orienta as secretarias do 184 munic\u00edpios cearenses que v\u00e3o realizar a vacina\u00e7\u00e3o contra a Covid-19 a fazer um novo cadastro dos vacinadores das unidades de sa\u00fade no Sistema de Cadastro de Permiss\u00e3o de Acesso (SCPA) que ir\u00e1 possibilitar o acesso e digita\u00e7\u00e3o dos dados (registro de vacinados) no [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-01-11T12:16:12+00:00","article_modified_time":"2021-01-11T19:33:33+00:00","og_image":[{"width":756,"height":486,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19","datePublished":"2021-01-11T12:16:12+00:00","dateModified":"2021-01-11T19:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/"},"wordCount":732,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png","keywords":["covid-19","imuniza\u00e7\u00e3o","Vacina\u00e7\u00e3o","vacinadores"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/","name":"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png","datePublished":"2021-01-11T12:16:12+00:00","dateModified":"2021-01-11T19:33:33+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/01\/BANNER_VACINACAO_COM_DEGRADE.png","width":756,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/01\/11\/secretaria-da-saude-do-estado-orienta-os-municipios-para-vacinacao-contra-a-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Secretaria da Sa\u00fade do Estado orienta os munic\u00edpios para vacina\u00e7\u00e3o contra a Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/92276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=92276"}],"version-history":[{"count":13,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/92276\/revisions"}],"predecessor-version":[{"id":92313,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/92276\/revisions\/92313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/92277"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=92276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=92276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=92276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}