{"id":90740,"date":"2020-10-27T10:44:19","date_gmt":"2020-10-27T13:44:19","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=90740"},"modified":"2020-10-27T10:44:19","modified_gmt":"2020-10-27T13:44:19","slug":"infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/","title":{"rendered":"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-90741\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Num cen\u00e1rio de vari\u00e1veis envolvendo transmiss\u00e3o, tratamento e cura da Covid-19, a popula\u00e7\u00e3o precisa seguir mantendo uma s\u00e9rie de a\u00e7\u00f5es rotineiras, de modo a incorporar pr\u00e1ticas sociais de cuidado. \u00c9 o que apontam os infectologistas Melissa Medeiros e Keny Colares, m\u00e9dicos do Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da Secretaria de Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado.<\/p>\n<p>\u201c\u00c9 preciso que a gente assimile novas condutas, porque isso precisa virar h\u00e1bito e fazer parte do nosso dia a dia. Essas medidas precisam ser encaradas como coisas naturais\u201d, afirma Melissa, refor\u00e7ando que o uso de m\u00e1scara necessita ser absorvido como um item essencial no contato social, sem brechas para relaxamento. \u201c\u00c9 importante tamb\u00e9m ter sempre uma boa higieniza\u00e7\u00e3o, sempre que tiver contato com sujidade, e continuar evitando o contato f\u00edsico com pessoas, estranhas ou n\u00e3o, que voc\u00ea encontra fora de casa\u201d, completa.<\/p>\n<p>A infectologista refor\u00e7a que, apesar dos avan\u00e7os no combate ao coronav\u00edrus, \u00e9 preciso entender que a situa\u00e7\u00e3o segue requerendo aten\u00e7\u00e3o. \u201cA gente n\u00e3o tem data prevista para a Covid-19 acabar. Hoje existem coisas que a gente n\u00e3o conhece ainda sobre a transmiss\u00e3o, sobre o risco de reinfec\u00e7\u00e3o e tamb\u00e9m sobre o tempo para desenvolver uma vacina que seja eficaz e possa ser utilizada a longo prazo\u201d, analisa.<\/p>\n<p>Keny Colares salienta a necessidade de manter as adapta\u00e7\u00f5es nas rela\u00e7\u00f5es sociais nos mais variados espa\u00e7os \u2013 a exemplo de transporte p\u00fablico, sala de aula e postos de trabalho. \u201c\u00c9 prov\u00e1vel que gente tenha que conviver com esses cuidados por algum tempo, talvez por alguns anos. Baseado em outras pandemias que aconteceram no passado, \u00e9 necess\u00e1rio que a gente continue somando medidas que j\u00e1 conhecemos muito bem e continue diminuindo a circula\u00e7\u00e3o na rua. A recomenda\u00e7\u00e3o \u00e9 sair de casa apenas quando for necess\u00e1rio e, quando sair, tentar ficar mais distante poss\u00edvel das outras pessoas\u201d.<\/p>\n<h3>Reuni\u00f5es familiares<\/h3>\n<p>Ap\u00f3s o per\u00edodo de lockdown, que acabou resultando no distanciamento moment\u00e2neo de parentes e amigos, muitas fam\u00edlias t\u00eam promovido encontros. Esses momentos, por\u00e9m, precisam seguir as recomenda\u00e7\u00f5es da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS). \u201cO risco das reuni\u00f5es familiares \u00e9 o mesmo risco de qualquer tipo de aglomerado de pessoas e, quanto mais pessoas estiverem aglomeradas, \u00e9 pior\u201d, pontua Keny. Ele detalha: \u201cUma coisa \u00e9 fazer uma reuni\u00e3o familiar num ambiente bem ventilado, na beira da praia, por exemplo, outra coisa \u00e9 num ambiente totalmente fechado\u201d.<\/p>\n<p>Melissa aponta que, nessas situa\u00e7\u00f5es privadas de contato social, muitas vezes n\u00e3o se mant\u00eam a aten\u00e7\u00e3o com o distanciamento m\u00ednimo. \u201cAs fam\u00edlias acabam tendo esse descuido nas condutas que s\u00e3o b\u00e1sicas para termos maior seguran\u00e7a e n\u00e3o se preocupam com o distanciamento de, pelo menos, dois metros\u201d, afirma, refor\u00e7ando que esses encontros entre parentes e amigos que n\u00e3o moram na mesma casa\u00a0precisam ter a mesma cautela das demais aglomera\u00e7\u00f5es. \u201cEssas medidas acabam sendo quebradas e pode haver um alto risco de transmiss\u00e3o se tiver uma pessoa doente ou que tenha sido exposto ao v\u00edrus e esteja assintom\u00e1tica&#8221;.<\/p>\n<p>Mesmo com todos os cuidados, Dr. Keny pondera que cada fam\u00edlia precisa avaliar quem, de fato, pode estar presente nesses encontros. \u201cSe tem pessoas com fator de risco, idade avan\u00e7ada ou tem doen\u00e7as cr\u00f4nicas \u2013 especialmente do cora\u00e7\u00e3o, do pulm\u00e3o e diabetes\u00a0 \u2013, \u00e9 importante considerar que talvez seja melhor que essas pessoas n\u00e3o compare\u00e7am\u201d, indica.<\/p>\n<h3>Academias<\/h3>\n<p>Outro espa\u00e7o de conv\u00edvio que requer aten\u00e7\u00e3o \u00e9 o ambiente de atividades f\u00edsicas compartilhadas. \u201cNas academias, muitas vezes, as pessoas compartilham m\u00e1quinas e objetos de exerc\u00edcio. Essa pr\u00e1tica tem um risco de transmiss\u00e3o maior\u201d, aponta Melissa, detalhando a necessidade de redobrar o cuidado ao dividir a rotina de muscula\u00e7\u00e3o e atividades aer\u00f3bicas com outras pessoas.<br \/>\n\u201cNuma academia, n\u00e3o tem motivo para tirar a m\u00e1scara e as pessoas n\u00e3o precisam ficar t\u00e3o pr\u00f3ximas assim. Tem um risco, porque as pessoas ficam em torno de uma hora e, muitas vezes, s\u00e3o ambientes fechados, com ar-condicionado\u201d, completa Kenny.<\/p>\n<h3>Restaurantes<\/h3>\n<p>Dentro da escala de riscos de contamina\u00e7\u00e3o, alguns ambientes de entretenimento acabam reunindo muitas das pr\u00e1ticas de risco. \u201cOs bares e restaurantes s\u00e3o considerados um dos locais mais arriscados, porque as pessoas est\u00e3o normalmente falando, emitindo mais as part\u00edculas que podem contaminar outras pessoas, e tamb\u00e9m s\u00e3o lugares em que as pessoas costumam ficar numa proximidade maior. Como elas est\u00e3o comendo e bebendo, elas passam boa parte do tempo sem a m\u00e1scara\u201d, avalia Dr. Keny.<\/p>\n<h3>Uso do celular<\/h3>\n<p>Outro ponto que merece aten\u00e7\u00e3o \u00e9 o uso de celular, item discutido desde o in\u00edcio da pandemia, mas que, para muita gente, ainda n\u00e3o \u00e9 prioridade na hora da limpeza. \u201cExistem estudos mostrando que esse v\u00edrus pode durar algumas horas ou alguns dias em superf\u00edcies como material de madeira e a\u00e7o. Recentemente, foi falado tamb\u00e9m da possibilidade da perman\u00eancia do v\u00edrus nos celulares, al\u00e9m de um estudo recente mostrando que ele pode ficar at\u00e9 9 horas sendo identificado na pele\u201d, afirma Melissa Medeiros.<\/p>\n<p>A m\u00e9dica ressalta, por\u00e9m, que a detec\u00e7\u00e3o do v\u00edrus numa superf\u00edcie n\u00e3o significa &#8220;necessariamente que ele \u00e9 transmiss\u00edvel e capaz de infectar&#8221;. Mesmo assim, o alerta segue necess\u00e1rio. \u201cIsso n\u00e3o quer dizer que a gente tenha que se descuidar da higieniza\u00e7\u00e3o, principalmente de celulares, computadores e outros materiais que a gente leva para a rua e traz pra dentro de casa. \u00c9 importante sempre higienizar com um pano umedecido com \u00e1lcool\u201d.<\/p>\n<p>Keny Colares finaliza: \u201c\u00c9 interessante que a gente mantenha a guarda alta, dentro do poss\u00edvel, para levar a vida da melhor forma poss\u00edvel. Precisamos manter ao m\u00e1ximo os cuidados para a gente n\u00e3o cantar vit\u00f3ria antes da hora e depois ter que enfrentar mais uma piora\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-90742\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona2.png\" alt=\"\" width=\"775\" height=\"1876\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona2.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona2-600x1452.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona2-768x1859.png 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona2-635x1536.png 635w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Num cen\u00e1rio de vari\u00e1veis envolvendo transmiss\u00e3o, tratamento e cura da Covid-19, a popula\u00e7\u00e3o precisa seguir mantendo uma s\u00e9rie de a\u00e7\u00f5es rotineiras, de modo a incorporar pr\u00e1ticas sociais de cuidado. \u00c9 o que apontam os infectologistas Melissa Medeiros e Keny Colares, m\u00e9dicos do Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da Secretaria de Sa\u00fade do Cear\u00e1 (Sesa), do [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":90741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1532,236],"class_list":["post-90740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-covid19","tag-prevencao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Num cen\u00e1rio de vari\u00e1veis envolvendo transmiss\u00e3o, tratamento e cura da Covid-19, a popula\u00e7\u00e3o precisa seguir mantendo uma s\u00e9rie de a\u00e7\u00f5es rotineiras, de modo a incorporar pr\u00e1ticas sociais de cuidado. \u00c9 o que apontam os infectologistas Melissa Medeiros e Keny Colares, m\u00e9dicos do Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da Secretaria de Sa\u00fade do Cear\u00e1 (Sesa), do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-27T13:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19\",\"datePublished\":\"2020-10-27T13:44:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\"},\"wordCount\":1031,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png\",\"keywords\":[\"coronavirus\",\"covid19\",\"preven\u00e7\u00e3o\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\",\"name\":\"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png\",\"datePublished\":\"2020-10-27T13:44:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Num cen\u00e1rio de vari\u00e1veis envolvendo transmiss\u00e3o, tratamento e cura da Covid-19, a popula\u00e7\u00e3o precisa seguir mantendo uma s\u00e9rie de a\u00e7\u00f5es rotineiras, de modo a incorporar pr\u00e1ticas sociais de cuidado. \u00c9 o que apontam os infectologistas Melissa Medeiros e Keny Colares, m\u00e9dicos do Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da Secretaria de Sa\u00fade do Cear\u00e1 (Sesa), do [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-10-27T13:44:19+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19","datePublished":"2020-10-27T13:44:19+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/"},"wordCount":1031,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png","keywords":["coronavirus","covid19","preven\u00e7\u00e3o"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/","name":"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png","datePublished":"2020-10-27T13:44:19+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/10\/banner_site_protecao_corona1.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/10\/27\/infectologistas-reforcam-importancia-de-medidas-de-prevencao-a-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Infectologistas refor\u00e7am import\u00e2ncia de medidas de preven\u00e7\u00e3o \u00e0 Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/90740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=90740"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/90740\/revisions"}],"predecessor-version":[{"id":90743,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/90740\/revisions\/90743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/90741"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=90740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=90740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=90740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}