{"id":89649,"date":"2020-09-09T13:10:17","date_gmt":"2020-09-09T16:10:17","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=89649"},"modified":"2020-09-09T13:16:32","modified_gmt":"2020-09-09T16:16:32","slug":"webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/","title":{"rendered":"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-89650 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), d\u00e1 continuidade nesta semana \u00e0 s\u00e9rie de webconfer\u00eancias sobre aten\u00e7\u00e3o \u00e0 sa\u00fade bucal no contexto da pandemia de Covid-19. Voltadas para profissionais de sa\u00fade, as transmiss\u00f5es acontecem no canal oficial da ESP\/CE no Youtube(<a href=\"https:\/\/www.youtube.com\/espceara\">youtube.com\/espceara<\/a>).<\/p>\n<p>Nesta quarta-feira (9), a partir de 14h, a doutora em Cl\u00ednica Odontol\u00f3gica pela Universidade Federal do Cear\u00e1 (UFC) e assessora t\u00e9cnica de sa\u00fade bucal da Secretaria Municipal de Sa\u00fade de Fortaleza (SMS), Jana\u00edna Rocha, discutir\u00e1 o atendimento odontol\u00f3gico \u00e0 gestante e puericultura. O objetivo \u00e9 orientar cirurgi\u00f5es-dentistas da aten\u00e7\u00e3o prim\u00e1ria e especializada acerca do tema.<\/p>\n<p>J\u00e1 na pr\u00f3xima sexta (11), no mesmo hor\u00e1rio, entra em pauta a dent\u00edstica minimamente invasiva com a proposta de atualizar cirurgi\u00f5es-dentistas da aten\u00e7\u00e3o prim\u00e1ria e especializada sobre protocolos de atendimento de c\u00e1rie n\u00e3o geradores de aeross\u00f3is. A convidada \u00e9 Cec\u00edlia Atem, professora da Universidade de Fortaleza (Unifor) e cirurgi\u00e3-dentista da Estrat\u00e9gia Sa\u00fade da Fam\u00edlia do munic\u00edpio de Fortaleza.<\/p>\n<p>As webconfer\u00eancias ser\u00e3o mediadas pela orientadora da C\u00e9lula de Aten\u00e7\u00e3o \u00e0 Sa\u00fade Bucal da Sesa, Paola Calvasina.<\/p>\n<p><strong>Agenda de webconfer\u00eancias sobre aten\u00e7\u00e3o \u00e0 sa\u00fade bucal<\/strong><\/p>\n<p>Tema: Atendimento odontol\u00f3gico \u00e0 gestante e puericultura<br \/>\nQuando: quarta-feira (9)<br \/>\nHor\u00e1rio: 14h<br \/>\nConvidada: Jana\u00edna Rocha, doutora em Cl\u00ednica Odontol\u00f3gica pela UFC e assessora t\u00e9cnica de sa\u00fade bucal da Secretaria Municipal de Sa\u00fade de Fortaleza.<br \/>\nLink de acesso: <a href=\"https:\/\/www.youtube.com\/watch?v=o2IbdK5PDXY\">clique aqui<\/a><\/p>\n<p>Tema: Dent\u00edstica minimamente invasiva<br \/>\nQuando: sexta-feira (11)<br \/>\nHor\u00e1rio: 14h<br \/>\nConvidada: Cec\u00edlia Atem, cirurgi\u00e3-dentista da Estrat\u00e9gia Sa\u00fade da Fam\u00edlia do munic\u00edpio de Fortaleza.<br \/>\nLink de acesso: <a href=\"https:\/\/www.youtube.com\/watch?v=ioFBDgLtZ9M\">clique aqui<\/a><\/p>\n<p><strong>Confira as webconfer\u00eancias j\u00e1 realizadas<\/strong>:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=nc9MJmbPfdQ\">Les\u00f5es Orais e Covid-19<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=8v2Z-o8tmaQ\">Biosseguran\u00e7a no Consult\u00f3rio Odontol\u00f3gico P\u00f3s-Covid-1<\/a>9<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=8v2Z-o8tmaQ\">Atendimento Odontol\u00f3gico de Pacientes com Necessidades Especiais (Nefropatas e Cardiopatas)<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=4US7WJuRyQc&amp;t=362s\">DTM e Dor Orofacial: diagn\u00f3stico e possibilidades de tratamento nos servi\u00e7os odontol\u00f3gicos do Estado do Cear\u00e1<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=uEfFgGoZJRU&amp;t=25s\">Urg\u00eancias e endodontia com t\u00e9cnicas minimamente invasivas<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=pHdskXh-AXE\">Especificidades da farmacologia na sa\u00fade bucal no contexto da Covid-19<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), d\u00e1 continuidade nesta semana \u00e0 s\u00e9rie de webconfer\u00eancias sobre aten\u00e7\u00e3o \u00e0 sa\u00fade bucal no contexto da pandemia de Covid-19. Voltadas para profissionais de sa\u00fade, as transmiss\u00f5es acontecem no canal oficial da ESP\/CE no Youtube(youtube.com\/espceara). [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":89650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[1965,1515,178,1537],"class_list":["post-89649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-atendimento-odontologico","tag-covid-19","tag-saude-bucal","tag-webconferencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), d\u00e1 continuidade nesta semana \u00e0 s\u00e9rie de webconfer\u00eancias sobre aten\u00e7\u00e3o \u00e0 sa\u00fade bucal no contexto da pandemia de Covid-19. Voltadas para profissionais de sa\u00fade, as transmiss\u00f5es acontecem no canal oficial da ESP\/CE no Youtube(youtube.com\/espceara). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-09T16:10:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-09T16:16:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante\",\"datePublished\":\"2020-09-09T16:10:17+00:00\",\"dateModified\":\"2020-09-09T16:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\"},\"wordCount\":392,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png\",\"keywords\":[\"atendimento odontol\u00f3gico\",\"covid-19\",\"Sa\u00fade Bucal\",\"webconfer\u00eancia\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\",\"name\":\"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png\",\"datePublished\":\"2020-09-09T16:10:17+00:00\",\"dateModified\":\"2020-09-09T16:16:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/","og_locale":"pt_BR","og_type":"article","og_title":"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), d\u00e1 continuidade nesta semana \u00e0 s\u00e9rie de webconfer\u00eancias sobre aten\u00e7\u00e3o \u00e0 sa\u00fade bucal no contexto da pandemia de Covid-19. Voltadas para profissionais de sa\u00fade, as transmiss\u00f5es acontecem no canal oficial da ESP\/CE no Youtube(youtube.com\/espceara). [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-09-09T16:10:17+00:00","article_modified_time":"2020-09-09T16:16:32+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante","datePublished":"2020-09-09T16:10:17+00:00","dateModified":"2020-09-09T16:16:32+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/"},"wordCount":392,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png","keywords":["atendimento odontol\u00f3gico","covid-19","Sa\u00fade Bucal","webconfer\u00eancia"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/","name":"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png","datePublished":"2020-09-09T16:10:17+00:00","dateModified":"2020-09-09T16:16:32+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/09\/banner_semanal_775x485.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/09\/09\/webconferencias-abordam-dentistica-minimamente-invasiva-e-atendimento-odontologico-a-gestante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Webconfer\u00eancias abordam dent\u00edstica minimamente invasiva e atendimento odontol\u00f3gico \u00e0 gestante"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/89649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=89649"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/89649\/revisions"}],"predecessor-version":[{"id":89653,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/89649\/revisions\/89653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/89650"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=89649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=89649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=89649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}