{"id":89296,"date":"2020-08-24T17:25:40","date_gmt":"2020-08-24T20:25:40","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=89296"},"modified":"2020-08-24T17:39:56","modified_gmt":"2020-08-24T20:39:56","slug":"intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/","title":{"rendered":"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-120452 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg\" alt=\"\" width=\"1040\" height=\"780\" \/><br \/>\n<em>Entre os dias 20 e 23 de agosto, mais de duas mil pessoas foram abordadas e orientadas pelos agentes de fiscaliza\u00e7\u00e3o a colocarem a m\u00e1scara ou corrigirem o modo como ela estava sendo utilizada. Foram registrados 24 casos de resist\u00eancia e um estabelecimento multado<\/em><\/p>\n<p>Ainda sem vacina ou rem\u00e9dio para combater o novo coronav\u00edrus, uma das principais medidas indicadas para a preven\u00e7\u00e3o \u00e9 o uso de m\u00e1scaras. Nesse sentido, os \u00f3rg\u00e3o de seguran\u00e7a fiscaliza\u00e7\u00e3o intensificam a\u00e7\u00f5es quanto \u00e0 import\u00e2ncia do uso do equipamento em todo o territ\u00f3rio cearense. Somente entre os dias 20 e 23 deste m\u00eas, agentes do Estado e munic\u00edpios abordaram 2.061 pessoas que estavam sem o utens\u00edlio ou fazendo uso da maneira incorreta. Foram multadas 24 pessoas que resistiram a colocar a m\u00e1scara, al\u00e9m de um estabelecimento comercial que n\u00e3o cumpriu as determina\u00e7\u00f5es sanit\u00e1rias.<\/p>\n<p>Recentemente, a Assembleia Legislativa do Cear\u00e1 aprovou lei que obriga o uso de m\u00e1scara em ambientes p\u00fablicos ou privados. A medida prev\u00ea aplica\u00e7\u00e3o de autos de infra\u00e7\u00e3o para aquele que descumprir. Jane Cris Cunha, da Vigil\u00e2ncia Sanit\u00e1ria da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), explica que esse tipo de \u201cabordagem j\u00e1 acontecia anteriormente, mas agora est\u00e1 sendo enfatizado que o n\u00e3o uso ou uso inadequado poder\u00e1 incorrer em penalidade\u201d.<\/p>\n<p>Nas a\u00e7\u00f5es realizadas nos \u00faltimos dias, apenas 24 pessoas e um restaurante n\u00e3o atenderam \u00e0 orienta\u00e7\u00e3o dos agentes e acabaram sendo autuados por descumprimento da legisla\u00e7\u00e3o. Os valores podem variar de R$ 100 a R$ 1.001, levando em considera\u00e7\u00e3o se \u00e9 pessoa f\u00edsica ou jur\u00eddica. O recurso recolhido das penalidades ser\u00e1 direcionado ao Fundo Estadual de Sa\u00fade (Fundes) para que possa ser aplicado em a\u00e7\u00f5es de sa\u00fade voltadas \u00e0 preven\u00e7\u00e3o e ao combate da pandemia da Covid-19.<\/p>\n<p>A puni\u00e7\u00e3o ser\u00e1 aplicada enquanto estiver vigente o estado de calamidade p\u00fablica em virtude da pandemia do novo coronav\u00edrus. Por\u00e9m, a t\u00e9cnica da Vigil\u00e2ncia Sanit\u00e1ria do Cear\u00e1 ressalta que o interesse n\u00e3o \u00e9 multar, e sim orientar e promover a sa\u00fade da popula\u00e7\u00e3o. \u201cA partir do momento em que a pessoa coloca a m\u00e1scara a multa n\u00e3o \u00e9 lavrada, porque essa \u00e9 uma a\u00e7\u00e3o educativa\u201d, informa Jane Cris Cunha. Felizmente, a grande maioria da popula\u00e7\u00e3o tem compreendido o car\u00e1ter educativo das abordagens, comenta Jane Cris Cunha. \u201cO que n\u00f3s temos observado durante as fiscaliza\u00e7\u00f5es \u00e9 que as pessoas quando n\u00f3s pedimos sempre colocam a m\u00e1scara. Dificilmente encontramos algu\u00e9m que n\u00e3o queira usar ou que tenha alguma resist\u00eancia\u201d, destaca.<\/p>\n<h3>Pessoa jur\u00eddica<\/h3>\n<p>Os estabelecimentos que permitirem o ingresso no local de quem n\u00e3o esteja utilizando m\u00e1scara de prote\u00e7\u00e3o tamb\u00e9m estar\u00e3o sujeitos \u00e0 multa no valor entre R$ 100,00 a R$ 300,00, por pessoa que n\u00e3o esteja utilizando a prote\u00e7\u00e3o facial. As empresas de grande porte podem desembolsar entre R$ 359,00 a R$ 1.001,00, caso seja verificado o descumprimento da medida sanit\u00e1ria de pessoas que ingressem ou permane\u00e7am no local.<\/p>\n<h3>Exce\u00e7\u00f5es<\/h3>\n<p>N\u00e3o ser\u00e1 multado o cidad\u00e3o que retirar a m\u00e1scara provisoriamente enquanto estiver consumindo produtos aliment\u00edcios nas depend\u00eancias de restaurantes, bares ou estabelecimentos similares. O mesmo vale para motoristas de ve\u00edculos automotores que estiverem sozinhos no interior do transporte.<\/p>\n<h3>Defesa<\/h3>\n<p>Ap\u00f3s procedimento para formalizar a infra\u00e7\u00e3o, o cidad\u00e3o ser\u00e1 notificado, no prazo de 30 dias, a efetuar o pagamento da multa ou a apresentar defesa impugnando os termos do auto, inclusive quanto ao valor da multa e sua dosimetria. Caso n\u00e3o seja apresentada defesa no prazo estabelecido, os autos ser\u00e3o enviados \u00e0 Procuradoria-Geral do Estado (PGE) para cobran\u00e7a da multa, mediante inscri\u00e7\u00e3o em d\u00edvida ativa estadual. A partir da segunda infra\u00e7\u00e3o formal, o infrator ser\u00e1 multado no valor correspondente ao dobro do valor antes aplicado, seja ele pessoa f\u00edsica ou jur\u00eddica.<\/p>\n<h3>Mais a\u00e7\u00f5es em Fortaleza<\/h3>\n<p>A Ag\u00eancia de Fiscaliza\u00e7\u00e3o de Fortaleza (Agefis), realizou, de 20 a 23 de agosto de 2020, 67 opera\u00e7\u00f5es de fiscaliza\u00e7\u00e3o entre: conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o, com distribui\u00e7\u00e3o de m\u00e1scaras de tecido, panfletos educativos e \u00e1lcool em gel 70%; ordenamento de filas de lojas, cart\u00f3rios e ag\u00eancias banc\u00e1rias, com a orienta\u00e7\u00e3o sobre o distanciamento social; monitoramentos cont\u00ednuos na Av. Beira-Mar para evitar aglomera\u00e7\u00f5es, orientando os permission\u00e1rios a cumprirem as recomenda\u00e7\u00f5es de n\u00e3o ocuparem a faixa de areia com mesas, cadeiras e guarda-s\u00f3is; fiscaliza\u00e7\u00e3o de Vigil\u00e2ncia Sanit\u00e1ria em restaurantes, supermercados e academias; vistoria de espa\u00e7os p\u00fablicos e estabelecimentos comerciais, em atendimento a den\u00fancias de polui\u00e7\u00e3o sonora, aglomera\u00e7\u00f5es e ocupa\u00e7\u00e3o de vias e cal\u00e7adas com mesas e cadeiras; monitoramento do Centro da cidade, com refor\u00e7os em dias de abertura dos galp\u00f5es no entorno da Catedral de Fortaleza e em vias pr\u00f3ximas; e abordagens a estabelecimentos para verificar o cumprimento das medidas de enfrentamento \u00e0 Covid-19, contidas nos decretos municipal e estadual, dentre outras a\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 20 e 23 de agosto, mais de duas mil pessoas foram abordadas e orientadas pelos agentes de fiscaliza\u00e7\u00e3o a colocarem a m\u00e1scara ou corrigirem o modo como ela estava sendo utilizada. Foram registrados 24 casos de resist\u00eancia e um estabelecimento multado Ainda sem vacina ou rem\u00e9dio para combater o novo coronav\u00edrus, uma [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":89298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1940,1941,328,181,1105,1927,774],"class_list":["post-89296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-acao-educativa","tag-autuacao","tag-lei","tag-sesa","tag-sspds","tag-uso-de-mascara","tag-vigilancia-sanitaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Entre os dias 20 e 23 de agosto, mais de duas mil pessoas foram abordadas e orientadas pelos agentes de fiscaliza\u00e7\u00e3o a colocarem a m\u00e1scara ou corrigirem o modo como ela estava sendo utilizada. Foram registrados 24 casos de resist\u00eancia e um estabelecimento multado Ainda sem vacina ou rem\u00e9dio para combater o novo coronav\u00edrus, uma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-24T20:25:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-24T20:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o\",\"datePublished\":\"2020-08-24T20:25:40+00:00\",\"dateModified\":\"2020-08-24T20:39:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\"},\"wordCount\":874,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg\",\"keywords\":[\"a\u00e7\u00e3o educativa\",\"autua\u00e7\u00e3o\",\"Lei\",\"Sesa\",\"SSPDS\",\"Uso de M\u00e1scara\",\"vigil\u00e2ncia sanit\u00e1ria\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\",\"name\":\"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg\",\"datePublished\":\"2020-08-24T20:25:40+00:00\",\"dateModified\":\"2020-08-24T20:39:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg\",\"width\":1040,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/","og_locale":"pt_BR","og_type":"article","og_title":"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Entre os dias 20 e 23 de agosto, mais de duas mil pessoas foram abordadas e orientadas pelos agentes de fiscaliza\u00e7\u00e3o a colocarem a m\u00e1scara ou corrigirem o modo como ela estava sendo utilizada. Foram registrados 24 casos de resist\u00eancia e um estabelecimento multado Ainda sem vacina ou rem\u00e9dio para combater o novo coronav\u00edrus, uma [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-08-24T20:25:40+00:00","article_modified_time":"2020-08-24T20:39:56+00:00","og_image":[{"width":1040,"height":780,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o","datePublished":"2020-08-24T20:25:40+00:00","dateModified":"2020-08-24T20:39:56+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/"},"wordCount":874,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg","keywords":["a\u00e7\u00e3o educativa","autua\u00e7\u00e3o","Lei","Sesa","SSPDS","Uso de M\u00e1scara","vigil\u00e2ncia sanit\u00e1ria"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/","name":"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg","datePublished":"2020-08-24T20:25:40+00:00","dateModified":"2020-08-24T20:39:56+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/WhatsApp-Image-2020-08-24-at-16.42.25.jpeg","width":1040,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/24\/intensificadas-acoes-de-fiscalizacao-e-conscientizacao-sobre-o-uso-de-mascaras-de-protecao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Intensificadas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre o uso de m\u00e1scaras de prote\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/89296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=89296"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/89296\/revisions"}],"predecessor-version":[{"id":89297,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/89296\/revisions\/89297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/89298"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=89296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=89296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=89296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}