{"id":88971,"date":"2020-08-10T08:54:55","date_gmt":"2020-08-10T11:54:55","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=88971"},"modified":"2020-08-10T09:01:01","modified_gmt":"2020-08-10T12:01:01","slug":"com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/","title":{"rendered":"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-119388 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/08\/IMG_3765T.jpg\" alt=\"\" width=\"2000\" height=\"1333\" \/><\/p>\n<p><em>Governador informou ainda que as equipes da sa\u00fade v\u00eam conversando com representantes daqueles setores ainda n\u00e3o autorizados a funcionar, para que seja definido o momento mais adequado da retomada, sempre colocando a sa\u00fade como prioridade nas decis\u00f5es<\/em><\/p>\n<p>O novo decreto estadual deliberando sobre o isolamento social e a\u00e7\u00f5es permitidas nos munic\u00edpios cearenses, observando a etapa de cada macrorregi\u00e3o, passa a valer a partir da pr\u00f3xima segunda-feira (10). De acordo com o dispositivo, todas as cidades cearenses devem permanecer na fase do Plano de Retomada Respons\u00e1vel das Atividades Econ\u00f4micas e Comportamentais em que se encontram no momento. A decis\u00e3o foi anunciada pelo governador Camilo Santana nesta sexta-feira (7), em suas redes sociais, ap\u00f3s decis\u00e3o do Comit\u00ea Cient\u00edfico criado para discutir a\u00e7\u00f5es voltadas ao enfrentamento da pandemia da Covid-19 no Cear\u00e1.<\/p>\n<p>\u201cEm reuni\u00e3o com o Comit\u00ea formado pelos nossos profissionais de Sa\u00fade, presidentes do Tribunal de Justi\u00e7a e Assembleia Legislativa, Prefeitura e Minist\u00e9rio P\u00fablico Estadual e Federal, avaliamos o cen\u00e1rio da pandemia do coronav\u00edrus no Cear\u00e1 e todas as a\u00e7\u00f5es que v\u00eam sendo tomadas. O pr\u00f3ximo decreto, que entra em vigor na pr\u00f3xima segunda-feira (10), manter\u00e1 as macrorregi\u00f5es de Sa\u00fade nas atuais fases\u201d, informou Camilo.<\/p>\n<p>Com a decis\u00e3o do colegiado de manter os 184 munic\u00edpios cearense no quadro atual de retomada das atividades, a Capital e os munic\u00edpios da Macrorregi\u00e3o de Fortaleza seguem na Fase 4; as macrorregi\u00f5es do Sert\u00e3o Central, Litoral Leste\/Jaguaribe e Norte na Fase 2; e o Cariri na Fase 1.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-119389 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/08\/IMG_3769T.jpg\" alt=\"\" width=\"2000\" height=\"1333\" \/><\/p>\n<h3>Di\u00e1logo<\/h3>\n<p>Mesmo Fortaleza e os munic\u00edpios que comp\u00f5em a sua Macrorregi\u00e3o estando na \u00faltima fase do Plano de Retomada Respons\u00e1vel das Atividades Econ\u00f4micas e Comportamentais, o Comit\u00ea decidiu pela n\u00e3o reabertura, ainda, de alguns setores, cujo potencial de aglomera\u00e7\u00e3o e prolifera\u00e7\u00e3o do coronav\u00edrus pode ser maior.<\/p>\n<p>Contudo, Camilo Santana ressaltou que conversas entre os profissionais da Sa\u00fade e representantes dos segmentos seguem sendo realizadas para avaliar momento mais prop\u00edcio para o retorno dessas atividades sem risco de uma piora nos indicadores. \u201cNossas equipes continuam fazendo avalia\u00e7\u00f5es e mantendo contato com os setores ainda n\u00e3o autorizados ao funcionamento, como eventos, bares e cinemas, analisando caso a caso, para que todas as decis\u00f5es sejam tomadas de forma segura e respons\u00e1vel, e para que n\u00e3o haja piora do cen\u00e1rio, que vem apresentando avan\u00e7os semana a semana\u201d, comunicou.<\/p>\n<p>O governador enfatizou que, antes de tudo, a prioridade neste momento \u00e9 cuidar da sa\u00fade da popula\u00e7\u00e3o e que essa tem um papel importante no trabalho conjunto de vencer a pandemia. \u201cNossa prioridade absoluta ser\u00e1 sempre proteger vidas. \u00c9 fundamental que todos colaborem, sempre usando m\u00e1scara e evitando aglomera\u00e7\u00f5es\u201d, refor\u00e7ou Santana.<\/p>\n<h3>Testes<\/h3>\n<p>O governador Camilo Santana tamb\u00e9m citou que o Cear\u00e1 ultrapassou nesta sexta-feira a marca de 500 mil testes realizados em todo o estado. \u201cSomos um dos estados que mais testam no Brasil, e vamos continuar realizando cada vez mais exames. Isso nos permite maior efic\u00e1cia nas estrat\u00e9gias e tomadas de decis\u00e3o no enfrentamento \u00e0 pandemia. Temos realizado pesquisas epidemiol\u00f3gicas na capital e no interior; instalamos drive-thru de testagens em dois pontos da capital (HGF e Shopping Rio Mar Kennedy), al\u00e9m da amplia\u00e7\u00e3o dos pontos de coleta nas unidades de sa\u00fade de todo o estado. Juntos, com trabalho e transpar\u00eancia, vamos vencer esse desafio\u201d, afirmou o governador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Governador informou ainda que as equipes da sa\u00fade v\u00eam conversando com representantes daqueles setores ainda n\u00e3o autorizados a funcionar, para que seja definido o momento mais adequado da retomada, sempre colocando a sa\u00fade como prioridade nas decis\u00f5es O novo decreto estadual deliberando sobre o isolamento social e a\u00e7\u00f5es permitidas nos munic\u00edpios cearenses, observando a etapa [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":88973,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1793,1591,1854,1850,1633],"class_list":["post-88971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-decreto-estadual","tag-isolamento-social","tag-macrorregioes-de-saude","tag-retomada-da-economia","tag-testes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Governador informou ainda que as equipes da sa\u00fade v\u00eam conversando com representantes daqueles setores ainda n\u00e3o autorizados a funcionar, para que seja definido o momento mais adequado da retomada, sempre colocando a sa\u00fade como prioridade nas decis\u00f5es O novo decreto estadual deliberando sobre o isolamento social e a\u00e7\u00f5es permitidas nos munic\u00edpios cearenses, observando a etapa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-10T11:54:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-10T12:01:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T-1200x800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia\",\"datePublished\":\"2020-08-10T11:54:55+00:00\",\"dateModified\":\"2020-08-10T12:01:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg\",\"keywords\":[\"decreto estadual\",\"isolamento social\",\"macrorregi\u00f5es de sa\u00fade\",\"Retomada da Economia\",\"Testes\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\",\"name\":\"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg\",\"datePublished\":\"2020-08-10T11:54:55+00:00\",\"dateModified\":\"2020-08-10T12:01:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/","og_locale":"pt_BR","og_type":"article","og_title":"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Governador informou ainda que as equipes da sa\u00fade v\u00eam conversando com representantes daqueles setores ainda n\u00e3o autorizados a funcionar, para que seja definido o momento mais adequado da retomada, sempre colocando a sa\u00fade como prioridade nas decis\u00f5es O novo decreto estadual deliberando sobre o isolamento social e a\u00e7\u00f5es permitidas nos munic\u00edpios cearenses, observando a etapa [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-08-10T11:54:55+00:00","article_modified_time":"2020-08-10T12:01:01+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T-1200x800.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia","datePublished":"2020-08-10T11:54:55+00:00","dateModified":"2020-08-10T12:01:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/"},"wordCount":607,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg","keywords":["decreto estadual","isolamento social","macrorregi\u00f5es de sa\u00fade","Retomada da Economia","Testes"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/","name":"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg","datePublished":"2020-08-10T11:54:55+00:00","dateModified":"2020-08-10T12:01:01+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/IMG_3765T.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/10\/com-novo-decreto-municipios-seguem-na-fase-atual-do-plano-de-retomada-da-economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Com novo decreto, munic\u00edpios seguem na fase atual do plano de retomada da economia"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=88971"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88971\/revisions"}],"predecessor-version":[{"id":88972,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88971\/revisions\/88972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/88973"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=88971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=88971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=88971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}