{"id":88806,"date":"2020-08-03T17:11:05","date_gmt":"2020-08-03T20:11:05","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=88806"},"modified":"2020-08-04T13:02:57","modified_gmt":"2020-08-04T16:02:57","slug":"governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/","title":{"rendered":"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-118991 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/08\/200618_SOBRAL-PESQ_TESTE-COVID_TF2236.jpg\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/p>\n<p><em>Nesta segunda-feira, 30 profissionais de sa\u00fade passaram por treinamento para a realiza\u00e7\u00e3o dos testes, al\u00e9m dos procedimentos de biosseguran\u00e7a<\/em><\/p>\n<p>A segunda fase da pesquisa epidemiol\u00f3gica que avalia o impacto do coronav\u00edrus em Sobral ter\u00e1 in\u00edcio nesta ter\u00e7a-feira (4). O levantamento \u00e9 promovido pelo Governo do Cear\u00e1, por meio da Secretaria da Sa\u00fade do Estado (Sesa), e pela Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Cear\u00e1 (Fiec). A realiza\u00e7\u00e3o do estudo em Sobral \u00e9 de responsabilidade da Prefeitura do munic\u00edpio e do Instituto Opnus. Nesta nova fase, ser\u00e3o realizados 800 testes RT-PCR (Swab) na popula\u00e7\u00e3o.<\/p>\n<p>As pessoas que participar\u00e3o da testagem ser\u00e3o submetidas a exames de biologia molecular, feitos a partir de secre\u00e7\u00f5es coletadas das vias respirat\u00f3rias (nariz e garganta) por meio do swab, um tipo de haste de pl\u00e1stico com algod\u00f5es nas pontas. A coordenadora de vigil\u00e2ncia epidemiol\u00f3gica e preven\u00e7\u00e3o da Secretaria da Sa\u00fade do Cear\u00e1, Ricristhi Gon\u00e7alves, explica que o inqu\u00e9rito \u00e9 fundamental para definir as a\u00e7\u00f5es de combate \u00e0 pandemia.<\/p>\n<p>\u201cA pesquisa de soropreval\u00eancia que aconteceu em Fortaleza, Iguatu e Sobral \u00e9 de extrema import\u00e2ncia para podermos compreender como a transmiss\u00e3o da Covid-19 se deu nesses tr\u00eas munic\u00edpios. Essa informa\u00e7\u00e3o vai orientar os pr\u00f3ximos passos sem d\u00favida alguma nesses tr\u00eas munic\u00edpios e para as regi\u00f5es de sa\u00fade\u201d, avalia Ricristhi Gon\u00e7alves.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-118992 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/08\/200618_SOBRAL-PESQ_TESTE-COVID_TF2364_3.jpg\" alt=\"\" width=\"1643\" height=\"1095\" \/><\/p>\n<p>Nesta segunda-feira (3), 30 profissionais de sa\u00fade entre enfermeiros, dentistas, fisioterapeutas e farmac\u00eauticos passaram por treinamento para a realiza\u00e7\u00e3o dos testes RT-PCR, al\u00e9m dos procedimentos de biosseguran\u00e7a. O treinamento aconteceu no Centro de Ci\u00eancias da Sa\u00fade da Universidade Vale do Acara\u00fa (UVA) facilitado pelo Instituto Opnus e por profissionais do Posto de Coleta do Hospital Dr Estevam.<\/p>\n<p>De acordo com o coordenador de Vigil\u00e2ncia do Sistema de Sa\u00fade da Secretaria Municipal de Sa\u00fade de Sobral, Marcos Aguiar Ribeiro, parte da equipe ser\u00e1 a mesma da primeira fase, que realizou outros 800 testes, e ser\u00e1 ampliada com novos profissionais, que contar\u00e3o com o apoio de 10 pesquisadores do Instituto Opnus, 37 estudantes de gradua\u00e7\u00e3o em sa\u00fade da Universidade Estadual Vale do Acara\u00fa, Uninta e Faculdade Luciano Feij\u00e3o, al\u00e9m dos agentes comunit\u00e1rios de sa\u00fade dos territ\u00f3rios.<\/p>\n<h3>Testagem<\/h3>\n<p>O RT-PCR \u00e9 o teste de biologia molecular, que detecta a presen\u00e7a do v\u00edrus no paciente. S\u00e3o coletadas amostras de secre\u00e7\u00e3o do fundo do nariz por meio da introdu\u00e7\u00e3o de um swab (cotonete). As amostras para o RT-PCR s\u00e3o encaminhadas ao LACEN para an\u00e1lise e os resultados ficam prontos ap\u00f3s alguns dias.<\/p>\n<p>Ricristhi Gon\u00e7alves explica que ao usar a metodologia do RT-PCR, os pesquisadores buscam part\u00edculas do DNA viral. \u201cSobral vai para a segunda fase e vai ser utilizada apenas a metodologia de biologia molecular, o RT-PCR, que vai ser muito importante para entendermos se ainda est\u00e1 acontecendo transmiss\u00e3o ativa\u201d, define.<\/p>\n<p>O diretor do Instituto Opnus, Pedro Barbosa, detalha que a pesquisa ir\u00e1 comparar a evolu\u00e7\u00e3o da circula\u00e7\u00e3o viral na popula\u00e7\u00e3o. \u201cNa primeira fase, tamb\u00e9m fizemos testes r\u00e1pidos para identificar a presen\u00e7a de anticorpos na popula\u00e7\u00e3o. Essa segunda fase \u00e9 mais espec\u00edfica. Precisamos identificar como est\u00e1 sendo a evolu\u00e7\u00e3o da circula\u00e7\u00e3o viral na popula\u00e7\u00e3o com a reabertura econ\u00f4mica\u201d, avalia. A pesquisa ser\u00e1 realizada nos mesmos 40 territ\u00f3rios da primeira fase, mas em domic\u00edlios diferentes. Os setores foram selecionados de forma aleat\u00f3ria por sorteio.<\/p>\n<h3>Como reconhecer os pesquisadores<\/h3>\n<p>Os pesquisadores est\u00e3o identificados com crach\u00e1, portam termos de consentimento para participa\u00e7\u00e3o e panfleto informativo da pesquisa, al\u00e9m de estarem paramentados com todos os equipamentos de seguran\u00e7a: touca, avental, \u00f3culos, m\u00e1scara e luvas. Todos s\u00e3o treinados para aplica\u00e7\u00e3o dos testes e sobre os procedimentos de biosseguran\u00e7a. Acompanhando os pesquisadores estar\u00e3o ainda os agentes comunit\u00e1rios de sa\u00fade. \u201cPedimos a receptividade das pessoas, que a popula\u00e7\u00e3o se sinta segura em receber os pesquisadores. Essa pesquisa \u00e9 fundamental para termos um processo de reabertura seguro\u201d, ressalta Barbosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira, 30 profissionais de sa\u00fade passaram por treinamento para a realiza\u00e7\u00e3o dos testes, al\u00e9m dos procedimentos de biosseguran\u00e7a A segunda fase da pesquisa epidemiol\u00f3gica que avalia o impacto do coronav\u00edrus em Sobral ter\u00e1 in\u00edcio nesta ter\u00e7a-feira (4). O levantamento \u00e9 promovido pelo Governo do Cear\u00e1, por meio da Secretaria da Sa\u00fade do Estado (Sesa), [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":88807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1515,427,1840,1633],"class_list":["post-88806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-covid-19","tag-epidemiologia","tag-pesquisa-de-soroprevalencia","tag-testes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Nesta segunda-feira, 30 profissionais de sa\u00fade passaram por treinamento para a realiza\u00e7\u00e3o dos testes, al\u00e9m dos procedimentos de biosseguran\u00e7a A segunda fase da pesquisa epidemiol\u00f3gica que avalia o impacto do coronav\u00edrus em Sobral ter\u00e1 in\u00edcio nesta ter\u00e7a-feira (4). O levantamento \u00e9 promovido pelo Governo do Cear\u00e1, por meio da Secretaria da Sa\u00fade do Estado (Sesa), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-03T20:11:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-04T16:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a\",\"datePublished\":\"2020-08-03T20:11:05+00:00\",\"dateModified\":\"2020-08-04T16:02:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\"},\"wordCount\":713,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg\",\"keywords\":[\"covid-19\",\"epidemiologia\",\"pesquisa de soropreval\u00eancia\",\"Testes\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\",\"name\":\"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg\",\"datePublished\":\"2020-08-03T20:11:05+00:00\",\"dateModified\":\"2020-08-04T16:02:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"PERSONAGEM JOSEFA TEIXEIRA TESTA NEGATIVO PARA COVID EM PESQUISA PORTA-A-PORTA E REALIZACAO DE TESTES RAPIDOS E SWAB EM SOBRAL; MEDIDAS DE COMBATE A COVID 19;CORONAVIRUS;SESA;SAUDE; TRABALHADORES DA SAUDE; CREDITO DAS FOTOS \u00a9 TATIANA FORTES\/ GOV. DO CEARA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Nesta segunda-feira, 30 profissionais de sa\u00fade passaram por treinamento para a realiza\u00e7\u00e3o dos testes, al\u00e9m dos procedimentos de biosseguran\u00e7a A segunda fase da pesquisa epidemiol\u00f3gica que avalia o impacto do coronav\u00edrus em Sobral ter\u00e1 in\u00edcio nesta ter\u00e7a-feira (4). O levantamento \u00e9 promovido pelo Governo do Cear\u00e1, por meio da Secretaria da Sa\u00fade do Estado (Sesa), [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-08-03T20:11:05+00:00","article_modified_time":"2020-08-04T16:02:57+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a","datePublished":"2020-08-03T20:11:05+00:00","dateModified":"2020-08-04T16:02:57+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/"},"wordCount":713,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg","keywords":["covid-19","epidemiologia","pesquisa de soropreval\u00eancia","Testes"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/","name":"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg","datePublished":"2020-08-03T20:11:05+00:00","dateModified":"2020-08-04T16:02:57+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/08\/banner_SOBRAL-PESQ_TESTE-COVID_TF2236-.jpg","width":1920,"height":1280,"caption":"PERSONAGEM JOSEFA TEIXEIRA TESTA NEGATIVO PARA COVID EM PESQUISA PORTA-A-PORTA E REALIZACAO DE TESTES RAPIDOS E SWAB EM SOBRAL; MEDIDAS DE COMBATE A COVID 19;CORONAVIRUS;SESA;SAUDE; TRABALHADORES DA SAUDE; CREDITO DAS FOTOS \u00a9 TATIANA FORTES\/ GOV. DO CEARA"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/08\/03\/governo-do-ceara-inicia-segunda-fase-da-pesquisa-de-soroprevalencia-em-sobral-nesta-terca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Governo do Cear\u00e1 inicia segunda fase da pesquisa de soropreval\u00eancia em Sobral nesta ter\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=88806"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88806\/revisions"}],"predecessor-version":[{"id":88822,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88806\/revisions\/88822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/88807"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=88806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=88806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=88806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}