{"id":88679,"date":"2020-07-29T10:16:40","date_gmt":"2020-07-29T13:16:40","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=88679"},"modified":"2020-07-29T10:16:40","modified_gmt":"2020-07-29T13:16:40","slug":"saude-do-trabalhador-e-tema-de-webconferencia","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/","title":{"rendered":"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-88680\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg\" alt=\"\" width=\"768\" height=\"481\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries-600x376.jpg 600w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>A sa\u00fade do trabalhador no contexto de pandemia ser\u00e1 \u00f3 foco da pr\u00f3xima webconfer\u00eancia da s\u00e9rie Conex\u00e3o Sa\u00fade. Com o tema \u201cA Sa\u00fade do Trabalhador em Tempos de Pandemia\u201d, a live ocorrer\u00e1 nesta quinta-feira, 30, a partir das 15 horas, e ser\u00e1 transmitida pelo canal no Youtube da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do Estado do Cear\u00e1 (Sesa).<\/p>\n<p>Participar\u00e3o do encontro a enfermeira, mestre em Ensino e Sa\u00fade e gerente do Centro Estadual de Refer\u00eancia em Sa\u00fade do Trabalhador e da Trabalhadora do Estado do Cear\u00e1 (Cerest\/CE), Eline Mara Tavares Mac\u00eado; e a doutora em Sa\u00fade Coletiva, mestre em Psicologia, professora da da Universidade de Fortaleza (Unifor) e pesquisadora na \u00e1rea de Sa\u00fade do trabalhador, Patr\u00edcia Passos.<\/p>\n<p>Esta ser\u00e1 a s\u00e9tima webconfer\u00eancia do projeto Conex\u00e3o Sa\u00fade. Idealizado pela Diretoria de Educa\u00e7\u00e3o Profissional em Sa\u00fade (Dieps) da ESP\/CE, a iniciativa teve in\u00edcio em junho de 2020 e tem como principal objetivo o desenvolvimento de estrat\u00e9gias de uma rede de comunica\u00e7\u00e3o e o di\u00e1logo a partir do uso de recursos tecnol\u00f3gicos dispon\u00edveis. As transmiss\u00f5es s\u00e3o voltadas \u00e0 popula\u00e7\u00e3o cearense, profissionais da sa\u00fade do Estado e de outras \u00e1reas interessados em participar das discuss\u00f5es.<\/p>\n<h3>Servi\u00e7o<\/h3>\n<p>Conex\u00e3o Sa\u00fade: di\u00e1logos para o enfrentamento da pandemia por Covid-19<br \/>\nTema:\u00a0A Sa\u00fade do Trabalhador em Tempos de Pandemia<br \/>\nQuando: quinta-feira, 30 de julho<br \/>\nHor\u00e1rio: 15h<br \/>\nAcesso <a href=\"https:\/\/www.youtube.com\/channel\/UC_G1Zak1oxOctqap579R9cA\">Youtube da ESP\/CE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sa\u00fade do trabalhador no contexto de pandemia ser\u00e1 \u00f3 foco da pr\u00f3xima webconfer\u00eancia da s\u00e9rie Conex\u00e3o Sa\u00fade. Com o tema \u201cA Sa\u00fade do Trabalhador em Tempos de Pandemia\u201d, a live ocorrer\u00e1 nesta quinta-feira, 30, a partir das 15 horas, e ser\u00e1 transmitida pelo canal no Youtube da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":88680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1532,1478,1537],"class_list":["post-88679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-covid19","tag-saudeceara","tag-webconferencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A sa\u00fade do trabalhador no contexto de pandemia ser\u00e1 \u00f3 foco da pr\u00f3xima webconfer\u00eancia da s\u00e9rie Conex\u00e3o Sa\u00fade. Com o tema \u201cA Sa\u00fade do Trabalhador em Tempos de Pandemia\u201d, a live ocorrer\u00e1 nesta quinta-feira, 30, a partir das 15 horas, e ser\u00e1 transmitida pelo canal no Youtube da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-29T13:16:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia\",\"datePublished\":\"2020-07-29T13:16:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\"},\"wordCount\":279,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg\",\"keywords\":[\"covid19\",\"saudeceara\",\"webconfer\u00eancia\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\",\"name\":\"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg\",\"datePublished\":\"2020-07-29T13:16:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg\",\"width\":768,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A sa\u00fade do trabalhador no contexto de pandemia ser\u00e1 \u00f3 foco da pr\u00f3xima webconfer\u00eancia da s\u00e9rie Conex\u00e3o Sa\u00fade. Com o tema \u201cA Sa\u00fade do Trabalhador em Tempos de Pandemia\u201d, a live ocorrer\u00e1 nesta quinta-feira, 30, a partir das 15 horas, e ser\u00e1 transmitida pelo canal no Youtube da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-07-29T13:16:40+00:00","og_image":[{"width":768,"height":481,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia","datePublished":"2020-07-29T13:16:40+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/"},"wordCount":279,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg","keywords":["covid19","saudeceara","webconfer\u00eancia"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/","name":"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg","datePublished":"2020-07-29T13:16:40+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/ESP_Webs\u00e9ries.jpg","width":768,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/29\/saude-do-trabalhador-e-tema-de-webconferencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade do trabalhador \u00e9 tema de webconfer\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=88679"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88679\/revisions"}],"predecessor-version":[{"id":88681,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88679\/revisions\/88681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/88680"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=88679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=88679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=88679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}