{"id":88197,"date":"2020-07-13T13:18:46","date_gmt":"2020-07-13T16:18:46","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=88197"},"modified":"2020-07-13T16:51:50","modified_gmt":"2020-07-13T19:51:50","slug":"iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/","title":{"rendered":"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-117382 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/07\/200713_PESQUISA-COVID19_CGCGM0486.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<p>S\u00e3o 8 horas da manh\u00e3 desta segunda-feira (13), e a enfermeira Nelise Di\u00f3genes, junto com outras duas agentes de sa\u00fade, percorre as ruas do bairro Vicente Pinz\u00f3n, em Fortaleza, de porta em porta, fazer testes para a detec\u00e7\u00e3o de covid-19. Essa \u00e9 a segunda fase da Pesquisa de Soropreval\u00eancia na Capital, promovida pelo Governo do Cear\u00e1, em parceria com a Prefeitura de Fortaleza, a Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Cear\u00e1 (Fiec) e execu\u00e7\u00e3o do Instituto Opnus.<\/p>\n<p>Depois de 3.300 testes na fase um, ser\u00e3o realizados mais 3.300 exames, entre testes r\u00e1pidos e RT-PCR, que estabelecer\u00e3o o percentual de pessoas que foram ou est\u00e3o contaminadas pelo v\u00edrus.<\/p>\n<p>\u201cA pesquisa epidemiol\u00f3gica detalha o real quadro de infec\u00e7\u00e3o pelo coronav\u00edrus em Fortaleza, assim como temos feito em Sobral e Iguatu. Esses 9.900 testes que ser\u00e3o realizados nas tr\u00eas fases da capital estabelecer\u00e3o o percentual de pessoas que foram ou est\u00e3o contaminadas pelo v\u00edrus, o que ajuda nas estrat\u00e9gias e tomadas de decis\u00e3o. Importante lembrar que Cear\u00e1 est\u00e1 entre os estados que mais testam no Brasil, com cerca de 350 mil exames realizados at\u00e9 o momento\u201d, citou o governador Camilo Santana.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-117384 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/07\/200713_PESQUISA-COVID19_CGCGM0613.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<p>A dona Maria Augustinha, 66, fez quest\u00e3o de receber a equipe de pesquisa em sua casa, curiosa para saber se tinha ou n\u00e3o o coronav\u00edrus. \u201cAqui moramos eu, meu marido e meu filho, e ele teve, fiquei morrendo de medo de pegar essa doen\u00e7a. Sei que o exame mal n\u00e3o faz, por isso \u00e9 melhor saber se tenho ou n\u00e3o a doen\u00e7a\u201d, disse.<\/p>\n<p>Na entrevista protocolar que segue antes e durante o exame, a dona de casa falou dos seus h\u00e1bitos caseiros, que n\u00e3o sai de casa sem m\u00e1scara, que n\u00e3o teve nenhum tipo de contato social nem sintomas, apesar do filho ser detectado com o coronav\u00edrus h\u00e1 cerca de um m\u00eas. \u201cTenho medo de sair por a\u00ed, pegar \u00f4nibus lotado. S\u00f3 saio de casa pro supermercado, e vou e volto muito r\u00e1pido\u201d, comentou. Com exame negativo em m\u00e3os, ela se diz aliviada, mas que manter\u00e1 os cuidados e isolamento por muito tempo ainda.<\/p>\n<p>Os pesquisadores foram capacitados, nos dias 6 e 7 de julho, na Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do Cear\u00e1 (SESA), do Governo do Cear\u00e1. Eles receberam treinamento para a aplica\u00e7\u00e3o dos testes, especialmente o RT-PCR (swab) que nessa fase come\u00e7a a ser realizado na Capital, al\u00e9m dos procedimentos de biosseguran\u00e7a. Ser\u00e3o realizados 3.300 testes em 113 bairros, das seis regionais de Fortaleza. Foram sorteados 330 setores censit\u00e1rios da cidade, sendo cada um deles correspondente a um conjunto de quarteir\u00f5es. Ao todo, o estudo realizar\u00e1 9,9 mil testagens em cerca de 10 mil moradores da Capital.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-117381 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/07\/200713_PESQUISA-COVID19_CGCGM0379.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<p>J\u00e1 Francisco Nascimento, conhecido como Franz\u00e9 no bairro, 59 anos, j\u00e1 passou por todas as fases da doen\u00e7a, mas hoje est\u00e1 curado e mesmo assim decidiu fazer o exame. \u201cN\u00e3o s\u00f3 eu, mas minha esposa e meu filho, todos tivemos coronav\u00edrus, fomos tratados no posto aqui do bairro, do lado da minha casa\u201d, relembrou.<\/p>\n<p>Artista pl\u00e1stico e que sedia uma r\u00e1dio comunit\u00e1ria em sua casa, ele teve tempo nessa quarentena para fazer um espa\u00e7o mais isolado em sua casa, para que sua fam\u00edlia pudesse se curar longe de todos. \u201cAinda sinto falta de cheiro e o paladar foi diminu\u00eddo. N\u00e3o tem problema, o importante \u00e9 que agora estou bem\u201d, informou.<\/p>\n<p>\u201c\u00c9 uma pesquisa que, inicialmente buscava a informa\u00e7\u00e3o se as pessoas j\u00e1 produziram anticorpos contra o covid-19, e se ampliou para saber quantas pessoas adoeceram, estimar a porcentagem de pessoas infectadas pelo v\u00edrus, e tentar saber dessas pessoas se houveram casos assintom\u00e1ticos\u201d ressalta Ricristhi Gon\u00e7alves, coordenadora da Vigil\u00e2ncia Epidemiol\u00f3gica e Preven\u00e7\u00e3o da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa).<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-117380 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/07\/200713_PESQUISA-COVID19_CGCGM0282.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<h3>Testagens<\/h3>\n<p>O morador a ser testado ser\u00e1 sorteado entre os presentes. No caso de pessoas com menos de 18 anos e de incapazes, os testes acontecer\u00e3o mediante autoriza\u00e7\u00e3o dos pais ou do respons\u00e1vel. A realiza\u00e7\u00e3o da pesquisa \u00e9 importante para ampliar o controle epidemiol\u00f3gico nos munic\u00edpios e orientar as pol\u00edticas p\u00fablicas de preven\u00e7\u00e3o e combate \u00e0 Covid-19.<\/p>\n<p>O teste r\u00e1pido detecta a presen\u00e7a de anticorpos para o novo coronav\u00edrus. O resultado fica pronto em 15 minutos, ap\u00f3s uma simples picada na ponta do dedo para a coleta de uma gota de sangue. Enquanto isso, os pesquisadores aplicam um question\u00e1rio com informa\u00e7\u00f5es sobre sexo, idade, escolaridade, condi\u00e7\u00f5es de sa\u00fade e poss\u00edveis sintomas que o morador tenha sentido recentemente.<\/p>\n<p>J\u00e1 o RT-PCR \u00e9 o teste de biologia molecular, que detecta a presen\u00e7a do v\u00edrus no paciente. Trata-se da coleta de amostras de secre\u00e7\u00e3o do fundo do nariz por meio da introdu\u00e7\u00e3o de um swab (cotonete). As amostras para o RT-PCR n\u00e3o t\u00eam resultado imediato. Elas s\u00e3o encaminhadas ao LACEN para an\u00e1lise e os resultados ficam prontos ap\u00f3s alguns dias.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-117385 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/07\/200713_PESQUISA-COVID19_CGCGM0191.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<h3>Como reconhecer o pesquisador<\/h3>\n<p>Os pesquisadores portam crach\u00e1 de identifica\u00e7\u00e3o, termos de consentimento para participa\u00e7\u00e3o e panfleto informativo da pesquisa, bem como est\u00e3o paramentados com todos os equipamentos de seguran\u00e7a: touca, avental, \u00f3culos, m\u00e1scara e luvas. Todos s\u00e3o treinados para aplica\u00e7\u00e3o dos testes e sobre os procedimentos de biosseguran\u00e7a.<\/p>\n<p>A enfermeira Nelise Di\u00f3genes lamenta que em muitos casos ainda h\u00e1 uma resist\u00eancia das pessoas, recusando a entrada dos profissionais de sa\u00fade nas casas. \u201cAcredito que \u00e9 uma pesquisa de extrema import\u00e2ncia para a ci\u00eancia, as pessoas t\u00eam de ver a nossa visita como uma oportunidade de se manterem informadas e continuarem cuidando da sa\u00fade. N\u00f3s sempre estaremos portando crach\u00e1 com f\u00e1cil identifica\u00e7\u00e3o, CPF e todo o material informativo da campanha contra o coronav\u00edrus\u201d, listou.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-117383 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/07\/200713_PESQUISA-COVID19_CGCGM0569.jpg\" alt=\"\" width=\"100%\" \/><\/p>\n<h3>Primeira fase<\/h3>\n<p>A primeira fase da testagem, realizada entre 2 e 15 de junho, contemplou as primeiras 3.300 pessoas e estima que 370 mil (14,2%) fortalezenses j\u00e1 t\u00eam anticorpos contra a Covid-19. As Regionais I, III e VI de Fortaleza apresentaram a maior incid\u00eancia de casos.<\/p>\n<p>Al\u00e9m de Fortaleza, o Governo do Cear\u00e1, em parceria com as secretarias de sa\u00fade dos munic\u00edpios realizam a pesquisa de soropreval\u00eancia em Sobral, na Regi\u00e3o Norte, e em Iguatu, na regi\u00e3o Sul do Cear\u00e1.<\/p>\n<h3>Ou\u00e7a<\/h3>\n<p>O governador Camilo Santana ressaltou a import\u00e2ncia estrat\u00e9gica da testagem no estado.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-CAMILO-1-TESTE.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-CAMILO-1-TESTE.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>A coordenadora de Vigil\u00e2ncia Epidemiol\u00f3gica e Preven\u00e7\u00e3o em Sa\u00fade, Ricristhi Gon\u00e7alves, apontou as conclus\u00f5es da pesquisa, ap\u00f3s mesmo levantamento acontecer tamb\u00e9m nos munic\u00edpios de Sobral e Iguatu.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-RICRISTHI-2-CONCLUS\u00c3O.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-RICRISTHI-2-CONCLUS\u00c3O.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>Ricristhi Gon\u00e7alves destaca que o aprimoramento da pesquisa hoje proporciona um levantamento mais completo das testagens por todo o Cear\u00e1. Esses dados s\u00e3o imprescind\u00edveis para a formula\u00e7\u00e3o de pol\u00edticas de enfrentamento ao coronav\u00edrus.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-RICRISTHI-3-APRIMORAMENTO.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-RICRISTHI-3-APRIMORAMENTO.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>A enfermeira pesquisadora Nelise Di\u00f3genes atenta para a identifica\u00e7\u00e3o correta dos profissionais que realizam a pesquisa.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-NELISE-4-IDENTIFICA.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/13.07-NELISE-4-IDENTIFICA.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o 8 horas da manh\u00e3 desta segunda-feira (13), e a enfermeira Nelise Di\u00f3genes, junto com outras duas agentes de sa\u00fade, percorre as ruas do bairro Vicente Pinz\u00f3n, em Fortaleza, de porta em porta, fazer testes para a detec\u00e7\u00e3o de covid-19. Essa \u00e9 a segunda fase da Pesquisa de Soropreval\u00eancia na Capital, promovida pelo Governo do [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":88198,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1515,1840,1633],"class_list":["post-88197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-covid-19","tag-pesquisa-de-soroprevalencia","tag-testes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"S\u00e3o 8 horas da manh\u00e3 desta segunda-feira (13), e a enfermeira Nelise Di\u00f3genes, junto com outras duas agentes de sa\u00fade, percorre as ruas do bairro Vicente Pinz\u00f3n, em Fortaleza, de porta em porta, fazer testes para a detec\u00e7\u00e3o de covid-19. Essa \u00e9 a segunda fase da Pesquisa de Soropreval\u00eancia na Capital, promovida pelo Governo do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-13T16:18:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-13T19:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1616\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza\",\"datePublished\":\"2020-07-13T16:18:46+00:00\",\"dateModified\":\"2020-07-13T19:51:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\"},\"wordCount\":1269,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg\",\"keywords\":[\"coronavirus\",\"covid-19\",\"pesquisa de soropreval\u00eancia\",\"Testes\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\",\"name\":\"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg\",\"datePublished\":\"2020-07-13T16:18:46+00:00\",\"dateModified\":\"2020-07-13T19:51:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg\",\"width\":1616,\"height\":1080,\"caption\":\"TESTE DOMILICIAR E PESQUISA DA COVID 19 REALIZADO PELA PREFEITIURA DE FORTALEZA E GOVERNO DO ESTADO; COVID 19;CORONAVIRUS;SAUDE;SESA;DOMICILIAR; FORTALEZA;MEDIDAS DE COMBATE AO CORONAVIRUS; FOTOS \u00a9 CARLOS GIBAJA\/ GOV. DO CEARA;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/","og_locale":"pt_BR","og_type":"article","og_title":"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"S\u00e3o 8 horas da manh\u00e3 desta segunda-feira (13), e a enfermeira Nelise Di\u00f3genes, junto com outras duas agentes de sa\u00fade, percorre as ruas do bairro Vicente Pinz\u00f3n, em Fortaleza, de porta em porta, fazer testes para a detec\u00e7\u00e3o de covid-19. Essa \u00e9 a segunda fase da Pesquisa de Soropreval\u00eancia na Capital, promovida pelo Governo do [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-07-13T16:18:46+00:00","article_modified_time":"2020-07-13T19:51:50+00:00","og_image":[{"width":1616,"height":1080,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza","datePublished":"2020-07-13T16:18:46+00:00","dateModified":"2020-07-13T19:51:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/"},"wordCount":1269,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg","keywords":["coronavirus","covid-19","pesquisa de soropreval\u00eancia","Testes"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/","name":"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg","datePublished":"2020-07-13T16:18:46+00:00","dateModified":"2020-07-13T19:51:50+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/07\/banner_PESQUISA-COVID19_CGCGM0486.jpg","width":1616,"height":1080,"caption":"TESTE DOMILICIAR E PESQUISA DA COVID 19 REALIZADO PELA PREFEITIURA DE FORTALEZA E GOVERNO DO ESTADO; COVID 19;CORONAVIRUS;SAUDE;SESA;DOMICILIAR; FORTALEZA;MEDIDAS DE COMBATE AO CORONAVIRUS; FOTOS \u00a9 CARLOS GIBAJA\/ GOV. DO CEARA;"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/07\/13\/iniciada-segunda-fase-da-pesquisa-de-soroprevalencia-em-fortaleza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Iniciada segunda fase da Pesquisa de Soropreval\u00eancia em Fortaleza"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=88197"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88197\/revisions"}],"predecessor-version":[{"id":88224,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/88197\/revisions\/88224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/88198"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=88197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=88197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=88197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}