{"id":87741,"date":"2020-06-28T11:38:35","date_gmt":"2020-06-28T14:38:35","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=87741"},"modified":"2020-06-28T22:25:34","modified_gmt":"2020-06-29T01:25:34","slug":"com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/","title":{"rendered":"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-116252\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/06\/200627_CHEGADA-RESPIRADORTES_CGM8794-1200x800.jpg\" alt=\"\" width=\"690\" height=\"460\" \/><\/p>\n<p><em>Os aparelho chegaram em Fortaleza na noite deste s\u00e1bado (27) em voo vindo da China<\/em><\/p>\n<p>A terceira carga de equipamentos adquiridos pelo Governo do Cear\u00e1 para auxiliar no combate \u00e0 pandemia do novo coronav\u00edrus chegou a Fortaleza na noite deste s\u00e1bado (27). O avi\u00e3o que decolou da China pousou em solo cearense por volta das 20h carregado com 300 respiradores. Os aparelhos ser\u00e3o utilizados em unidades de terapia intensiva (UTIs) da rede p\u00fablica, principalmente em cidades do Interior onde a pandemia apresenta crescimento de novos casos neste momento, de acordo com o governador Camilo Santana.<\/p>\n<p>\u201cA maior parte segue para refor\u00e7o das unidades do interior. Ser\u00e3o important\u00edssimos nessa nossa luta para salvar vidas\u201d, disse o chefe do Executivo estadual, que fez quest\u00e3o de relembrar que a popula\u00e7\u00e3o necessita continuar com os cuidados para se proteger do v\u00edrus. \u201cVolto a refor\u00e7ar: evite aglomera\u00e7\u00f5es. S\u00f3 saia de casa se for necess\u00e1rio e sempre usando m\u00e1scara\u201d, comentou.<\/p>\n<p>Grande parte dos equipamentos rec\u00e9m-chegados ir\u00e1 para munic\u00edpios do Interior, como Aracati, Canind\u00e9, Crato, Barbalha, Brejo Santo, Iguatu, Ic\u00f3, Crate\u00fas, Tiangu\u00e1, Ubajara, Itapipoca, Caucaia. Os hospitais regionais (Sert\u00e3o Central, Norte e Cariri) tamb\u00e9m ter\u00e3o amplia\u00e7\u00e3o com 30 leitos de UTI em cada um a partir da chegada dos aparelhos. Em Fortaleza ficar\u00e1 uma pequena quantidade, por j\u00e1 estar com a rede de sa\u00fade mais organizada e por viver um momento com queda progressiva em ovos n\u00famero de casos e de pacientes na UTI.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-116253\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/06\/200627_CHEGADA-RESPIRADORTES_CGM8740-1200x802.jpg\" alt=\"\" width=\"688\" height=\"460\" \/><\/p>\n<p>O secret\u00e1rio da Sa\u00fade, Dr. Cabeto, destacou que o planejamento feito pelo Cear\u00e1 est\u00e1 sendo fundamental para garantir atendimento \u00e0queles que necessitam. \u201cPor conta do isolamento social adequado, os picos (da doen\u00e7a) foram adiados no Interior para que a gente pudesse suprir essa demanda. Quase nenhum estado brasileiro est\u00e1 conseguindo receber em meio a essa grande disputa por medicamentos, insumos, EPIs, respiradores. Para n\u00f3s, essa chegada seda muito da nossa afli\u00e7\u00e3o. A medicina est\u00e1 a\u00ed para acolher, tratar e salvar, e quando voc\u00ea tira uma ferramenta essencial voc\u00ea tira essa oportunidade\u201d, destacou o secret\u00e1rio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-116254\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2020\/06\/200627_CHEGADA-RESPIRADORTES_CGM8897-1200x800.jpg\" alt=\"\" width=\"690\" height=\"460\" \/><\/p>\n<p>Com a chegada dos novos aparelhos, o Cear\u00e1 j\u00e1 totaliza 550 respiradores adquiridos para auxiliar no tratamento a pacientes com a Covid-19, sendo 500 comprados da China e 50 aqui no Brasil. At\u00e9 julho, o Estado deve receber mais dois avi\u00f5es vindos do exterior com mais 200 respiradores e toneladas de equipamentos de prote\u00e7\u00e3o individual.<\/p>\n<h3>Ou\u00e7a<\/h3>\n<p>Os aparelhos ser\u00e3o utilizados em unidades de terapia intensiva (UTIs) da rede p\u00fablica, principalmente em cidades do Interior onde a pandemia apresenta crescimento de novos casos neste momento, de acordo com o governador Camilo Santana.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/28.06-CAMILO-1-RESPIRADORES.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/28.06-CAMILO-1-RESPIRADORES.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>O secret\u00e1rio da Sa\u00fade, Dr. Cabeto, destacou que o planejamento feito pelo Cear\u00e1 est\u00e1 sendo fundamental para garantir atendimento \u00e0queles que necessitam.<\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/28.06-CABETO-2-EQUIPAMENTO.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/28.06-CABETO-2-EQUIPAMENTO.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n<p>Com a chegada dos novos aparelhos, o Cear\u00e1 j\u00e1 totaliza 550 respiradores adquiridos para auxiliar no tratamento a pacientes com a Covid-19, sendo 500 comprados da China e 50 aqui no Brasil. At\u00e9 julho, o Estado deve receber mais dois avi\u00f5es vindos do exterior com mais 200 respiradores e toneladas de equipamentos de prote\u00e7\u00e3o individual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os aparelho chegaram em Fortaleza na noite deste s\u00e1bado (27) em voo vindo da China A terceira carga de equipamentos adquiridos pelo Governo do Cear\u00e1 para auxiliar no combate \u00e0 pandemia do novo coronav\u00edrus chegou a Fortaleza na noite deste s\u00e1bado (27). O avi\u00e3o que decolou da China pousou em solo cearense por volta das [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":87742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1532,211,412,1630,457],"class_list":["post-87741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-covid19","tag-hospitais","tag-interior","tag-respiradores","tag-uti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Os aparelho chegaram em Fortaleza na noite deste s\u00e1bado (27) em voo vindo da China A terceira carga de equipamentos adquiridos pelo Governo do Cear\u00e1 para auxiliar no combate \u00e0 pandemia do novo coronav\u00edrus chegou a Fortaleza na noite deste s\u00e1bado (27). O avi\u00e3o que decolou da China pousou em solo cearense por volta das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-28T14:38:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T01:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior\",\"datePublished\":\"2020-06-28T14:38:35+00:00\",\"dateModified\":\"2020-06-29T01:25:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\"},\"wordCount\":572,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg\",\"keywords\":[\"covid19\",\"Hospitais\",\"Interior\",\"Respiradores\",\"UTI\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\",\"name\":\"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg\",\"datePublished\":\"2020-06-28T14:38:35+00:00\",\"dateModified\":\"2020-06-29T01:25:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/","og_locale":"pt_BR","og_type":"article","og_title":"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Os aparelho chegaram em Fortaleza na noite deste s\u00e1bado (27) em voo vindo da China A terceira carga de equipamentos adquiridos pelo Governo do Cear\u00e1 para auxiliar no combate \u00e0 pandemia do novo coronav\u00edrus chegou a Fortaleza na noite deste s\u00e1bado (27). O avi\u00e3o que decolou da China pousou em solo cearense por volta das [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-06-28T14:38:35+00:00","article_modified_time":"2020-06-29T01:25:34+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior","datePublished":"2020-06-28T14:38:35+00:00","dateModified":"2020-06-29T01:25:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/"},"wordCount":572,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg","keywords":["covid19","Hospitais","Interior","Respiradores","UTI"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/","name":"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg","datePublished":"2020-06-28T14:38:35+00:00","dateModified":"2020-06-29T01:25:34+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner_CHEGADA-RESPIRADORTES_CGM8794-768x512.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/28\/com-a-chegada-de-mais-300-respiradores-governo-do-ceara-vai-ampliar-leitos-de-uti-no-interior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Com a chegada de mais 300 respiradores, Governo do Cear\u00e1 vai ampliar leitos de UTI no Interior"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/87741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=87741"}],"version-history":[{"count":7,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/87741\/revisions"}],"predecessor-version":[{"id":87765,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/87741\/revisions\/87765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/87742"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=87741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=87741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=87741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}