{"id":873,"date":"2009-09-16T14:06:25","date_gmt":"2009-09-16T17:06:25","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/"},"modified":"2009-09-16T14:06:25","modified_gmt":"2009-09-16T17:06:25","slug":"joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/","title":{"rendered":"Jo\u00e3o Ananias defende CSS no artigo &#8220;SUS, luta pela melhoria&#8221;"},"content":{"rendered":"<p>Os mesmos que abrem a boca hoje para dizer que a Contribui\u00e7\u00e3o Social para a Sa\u00fade (CSS) vai prejudicar o trabalhador porque o custo ser\u00e1 repassado aos pre\u00e7os dos produtos s\u00e3o os mesmos que n\u00e3o baixaram pre\u00e7os de nada quando a CPMF foi extinta. Emudeceram e esqueceram os trabalhadores. A verdade \u00e9 que o Sistema \u00danico de Sa\u00fade, que est\u00e1 cuidando dos que podem menos e oferecendo as m\u00ednimas condi\u00e7\u00f5es de sobreviv\u00eancia, pode fazer bem mais. Faltam recursos. O tributo n\u00e3o deixar\u00e1 menos rico quem emite um cheque de mil reais e vai pagar uma CSS de 1 real. Mas o novo tributo far\u00e1 grande diferen\u00e7a para quem \u00e9 acolhido e assistido pelo SUS.<\/p>\n<p>A Constitui\u00e7\u00e3o de 1988 trouxe cidadania \u00e0 popula\u00e7\u00e3o quando definiu o direito universal \u00e0 sa\u00fade como dever do Estado. At\u00e9 ent\u00e3o, somente os que tinham emprego formal e contribu\u00edam para a Previd\u00eancia Social tinham direito \u00e0 sa\u00fade p\u00fablica. Hoje o SUS realiza 3 milh\u00f5es de partos, por ano, em todos os lugares do Pa\u00eds. Faz 12 milh\u00f5es de interna\u00e7\u00f5es hospitalares. Financia 14 mil transplantes por ano no Pa\u00eds. No Cear\u00e1, em 2008, foram realizados 739 transplantes de \u00f3rg\u00e3os e tecidos. Um \u00fanico transplante de cora\u00e7\u00e3o custa R$45 mil. Isso sem incluir a assist\u00eancia para o resto da vida, feita por multiprofissionais e com medicamentos. Mais de 100 milh\u00f5es de brasileiros s\u00e3o acompanhados pelas equipes do Sa\u00fade da Fam\u00edlia, que contribu\u00edram, efetivamente, para a redu\u00e7\u00e3o da taxa de mortalidade infantil. No Cear\u00e1, caiu de 80 para mil nascidos em 1994 para 16.1 em 2008. Nenhum pa\u00eds do mundo vacina mais do que o Brasil.<\/p>\n<p>Tudo isso com o cobertor curto do SUS. E ainda h\u00e1 os que tentam desmoralizar os gestores da sa\u00fade p\u00fablica. Sem entender nada de sa\u00fade, ficam falando de que o problema \u00e9 de gest\u00e3o e n\u00e3o de escassez de recursos. N\u00e3o ser\u00edamos honestos se n\u00e3o admit\u00edssemos que h\u00e1 algumas dificuldades de gest\u00e3o.<\/p>\n<p>Assim como em qualquer \u00e1rea. O que \u00e9 desonesto \u00e9 sair por a\u00ed, anunciando uma cruzada nacional, querendo convencer de que h\u00e1 recursos e que o problema est\u00e1 na gest\u00e3o do SUS. \u00c9 o caso do presidente da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de S\u00e3o Paulo, Paulo Skaf. Ele est\u00e1 sendo porta-voz dos mesmos industriais, que em 2007 impediram a continuidade da CPMF, e pensam que enganam se intitulando de defensores da sociedade brasileira. N\u00e3o ser\u00e3o contra a CSS por que o tributo vai funcionar como um efetivo fiscal dos que movimentam muito dinheiro mas d\u00e3o um jeito de pagar pouco imposto de renda?<\/p>\n<p>O ex-ministro Adib Jatene, em recente entrevista ao UOL Not\u00edcias, desmonta essa fal\u00e1cia da elite financeira e pol\u00edtica, lembrando que hospitais de primeira linha foram buscar no SUS os seus gestores e cita o caso do superintendente do hospital S\u00edrio Liban\u00eas. Antes o superintendente Gon\u00e7alo Vecina foi presidente da Anvisa e secret\u00e1rio de sa\u00fade de S\u00e3o Paulo. Mudou de p\u00e9ssimo para bom gestor? No SUS ele n\u00e3o tinha recursos para gerir.<\/p>\n<p>A luta pela melhoria do SUS deveria ser de todos. Mas n\u00e3o podemos esperar que a elite brasileira rompa com o seu perfil hist\u00f3rico e estenda a m\u00e3o para a sa\u00fade universal, integral e com equidade. A luta \u00e9 nossa, gestores e, em especial, da popula\u00e7\u00e3o.<\/p>\n<p>Jo\u00e3o Ananias &#8211; Secret\u00e1rio da Sa\u00fade do Estado do Cear\u00e1 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os mesmos que abrem a boca hoje para dizer que a Contribui\u00e7\u00e3o Social para a Sa\u00fade (CSS) vai prejudicar o trabalhador porque o custo ser\u00e1 repassado aos pre\u00e7os dos produtos s\u00e3o os mesmos que n\u00e3o baixaram pre\u00e7os de nada quando a CPMF foi extinta. Emudeceram e esqueceram os trabalhadores. A verdade \u00e9 que o Sistema [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-873","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jo\u00e3o Ananias defende CSS no artigo &quot;SUS, luta pela melhoria&quot; - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jo\u00e3o Ananias defende CSS no artigo &quot;SUS, luta pela melhoria&quot; - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Os mesmos que abrem a boca hoje para dizer que a Contribui\u00e7\u00e3o Social para a Sa\u00fade (CSS) vai prejudicar o trabalhador porque o custo ser\u00e1 repassado aos pre\u00e7os dos produtos s\u00e3o os mesmos que n\u00e3o baixaram pre\u00e7os de nada quando a CPMF foi extinta. Emudeceram e esqueceram os trabalhadores. A verdade \u00e9 que o Sistema [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-16T17:06:25+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Jo\u00e3o Ananias defende CSS no artigo &#8220;SUS, luta pela melhoria&#8221;\",\"datePublished\":\"2009-09-16T17:06:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\"},\"wordCount\":609,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\",\"name\":\"Jo\u00e3o Ananias defende CSS no artigo \\\"SUS, luta pela melhoria\\\" - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-09-16T17:06:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jo\u00e3o Ananias defende CSS no artigo &#8220;SUS, luta pela melhoria&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jo\u00e3o Ananias defende CSS no artigo \"SUS, luta pela melhoria\" - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/","og_locale":"pt_BR","og_type":"article","og_title":"Jo\u00e3o Ananias defende CSS no artigo \"SUS, luta pela melhoria\" - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Os mesmos que abrem a boca hoje para dizer que a Contribui\u00e7\u00e3o Social para a Sa\u00fade (CSS) vai prejudicar o trabalhador porque o custo ser\u00e1 repassado aos pre\u00e7os dos produtos s\u00e3o os mesmos que n\u00e3o baixaram pre\u00e7os de nada quando a CPMF foi extinta. Emudeceram e esqueceram os trabalhadores. A verdade \u00e9 que o Sistema [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-09-16T17:06:25+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Jo\u00e3o Ananias defende CSS no artigo &#8220;SUS, luta pela melhoria&#8221;","datePublished":"2009-09-16T17:06:25+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/"},"wordCount":609,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/","name":"Jo\u00e3o Ananias defende CSS no artigo \"SUS, luta pela melhoria\" - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-09-16T17:06:25+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/16\/joao-ananias-defende-css-no-artigo-qsus-luta-pela-melhoriaq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Jo\u00e3o Ananias defende CSS no artigo &#8220;SUS, luta pela melhoria&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=873"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/873\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}