{"id":87268,"date":"2020-06-10T09:46:26","date_gmt":"2020-06-10T12:46:26","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=87268"},"modified":"2020-06-10T09:46:26","modified_gmt":"2020-06-10T12:46:26","slug":"confira-a-agenda-de-webconferencias-desta-semana","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/","title":{"rendered":"Confira a agenda de webconfer\u00eancias desta semana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-87270 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Inseridas no contexto da pandemia do novo coronav\u00edrus, duas tem\u00e1ticas s\u00e3o destaque nesta semana nas webconferencias realizadas pela Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues. Realizadas no\u00a0<a href=\"https:\/\/youtube.com\/espceara\" target=\"_blank\" rel=\"noopener\">canal no YouTube da ESP\/CE<\/a>, as transmiss\u00f5es d\u00e3o suporte \u00e0 atua\u00e7\u00e3o dos profissionais de sa\u00fade da rede p\u00fablica do estado.<\/p>\n<p>Na pr\u00f3xima quarta-feira, 10, a transmiss\u00e3o come\u00e7a \u00e0s 10h e vai levantar reflex\u00f5es sobre o cen\u00e1rio da Covid-19 no Cear\u00e1 e Portugal. Aberta ao p\u00fablico, a web contar\u00e1 com a psic\u00f3loga, mestre em Educa\u00e7\u00e3o pela Universidade Federal do Cear\u00e1 e doutoranda em Educa\u00e7\u00e3o pela Universidade de Aveiro em Portugal, Joan Rios, e com o diretor de Educa\u00e7\u00e3o Profissional em Sa\u00fade da ESP\/CE, Caio Cavalcanti. A conversa ser\u00e1 mediada por Adriano Rodrigues de Souza, doutor em Sa\u00fade Coletiva pela UFC e coordenador da Sa\u00fade Mental do Estado do Cear\u00e1.<\/p>\n<p>J\u00e1 na sexta-feira, 12, entra em pauta a atua\u00e7\u00e3o do Sistema CEP\/Conep (Comit\u00ea de \u00c9tica em Pesquisa da Comiss\u00e3o Nacional de \u00c9tica em Pesquisa) e a prote\u00e7\u00e3o dos participantes nas pesquisas sobre coronav\u00edrus. O encontro online come\u00e7a \u00e0s 10 da manh\u00e3. O palestrante ser\u00e1 o coordenador da Comiss\u00e3o Nacional de \u00c9tica em Pesquisa do Conselho Nacional de Sa\u00fade, Jorge Alves de Almeida Venancio. Ele falar\u00e1 para membros de comit\u00eas de \u00e9tica em pesquisa, pesquisadores, conselheiros de sa\u00fade, acad\u00eamicos e comunidade docente.<\/p>\n<h3>Confira a agenda da semana de webconfer\u00eancias<\/h3>\n<p><strong>Covid-19: reflex\u00f5es sobre a realidade portuguesa e cearense<\/strong><br \/>\nQuando: quarta-feira, 10<br \/>\nHor\u00e1rio: 10 horas<br \/>\nMediador: Adriano Rodrigues de Souza (enfermeiro, doutor em Sa\u00fade Coletiva pela UFC e coordenador da Sa\u00fade Mental do Estado do Cear\u00e1)<br \/>\nFacilitadores:<br \/>\n\u2013 Joan Rios (psic\u00f3loga, mestre em Educa\u00e7\u00e3o pela UFC, doutoranda em Educa\u00e7\u00e3o pela Universidade de Aveiro em Portugal, docente e supervisora em cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o nas \u00e1reas de Psicologia da Educa\u00e7\u00e3o e Avalia\u00e7\u00e3o Psicol\u00f3gica).<br \/>\n\u2013 Caio Garcia Correia S\u00e1 Cavalcanti (fisioterapeuta, sanitarista, mestre em Sa\u00fade P\u00fablica, doutorando em Sa\u00fade Coletiva e diretor de Educa\u00e7\u00e3o Profissional em Sa\u00fade da Escola de Sa\u00fade P\u00fablica do Cear\u00e1<br \/>\nP\u00fablico-alvo: aberto ao p\u00fablico<\/p>\n<p>Acesse a webconfer\u00eancia em\u00a0<a href=\"https:\/\/youtube.com\/espceara\" target=\"_blank\" rel=\"noopener\">youtube.com\/espceara<\/a><\/p>\n<p><strong>A atua\u00e7\u00e3o do Sistema CEP\/CONEP e a prote\u00e7\u00e3o dos participantes nas pesquisas sobre coronav\u00edrus<\/strong><br \/>\nFacilitador: Dr. Jorge Alves de Almeida Venancio (coordenador da Comiss\u00e3o Nacional de \u00c9tica em Pesquisa do Conselho Nacional de Sa\u00fade)<br \/>\nQuando: sexta-feira, 12 de junho<br \/>\nHor\u00e1rio: 10 horas<br \/>\nP\u00fablico-alvo: membros dos Comit\u00eas de \u00c9tica em Pesquisa, pesquisadores, conselheiros de sa\u00fade e acad\u00eamicos<br \/>\nAcesso excepcionalmente pelo Google Meet:\u00a0<a href=\"https:\/\/meet.google.com\/nbw-psht-mjv\">meet.google.com\/nbw-psht-mjv<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Inseridas no contexto da pandemia do novo coronav\u00edrus, duas tem\u00e1ticas s\u00e3o destaque nesta semana nas webconferencias realizadas pela Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues. Realizadas no\u00a0canal no YouTube da ESP\/CE, as transmiss\u00f5es d\u00e3o suporte \u00e0 atua\u00e7\u00e3o dos profissionais de sa\u00fade da rede p\u00fablica do estado. Na pr\u00f3xima quarta-feira, 10, a [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":87270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[133,1798,1515,1320,1799],"class_list":["post-87268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-ceara","tag-cep-conep","tag-covid-19","tag-portugal","tag-webconferencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira a agenda de webconfer\u00eancias desta semana - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira a agenda de webconfer\u00eancias desta semana - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Inseridas no contexto da pandemia do novo coronav\u00edrus, duas tem\u00e1ticas s\u00e3o destaque nesta semana nas webconferencias realizadas pela Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues. Realizadas no\u00a0canal no YouTube da ESP\/CE, as transmiss\u00f5es d\u00e3o suporte \u00e0 atua\u00e7\u00e3o dos profissionais de sa\u00fade da rede p\u00fablica do estado. Na pr\u00f3xima quarta-feira, 10, a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T12:46:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Confira a agenda de webconfer\u00eancias desta semana\",\"datePublished\":\"2020-06-10T12:46:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png\",\"keywords\":[\"Cear\u00e1\",\"CEP\/CONEP\",\"covid-19\",\"Portugal\",\"Webconfer\u00eancias\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\",\"name\":\"Confira a agenda de webconfer\u00eancias desta semana - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png\",\"datePublished\":\"2020-06-10T12:46:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confira a agenda de webconfer\u00eancias desta semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira a agenda de webconfer\u00eancias desta semana - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/","og_locale":"pt_BR","og_type":"article","og_title":"Confira a agenda de webconfer\u00eancias desta semana - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&nbsp; Inseridas no contexto da pandemia do novo coronav\u00edrus, duas tem\u00e1ticas s\u00e3o destaque nesta semana nas webconferencias realizadas pela Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues. Realizadas no\u00a0canal no YouTube da ESP\/CE, as transmiss\u00f5es d\u00e3o suporte \u00e0 atua\u00e7\u00e3o dos profissionais de sa\u00fade da rede p\u00fablica do estado. Na pr\u00f3xima quarta-feira, 10, a [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-06-10T12:46:26+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Confira a agenda de webconfer\u00eancias desta semana","datePublished":"2020-06-10T12:46:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/"},"wordCount":474,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png","keywords":["Cear\u00e1","CEP\/CONEP","covid-19","Portugal","Webconfer\u00eancias"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/","name":"Confira a agenda de webconfer\u00eancias desta semana - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png","datePublished":"2020-06-10T12:46:26+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/06\/banner-mat\u00e9ria.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/06\/10\/confira-a-agenda-de-webconferencias-desta-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Confira a agenda de webconfer\u00eancias desta semana"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/87268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=87268"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/87268\/revisions"}],"predecessor-version":[{"id":87271,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/87268\/revisions\/87271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/87270"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=87268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=87268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=87268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}