{"id":86767,"date":"2020-05-26T11:03:18","date_gmt":"2020-05-26T14:03:18","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=86767"},"modified":"2020-05-27T13:02:39","modified_gmt":"2020-05-27T16:02:39","slug":"novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/","title":{"rendered":"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-86768 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>A partir desta ter\u00e7a-feira (26), o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado, iniciar\u00e1 o funcionamento do Centro de Triagem, montado ao lado do hospital de campanha anexo \u00e0 unidade. O espa\u00e7o receber\u00e1 pacientes que necessitam de atendimento emergencial e funcionar\u00e1 diariamente, das 7 \u00e0s 19 horas. No plant\u00e3o noturno, as emerg\u00eancias do Hospital mant\u00eam o fluxo normal de atendimento.<\/p>\n<p>O Centro de Triagem do HGF foi criado para unificar o fluxo inicial de atendimento da emerg\u00eancia. \u201cO novo servi\u00e7o \u00e9 direcionado aos pacientes que j\u00e1 procuravam nossa emerg\u00eancia com sintomas neurol\u00f3gicos, problemas renais, entre outros, e tamb\u00e9m com sintomas respirat\u00f3rios. Ou seja, quem deve nos procurar s\u00e3o os pacientes que estejam realmente necessitando de atendimento emergencial\u201d, explica o chefe da emerg\u00eancia do HGF, Khalil Feitosa.<\/p>\n<p>O servi\u00e7o ter\u00e1 equipe composta por dois profissionais de enfermagem, dois m\u00e9dicos e recepcionista. Os pacientes far\u00e3o a triagem inicial e, em seguida, ser\u00e3o encaminhados para os procedimentos necess\u00e1rios. Pessoas transferidas de outras unidades de sa\u00fade pela Central de Regula\u00e7\u00e3o do Estado n\u00e3o necessitam passar por triagem inicial.<\/p>\n<h3>Drive-thru<\/h3>\n<p>A Secretaria da Sa\u00fade do Cear\u00e1 est\u00e1 implantando a estrat\u00e9gia da realiza\u00e7\u00e3o de testagem em massa para Covid-19 no formato de drive-thru. O objetivo \u00e9 ampliar o sistema de testagem para identificar as pessoas que j\u00e1 foram infectadas pela Covid-19 e quais ainda est\u00e3o suscet\u00edveis \u00e0 doen\u00e7a. O Cear\u00e1 j\u00e1 realizou mais de 88,3 mil exames para identificar Covid-19. Destes, 34.949 testes r\u00e1pidos.<\/p>\n<p>&#8220;O drive-thru \u00e9 uma outra proposta em que a gente consegue coletar mais rapidamente os exames, aumentando a nossa testagem. O fato de ele ser realizado dentro do carro da pr\u00f3pria pessoa, torna o ambiente mais seguro. Ent\u00e3o a gente n\u00e3o precisa de desinfec\u00e7\u00e3o de ambiente, de troca de EPIs. Isso facilita a coleta dos procedimentos que s\u00e3o realizados nos ambulat\u00f3rios e d\u00e1 celeridade&#8221;, explica a secret\u00e1ria executiva de Vigil\u00e2ncia e Regula\u00e7\u00e3o da Sesa, Magda Almeida.<\/p>\n<p>De acordo com a secret\u00e1ria executiva, no primeiro momento, o servi\u00e7o de drive-thru ser\u00e1 implementado no HGF e funcionar\u00e1 por agendamento. A log\u00edstica est\u00e1 em execu\u00e7\u00e3o para, em breve, iniciar o funcionamento. &#8220;Vamos avaliar o funcionamento nas primeiras semanas, corrigindo as poss\u00edveis fragilidades. A gente vai ampliar para outros locais como estacionamento de shoppings&#8221;, afirma.<\/p>\n<h3>Teste r\u00e1pido<\/h3>\n<p>O teste r\u00e1pido detecta a exist\u00eancia no sangue dos anticorpos de defesa IgG e IgM, produzidos pelo corpo humano contra o v\u00edrus SARS-CoV-2, causador da Covid-19. O teste pode ser feito pela t\u00e9cnica sorol\u00f3gica e ponta dos dedos. A recomenda\u00e7\u00e3o \u00e9 que o exame seja feito uma semana ap\u00f3s o aparecimento de sintomas como febre, tosse e dificuldade para respirar. O resultado sai em at\u00e9 vinte minutos.<\/p>\n<p><em>O Centro de Triagem do HGF foi criado para unificar o fluxo inicial de atendimento da emerg\u00eancia, como explica o chefe da Emerg\u00eancia do HGF, Khalil Feitosa.<\/em><\/p>\n\n            <audio controls=\"controls\">\n            <source src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/26.05-KHALIL-1-TRIAGEM.mp3\" type=\"audio\/mp3\">\n                \n                Seu Navegador n\u00e3o tem suporte para reprodu\u00e7\u00e3o de \u00e1udio <br>\n                voc\u00ea pode fazer o download e ouvir em um player de sua prefer\u00eancia <a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/26.05-KHALIL-1-TRIAGEM.mp3\" tabindex=\"0\">clicando aqui<\/a>\n            <\/audio>\n","protected":false},"excerpt":{"rendered":"<p>A partir desta ter\u00e7a-feira (26), o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado, iniciar\u00e1 o funcionamento do Centro de Triagem, montado ao lado do hospital de campanha anexo \u00e0 unidade. O espa\u00e7o receber\u00e1 pacientes que necessitam de atendimento emergencial e funcionar\u00e1 diariamente, das [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":86768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1532,130],"class_list":["post-86767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-covid19","tag-hgf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A partir desta ter\u00e7a-feira (26), o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado, iniciar\u00e1 o funcionamento do Centro de Triagem, montado ao lado do hospital de campanha anexo \u00e0 unidade. O espa\u00e7o receber\u00e1 pacientes que necessitam de atendimento emergencial e funcionar\u00e1 diariamente, das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-26T14:03:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-27T16:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26\",\"datePublished\":\"2020-05-26T14:03:18+00:00\",\"dateModified\":\"2020-05-27T16:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\"},\"wordCount\":549,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png\",\"keywords\":[\"coronavirus\",\"covid19\",\"HGF\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\",\"name\":\"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png\",\"datePublished\":\"2020-05-26T14:03:18+00:00\",\"dateModified\":\"2020-05-27T16:02:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A partir desta ter\u00e7a-feira (26), o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), do Governo do Estado, iniciar\u00e1 o funcionamento do Centro de Triagem, montado ao lado do hospital de campanha anexo \u00e0 unidade. O espa\u00e7o receber\u00e1 pacientes que necessitam de atendimento emergencial e funcionar\u00e1 diariamente, das [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-05-26T14:03:18+00:00","article_modified_time":"2020-05-27T16:02:39+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26","datePublished":"2020-05-26T14:03:18+00:00","dateModified":"2020-05-27T16:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/"},"wordCount":549,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png","keywords":["coronavirus","covid19","HGF"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/","name":"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png","datePublished":"2020-05-26T14:03:18+00:00","dateModified":"2020-05-27T16:02:39+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_centrodetriagem.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/26\/novo-centro-de-triagem-comeca-a-funcionar-no-hgf-nesta-terca-feira-dia-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Novo Centro de Triagem come\u00e7a a funcionar no HGF nesta ter\u00e7a-feira, dia 26"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=86767"}],"version-history":[{"count":6,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86767\/revisions"}],"predecessor-version":[{"id":86796,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86767\/revisions\/86796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/86768"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=86767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=86767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=86767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}