{"id":86356,"date":"2020-05-08T15:36:00","date_gmt":"2020-05-08T18:36:00","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=86356"},"modified":"2020-05-08T16:31:28","modified_gmt":"2020-05-08T19:31:28","slug":"pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/","title":{"rendered":"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86357\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png\" alt=\"\" width=\"775\" height=\"489\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid-600x379.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid-768x485.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>&#8220;Assusta. A gente pensa que \u00e9 s\u00f3 uma gripe\u201d, disse o pescador Valmyr Alves de S\u00e1, de 77 anos. Diagnosticado com coronav\u00edrus, o idoso ficou oito dias internado no Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da rede p\u00fablica da Secretaria de Sa\u00fade do Cear\u00e1, do Governo do Estado. Ap\u00f3s receber alta, ele finalmente p\u00f4de voltar para casa.<\/p>\n<p>\u201cFiquei feliz. Foi bonito, cantaram pra mim, nem sabia que tinha m\u00fasica de pescador. Todo mundo aqui [no Bairro Servluz] ficou emocionado. Mas a doutora ainda mandou ficar isolado\u201d, contou Valmyr, que \u00e9 conhecido na praia do Titanzinho.<\/p>\n<div id=\"attachment_86359\" style=\"width: 785px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86359\" class=\"wp-image-86359 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados1.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados1.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados1-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados1-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><p id=\"caption-attachment-86359\" class=\"wp-caption-text\">Valmyr Alves de S\u00e1 ao lado da fam\u00edlia antes de ser diagnosticado com coronav\u00edrus. Foto: arquivo pessoal<\/p><\/div>\n<p>A recomenda\u00e7\u00e3o de isolamento n\u00e3o \u00e9 \u00e0 toa, pois, mesmo recebendo alta do hospital, o o v\u00edrus ainda pode estar no organismo. \u00c9 o que explica o m\u00e9dico infectologista Keny Colares, do HSJ. Segundo o especialista, o processo de recupera\u00e7\u00e3o dos pacientes acontece de duas formas.<\/p>\n<p>A primeira, a \u201ccura cl\u00ednica\u201d, ocorre quando n\u00e3o h\u00e1 mais sintomas da doen\u00e7a. J\u00e1 a \u201ccura microbiol\u00f3gica\u201d significa que organismo eliminou totalmente o v\u00edrus, algo que pode demorar mais para acontecer. \u201cIsso varia muito de pessoa para pessoa. Aparentemente, os pacientes levam algum tempo eliminando o v\u00edrus, principalmente se compararmos casos leves e graves\u201d, explica.<\/p>\n<p>Nos casos mais graves, normalmente, as pessoas apresentam dificuldades para respirar e precisam de interna\u00e7\u00e3o. \u201cPode ser um caso de um dia de interna\u00e7\u00e3o ou dois. A depender da situa\u00e7\u00e3o, medicamentos e oxig\u00eanio deixam o paciente bem o suficiente para ir para casa. O ideal \u00e9 que ele fique o menor tempo poss\u00edvel no hospital\u201d, afirmou o m\u00e9dico. Nestes casos, o isolamento em casa deve ser feito de prefer\u00eancia em um quarto, sem manter contato direto com os demais membros da fam\u00edlia para n\u00e3o haver contamina\u00e7\u00e3o.<\/p>\n<p>\u201cH\u00e1 casos graves mais severos em que, mesmo com o tratamento, n\u00e3o conseguem respirar, se cansam. Esses [pacientes] precisam de apoio, entubar, traqueotomia. Isso tudo vai depender da avalia\u00e7\u00e3o m\u00e9dica. E eles podem ficar muitos dias at\u00e9 que o pulm\u00e3o funcione sem ajuda\u201d, ressaltou.<\/p>\n<p>Nestes casos, ap\u00f3s a alta hospitalar, cabe ao m\u00e9dico avaliar a necessidade de isolamento em casa e orientar o paciente. \u201cO paciente s\u00f3 est\u00e1 de fato recuperado quando ele est\u00e1 sem sintomas. Mais especificamente sem febre e tosse (forte) por, pelo menos, tr\u00eas dias. Lembrando que uma tosse leve, pigarro, pode permanecer com o paciente por um tempo\u201d, ressaltou o especialista.<\/p>\n<p>Os casos leves s\u00e3o aqueles que podem permanecer em casa. Por\u00e9m, entre o quinto e o s\u00e9timo dia, o paciente deve ficar atento para uma poss\u00edvel piora ou melhora dos sintomas. Caso n\u00e3o apresente qualquer melhora, \u00e9 preciso procurar ajuda m\u00e9dica. \u201cPrincipalmente se se tratar de grupo de risco, ou seja, hipertenso, diab\u00e9tico, card\u00edaco, entre outras coisas\u201d, disse o m\u00e9dico<\/p>\n<h3>Casos assintom\u00e1ticos<\/h3>\n<p>Algumas pessoas podem ter o v\u00edrus e n\u00e3o apresentar sintomas. Com isso, n\u00e3o saber\u00e3o que est\u00e3o doentes. \u201cA propor\u00e7\u00e3o da quantidade desses casos ainda n\u00e3o \u00e9 clara. Imagina-se que a pessoa tamb\u00e9m possa transmitir, mas ainda n\u00e3o se sabe o alcance disso. Esse \u00e9 um dos motivos que tornam o distanciamento social t\u00e3o importante. Ele dificulta a transmiss\u00e3o, n\u00e3o importa se o transmissor \u00e9 um caso leve, grave ou assintom\u00e1tico\u201d, disse Keny Colares.<\/p>\n<h3>Vida p\u00f3s-Covid-19<\/h3>\n<p>Uma semana ap\u00f3s receber alta hospitalar, Valmyr Alves de S\u00e1 teve de comparecer a uma consulta de acompanhamento ambulatorial no HSJ. Dependendo de como o paciente reage \u00e0 doen\u00e7a, a avalia\u00e7\u00e3o \u00e9 necess\u00e1ria para evitar complica\u00e7\u00f5es futuras. \u201cEu fui pra consulta, a doutora me examinou e passou uns exames. Eu vou fazer pra ficar bom. Gra\u00e7as a Deus e aos doutores do S\u00e3o Jos\u00e9, eu estou \u00f3timo, respiro e como bem\u201d, disse o pescador, ainda est\u00e1 em processo de recupera\u00e7\u00e3o.<\/p>\n<div id=\"attachment_86358\" style=\"width: 785px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86358\" class=\"wp-image-86358 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados5.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados5.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados5-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_site_pacientes_recuperados5-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><p id=\"caption-attachment-86358\" class=\"wp-caption-text\">Valmyr em um dia de pescaria. Foto: arquivo pessoal<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Assusta. A gente pensa que \u00e9 s\u00f3 uma gripe\u201d, disse o pescador Valmyr Alves de S\u00e1, de 77 anos. Diagnosticado com coronav\u00edrus, o idoso ficou oito dias internado no Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da rede p\u00fablica da Secretaria de Sa\u00fade do Cear\u00e1, do Governo do Estado. Ap\u00f3s receber alta, ele finalmente p\u00f4de voltar para [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":86357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1532,283],"class_list":["post-86356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-covid19","tag-recuperacao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&#8220;Assusta. A gente pensa que \u00e9 s\u00f3 uma gripe\u201d, disse o pescador Valmyr Alves de S\u00e1, de 77 anos. Diagnosticado com coronav\u00edrus, o idoso ficou oito dias internado no Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da rede p\u00fablica da Secretaria de Sa\u00fade do Cear\u00e1, do Governo do Estado. Ap\u00f3s receber alta, ele finalmente p\u00f4de voltar para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-08T18:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-08T19:31:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar\",\"datePublished\":\"2020-05-08T18:36:00+00:00\",\"dateModified\":\"2020-05-08T19:31:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\"},\"wordCount\":710,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png\",\"keywords\":[\"coronavirus\",\"covid19\",\"recupera\u00e7\u00e3o\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\",\"name\":\"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png\",\"datePublished\":\"2020-05-08T18:36:00+00:00\",\"dateModified\":\"2020-05-08T19:31:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png\",\"width\":775,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/","og_locale":"pt_BR","og_type":"article","og_title":"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&#8220;Assusta. A gente pensa que \u00e9 s\u00f3 uma gripe\u201d, disse o pescador Valmyr Alves de S\u00e1, de 77 anos. Diagnosticado com coronav\u00edrus, o idoso ficou oito dias internado no Hospital S\u00e3o Jos\u00e9 (HSJ), unidade da rede p\u00fablica da Secretaria de Sa\u00fade do Cear\u00e1, do Governo do Estado. Ap\u00f3s receber alta, ele finalmente p\u00f4de voltar para [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-05-08T18:36:00+00:00","article_modified_time":"2020-05-08T19:31:28+00:00","og_image":[{"width":775,"height":489,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar","datePublished":"2020-05-08T18:36:00+00:00","dateModified":"2020-05-08T19:31:28+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/"},"wordCount":710,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png","keywords":["coronavirus","covid19","recupera\u00e7\u00e3o"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/","name":"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png","datePublished":"2020-05-08T18:36:00+00:00","dateModified":"2020-05-08T19:31:28+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner_cura_covid.png","width":775,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/08\/pacientes-recuperados-devem-manter-rotina-de-cuidados-apos-alta-hospitalar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Pacientes recuperados devem manter rotina de cuidados ap\u00f3s alta hospitalar"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=86356"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86356\/revisions"}],"predecessor-version":[{"id":86365,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86356\/revisions\/86365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/86357"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=86356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=86356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=86356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}