{"id":86329,"date":"2020-05-07T18:50:11","date_gmt":"2020-05-07T21:50:11","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=86329"},"modified":"2020-05-07T20:49:53","modified_gmt":"2020-05-07T23:49:53","slug":"em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/","title":{"rendered":"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86331\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg\" alt=\"\" width=\"1199\" height=\"607\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg 1199w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07-600x304.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07-768x389.jpg 768w\" sizes=\"auto, (max-width: 1199px) 100vw, 1199px\" \/><\/p>\n<p>O secret\u00e1rio da Sa\u00fade do Cear\u00e1, Carlos Roberto Martins Rodrigues Sobrinho (Dr. Cabeto), participou de uma coletiva de imprensa por meio de videoconfer\u00eancia realizada pela Secretaria Municipal da Sa\u00fade de Fortaleza (SMS) na manh\u00e3 desta quinta-feira (7). Na ocasi\u00e3o, foi apresentado o relat\u00f3rio t\u00e9cnico sobre a incid\u00eancia de Covid-19 na Capital cearense.<\/p>\n<p>Durante o encontro, Dr. Cabeto ressaltou a import\u00e2ncia das medidas estabelecidas pelo decreto do Governo do Cear\u00e1, que prorroga o isolamento social por mais 15 dias. \u201cNingu\u00e9m gosta de restri\u00e7\u00e3o nas suas vidas, mas estamos assistindo a um aumento exponencial de casos de Covid-19 e a principal proposta para sairmos desse cen\u00e1rio \u00e9 a ado\u00e7\u00e3o de um distanciamento social r\u00edgido. Essa forma funciona e foi elaborada a partir de dados t\u00e9cnicos, epidemiol\u00f3gicos e assistenciais\u201d, ressalta o gestor.<\/p>\n<p>A coletiva tamb\u00e9m contou com a participa\u00e7\u00e3o da secret\u00e1ria adjunta da SMS, Ana Estela Fernandes; do gerente da C\u00e9lula de Vigil\u00e2ncia Epidemiol\u00f3gica da SMS, Ant\u00f4nio Lima Neto, e do professor Jos\u00e9 Soares, da Universidade Federal do Cear\u00e1 (UFC). Em conversa com jornalistas, os gestores discutiram, entre outros assuntos, o atual cen\u00e1rio epidemiol\u00f3gico do coronav\u00edrus no Estado e um estudo da proje\u00e7\u00e3o da pandemia em Fortaleza.<\/p>\n<p>Na videoconfer\u00eancia, Dr. Cabeto anunciou a chegada de mais equipamentos para fortalecer o enfrentamento \u00e0 pandamia de coronav\u00edrus. \u201cO Estado est\u00e1 comprando respiradores e, na semana que vem, est\u00e1 chegando 200 novos aparelhos, al\u00e9m de 100 toneladas de EPIs para poder suprir todos os munic\u00edpios\u201d, destacou.<\/p>\n<p>A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) segue todas as recomenda\u00e7\u00f5es do Minist\u00e9rio da Sa\u00fade (MS) e da Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) para a conten\u00e7\u00e3o do coronav\u00edrus no Estado. A popula\u00e7\u00e3o pode se informar sobre a doen\u00e7a, conhecer os sintomas e dicas de preven\u00e7\u00e3o no site e nas redes socais da Sesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio da Sa\u00fade do Cear\u00e1, Carlos Roberto Martins Rodrigues Sobrinho (Dr. Cabeto), participou de uma coletiva de imprensa por meio de videoconfer\u00eancia realizada pela Secretaria Municipal da Sa\u00fade de Fortaleza (SMS) na manh\u00e3 desta quinta-feira (7). Na ocasi\u00e3o, foi apresentado o relat\u00f3rio t\u00e9cnico sobre a incid\u00eancia de Covid-19 na Capital cearense. Durante o encontro, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[],"class_list":["post-86329","post","type-post","status-publish","format-standard","hentry","category-covid-19"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O secret\u00e1rio da Sa\u00fade do Cear\u00e1, Carlos Roberto Martins Rodrigues Sobrinho (Dr. Cabeto), participou de uma coletiva de imprensa por meio de videoconfer\u00eancia realizada pela Secretaria Municipal da Sa\u00fade de Fortaleza (SMS) na manh\u00e3 desta quinta-feira (7). Na ocasi\u00e3o, foi apresentado o relat\u00f3rio t\u00e9cnico sobre a incid\u00eancia de Covid-19 na Capital cearense. Durante o encontro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-07T21:50:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-07T23:49:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido\",\"datePublished\":\"2020-05-07T21:50:11+00:00\",\"dateModified\":\"2020-05-07T23:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\"},\"wordCount\":348,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg\",\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\",\"name\":\"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg\",\"datePublished\":\"2020-05-07T21:50:11+00:00\",\"dateModified\":\"2020-05-07T23:49:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg\",\"width\":1199,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/","og_locale":"pt_BR","og_type":"article","og_title":"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O secret\u00e1rio da Sa\u00fade do Cear\u00e1, Carlos Roberto Martins Rodrigues Sobrinho (Dr. Cabeto), participou de uma coletiva de imprensa por meio de videoconfer\u00eancia realizada pela Secretaria Municipal da Sa\u00fade de Fortaleza (SMS) na manh\u00e3 desta quinta-feira (7). Na ocasi\u00e3o, foi apresentado o relat\u00f3rio t\u00e9cnico sobre a incid\u00eancia de Covid-19 na Capital cearense. Durante o encontro, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-05-07T21:50:11+00:00","article_modified_time":"2020-05-07T23:49:53+00:00","og_image":[{"url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido","datePublished":"2020-05-07T21:50:11+00:00","dateModified":"2020-05-07T23:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/"},"wordCount":348,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg","articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/","name":"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg","datePublished":"2020-05-07T21:50:11+00:00","dateModified":"2020-05-07T23:49:53+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/Coletiva_07.jpg","width":1199,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/07\/em-videoconferencia-com-jornalistas-secretario-da-saude-ressalta-importancia-de-isolamento-social-mais-rigido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Em videoconfer\u00eancia com jornalistas, secret\u00e1rio da Sa\u00fade ressalta import\u00e2ncia de isolamento social mais r\u00edgido"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=86329"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86329\/revisions"}],"predecessor-version":[{"id":86333,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86329\/revisions\/86333"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=86329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=86329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=86329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}