{"id":86246,"date":"2020-05-05T15:15:12","date_gmt":"2020-05-05T18:15:12","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=86246"},"modified":"2020-05-06T16:34:42","modified_gmt":"2020-05-06T19:34:42","slug":"idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/","title":{"rendered":"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86248\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png\" alt=\"\" width=\"1647\" height=\"814\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png 1647w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM-600x297.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM-768x380.png 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM-1200x593.png 1200w\" sizes=\"auto, (max-width: 1647px) 100vw, 1647px\" \/><\/p>\n<p>O distanciamento social \u00e9 a \u00fanica maneira efetiva de conter o avan\u00e7o r\u00e1pido do coronav\u00edrus. A recomenda\u00e7\u00e3o dos especialistas \u00e9 que a medida seja seguida \u00e0 risca por todos. Em especial, pelas pessoas acima de 60 anos, que fazem parte do grupo de risco. O psiquiatra Carlos Celso Serra Azul, que atua no Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM), da rede p\u00fablica da Secretaria da Sa\u00fade do Estado, do Governo do Cear\u00e1, afirma que os idosos devem ter uma aten\u00e7\u00e3o maior com a sa\u00fade mental neste per\u00edodo.<\/p>\n<p>De acordo com o psiquiatra, alguns idosos podem desenvolver transtornos mentais, principalmente aqueles relacionados \u00e0 ansiedade, estresse e depress\u00e3o. \u201cA vulnerabilidade social, a limita\u00e7\u00e3o da rotina e a dist\u00e2ncia dos familiares s\u00e3o alguns aspectos que tendem a alterar o estado emocional, afetando a sa\u00fade mental. Embora seja necess\u00e1ria nesse momento, a limita\u00e7\u00e3o da rotina do idoso pode desencadear algum transtorno\u201d, alerta.<\/p>\n<p>Para enfrentar este momento de maneira saud\u00e1vel, evitando problemas emocionais e ps\u00edquicos, a recomenda\u00e7\u00e3o \u00e9 que os idosos realizem o m\u00e1ximo de atividades dentro de casa. \u201cTem que ocupar o tempo e criar uma rotina com exerc\u00edcios f\u00edsicos, medita\u00e7\u00e3o, conversas por videoconfer\u00eancia com os familiares e com a realiza\u00e7\u00e3o de atividades que sejam prazerosas\u201d, completa.<\/p>\n<p>Al\u00e9m disso, \u00e9 fundamental manter uma alimenta\u00e7\u00e3o saud\u00e1vel e prezar por um sono reparador. Para os que usam medica\u00e7\u00e3o e fazem algum tipo de tratamento, a recomenda\u00e7\u00e3o \u00e9 dar continuidade \u00e0s orienta\u00e7\u00f5es m\u00e9dicas.<\/p>\n<h3>Mal de Alzheimer<\/h3>\n<p>Devido \u00e0 pandemia, os idosos com mal de Alzheimer podem apresentar algumas altera\u00e7\u00f5es comportamentais. A recomenda\u00e7\u00e3o para os cuidadores \u00e9 que mantenham a rotina de atividades dentro de casa. O Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM) est\u00e1 atendendo os casos mais graves na emerg\u00eancia da unidade, que funciona 24 horas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-86283 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner-1-saudemental.png\" alt=\"\" width=\"775\" height=\"1044\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner-1-saudemental.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner-1-saudemental-600x808.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner-1-saudemental-768x1035.png 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/banner-1-saudemental-170x230.png 170w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O distanciamento social \u00e9 a \u00fanica maneira efetiva de conter o avan\u00e7o r\u00e1pido do coronav\u00edrus. A recomenda\u00e7\u00e3o dos especialistas \u00e9 que a medida seja seguida \u00e0 risca por todos. Em especial, pelas pessoas acima de 60 anos, que fazem parte do grupo de risco. O psiquiatra Carlos Celso Serra Azul, que atua no Hospital de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":86248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1532,360],"class_list":["post-86246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-covid19","tag-saudemental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O distanciamento social \u00e9 a \u00fanica maneira efetiva de conter o avan\u00e7o r\u00e1pido do coronav\u00edrus. A recomenda\u00e7\u00e3o dos especialistas \u00e9 que a medida seja seguida \u00e0 risca por todos. Em especial, pelas pessoas acima de 60 anos, que fazem parte do grupo de risco. O psiquiatra Carlos Celso Serra Azul, que atua no Hospital de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T18:15:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-06T19:34:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1647\" \/>\n\t<meta property=\"og:image:height\" content=\"814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena\",\"datePublished\":\"2020-05-05T18:15:12+00:00\",\"dateModified\":\"2020-05-06T19:34:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png\",\"keywords\":[\"coronavirus\",\"covid19\",\"Sa\u00fadeMental\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\",\"name\":\"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png\",\"datePublished\":\"2020-05-05T18:15:12+00:00\",\"dateModified\":\"2020-05-06T19:34:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png\",\"width\":1647,\"height\":814},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/","og_locale":"pt_BR","og_type":"article","og_title":"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O distanciamento social \u00e9 a \u00fanica maneira efetiva de conter o avan\u00e7o r\u00e1pido do coronav\u00edrus. A recomenda\u00e7\u00e3o dos especialistas \u00e9 que a medida seja seguida \u00e0 risca por todos. Em especial, pelas pessoas acima de 60 anos, que fazem parte do grupo de risco. O psiquiatra Carlos Celso Serra Azul, que atua no Hospital de [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-05-05T18:15:12+00:00","article_modified_time":"2020-05-06T19:34:42+00:00","og_image":[{"width":1647,"height":814,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena","datePublished":"2020-05-05T18:15:12+00:00","dateModified":"2020-05-06T19:34:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/"},"wordCount":329,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png","keywords":["coronavirus","covid19","Sa\u00fadeMental"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/","name":"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png","datePublished":"2020-05-05T18:15:12+00:00","dateModified":"2020-05-06T19:34:42+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/05\/IDOSOS_HSM.png","width":1647,"height":814},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/05\/05\/idosos-devem-redobrar-cuidados-com-saude-mental-durante-quarentena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Idosos devem redobrar cuidados com sa\u00fade mental durante quarentena"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=86246"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86246\/revisions"}],"predecessor-version":[{"id":90281,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/86246\/revisions\/90281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/86248"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=86246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=86246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=86246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}