{"id":85944,"date":"2020-04-22T14:09:34","date_gmt":"2020-04-22T17:09:34","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=85944"},"modified":"2020-04-22T14:09:34","modified_gmt":"2020-04-22T17:09:34","slug":"pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/","title":{"rendered":"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85947\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Os cuidados com a higiene e o respeito ao isolamento social t\u00eam sido fundamentais para diminuir a transmiss\u00e3o da Covid-19. Quando um caso da doen\u00e7a \u00e9 confirmado, algumas atitudes devem ser tomadas em casa para evitar a dissemina\u00e7\u00e3o do v\u00edrus e preservar vidas. A infectologista do Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), Christianne Takeda, refor\u00e7a as orienta\u00e7\u00f5es para a popula\u00e7\u00e3o.<\/p>\n<p>Ao ser diagnosticada com o v\u00edrus e apresentar sintomas leves, a pessoa deve permanecer em casa por 14 dias em um quarto. \u00c9 necess\u00e1rio manter a porta fechada e as janelas abertas para facilitar a circula\u00e7\u00e3o de ar. M\u00f3veis e ma\u00e7anetas devem ser frequentemente limpos. Utens\u00edlios de uso pessoal, como toalhas de banho e talheres, ou m\u00f3veis, como sof\u00e1s e cadeiras, precisam ser separados, assim como o lixo produzido pelo paciente contaminado.<\/p>\n<h3>Cuidados em casa<\/h3>\n<p>Dentro de casa, o paciente precisa seguir \u00e0 risca algumas regras. O uso de m\u00e1scara \u00e9 obrigat\u00f3rio em todos os momentos. Ao utilizar o banheiro, \u00e9 necess\u00e1rio lavar as m\u00e3os com \u00e1gua e sab\u00e3o, al\u00e9m de sempre limpar vaso, pia e demais superf\u00edcies com \u00e1lcool ou \u00e1gua sanit\u00e1ria para a desinfec\u00e7\u00e3o do ambiente. Entretanto, segundo a m\u00e9dica, estar isolado socialmente n\u00e3o quer dizer ficar parado o tempo todo. \u201c\u00c9 importante o paciente se movi-mentar regularmente para evitar problemas como embolia pulmonar\u201d, aponta.<\/p>\n<p>Para pacientes lactantes, a infectologista refor\u00e7a a ado\u00e7\u00e3o de medidas constantes de higiene. \u201cAntes de amamentar, \u00e9 preciso sempre tomar banho e estar de m\u00e1scara o tempo todo, al\u00e9m de higienizar as m\u00e3os constantemente\u201d, aconselha.<\/p>\n<p>O per\u00edodo de isolamento deve ser respeitado n\u00e3o s\u00f3 pelo paciente, mas por todos da casa. Caso apare\u00e7am sintomas leves em outro familiar, o isolamento dever\u00e1 ser reiniciado. \u201cSe os sintomas se agravarem, ele deve procurar orienta\u00e7\u00e3o m\u00e9dica, informando o profissional sobre a situa\u00e7\u00e3o\u201d, complementa a m\u00e9dica.<\/p>\n<p>Christianne refor\u00e7a a import\u00e2ncia do engajamento da popula\u00e7\u00e3o no respeito ao isolamento social e no refor\u00e7o dos cuidados com a higiene. \u201cEsse conjunto de medidas faz a diferen\u00e7a no combate ao coronav\u00edrus\u201d, finaliza.<\/p>\n<h3>Canais de atendimento<\/h3>\n<p>Criado pelo Governo do Cear\u00e1, o Plant\u00e3o Coronav\u00edrus funciona 24 horas para tirar d\u00favidas e oferecer atendimento especializado \u00e0 popula\u00e7\u00e3o. Quem apresentar sintomas de Covid-19 pode enviar uma mensagem via WhatsApp para (85) 98439-0647 e buscar a orienta\u00e7\u00e3o. Tamb\u00e9m \u00e9 poss\u00edvel entrar em contato com o TeleSa\u00fade, ligando 0800 275 1475.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85948\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_info_isolamento_casa.png\" alt=\"\" width=\"775\" height=\"1876\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_info_isolamento_casa.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_info_isolamento_casa-600x1452.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_info_isolamento_casa-768x1859.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os cuidados com a higiene e o respeito ao isolamento social t\u00eam sido fundamentais para diminuir a transmiss\u00e3o da Covid-19. Quando um caso da doen\u00e7a \u00e9 confirmado, algumas atitudes devem ser tomadas em casa para evitar a dissemina\u00e7\u00e3o do v\u00edrus e preservar vidas. A infectologista do Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), Christianne Takeda, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":85947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1703,1532,697,1701],"class_list":["post-85944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-casa","tag-covid19","tag-cuidados","tag-isolamento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Os cuidados com a higiene e o respeito ao isolamento social t\u00eam sido fundamentais para diminuir a transmiss\u00e3o da Covid-19. Quando um caso da doen\u00e7a \u00e9 confirmado, algumas atitudes devem ser tomadas em casa para evitar a dissemina\u00e7\u00e3o do v\u00edrus e preservar vidas. A infectologista do Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), Christianne Takeda, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-22T17:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica\",\"datePublished\":\"2020-04-22T17:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\"},\"wordCount\":441,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png\",\"keywords\":[\"Casa\",\"covid19\",\"cuidados\",\"Isolamento\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\",\"name\":\"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png\",\"datePublished\":\"2020-04-22T17:09:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/","og_locale":"pt_BR","og_type":"article","og_title":"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Os cuidados com a higiene e o respeito ao isolamento social t\u00eam sido fundamentais para diminuir a transmiss\u00e3o da Covid-19. Quando um caso da doen\u00e7a \u00e9 confirmado, algumas atitudes devem ser tomadas em casa para evitar a dissemina\u00e7\u00e3o do v\u00edrus e preservar vidas. A infectologista do Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), Christianne Takeda, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-04-22T17:09:34+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica","datePublished":"2020-04-22T17:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/"},"wordCount":441,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png","keywords":["Casa","covid19","cuidados","Isolamento"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/","name":"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png","datePublished":"2020-04-22T17:09:34+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_site_isolamento_casa.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/22\/pessoas-diagnosticadas-com-doenca-devem-manter-isolamento-domiciliar-conforme-orientacao-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Pessoas diagnosticadas com doen\u00e7a devem manter isolamento domiciliar, conforme orienta\u00e7\u00e3o m\u00e9dica"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=85944"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85944\/revisions"}],"predecessor-version":[{"id":85950,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85944\/revisions\/85950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/85947"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=85944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=85944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=85944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}