{"id":85909,"date":"2020-04-21T11:28:17","date_gmt":"2020-04-21T14:28:17","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=85909"},"modified":"2020-04-22T16:04:52","modified_gmt":"2020-04-22T19:04:52","slug":"pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/","title":{"rendered":"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85910\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png\" alt=\"\" width=\"775\" height=\"511\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus-600x396.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus-768x506.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Pessoas com doen\u00e7as cardiovasculares est\u00e3o entre os grupos mais suscet\u00edveis a com-plica\u00e7\u00f5es relacionadas ao coronav\u00edrus (Covid-19). Geralmente, pacientes com doen\u00e7as cr\u00f4nicas, como os que possuem problemas no cora\u00e7\u00e3o, apresentam um sistema imunol\u00f3gico mais fragilizado.<\/p>\n<p>\u201cHipertens\u00e3o arterial, diabetes e doen\u00e7as cardiovasculares em geral s\u00e3o as comorbidades mais prevalentes entre as pessoas v\u00edtimas do coronav\u00edrus. N\u00e3o se sabe exatamente o porqu\u00ea desse achado, por\u00e9m pode-se explicar por serem popula\u00e7\u00f5es mais idosas, por apresentarem defici\u00eancias no sistema imunol\u00f3gico causado pelas pr\u00f3prias doen\u00e7as de base ou pela predisposi\u00e7\u00e3o pr\u00f3pria desses indiv\u00edduos\u201d, explica a cardiologista Danielli Lino, do Hospital de Messejana Dr. Carlos Alberto Studart Gomes (HM).<\/p>\n<p>Refer\u00eancia no tratamento de doen\u00e7as cardiopulmonares, o hospital do Governo do Cear\u00e1 estabeleceu fluxos diferenciados para o atendimento dos pacientes com suspeita de Covid-19 ou s\u00edndrome gripal. \u201cN\u00f3s sabemos que essas doen\u00e7as t\u00eam uma alta transmissibilidade. Por isso, \u00e9 indispens\u00e1vel o estabelecimento de fluxos diferenciados de atendimento. O objetivo \u00e9 n\u00e3o oferecer risco de contamina\u00e7\u00e3o aos pacientes cardiopatas ou com doen\u00e7as pulmonares que procurarem a unidade para atendimento de suas doen\u00e7as de base\u201d, explica o coordenador da emerg\u00eancia do Hospital, Breno Dantas.<\/p>\n<h3>Preven\u00e7\u00e3o<\/h3>\n<p>De acordo com a cardiologista Danielli Lino, \u00e9 importante que os pacientes com cardiopatias mantenham as doen\u00e7as de base controladas e as vacinas em dia. As mais importantes, neste momento, s\u00e3o a da gripe e a da pneumonia, mesmo que n\u00e3o protejam especificamente contra a Covid-19.<\/p>\n<p>\u201cOs pacientes cardiopatas devem ter aten\u00e7\u00e3o especial com seus tratamentos, seguir corretamente a prescri\u00e7\u00e3o m\u00e9dica e os cuidados com suas doen\u00e7as de base. Neste per\u00edodo de quarentena tamb\u00e9m \u00e9 importante n\u00e3o descuidar da alimenta\u00e7\u00e3o, ter um sono adequado, tentar na medida do poss\u00edvel praticar alguma atividade f\u00edsica em casa e sem d\u00favidas cuidar da sa\u00fade mental\u201d, orienta.<\/p>\n<p>Al\u00e9m disso, \u00e9 necess\u00e1rio tomar os cuidados gerais, como limpeza frequente das m\u00e3os com \u00e1gua e sab\u00e3o ou \u00e1lcool a 70%, evitar levar as m\u00e3os sujas aos olhos, nariz e boca, limpar e desinfectar objetos frequentemente, manter o ambiente arejado, evitar locais com muitas pessoas, al\u00e9m de cobrir boca e nariz ao tossir ou espirrar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85912\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_info_HM_cardio_coronavirus.png\" alt=\"\" width=\"775\" height=\"1098\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_info_HM_cardio_coronavirus.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_info_HM_cardio_coronavirus-600x850.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_info_HM_cardio_coronavirus-768x1088.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<h3>Quando procurar assist\u00eancia<\/h3>\n<p>Quando os pacientes do grupo de risco apresentam sintomas de Covid-19 ou de s\u00edndrome gripal, como febre persistente, tosse ou falta de ar, o recomendado \u00e9 procurar uma assist\u00eancia m\u00e9dica para avalia\u00e7\u00e3o e prescri\u00e7\u00e3o de medica\u00e7\u00f5es espec\u00edficas. O diagn\u00f3stico precoce e o tratamento correto podem ajudar o paciente a n\u00e3o desenvolver a fase mais severa das doen\u00e7as. Em caso da manifesta\u00e7\u00e3o de sintomas relacionados \u00e0s doen\u00e7as de base, o paciente tamb\u00e9m deve procurar um servi\u00e7o de sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pessoas com doen\u00e7as cardiovasculares est\u00e3o entre os grupos mais suscet\u00edveis a com-plica\u00e7\u00f5es relacionadas ao coronav\u00edrus (Covid-19). Geralmente, pacientes com doen\u00e7as cr\u00f4nicas, como os que possuem problemas no cora\u00e7\u00e3o, apresentam um sistema imunol\u00f3gico mais fragilizado. \u201cHipertens\u00e3o arterial, diabetes e doen\u00e7as cardiovasculares em geral s\u00e3o as comorbidades mais prevalentes entre as pessoas v\u00edtimas do coronav\u00edrus. N\u00e3o se [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":85910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1532,1700],"class_list":["post-85909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-covid19","tag-doencascronicas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Pessoas com doen\u00e7as cardiovasculares est\u00e3o entre os grupos mais suscet\u00edveis a com-plica\u00e7\u00f5es relacionadas ao coronav\u00edrus (Covid-19). Geralmente, pacientes com doen\u00e7as cr\u00f4nicas, como os que possuem problemas no cora\u00e7\u00e3o, apresentam um sistema imunol\u00f3gico mais fragilizado. \u201cHipertens\u00e3o arterial, diabetes e doen\u00e7as cardiovasculares em geral s\u00e3o as comorbidades mais prevalentes entre as pessoas v\u00edtimas do coronav\u00edrus. N\u00e3o se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T14:28:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-22T19:04:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia\",\"datePublished\":\"2020-04-21T14:28:17+00:00\",\"dateModified\":\"2020-04-22T19:04:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\"},\"wordCount\":502,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png\",\"keywords\":[\"coronavirus\",\"covid19\",\"DoencasCr\u00f4nicas\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\",\"name\":\"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png\",\"datePublished\":\"2020-04-21T14:28:17+00:00\",\"dateModified\":\"2020-04-22T19:04:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png\",\"width\":775,\"height\":511},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/","og_locale":"pt_BR","og_type":"article","og_title":"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Pessoas com doen\u00e7as cardiovasculares est\u00e3o entre os grupos mais suscet\u00edveis a com-plica\u00e7\u00f5es relacionadas ao coronav\u00edrus (Covid-19). Geralmente, pacientes com doen\u00e7as cr\u00f4nicas, como os que possuem problemas no cora\u00e7\u00e3o, apresentam um sistema imunol\u00f3gico mais fragilizado. \u201cHipertens\u00e3o arterial, diabetes e doen\u00e7as cardiovasculares em geral s\u00e3o as comorbidades mais prevalentes entre as pessoas v\u00edtimas do coronav\u00edrus. N\u00e3o se [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-04-21T14:28:17+00:00","article_modified_time":"2020-04-22T19:04:52+00:00","og_image":[{"width":775,"height":511,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia","datePublished":"2020-04-21T14:28:17+00:00","dateModified":"2020-04-22T19:04:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/"},"wordCount":502,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png","keywords":["coronavirus","covid19","DoencasCr\u00f4nicas"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/","name":"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png","datePublished":"2020-04-21T14:28:17+00:00","dateModified":"2020-04-22T19:04:52+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_CB_HSM_cardio_coronavirus.png","width":775,"height":511},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/21\/pacientes-com-doencas-cardiovasculares-devem-reforcar-prevencao-durante-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Pacientes com doen\u00e7as cardiovasculares devem refor\u00e7ar preven\u00e7\u00e3o durante pandemia"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=85909"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85909\/revisions"}],"predecessor-version":[{"id":85953,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85909\/revisions\/85953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/85910"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=85909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=85909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=85909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}