{"id":85751,"date":"2020-04-15T18:26:57","date_gmt":"2020-04-15T21:26:57","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=85751"},"modified":"2020-04-16T11:44:20","modified_gmt":"2020-04-16T14:44:20","slug":"isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/","title":{"rendered":"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85753\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Enquanto milhares de pessoas podem permanecer em casa e trabalhar no conforto do lar, os profissionais de sa\u00fade atuam, diariamente, no enfrentamento ao coronav\u00edrus (Covid-19). S\u00e3o homens e mulheres que t\u00eam a miss\u00e3o de combater a doen\u00e7a e, principalmente, salvar vidas em meio a uma rotina intensa e desafiadora.<\/p>\n<p>Joana (nome fict\u00edcio) \u00e9 t\u00e9cnica de enfermagem e colaboradora do Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), unidade do Governo do Cear\u00e1. Mesmo com anos de experi\u00eancia, ela conta que n\u00e3o tem sido f\u00e1cil lidar com a pandemia. \u201cEu estava me sentindo insegura. Estava muito ansiosa, indo trabalhar muito preocupada, e isso estava me desgastando\u201d, afirmou.<\/p>\n<p>Para cuidar da sa\u00fade mental dos profissionais da \u00e1rea da sa\u00fade neste momento de d\u00favidas e incertezas, os dez hospitais da rede estadual disponibilizam aos profissionais atendimento psicol\u00f3gico de forma presencial e online.<\/p>\n<p>Joana aproveitou a oportunidade para fazer um acompanhamento regular no HSJ. \u201cComo o atendimento \u00e9 por livre demanda, pude ver um hor\u00e1rio para mim e elas [psic\u00f3logas] me ouviram, me ajudaram. Isso faz com que a gente se sinta melhor\u201d, definiu.<\/p>\n<p>A coordenadora do servi\u00e7o de psicologia do Hospital de Messejana Dr. Carlos Alberto Studart Gomes (HM), M\u00e1rcia Lima, ressalta que a escuta \u00e9 uma maneira de acolher os profissionais em momentos de tens\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-85754 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_2.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_2.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_2-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_2-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>\u201cA situa\u00e7\u00e3o atual \u00e9 de muito estresse f\u00edsico e mental. De modo geral, os profissionais sabem lidar com o adoecimento, mas nessa pandemia \u00e9 tudo muito r\u00e1pido e desconhecido. Al\u00e9m do cansa\u00e7o f\u00edsico, os profissionais tamb\u00e9m t\u00eam consci\u00eancia da vulnerabilidade a que est\u00e3o submetidos ao cuidar dos pacientes contaminados. Queremos colaborar e dizer para eles que estamos juntos nessa batalha\u201d, explica.<\/p>\n<h3>Isolamento Social<\/h3>\n<p>Ao respeitar o isolamento social, a popula\u00e7\u00e3o contribui para amenizar a dissemina\u00e7\u00e3o do coronav\u00edrus e facilita o trabalho dos profissionais de sa\u00fade. A diminui\u00e7\u00e3o do n\u00famero de casos faz com que as unidades n\u00e3o fiquem sobrecarregadas. Com isso, as equipes podem oferecer um atendimento cada vez melhor aos pacientes.<\/p>\n<p>\u201cA medida \u00e9 bastante importante, pois evita a transmiss\u00e3o comunit\u00e1ria, ajudando no trabalho dos hospitais e evitando a exposi\u00e7\u00e3o dos profissionais ao v\u00edrus. Isso ameniza a exaust\u00e3o de quem est\u00e1 na linha de frente\u201d, afirma a fisioterapeuta do Hospital Regional Norte (HRN), em Sobral, Nayara Caroline Ribeiro.<\/p>\n<h3>Medidas de seguran\u00e7a<\/h3>\n<p>Os hospitais da rede estadual investem em a\u00e7\u00f5es permanentes de capacita\u00e7\u00e3o e cuidado com o colaborador. Os profissionais das unidades que fazem parte dos grupos considerados de risco s\u00e3o afastados das atividades de assist\u00eancia aos pacientes. A aten\u00e7\u00e3o especial tem sido dada a idosos a partir de 60 anos, pessoas que nasceram com algum tipo de defici\u00eancia imunol\u00f3gica, al\u00e9m de gr\u00e1vidas e lactantes.<\/p>\n<p>\u201cO afastamento de trabalhadores do grupo de risco \u00e9 importante para garantir a seguran\u00e7a e proteg\u00ea-los da possibilidade de uma contamina\u00e7\u00e3o\u201d, ressalta a coordenadora de Recursos Humanos do HRN, Emanuela Carneiro Tabosa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85755\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/rodap\u00e9_saude_de_todos_missao_cada_um2.png\" alt=\"\" width=\"775\" height=\"235\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/rodap\u00e9_saude_de_todos_missao_cada_um2.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/rodap\u00e9_saude_de_todos_missao_cada_um2-600x182.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/rodap\u00e9_saude_de_todos_missao_cada_um2-768x233.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto milhares de pessoas podem permanecer em casa e trabalhar no conforto do lar, os profissionais de sa\u00fade atuam, diariamente, no enfrentamento ao coronav\u00edrus (Covid-19). S\u00e3o homens e mulheres que t\u00eam a miss\u00e3o de combater a doen\u00e7a e, principalmente, salvar vidas em meio a uma rotina intensa e desafiadora. Joana (nome fict\u00edcio) \u00e9 t\u00e9cnica de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":85753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1681,1506],"class_list":["post-85751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-coronavirus","tag-isolamentosocial","tag-profissionaisdasaude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Enquanto milhares de pessoas podem permanecer em casa e trabalhar no conforto do lar, os profissionais de sa\u00fade atuam, diariamente, no enfrentamento ao coronav\u00edrus (Covid-19). S\u00e3o homens e mulheres que t\u00eam a miss\u00e3o de combater a doen\u00e7a e, principalmente, salvar vidas em meio a uma rotina intensa e desafiadora. Joana (nome fict\u00edcio) \u00e9 t\u00e9cnica de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T21:26:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-16T14:44:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais\",\"datePublished\":\"2020-04-15T21:26:57+00:00\",\"dateModified\":\"2020-04-16T14:44:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\"},\"wordCount\":532,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png\",\"keywords\":[\"coronavirus\",\"isolamentosocial\",\"profissionaisdasa\u00fade\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\",\"name\":\"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png\",\"datePublished\":\"2020-04-15T21:26:57+00:00\",\"dateModified\":\"2020-04-16T14:44:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/","og_locale":"pt_BR","og_type":"article","og_title":"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Enquanto milhares de pessoas podem permanecer em casa e trabalhar no conforto do lar, os profissionais de sa\u00fade atuam, diariamente, no enfrentamento ao coronav\u00edrus (Covid-19). S\u00e3o homens e mulheres que t\u00eam a miss\u00e3o de combater a doen\u00e7a e, principalmente, salvar vidas em meio a uma rotina intensa e desafiadora. Joana (nome fict\u00edcio) \u00e9 t\u00e9cnica de [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-04-15T21:26:57+00:00","article_modified_time":"2020-04-16T14:44:20+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais","datePublished":"2020-04-15T21:26:57+00:00","dateModified":"2020-04-16T14:44:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/"},"wordCount":532,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png","keywords":["coronavirus","isolamentosocial","profissionaisdasa\u00fade"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/","name":"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png","datePublished":"2020-04-15T21:26:57+00:00","dateModified":"2020-04-16T14:44:20+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_saude_de_todos_missao_cada_um_2_1.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/isolamento-social-diminui-sobrecarga-de-unidades-de-saude-e-facilita-trabalho-de-profissionais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Isolamento social diminui sobrecarga de unidades de sa\u00fade e facilita trabalho de profissionais"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=85751"}],"version-history":[{"count":12,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85751\/revisions"}],"predecessor-version":[{"id":85784,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85751\/revisions\/85784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/85753"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=85751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=85751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=85751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}