{"id":85735,"date":"2020-04-15T16:34:11","date_gmt":"2020-04-15T19:34:11","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=85735"},"modified":"2020-04-16T09:16:07","modified_gmt":"2020-04-16T12:16:07","slug":"recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/","title":{"rendered":"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar"},"content":{"rendered":"<p>Desde que os primeiros casos de coronav\u00edrus foram confirmados no Cear\u00e1, as medidas adotadas no enfrentamento \u00e0 doen\u00e7a t\u00eam objetivos claros: evitar a propaga\u00e7\u00e3o acelerada do v\u00edrus e assegurar o atendimento nos servi\u00e7os de sa\u00fade. Atualmente, o Cear\u00e1 n\u00e3o registra casos de cura, mas de pessoas em recupera\u00e7\u00e3o. De 413 pacientes internados em todo o Estado por Covid-19, 88 receberam alta, at\u00e9 14 de abril.<\/p>\n<p>O empres\u00e1rio Newton Cavalcante de Castro, 66, que recebeu alta ap\u00f3s 16 dias de interna\u00e7\u00e3o, apesar de sofrer com problemas pulmonares, n\u00e3o necessitou de UTI . \u201cAinda tenho medo, por isso estou mantendo dist\u00e2ncia das pessoas em casa e usando m\u00e1scara. Mas o m\u00e9dico me disse que eu estava bem\u201d, afirmou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-85737\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png\" alt=\"\" width=\"775\" height=\"497\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19-600x385.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19-768x493.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Ele conta ainda que antes de ser internado estava seguindo todas as recomenda\u00e7\u00f5es. Estava em quarentena em casa. &#8220;Fiz uma sa\u00edda com meu filho at\u00e9 um shopping e fui medir minha press\u00e3o. Um homem espirrou bem perto de mim. Dias depois a febre come\u00e7ou, com muita tosse, foram seis dias assim at\u00e9 que fui para UPA do Bairro Edson Queiroz e de l\u00e1 transferido para o Hospital Leonardo da Vinci\u201d, comenta.<\/p>\n<h3>Recupera\u00e7\u00e3o<\/h3>\n<p>O processo de recupera\u00e7\u00e3o dos pacientes acontece de duas formas, segundo o infectologista Keny Colares, do Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), do Governo do Estado.<\/p>\n<p>A primeira, a \u201ccura cl\u00ednica\u201d, ocorre quando n\u00e3o h\u00e1 mais sintomas da doen\u00e7a. J\u00e1 a \u201ccura microbiol\u00f3gica\u201d significa que organismo eliminou totalmente o v\u00edrus, algo que pode demorar mais para acontecer. \u201cIsso varia muito de pessoa para pessoa. Aparentemente, os pacientes levam algum tempo eliminando o v\u00edrus, principalmente se compararmos casos leves e graves\u201d, explica.<\/p>\n<p>Os casos leves s\u00e3o aqueles que podem permanecer em casa. Normalmente o paciente \u00e9 orientado a permanecer isolado em um c\u00f4modo dentro de casa, sem manter contato com a fam\u00edlia. Saindo deste c\u00f4modo apenas em caso de necessidade e usando m\u00e1scara para proteger os demais moradores da resid\u00eancia. Mas nunca saindo de casa. Nestes casos, conforme o infectologista, o mais comum \u00e9 que o v\u00edrus permane\u00e7a presente por 14 dias a partir do come\u00e7o dos sintomas.<\/p>\n<p>\u201cQuando n\u00e3o mais houver sintomas, tiver pelo menos tr\u00eas dias sem febre ou sintomas respirat\u00f3rios (como tosse), \u00e9 poss\u00edvel dizer que ele esteja curado. \u00c9 importante ressaltar que a tosse pode ficar com o paciente por uns dias, mas ela n\u00e3o pode ser forte, nem causar inc\u00f4modos. E isso para casos leves e com acompanhamento m\u00e9dico\u201d, diz Keny.<\/p>\n<p>O m\u00e9dico explica ainda que a realidade para casos graves \u00e9 outra. \u201cCada paciente tem sua pr\u00f3pria avalia\u00e7\u00e3o m\u00e9dica em casos graves. Alguns levam mais tempo que outros para se recuperar\u201d, disse.Algumas interna\u00e7\u00f5es levam um dia, outras duas semanas. Alguns pacientes chegam a necessitar de UTI, mas tudo sob o olhar atento da equipe m\u00e9dica que avalia as necessidades de cada paciente.<\/p>\n<p>\u201cA alta hospitalar pode significar apenas que ele n\u00e3o precisa mais de interna\u00e7\u00e3o. Ent\u00e3o ele vai passar a ter o isolamento domiciliar, como ocorre nos casos leves, at\u00e9 eliminar o v\u00edrus completamente\u201d, comenta o infectologista.<\/p>\n<h3>Casos assintom\u00e1ticos<\/h3>\n<p>Uma quest\u00e3o preocupante s\u00e3o o registro de casos assintom\u00e1ticos. Ou seja, pessoas que t\u00eam o v\u00edrus, mas n\u00e3o apresentam sintomas, fazendo com que nem mesmo saibam que est\u00e3o doentes. \u201cA propor\u00e7\u00e3o da quantidade dessas pessoas ainda n\u00e3o \u00e9 clara. Imagina-se que ela tamb\u00e9m possa transmitir, mas ainda n\u00e3o se sabe o alcance disso. Esse \u00e9 um dos motivos que tornam o distanciamento social t\u00e3o importante. Na verdade, fundamental. Ele dificulta a transmiss\u00e3o, n\u00e3o importa se o transmissor \u00e9 um caso leve, grave ou assintom\u00e1tico. E mesmo ap\u00f3s a cura, todos eles devem seguir essa recomenda\u00e7\u00e3o\u201d, disse Keny Colares.<\/p>\n<h3>Isolamento social<\/h3>\n<p>O infectologista faz um alerta para a popula\u00e7\u00e3o. \u201cEstamos nos dedicando profundamente. Queremos muito ver todos bem, e os doentes se curarem. Mas se a popula\u00e7\u00e3o n\u00e3o fizer sua parte, pode se tornar um esfor\u00e7o em v\u00e3o\u201d, destacou.<\/p>\n<p>Newton refor\u00e7a a mensagem do m\u00e9dico. \u201cGra\u00e7as a Deus e a equipe m\u00e9dica, estou bem. Quero dizer para as pessoas que ainda est\u00e3o saindo de casa, se descuidando, que respeite as outras pessoas. A vida dos outros tem de ser respeitada sempre. Fique em casa. Sinto que o problema s\u00f3 est\u00e1 come\u00e7ando e temos de ter muito cuidado se n\u00e3o quisermos perder quem a gente ama\u201d, diz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que os primeiros casos de coronav\u00edrus foram confirmados no Cear\u00e1, as medidas adotadas no enfrentamento \u00e0 doen\u00e7a t\u00eam objetivos claros: evitar a propaga\u00e7\u00e3o acelerada do v\u00edrus e assegurar o atendimento nos servi\u00e7os de sa\u00fade. Atualmente, o Cear\u00e1 n\u00e3o registra casos de cura, mas de pessoas em recupera\u00e7\u00e3o. De 413 pacientes internados em todo o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1531],"tags":[1476,1532,1446],"class_list":["post-85735","post","type-post","status-publish","format-standard","hentry","category-covid-19","tag-coronavirus","tag-covid19","tag-cura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Desde que os primeiros casos de coronav\u00edrus foram confirmados no Cear\u00e1, as medidas adotadas no enfrentamento \u00e0 doen\u00e7a t\u00eam objetivos claros: evitar a propaga\u00e7\u00e3o acelerada do v\u00edrus e assegurar o atendimento nos servi\u00e7os de sa\u00fade. Atualmente, o Cear\u00e1 n\u00e3o registra casos de cura, mas de pessoas em recupera\u00e7\u00e3o. De 413 pacientes internados em todo o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T19:34:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-16T12:16:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar\",\"datePublished\":\"2020-04-15T19:34:11+00:00\",\"dateModified\":\"2020-04-16T12:16:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\"},\"wordCount\":790,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png\",\"keywords\":[\"coronavirus\",\"covid19\",\"cura\"],\"articleSection\":[\"Covid-19\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\",\"name\":\"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png\",\"datePublished\":\"2020-04-15T19:34:11+00:00\",\"dateModified\":\"2020-04-16T12:16:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png\",\"width\":775,\"height\":497},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/","og_locale":"pt_BR","og_type":"article","og_title":"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Desde que os primeiros casos de coronav\u00edrus foram confirmados no Cear\u00e1, as medidas adotadas no enfrentamento \u00e0 doen\u00e7a t\u00eam objetivos claros: evitar a propaga\u00e7\u00e3o acelerada do v\u00edrus e assegurar o atendimento nos servi\u00e7os de sa\u00fade. Atualmente, o Cear\u00e1 n\u00e3o registra casos de cura, mas de pessoas em recupera\u00e7\u00e3o. De 413 pacientes internados em todo o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2020-04-15T19:34:11+00:00","article_modified_time":"2020-04-16T12:16:07+00:00","og_image":[{"url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar","datePublished":"2020-04-15T19:34:11+00:00","dateModified":"2020-04-16T12:16:07+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/"},"wordCount":790,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png","keywords":["coronavirus","covid19","cura"],"articleSection":["Covid-19"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/","name":"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png","datePublished":"2020-04-15T19:34:11+00:00","dateModified":"2020-04-16T12:16:07+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2020\/04\/banner_alta_paciente_covid_19.png","width":775,"height":497},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2020\/04\/15\/recuperacao-de-pacientes-com-covid-19-continua-apos-alta-hospitalar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Recupera\u00e7\u00e3o de pacientes com Covid-19 continua ap\u00f3s alta hospitalar"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=85735"}],"version-history":[{"count":8,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85735\/revisions"}],"predecessor-version":[{"id":85775,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/85735\/revisions\/85775"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=85735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=85735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=85735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}