{"id":835,"date":"2010-11-24T20:34:24","date_gmt":"2010-11-24T23:34:24","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/"},"modified":"2010-11-24T20:34:24","modified_gmt":"2010-11-24T23:34:24","slug":"inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/","title":{"rendered":"In\u00e1cio Arruda destaca no Senado trabalho realizado  na sa\u00fade do Cear\u00e1"},"content":{"rendered":"<p> \u201cO Cariri \u00e9 uma regi\u00e3o imensa do Nordeste brasileiro porque inclui o Cear\u00e1, a Para\u00edba, uma ponta do Piau\u00ed e uma parte significativa do Estado de Pernambuco. Essa regi\u00e3o inteira, que no centro ficam os munic\u00edpios de Juazeiro, Crato e Barbalha, com mais de 1 milh\u00e3o e meio de habitantes n\u00e3o tinha um hospital p\u00fablico de alta complexidade\u201d. O senador In\u00e1cio Arruda deu essa informa\u00e7\u00e3o em pronunciamento feito na \u00faltima ter\u00e7a-feira, 23, no Senado, em Bras\u00edlia, para mostrar a import\u00e2ncia do Hospital Regional do Cariri no aceso e melhoria do atendimento especializado \u00e0 popula\u00e7\u00e3o na pr\u00f3pria regi\u00e3o, que ser\u00e1 inaugurado no pr\u00f3ximo dia 10 de dezembro pelo governador Cid Gomes e o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, com a presen\u00e7a do presidente Luis In\u00e1cio Lula da Silva. O HRC fica estrategicamente localizado entre Juazeiro, Crato e Barbalha para facilitar o acesso aos pacientes de toda a regi\u00e3o.<\/p>\n<p> A constru\u00e7\u00e3o do Hospital Regional do Cariri, observa In\u00e1cio Arruda no seu pronunciamento, \u201c\u00e9 o esfor\u00e7o que destaco do governador do Estado , que, na sua campanha, em 2006, anunciou que iria construir dois hospitais, um na regi\u00e3o do Cariri e outro na regi\u00e3o Norte\u201d. Em Sobral, o HRN deve ser conclu\u00eddo em meados do pr\u00f3ximo ano. O senador fala de esfor\u00e7o, conforme frisa no pronunciamento, devido as dificuldades de recursos financeiros: \u201cH\u00e1 uma cantinela seguida no nosso pa\u00eds de conten\u00e7\u00e3o de gastos, de corte de gastos. Onde ser\u00e3o realizados os cortes? Os cortes s\u00e3o feitos para geralmente beneficiar os mesmos de sempre, os grandes banqueiros e investidores\u201d. Mesmo com as dificuldades, o Hospital Regional do Cariri foi constru\u00eddo. In\u00e1cio Arruda afirmou&nbsp; no seu pronunciamento que \u201ctrabalhei intensamente para a libera\u00e7\u00e3o de recursos federais, como coordenador da bancada na \u00e9poca para garantir o sucesso do que agora estamos vendo, que \u00e9 a inaugura\u00e7\u00e3o dessa grande unidade hospitalar\u201d. O HRC tem 294. Far\u00e1 atendimento de urg\u00eancia e emerg\u00eancia e realiza\u00e7\u00e3o de servi\u00e7os e exames de m\u00e9dia e alta complexidade.<\/p>\n<p> O senador disse tamb\u00e9m que nesse \u201cesfor\u00e7o \u00e9 preciso agregar dois grandes profissionais da \u00e1rea de sa\u00fade no Estado, o deputado estadual Jo\u00e3o Ananias, eleito deputado federal, e o secret\u00e1rio da sa\u00fade, Arruda Bastos\u201d. No pronunciamento In\u00e1cio Arruda disse:&nbsp; \u201cesses dois homens est\u00e3o trabalhando de m\u00e3os dadas com o Governador do Estado n\u00e3o s\u00f3 para a&nbsp; constru\u00e7\u00e3o do hospital do Cariri e da regi\u00e3o Norte. Trabalham para estender a rede de assist\u00eancia \u00e0 sa\u00fade da popula\u00e7\u00e3o em todo o nosso Estado\u201d. E citou os trabalhos dos dois, destacando as 21 policl\u00ednicas regionais, que no Cear\u00e1 n\u00e3o est\u00e3o apenas nas propostas como saiu no debate nacional. No Cear\u00e1, tr\u00eas policl\u00ednicas regionais j\u00e1 foram inauguradas e 18 est\u00e3o em constru\u00e7\u00e3o. Falou tamb\u00e9m dos 17 Centros de Especialidades Odontol\u00f3gicas regionais, ampliando o acesso a servi\u00e7os especializados em sa\u00fade bucal e das 33 Unidades de Pronto Atendimento (UPAs 24 horas) que funcionar\u00e3o no Cear\u00e1. Quatro est\u00e3o com as obras quase prontas.<\/p>\n<p> Ao mesmo tempo em que constru\u00edam as novas unidades de sa\u00fade, Arruda Bastos e Jo\u00e3o Ananias, observa o senador no pronunciamento feito na \u00faltima ter\u00e7a-feira no Senado, desenvolviam no debate permanente com profissionais e gestores e entidades da sa\u00fade uma nova estrat\u00e9gia de gest\u00e3o para fortalecer a regionaliza\u00e7\u00e3o. Respaldado legalmente, criaram os cons\u00f3rcios p\u00fablicos de sa\u00fade. S\u00e3o o modelo de gest\u00e3o das policl\u00ednicas e CEOs regionais constru\u00eddos pelo Governo do Estado.<\/p>\n<p> O senador concluiu o pronunciamento dizendo que \u201ca sa\u00fade p\u00fablica do Cear\u00e1 nunca esteve nas m\u00e3os de pessoas t\u00e3o comprometidas com o Sistema \u00danico de Sa\u00fade em nosso pa\u00eds\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO Cariri \u00e9 uma regi\u00e3o imensa do Nordeste brasileiro porque inclui o Cear\u00e1, a Para\u00edba, uma ponta do Piau\u00ed e uma parte significativa do Estado de Pernambuco. Essa regi\u00e3o inteira, que no centro ficam os munic\u00edpios de Juazeiro, Crato e Barbalha, com mais de 1 milh\u00e3o e meio de habitantes n\u00e3o tinha um hospital p\u00fablico [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-835","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"\u201cO Cariri \u00e9 uma regi\u00e3o imensa do Nordeste brasileiro porque inclui o Cear\u00e1, a Para\u00edba, uma ponta do Piau\u00ed e uma parte significativa do Estado de Pernambuco. Essa regi\u00e3o inteira, que no centro ficam os munic\u00edpios de Juazeiro, Crato e Barbalha, com mais de 1 milh\u00e3o e meio de habitantes n\u00e3o tinha um hospital p\u00fablico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-24T23:34:24+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1\",\"datePublished\":\"2010-11-24T23:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\"},\"wordCount\":674,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\",\"name\":\"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-11-24T23:34:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/","og_locale":"pt_BR","og_type":"article","og_title":"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"\u201cO Cariri \u00e9 uma regi\u00e3o imensa do Nordeste brasileiro porque inclui o Cear\u00e1, a Para\u00edba, uma ponta do Piau\u00ed e uma parte significativa do Estado de Pernambuco. Essa regi\u00e3o inteira, que no centro ficam os munic\u00edpios de Juazeiro, Crato e Barbalha, com mais de 1 milh\u00e3o e meio de habitantes n\u00e3o tinha um hospital p\u00fablico [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-11-24T23:34:24+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1","datePublished":"2010-11-24T23:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/"},"wordCount":674,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/","name":"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-11-24T23:34:24+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/11\/24\/inacio-arruda-destaca-no-senado-trabalho-realizado-na-saude-do-ceara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"In\u00e1cio Arruda destaca no Senado trabalho realizado na sa\u00fade do Cear\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=835"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/835\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}