{"id":82853,"date":"2019-12-23T16:23:22","date_gmt":"2019-12-23T19:23:22","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=82853"},"modified":"2019-12-23T16:25:53","modified_gmt":"2019-12-23T19:25:53","slug":"especialista-orienta-como-aproveitar-as-ceias-com-saude","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/","title":{"rendered":"Especialista orienta como aproveitar as ceias com sa\u00fade"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-82854 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png\" alt=\"\" width=\"775\" height=\"486\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG-768x482.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>O fim de ano \u00e9 um per\u00edodo marcado por confraterniza\u00e7\u00f5es e muitas ceias. Por\u00e9m, se n\u00e3o forem tomados os devidos cuidados, as festas podem ser verdadeiras armadilhas. Para aproveitar as celebra\u00e7\u00f5es, a nutricionista do Centro de Sa\u00fade Meireles, da rede p\u00fablica do Governo do Cear\u00e1, Rochele Riquet, orienta sobre os principais alimentos consumidos nas ceias e como comer sem culpa e preju\u00edzos para a sa\u00fade.<\/p>\n<p>Para entrar no clima das festas, a especialista enfatiza que \u00e9 ben\u00e9fico pensar em uma alimenta\u00e7\u00e3o mais equilibrada e saud\u00e1vel nesse per\u00edodo do ano. As dicas valem para quem quer aproveitar as ceias sem consumir alimentos gordurosos e cal\u00f3ricos.<\/p>\n<p>\u201cCom certeza frutas, legumes e verduras merecem um espa\u00e7o no card\u00e1pio nessas ocasi\u00f5es. Outro erro comum relacionado \u00e0 alimenta\u00e7\u00e3o neste per\u00edodo \u00e9 o jejum. \u00c9 importante n\u00e3o pular as refei\u00e7\u00f5es nos dias de festas. O ideal \u00e9 fazer refei\u00e7\u00f5es leves e n\u00e3o ficar muito tempo sem se alimentar. Durante o dia \u00e9 fundamental hidratar-se ingerindo bastante \u00e1gua\u201d, afirma Rochele Riquet.<\/p>\n<p>A nutricionista tamb\u00e9m recomenda caprichar nas saladas durante as ceias e nas refei\u00e7\u00f5es da semana. \u201cCouve, repolho, espinafre e r\u00facula aumentam a saciedade pelo teor de fibras. Manter-se hidratado, planejar o prato e preferir gorduras boas como o azeite, nozes, castanhas, devem compor os pratos\u201d, ressalta.<\/p>\n<p>\u201cEvitar sal, a\u00e7\u00facares, farinhas refinadas e carnes gordurosas. Tentar fazer melhores escolhas evitando carboidratos simples e gorduras saturadas que favorecem o ganho de peso\u201d, refor\u00e7a Rochele.<\/p>\n<p>A nutricionista frisa ainda que as celebra\u00e7\u00f5es devem ser aproveitadas e que \u00e9 importante ter aten\u00e7\u00e3o para os excessos. \u201cNo fim de ano \u00e9 tempo de rever a fam\u00edlia e amigos. Nas ceias conseguimos reunir pessoas queridas e confraternizar com afeto. Por isso, \u00e9 importante apenas aten\u00e7\u00e3o nos excessos durante as refei\u00e7\u00f5es e ter alguns cuidados\u201d.<\/p>\n<p><strong>Cuidados<\/strong><\/p>\n<p>Rochele ressalta aten\u00e7\u00e3o no preparo dos pratos e optar por refei\u00e7\u00f5es com mais saladas e carnes magras. \u201cSe as festas ocorrerem com muita frequ\u00eancia podem causar um desequil\u00edbrio no peso. Procure comer bem sem beliscar muito nas refei\u00e7\u00f5es\u201d, diz.<\/p>\n<p>Ao mesmo tempo, a especialista evidencia a import\u00e2ncia de ficar atento ao exagero durante as ceias e ao excesso de bebidas alco\u00f3licas, que podem ocasionar desidrata\u00e7\u00e3o, n\u00e1useas, dores de cabe\u00e7a, incha\u00e7o ou dor de barriga.<\/p>\n<p>Ela tamb\u00e9m direciona escolher alimentos naturais em detrimento dos que apresentam grande quantidade de farinhas, sal e a\u00e7\u00facares. Estes \u00faltimos t\u00eam um potencial inflamat\u00f3rio e, se consumidos em excesso, levam ao desenvolvimento de diversos problemas, principalmente metab\u00f3licos como diabetes e doen\u00e7as cardiovasculares.<\/p>\n<p><strong>Dicas da nutricionista<\/strong><\/p>\n<p>&#8211; Programe o card\u00e1pio das ceias evitando sobras e excessos.<\/p>\n<p>&#8211; Comece a ceia por frutas, saladas ou oleaginosas (castanhas, amendoins ou am\u00eandoas).<\/p>\n<p>&#8211; Mantenha a hidrata\u00e7\u00e3o ao longo do dia.<\/p>\n<p>&#8211; Comece o dia seguinte bebendo bastante \u00e1gua e consumindo fibras j\u00e1 no caf\u00e9 da manh\u00e3.<\/p>\n<p><strong>Fa\u00e7a em casa<\/strong><\/p>\n<p><strong>Salada Refrescante<br \/>\n<\/strong><br \/>\n4 folhas de alface crespa<br \/>\n2 folhas de alface lisa<br \/>\n400 g de frango desfiado<br \/>\n1 x\u00edcara de ma\u00e7a verde picada<br \/>\n2 rodelas de abacaxi em cubos<br \/>\nCheiro verde e castanhas a gosto<\/p>\n<p><strong>Molho<br \/>\n<\/strong><br \/>\n1 pote de iogurte desnatado<br \/>\n2 colher de sopa de azeite<br \/>\n1 colher de sopa de alho picado<br \/>\n1 punhado de hortel\u00e3 picada<br \/>\nSal e pimenta a gosto<\/p>\n<p><strong>Rabanada<\/strong><\/p>\n<p>10 fatias de p\u00e3o sem gl\u00faten ou p\u00e3o dormido<\/p>\n<p>100ml de leite desnatado<\/p>\n<p>3 colheres de sopa de \u00e1gua<\/p>\n<p>1 colheres de sopa de ess\u00eancia de baunilha<\/p>\n<p>4 colheres de sopa de a\u00e7\u00facar de coco<\/p>\n<p>1 colher de sobremesa de canela em p\u00f3<\/p>\n<p>1 ovo inteiro<\/p>\n<p><strong>Prepara\u00e7\u00e3o:<\/strong><\/p>\n<p>Corte os p\u00e3o na diagonal. Misture o leite, a canela e o a\u00e7\u00facar. Bata o ovo em uma batedeira com a \u00e1gua. Depois passe o p\u00e3o no leite e em seguida no ovo. Coloque em forma untada at\u00e9 dourar e por \u00faltimo passe as rabanadas no a\u00e7\u00facar de coco e na canela.<\/p>\n<p><strong>Farofa<\/strong><\/p>\n<p>2 colheres de sopa de cebola picada<\/p>\n<p>3 colheres de sopa de macad\u00e2mia<\/p>\n<p>3 x\u00edcaras de farinha de coco<\/p>\n<p>3 colheres de sopa de passas<\/p>\n<p>1\/2 x\u00edcaras de azeite<\/p>\n<p>1\/2 de cenoura ralada<\/p>\n<p><strong>Prepara\u00e7\u00e3o:<\/strong><\/p>\n<p>Refogar a cebola no azeite e depois misturar todos os outros ingredientes. Por \u00faltimo leve ao forno at\u00e9 dourar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fim de ano \u00e9 um per\u00edodo marcado por confraterniza\u00e7\u00f5es e muitas ceias. Por\u00e9m, se n\u00e3o forem tomados os devidos cuidados, as festas podem ser verdadeiras armadilhas. Para aproveitar as celebra\u00e7\u00f5es, a nutricionista do Centro de Sa\u00fade Meireles, da rede p\u00fablica do Governo do Cear\u00e1, Rochele Riquet, orienta sobre os principais alimentos consumidos nas ceias [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":82854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1424],"tags":[1044,1425,236],"class_list":["post-82853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacao","tag-alimentacao","tag-ceias","tag-prevencao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Especialista orienta como aproveitar as ceias com sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Especialista orienta como aproveitar as ceias com sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O fim de ano \u00e9 um per\u00edodo marcado por confraterniza\u00e7\u00f5es e muitas ceias. Por\u00e9m, se n\u00e3o forem tomados os devidos cuidados, as festas podem ser verdadeiras armadilhas. Para aproveitar as celebra\u00e7\u00f5es, a nutricionista do Centro de Sa\u00fade Meireles, da rede p\u00fablica do Governo do Cear\u00e1, Rochele Riquet, orienta sobre os principais alimentos consumidos nas ceias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-23T19:23:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-23T19:25:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Especialista orienta como aproveitar as ceias com sa\u00fade\",\"datePublished\":\"2019-12-23T19:23:22+00:00\",\"dateModified\":\"2019-12-23T19:25:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\"},\"wordCount\":728,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png\",\"keywords\":[\"alimenta\u00e7\u00e3o\",\"ceias\",\"preven\u00e7\u00e3o\"],\"articleSection\":[\"Alimenta\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\",\"name\":\"Especialista orienta como aproveitar as ceias com sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png\",\"datePublished\":\"2019-12-23T19:23:22+00:00\",\"dateModified\":\"2019-12-23T19:25:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png\",\"width\":775,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especialista orienta como aproveitar as ceias com sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Especialista orienta como aproveitar as ceias com sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/","og_locale":"pt_BR","og_type":"article","og_title":"Especialista orienta como aproveitar as ceias com sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O fim de ano \u00e9 um per\u00edodo marcado por confraterniza\u00e7\u00f5es e muitas ceias. Por\u00e9m, se n\u00e3o forem tomados os devidos cuidados, as festas podem ser verdadeiras armadilhas. Para aproveitar as celebra\u00e7\u00f5es, a nutricionista do Centro de Sa\u00fade Meireles, da rede p\u00fablica do Governo do Cear\u00e1, Rochele Riquet, orienta sobre os principais alimentos consumidos nas ceias [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2019-12-23T19:23:22+00:00","article_modified_time":"2019-12-23T19:25:53+00:00","og_image":[{"width":775,"height":486,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Especialista orienta como aproveitar as ceias com sa\u00fade","datePublished":"2019-12-23T19:23:22+00:00","dateModified":"2019-12-23T19:25:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/"},"wordCount":728,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png","keywords":["alimenta\u00e7\u00e3o","ceias","preven\u00e7\u00e3o"],"articleSection":["Alimenta\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/","name":"Especialista orienta como aproveitar as ceias com sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png","datePublished":"2019-12-23T19:23:22+00:00","dateModified":"2019-12-23T19:25:53+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/12\/banner_comer_bem_natal_dez2019_siteG.png","width":775,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/12\/23\/especialista-orienta-como-aproveitar-as-ceias-com-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Especialista orienta como aproveitar as ceias com sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/82853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=82853"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/82853\/revisions"}],"predecessor-version":[{"id":82857,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/82853\/revisions\/82857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/82854"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=82853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=82853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=82853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}