{"id":81268,"date":"2019-09-23T14:15:54","date_gmt":"2019-09-23T17:15:54","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=81268"},"modified":"2019-09-23T14:22:14","modified_gmt":"2019-09-23T17:22:14","slug":"cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/","title":{"rendered":"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-81273\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>A sa\u00fade bucal \u00e9 mais importante do que se imagina. A boca \u00e9 a porta de entrada de germes e bact\u00e9rias que podem circular em todo o organismo. E cuidar desde a inf\u00e2ncia \u00e9 fundamental. No Hospital Infantil Albert Sabin (Hias), do Governo do Cear\u00e1, o servi\u00e7o de odontologia est\u00e1 presente em todos os setores. Do ambulat\u00f3rio \u00e0 UTI.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-81276\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias2.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias2.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias2-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias2-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>\u201cS\u00e3o pacientes com necessidades especiais, oncol\u00f3gicos, fissurados, card\u00edacos, nefr\u00f3ticos (dist\u00farbios renais). Mas, sobretudo, neurol\u00f3gicos. \u00c9 fundamental cuidar da sa\u00fade bucal. A limpeza e cuidados especializados evita infec\u00e7\u00f5es e, consequentemente, o agravamento de outras doen\u00e7as\u201d, ressalta a coordenadora do servi\u00e7o, a cirurgi\u00e3 dentista Ana Cely Machado de Sousa.Dessa forma, a equipe da unidade atua com aten\u00e7\u00e3o redobrada, inclusive nos cuidados b\u00e1sicos.<\/p>\n<p>Formada por nove profissionais e residentes, a odontologia do Hias realiza, em m\u00e9dia, mais de 750 atendimentos ambulatoriais por m\u00eas.\u201cA odontologia daqui \u00e9 bem completa e tamb\u00e9m trabalhamos de forma preventiva. E quando n\u00e3o \u00e9 poss\u00edvel resolver o problema no ambulat\u00f3rio, vamos at\u00e9 o paciente, onde \u00e9 necess\u00e1rio, no Hias\u201d, garante Ana Cely.<\/p>\n<h4>Odontologia no Centro Cir\u00fargico<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-81274\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias1.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias1.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias1-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias1-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>O paciente Jos\u00e9 Madjer, de 8 anos, precisava realizar um canal. Ele, no entanto, tem Transtorno do Espectro Autista e Esclerose Tuberosa, uma disfun\u00e7\u00e3o gen\u00e9tica de heran\u00e7a dominante na qual os tumores (geralmente hamartomas) afetam m\u00faltiplos \u00f3rg\u00e3os. Fatores que inviabilizavam o atendimento a n\u00edvel ambulatorial. \u201cQuando o paciente \u00e9 especial, as vezes \u00e9 necess\u00e1rio utilizarmos o Centro Cir\u00fargico\u201d, explica a cirurgi\u00e3 dentista Talita Jord\u00e2nia, que acompanha o paciente.<\/p>\n<p>O procedimento foi realizado na manh\u00e3 do dia 30 de agosto e trouxe al\u00edvio para preocupa\u00e7\u00f5es da m\u00e3e, a t\u00e9cnica de enfermagem Nadja Braga. \u201cA gente fica apreensiva (por causa da seda\u00e7\u00e3o), mas estou dando gra\u00e7as a Deus. Ele j\u00e1 vem sofrendo h\u00e1 alguns dias e tem um abcesso no c\u00e9u da boca. \u00c9 um al\u00edvio saber que ele vai melhorar\u201d, fala.<\/p>\n<p>\u201cNo caso do Madjer, ele fez o canal porque j\u00e1 estava com infec\u00e7\u00e3o. E se n\u00e3o fosse tratada, a infec\u00e7\u00e3o poderia se estender pela face toda e agravar a condi\u00e7\u00e3o dele\u201d, afirma Talita. O procedimento ocorreu sem complica\u00e7\u00f5es e o pequeno Jos\u00e9 p\u00f4de ir para casa no mesmo dia, ap\u00f3s passado o efeito da seda\u00e7\u00e3o.<\/p>\n<h3>Pacientes oncol\u00f3gicos<\/h3>\n<p>O Hospital Albert Sabin realiza procedimento odontol\u00f3gico preventivo nos pacientes da oncologia que passam por quimioterapia. Trata-se da laserterapia, um procedimento indolor e que leva menos de 10 minutos, o suficiente para evitar a mucosite, uma inflama\u00e7\u00e3o que causa \u00falceras na boca do paciente. \u201cElas (\u00falceras) s\u00e3o bem agressivas e aparecem na boca inteira. Isso leva a per\u00edodos maiores de interna\u00e7\u00e3o, o paciente fica sem comer. Se a \u00falcera j\u00e1 existir, o laser ajuda com a cicatriza\u00e7\u00e3o e a dor\u201d, explica a cirurgi\u00e3 dentista Talita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-81275\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias3.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias3.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias3-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias3-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>O pequeno Hemanuel, de 3 anos, foi trazido ao Albert Sabin com suspeita de leucemia em 25 de dezembro de 2018. \u201cO diagn\u00f3stico foi confirmado aqui no Hias no dia 26 de dezembro, leucemia, e j\u00e1 come\u00e7ou o tratamento\u201d, relembra a m\u00e3e, a dona de casa Andreia da Silva Costa. Segundo ela, a doen\u00e7a agiu r\u00e1pido, por cerca de 15 dias o menino se queixou de dores nas pernas, cansa\u00e7o, a\u00ed surgiram as manchas e a perda de peso. O tratamento deve durar pouco mais de dois anos e aceitou a laserterapia do filho com al\u00edvio. \u201cSe vai ajudar \u00e9 bem-vindo\u201d, diz.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-81277\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias4.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias4.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias4-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias4-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<h3>Por todos os setores<\/h3>\n<p>A odontologia do Albert Sabin atende pacientes com fissura de l\u00e1bio e palato, um processo que vai desde avalia\u00e7\u00e3o at\u00e9 realiza\u00e7\u00e3o cirurgias, da limpeza e restaura\u00e7\u00e3o de c\u00e1ries at\u00e9 o enxerto \u00f3sseo. Acompanha pacientes internados realizando procedimento mesmo no leito, caso a crian\u00e7a ou adolescente n\u00e3o possa se locomover at\u00e9 o ambulat\u00f3rio. H\u00e1 tamb\u00e9m o servi\u00e7o nas Unidades de Tratamento Intensivo (UTIs), para evitar infec\u00e7\u00f5es bucais, as quais podem agravar o estado do paciente.<\/p>\n<p>\u201cTemos de entender que o perfil de pacientes do Hias \u00e9 outro, \u00e9 bem mais complexo e quaisquer complica\u00e7\u00f5es podem trazer graves consequ\u00eancias. Agora, se voc\u00ea normalmente cuida da sua sa\u00fade bucal com escova\u00e7\u00e3o ap\u00f3s as refei\u00e7\u00f5es, se alimenta bem e consultando seu dentista regulamente, voc\u00ea n\u00e3o deve ter problemas. Escova\u00e7\u00e3o e boa alimenta\u00e7\u00e3o s\u00e3o fundamentais para uma boa sa\u00fade bucal\u201d, destaca coordenadora do servi\u00e7o Ana Cely Machado de Sousa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sa\u00fade bucal \u00e9 mais importante do que se imagina. A boca \u00e9 a porta de entrada de germes e bact\u00e9rias que podem circular em todo o organismo. E cuidar desde a inf\u00e2ncia \u00e9 fundamental. No Hospital Infantil Albert Sabin (Hias), do Governo do Cear\u00e1, o servi\u00e7o de odontologia est\u00e1 presente em todos os setores. [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":81273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[521],"tags":[152,236,178],"class_list":["post-81268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saudebucal","tag-odontologia","tag-prevencao","tag-saude-bucal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A sa\u00fade bucal \u00e9 mais importante do que se imagina. A boca \u00e9 a porta de entrada de germes e bact\u00e9rias que podem circular em todo o organismo. E cuidar desde a inf\u00e2ncia \u00e9 fundamental. No Hospital Infantil Albert Sabin (Hias), do Governo do Cear\u00e1, o servi\u00e7o de odontologia est\u00e1 presente em todos os setores. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-23T17:15:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-23T17:22:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado\",\"datePublished\":\"2019-09-23T17:15:54+00:00\",\"dateModified\":\"2019-09-23T17:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\"},\"wordCount\":777,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg\",\"keywords\":[\"Odontologia\",\"preven\u00e7\u00e3o\",\"Sa\u00fade Bucal\"],\"articleSection\":[\"Sa\u00fade bucal\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\",\"name\":\"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg\",\"datePublished\":\"2019-09-23T17:15:54+00:00\",\"dateModified\":\"2019-09-23T17:22:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/","og_locale":"pt_BR","og_type":"article","og_title":"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A sa\u00fade bucal \u00e9 mais importante do que se imagina. A boca \u00e9 a porta de entrada de germes e bact\u00e9rias que podem circular em todo o organismo. E cuidar desde a inf\u00e2ncia \u00e9 fundamental. No Hospital Infantil Albert Sabin (Hias), do Governo do Cear\u00e1, o servi\u00e7o de odontologia est\u00e1 presente em todos os setores. [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2019-09-23T17:15:54+00:00","article_modified_time":"2019-09-23T17:22:14+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado","datePublished":"2019-09-23T17:15:54+00:00","dateModified":"2019-09-23T17:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/"},"wordCount":777,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg","keywords":["Odontologia","preven\u00e7\u00e3o","Sa\u00fade Bucal"],"articleSection":["Sa\u00fade bucal"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/","name":"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg","datePublished":"2019-09-23T17:15:54+00:00","dateModified":"2019-09-23T17:22:14+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_saude_bucal_hias0.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/23\/cuidado-com-saude-bucal-de-criancas-deve-ser-redobrado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Cuidado com sa\u00fade bucal de crian\u00e7as deve ser redobrado"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/81268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=81268"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/81268\/revisions"}],"predecessor-version":[{"id":81279,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/81268\/revisions\/81279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/81273"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=81268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=81268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=81268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}