{"id":81213,"date":"2019-09-18T14:55:44","date_gmt":"2019-09-18T17:55:44","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=81213"},"modified":"2019-09-18T15:24:19","modified_gmt":"2019-09-18T18:24:19","slug":"hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/","title":{"rendered":"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-81222\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>O Centro de Hematologia e Hemoterapia do Cear\u00e1 (Hemoce), da rede p\u00fablica do Governo do Cear\u00e1, promove neste s\u00e1bado, 21 de setembro, a partir das 9h, no posto de coleta na Pra\u00e7a das Flores, uma atividade de conscientiza\u00e7\u00e3o para o cadastro de medula \u00f3ssea. A a\u00e7\u00e3o acontece em refer\u00eancia ao Dia Mundial do Doador de Medula que \u00e9 celebrado no terceiro s\u00e1bado do m\u00eas de setembro. Os hemocentros regionais tamb\u00e9m realizar\u00e3o uma programa\u00e7\u00e3o para mobilizar os doadores.<\/p>\n<p>Com o objetivo de ampliar o n\u00famero de pessoas cadastradas para doa\u00e7\u00e3o de medula \u00f3ssea o Hemoce preparou uma programa\u00e7\u00e3o diferenciada para conscientizar a popula\u00e7\u00e3o. Os volunt\u00e1rios ser\u00e3o recepcionados com material informativo e lacinhos laranja, cor s\u00edmbolo da doa\u00e7\u00e3o de medula. Ser\u00e3o oferecidos tamb\u00e9m servi\u00e7os de avalia\u00e7\u00e3o nutricional com bioimped\u00e2ncia, teste de glicemia, aferi\u00e7\u00e3o de press\u00e3o arterial e orienta\u00e7\u00e3o sobre a import\u00e2ncia do cadastro para doa\u00e7\u00e3o de medula \u00f3ssea.<\/p>\n<p>A a\u00e7\u00e3o contar\u00e1 tamb\u00e9m com um espa\u00e7o kids com pintura e entretenimento para que os pais possam levar as crian\u00e7as. Grupos de incentivos a solidariedade como: Ca\u00e7adores de Medula, Panapan\u00e1 e FlaMedula estar\u00e3o presentes mobilizando o p\u00fablico. \u201cO primeiro passo para ser um doador de medula \u00f3ssea \u00e9 realizar um cadastro em uma das unidades do Hemoce. Para se cadastrar basta ter entre 18 e 55 anos de idade, n\u00e3o ter hist\u00f3rico pessoal de c\u00e2ncer e apresentar um documento de identifica\u00e7\u00e3o oficial com foto. Voc\u00ea preenche um formul\u00e1rio com dados pessoais, fornece dois telefones para contato e ser\u00e1 coletada uma amostra de sangue de 5ml para a realiza\u00e7\u00e3o de testes\u201d, explica N\u00e1gela Lima, coordenadora da capta\u00e7\u00e3o de doadores do Hemoce.<\/p>\n<p><strong>Cadastro no interior<\/strong><\/p>\n<p>Como parte da programa\u00e7\u00e3o do Setembro Verde, m\u00eas de incentivo \u00e0 doa\u00e7\u00e3o de \u00f3rg\u00e3os e tecidos. Os hemocentros regionais nas cidades de Sobral, Quixad\u00e1, Iguatu, Crato e Juazeiro do Norte tamb\u00e9m est\u00e3o intensificando a import\u00e2ncia do cadastro para doa\u00e7\u00e3o de medula \u00f3ssea.<\/p>\n<p>No s\u00e1bado, 21, \u00e0s 8h, o Hemoce Quixad\u00e1 realiza uma palestra educativa para explicar e tirar d\u00favidas sobre cadastro e doa\u00e7\u00e3o de medula. Os volunt\u00e1rios poder\u00e3o participar de uma manh\u00e3 de bem-estar com servi\u00e7os de maquiagem e limpeza de pele. Para refor\u00e7ar o n\u00famero de pessoas cadastradas, o Hemoce Sobral ampliou as coletas externas no munic\u00edpio e realiza palestras educativas.<br \/>\nEm Iguatu o hemocentro regional tamb\u00e9m incentiva a doa\u00e7\u00e3o de medula \u00f3ssea com a\u00e7\u00f5es de conscientiza\u00e7\u00e3o em eventos e coletas externas na regi\u00e3o. No Hemoce do Crato e Juazeiro do Norte, a mobiliza\u00e7\u00e3o para o cadastro de volunt\u00e1rios ser\u00e1 feita por meio de coletas externas e haver\u00e1 programa\u00e7\u00e3o cultural e palestras no Dia Mundial do Doador de Medula \u00d3ssea.<\/p>\n<p><strong>Como ser um doador<\/strong><\/p>\n<p>Para encontrar um doador de medula \u00f3ssea compat\u00edvel n\u00e3o aparentado \u00e9 necess\u00e1rio realizar o cadastro nos hemocentros do pa\u00eds. No Cear\u00e1, o Hemoce \u00e9 respons\u00e1vel pelo cadastramento. Atualmente cerca de 190 mil pessoas j\u00e1 se cadastraram como poss\u00edveis doadores de medula \u00f3ssea no Estado. O servi\u00e7o de coleta das c\u00e9lulas \u00e9 realizado pelo hemocentro cearense desde 2012.<\/p>\n<p>A doa\u00e7\u00e3o de medula acontece quando o volunt\u00e1rio cadastrado \u00e9 compat\u00edvel com o paciente que necessita do transplante de medula. A chance de encontrar a compatibilidade \u00e9 de uma para cada 100 mil pessoas. Apesar de a probabilidade ser pequena, o Hemoce j\u00e1 coletou 67 bolsas de medula \u00f3ssea, sendo 38 para transplantes de medula em outros estados e 29 para outros pa\u00edses como: Argentina, Estados Unidos, Canad\u00e1, It\u00e1lia, Fran\u00e7a, Portugal, Holanda, Alemanha, Espanha, Inglaterra, Turquia e Israel.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro de Hematologia e Hemoterapia do Cear\u00e1 (Hemoce), da rede p\u00fablica do Governo do Cear\u00e1, promove neste s\u00e1bado, 21 de setembro, a partir das 9h, no posto de coleta na Pra\u00e7a das Flores, uma atividade de conscientiza\u00e7\u00e3o para o cadastro de medula \u00f3ssea. A a\u00e7\u00e3o acontece em refer\u00eancia ao Dia Mundial do Doador de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":81222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-81213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sesa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O Centro de Hematologia e Hemoterapia do Cear\u00e1 (Hemoce), da rede p\u00fablica do Governo do Cear\u00e1, promove neste s\u00e1bado, 21 de setembro, a partir das 9h, no posto de coleta na Pra\u00e7a das Flores, uma atividade de conscientiza\u00e7\u00e3o para o cadastro de medula \u00f3ssea. A a\u00e7\u00e3o acontece em refer\u00eancia ao Dia Mundial do Doador de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T17:55:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-18T18:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21\",\"datePublished\":\"2019-09-18T17:55:44+00:00\",\"dateModified\":\"2019-09-18T18:24:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\"},\"wordCount\":646,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg\",\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\",\"name\":\"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg\",\"datePublished\":\"2019-09-18T17:55:44+00:00\",\"dateModified\":\"2019-09-18T18:24:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/","og_locale":"pt_BR","og_type":"article","og_title":"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O Centro de Hematologia e Hemoterapia do Cear\u00e1 (Hemoce), da rede p\u00fablica do Governo do Cear\u00e1, promove neste s\u00e1bado, 21 de setembro, a partir das 9h, no posto de coleta na Pra\u00e7a das Flores, uma atividade de conscientiza\u00e7\u00e3o para o cadastro de medula \u00f3ssea. A a\u00e7\u00e3o acontece em refer\u00eancia ao Dia Mundial do Doador de [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2019-09-18T17:55:44+00:00","article_modified_time":"2019-09-18T18:24:19+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21","datePublished":"2019-09-18T17:55:44+00:00","dateModified":"2019-09-18T18:24:19+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/"},"wordCount":646,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg","articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/","name":"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg","datePublished":"2019-09-18T17:55:44+00:00","dateModified":"2019-09-18T18:24:19+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/09\/banner_dia_doador_medula_hemoce.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/09\/18\/hemoce-mobiliza-populacao-a-doar-medula-ossea-neste-sabado-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Hemoce mobiliza popula\u00e7\u00e3o a doar medula \u00f3ssea neste s\u00e1bado, 21"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/81213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=81213"}],"version-history":[{"count":5,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/81213\/revisions"}],"predecessor-version":[{"id":81223,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/81213\/revisions\/81223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/81222"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=81213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=81213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=81213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}