{"id":804,"date":"2009-11-17T18:48:48","date_gmt":"2009-11-17T21:48:48","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/"},"modified":"2009-11-17T18:48:48","modified_gmt":"2009-11-17T21:48:48","slug":"hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/","title":{"rendered":"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama"},"content":{"rendered":"<p>O Hospital Geral C\u00e9sar Cals, em parceria com a Sociedade Brasileira de Mastologia, realizar\u00e1, no dia 21 de novembro, a partir de 7h, uma manh\u00e3 dedicada ao atendimento \u00e0s mulheres, como parte da programa\u00e7\u00e3o da X Semana Nacional de Incentivo a Sa\u00fade Mamaria. O evento ser\u00e1 no Setor Ambulatorial do HGCC, na Av. Imperador, 372. A finalidade \u00e9 orientar a popula\u00e7\u00e3o para o diagn\u00f3stico precoce do c\u00e2ncer de mama. Ser\u00e3o atendidas cerca de 300 mulheres. As pacientes ouvir\u00e3o uma palestra de abertura e, em seguida, passar\u00e3o por consultas e\u00a0 exames de mamografia, realizados por 15 m\u00e9dicos mastologistas.\u00a0 <\/p>\n<p>Com o objetivo de chamar aten\u00e7\u00e3o da popula\u00e7\u00e3o feminina para a import\u00e2ncia dos cuidados com a sa\u00fade mam\u00e1ria, o HGCC dedica uma manh\u00e3 inteira a presta\u00e7\u00e3o de servi\u00e7os com palestra, orienta\u00e7\u00f5es sobre a sa\u00fade mam\u00e1ria e atendimento a mulheres, destacando a preven\u00e7\u00e3o contra o c\u00e2ncer de mama. Segundo Ant\u00f4nio de P\u00e1dua Almeida Carneiro, m\u00e9dico e vice-presidente da Sociedade Brasileira de Mastologia &#8211; CE, \u201co c\u00e2ncer de mama \u00e9 o mais comum e o mais letal entre as mulheres em todo o mundo\u201d.\u00a0 De acordo com o Instituto nacional do C\u00e2ncer, s\u00e3o esperados 1600 novos casos de c\u00e2ncer de mama no Cear\u00e1. Da\u00ed, a relev\u00e2ncia do mutir\u00e3o de atendimento, que pretende destacar a import\u00e2ncia de toda mulher fazer o exame de\u00a0 mamografia anualmente ap\u00f3s os 40 anos.<\/p>\n<p>O Hospital Geral C\u00e9sar Cals pretende ainda, j\u00e1 no pr\u00f3ximo ano, criar a Resid\u00eancia de Mastologia, contribuindo para a forma\u00e7\u00e3o de novos mastologistas no Cear\u00e1.<\/p>\n<p>MAIS INFORMA\u00c7\u00d5ES:<br \/>Assessoria de Comunica\u00e7\u00e3o do Hospital Geral C\u00e9sar Cals<br \/>Telefone: 3101 5422<br \/><a href=\"https:\/\/www.hgcc.ce.gov.br\" target=\"_blank\">www.hgcc.ce.gov.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital Geral C\u00e9sar Cals, em parceria com a Sociedade Brasileira de Mastologia, realizar\u00e1, no dia 21 de novembro, a partir de 7h, uma manh\u00e3 dedicada ao atendimento \u00e0s mulheres, como parte da programa\u00e7\u00e3o da X Semana Nacional de Incentivo a Sa\u00fade Mamaria. O evento ser\u00e1 no Setor Ambulatorial do HGCC, na Av. Imperador, 372. [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-804","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O Hospital Geral C\u00e9sar Cals, em parceria com a Sociedade Brasileira de Mastologia, realizar\u00e1, no dia 21 de novembro, a partir de 7h, uma manh\u00e3 dedicada ao atendimento \u00e0s mulheres, como parte da programa\u00e7\u00e3o da X Semana Nacional de Incentivo a Sa\u00fade Mamaria. O evento ser\u00e1 no Setor Ambulatorial do HGCC, na Av. Imperador, 372. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-17T21:48:48+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama\",\"datePublished\":\"2009-11-17T21:48:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\",\"name\":\"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-11-17T21:48:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O Hospital Geral C\u00e9sar Cals, em parceria com a Sociedade Brasileira de Mastologia, realizar\u00e1, no dia 21 de novembro, a partir de 7h, uma manh\u00e3 dedicada ao atendimento \u00e0s mulheres, como parte da programa\u00e7\u00e3o da X Semana Nacional de Incentivo a Sa\u00fade Mamaria. O evento ser\u00e1 no Setor Ambulatorial do HGCC, na Av. Imperador, 372. [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-11-17T21:48:48+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama","datePublished":"2009-11-17T21:48:48+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/"},"wordCount":306,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/","name":"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-11-17T21:48:48+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/17\/hospital-cesar-cals-orienta-mulheres-sobre-cancer-de-mama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Hospital C\u00e9sar Cals orienta mulheres sobre c\u00e2ncer de mama"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=804"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/804\/revisions"}],"predecessor-version":[{"id":77294,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/804\/revisions\/77294"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}