{"id":8014,"date":"2016-07-12T13:02:52","date_gmt":"2016-07-12T16:02:52","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/"},"modified":"2016-07-12T13:02:52","modified_gmt":"2016-07-12T16:02:52","slug":"contexto","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/","title":{"rendered":"Contexto"},"content":{"rendered":"<div> \tPara reorganizar o modelo de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade da popula\u00e7\u00e3o, a partir da reestrutura\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria nos munic\u00edpios, em 2014 foi iniciada a Planifica\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade no Cear\u00e1. Proposta do Conselho Nacional de Secret\u00e1rios de Sa\u00fade (CONASS) e realizada pela Secretaria da Sa\u00fade do Estado (Sesa) com o apoio da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE) e da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz), a planifica\u00e7\u00e3o teve as primeiras oficinas de atualiza\u00e7\u00e3o e capacita\u00e7\u00e3o dos profissionais da aten\u00e7\u00e3o prim\u00e1ria realizadas em Tau\u00e1, onde foi desenvolvido o Laborat\u00f3rio de Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade, com a participa\u00e7\u00e3o dos munic\u00edpios da Regi\u00e3o de Sa\u00fade de Tau\u00e1 (Arneiroz, Aiuaba, Parambu e Tau\u00e1) e um total de 220 participantes nas oficinas regionais.\u00a0<\/div>\n<div> \t\u00a0<\/div>\n<div> \tA qualifica\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade tamb\u00e9m tem ocorrido em outros munic\u00edpios cearenses, como Sobral e Fortaleza, por iniciativa pr\u00f3pria, no mesmo modelo de aten\u00e7\u00e3o \u00e0 sa\u00fade praticado em Tau\u00e1. Os resultados alcan\u00e7ados na reorganiza\u00e7\u00e3o e qualifica\u00e7\u00e3o dos processos de trabalho com impacto na melhoria dos indicadores de sa\u00fade desses munic\u00edpios, fez com que a Sesa lan\u00e7asse a expans\u00e3o da planifica\u00e7\u00e3o, atrav\u00e9s do Projeto de Qualifica\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade &#8211; QualificaAPSUS Cear\u00e1.<\/div>\n<div> \t\u00a0<\/div>\n<div> \tO Projeto QualificaAPSUS Cear\u00e1 foi lan\u00e7ado pela Secretaria da Sa\u00fade do Estado em janeiro de 2016 com o objetivo de subsidiar a reorganiza\u00e7\u00e3o do modelo de aten\u00e7\u00e3o a partir da reestrutura\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria nos munic\u00edpios e, consequentemente, da implanta\u00e7\u00e3o e implementa\u00e7\u00e3o das Redes de Aten\u00e7\u00e3o (RAS). As oficinas s\u00e3o intercaladas com a tutoria para a aplica\u00e7\u00e3o dos conte\u00fados te\u00f3ricos na pr\u00e1tica di\u00e1ria das equipes da aten\u00e7\u00e3o prim\u00e1ria na unidade b\u00e1sica de sa\u00fade. Os participantes das oficinas fazem a replica\u00e7\u00e3o dos conte\u00fados nos munic\u00edpios, com o apoio das Coordenadorias Regionais de Sa\u00fade (CRES), e atuam como facilitadores na reestrutura\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria. Essas atividades proporcionam instrumentos, ferramentas, tecnologias de planejamento e de organiza\u00e7\u00e3o do trabalho para a qualifica\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria.\u00a0<\/div>\n<div> \t\u00a0<\/div>\n<div> \tAs oficinas realizadas nas Regi\u00f5es de Sa\u00fade de Tau\u00e1, Limoeiro do Norte e Sobral capacitaram 290 facilitadores e replicaram o conte\u00fado para 1.720 trabalhadores das equipes de Sa\u00fade da Fam\u00edlia e Unidades B\u00e1sicas de Sa\u00fade dos 37 munic\u00edpios envolvidos. Em junho de 2016, haver\u00e1 o lan\u00e7amento do projeto e a primeira oficina nas Regi\u00f5es de Sa\u00fade de Baturit\u00e9 e Canind\u00e9. Ao todo, 2.130 facilitadores ser\u00e3o capacitados nesse per\u00edodo.\u00a0<\/div>\n<div> \t\u00a0<\/div>\n<div> \tO QualificaAPSUS est\u00e1 vinculado \u00e0 Coordenadoria de Pol\u00edticas e Aten\u00e7\u00e3o \u00e0 Sa\u00fade da Sesa, cuja miss\u00e3o \u00e9 fortalecer as Pol\u00edticas de Sa\u00fade no \u00e2mbito das Redes de Aten\u00e7\u00e3o. A consolida\u00e7\u00e3o das Redes de Aten\u00e7\u00e3o \u00e0 Sa\u00fade depende de uma Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade (APS) que cumpra seu papel de responsabiliza\u00e7\u00e3o, coordena\u00e7\u00e3o e resolu\u00e7\u00e3o dos problemas de sa\u00fade da popula\u00e7\u00e3o, garantindo, sobretudo, a longitudinalidade e a integralidade do cuidado em sa\u00fade. Assim, o Projeto QualificaAPSUS Cear\u00e1 \u00e9 estrat\u00e9gico para o Estado, no intuito de se obter melhores resultados sanit\u00e1rios e econ\u00f4micos no \u00e2mbito do SUS. <span class=\"Apple-tab-span\" style=\"white-space:pre\"> <\/span><\/p>\n<p> \t\u00a0<\/div>\n<div> \t\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para reorganizar o modelo de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade da popula\u00e7\u00e3o, a partir da reestrutura\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria nos munic\u00edpios, em 2014 foi iniciada a Planifica\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade no Cear\u00e1. Proposta do Conselho Nacional de Secret\u00e1rios de Sa\u00fade (CONASS) e realizada pela Secretaria da Sa\u00fade do Estado (Sesa) com o apoio da [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8014","post","type-post","status-publish","format-standard","hentry","category-sesa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contexto - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contexto - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Para reorganizar o modelo de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade da popula\u00e7\u00e3o, a partir da reestrutura\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria nos munic\u00edpios, em 2014 foi iniciada a Planifica\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade no Cear\u00e1. Proposta do Conselho Nacional de Secret\u00e1rios de Sa\u00fade (CONASS) e realizada pela Secretaria da Sa\u00fade do Estado (Sesa) com o apoio da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-12T16:02:52+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Contexto\",\"datePublished\":\"2016-07-12T16:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\",\"name\":\"Contexto - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2016-07-12T16:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contexto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contexto - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/","og_locale":"pt_BR","og_type":"article","og_title":"Contexto - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Para reorganizar o modelo de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade da popula\u00e7\u00e3o, a partir da reestrutura\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria nos munic\u00edpios, em 2014 foi iniciada a Planifica\u00e7\u00e3o da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade no Cear\u00e1. Proposta do Conselho Nacional de Secret\u00e1rios de Sa\u00fade (CONASS) e realizada pela Secretaria da Sa\u00fade do Estado (Sesa) com o apoio da [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-07-12T16:02:52+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Contexto","datePublished":"2016-07-12T16:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/"},"wordCount":580,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/","name":"Contexto - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2016-07-12T16:02:52+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/07\/12\/contexto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Contexto"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/8014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=8014"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/8014\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=8014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=8014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=8014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}