{"id":79220,"date":"2019-05-23T15:00:17","date_gmt":"2019-05-23T18:00:17","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=79220"},"modified":"2019-05-24T17:13:06","modified_gmt":"2019-05-24T20:13:06","slug":"dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/","title":{"rendered":"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-79223 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png\" alt=\"\" width=\"755\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png 755w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1-600x385.png 600w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/p>\n<p>Alucina\u00e7\u00f5es, del\u00edrios, problemas de racioc\u00ednio e concentra\u00e7\u00e3o, falta de motiva\u00e7\u00e3o. Esses podem ser alguns dos sintomas da esquizofrenia, uma doen\u00e7a mental grave que altera a maneira como a pessoa sente, pensa e se comporta. De acordo com a Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade, 23 milh\u00f5es de pessoas no mundo s\u00e3o portadoras de esquizofrenia. Somente no Brasil, dois milh\u00f5es de brasileiros apresentam o dist\u00farbio.<\/p>\n<p>Segundo o psiquiatra e pesquisador do Hospital de Sa\u00fade Mental Professor Frota Pinto, Saulo Albuquerque, a doen\u00e7a faz com que as pessoas passem a interpretar a realidade de forma anormal. &#8220;Nos per\u00edodos em que os sintomas est\u00e3o ativos, geralmente h\u00e1 alucina\u00e7\u00f5es (ver ou ouvir coisas inexistentes), del\u00edrios (acreditar em algo que n\u00e3o est\u00e1 acontecendo, como achar que est\u00e1 sendo perseguido, por exemplo), altera\u00e7\u00e3o do comportamento e pensamento desorganizado&#8221;, afirma.<\/p>\n<p>Em alguns casos, os primeiros sinais da esquizofrenia aparecem entre a adolesc\u00eancia e a fase adulta. \u00c9 quando, geralmente, muitos pacientes deixam de lado atividades do cotidiano e se isolam do conv\u00edvio social. Rea\u00e7\u00f5es estranhas e despropositadas s\u00e3o outras caracter\u00edsticas marcantes no comportamento de quem tem o dist\u00farbio. A falta de informa\u00e7\u00e3o a respeito doen\u00e7a causa d\u00favidas e refor\u00e7a preconceitos. Por isso, Saulo Albuquerque ressalta a import\u00e2ncia do Dia Mundial da Pessoa com Esquizofrenia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-79259\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_psiquiatra_pesquisador_HSM_maio2019.png\" alt=\"\" width=\"774\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_psiquiatra_pesquisador_HSM_maio2019.png 774w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_psiquiatra_pesquisador_HSM_maio2019-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_psiquiatra_pesquisador_HSM_maio2019-768x481.png 768w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><\/p>\n<p>Com o lema Esperan\u00e7a Realista e Possibilidades na Vida com Esquizofrenia, a campanha deste ano debate o estigma que existe em torno do dist\u00farbio e as possibilidades de tratamento. &#8220;A desinforma\u00e7\u00e3o, por falta de acesso ou interesse, gera uma s\u00e9rie de equ\u00edvocos sobre a esquizofrenia. Envolvem, entre outras coisas, as causas da doen\u00e7a e o perfil dos portadores, considerados erroneamente por muitos como perigosos, violentos e inaptos para o conv\u00edvio e para atividades como estudo e trabalho&#8221;, comenta o pesquisador.<\/p>\n<p><strong>Diagn\u00f3stico e tratamento<\/strong><\/p>\n<p>Como n\u00e3o existe um exame laboratorial espec\u00edfico para identificar a esquizofrenia, o diagn\u00f3stico da doen\u00e7a depende de an\u00e1lise cl\u00ednica e comportamental e se d\u00e1 por meio de uma entrevista psiqui\u00e1trica cuidadosa feita com o paciente e familiares dele. Os m\u00e9dicos se baseiam em crit\u00e9rios estabelecidos pela CID-10, a Classifica\u00e7\u00e3o Internacional de Doen\u00e7as da Organiza\u00e7\u00e3o Mundial da Sa\u00fade. Pessoas com esquizofrenia precisam de tratamento com medica\u00e7\u00e3o, al\u00e9m de suporte psicossocial. Especialistas acreditam que, quanto mais cedo a doen\u00e7a \u00e9 tratada, melhor os sintomas s\u00e3o controlados e mais chances a pessoa tem de se recuperar.<\/p>\n<p><strong>Tratamento na Rede P\u00fablica de Sa\u00fade<\/strong><\/p>\n<p>Pessoas com transtorno mental podem recorrer \u00e0 Rede de Aten\u00e7\u00e3o Psicossocial (RAPS). A RAPS oferece servi\u00e7os como atendimento de sa\u00fade mental na unidade b\u00e1sica e leitos psicossociais em hospitais gerais. Al\u00e9m disso, a rede conta com Centros de Aten\u00e7\u00e3o Psicossocial (CAPS) e com o Hospital de Sa\u00fade Mental Professor Frota Pinto, do Governo do Cear\u00e1. O HSM \u00e9 refer\u00eancia para o atendimento em psiquiatria no estado. Em m\u00e9dia, mais de 3 mil pacientes s\u00e3o atendidos por m\u00eas na unidade. Integrante da rede hospitalar do Sistema \u00danico de Sa\u00fade (SUS), o HSM disp\u00f5e de dois hospitais-dia com sessenta leitos distribu\u00eddos no atendimento a pessoas com transtornos mentais e usu\u00e1rios de \u00e1lcool e de outras drogas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Alucina\u00e7\u00f5es, del\u00edrios, problemas de racioc\u00ednio e concentra\u00e7\u00e3o, falta de motiva\u00e7\u00e3o. Esses podem ser alguns dos sintomas da esquizofrenia, uma doen\u00e7a mental grave que altera a maneira como a pessoa sente, pensa e se comporta. De acordo com a Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade, 23 milh\u00f5es de pessoas no mundo s\u00e3o portadoras de esquizofrenia. Somente no [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":79223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[1021,1020,82],"class_list":["post-79220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sesa","tag-atencao-psicossocial","tag-esquizofrenia","tag-saude-mental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Alucina\u00e7\u00f5es, del\u00edrios, problemas de racioc\u00ednio e concentra\u00e7\u00e3o, falta de motiva\u00e7\u00e3o. Esses podem ser alguns dos sintomas da esquizofrenia, uma doen\u00e7a mental grave que altera a maneira como a pessoa sente, pensa e se comporta. De acordo com a Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade, 23 milh\u00f5es de pessoas no mundo s\u00e3o portadoras de esquizofrenia. Somente no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-23T18:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-24T20:13:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"755\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a\",\"datePublished\":\"2019-05-23T18:00:17+00:00\",\"dateModified\":\"2019-05-24T20:13:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png\",\"keywords\":[\"aten\u00e7\u00e3o psicossocial\",\"esquizofrenia\",\"sa\u00fade mental\"],\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\",\"name\":\"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png\",\"datePublished\":\"2019-05-23T18:00:17+00:00\",\"dateModified\":\"2019-05-24T20:13:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png\",\"width\":755,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&nbsp; Alucina\u00e7\u00f5es, del\u00edrios, problemas de racioc\u00ednio e concentra\u00e7\u00e3o, falta de motiva\u00e7\u00e3o. Esses podem ser alguns dos sintomas da esquizofrenia, uma doen\u00e7a mental grave que altera a maneira como a pessoa sente, pensa e se comporta. De acordo com a Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade, 23 milh\u00f5es de pessoas no mundo s\u00e3o portadoras de esquizofrenia. Somente no [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2019-05-23T18:00:17+00:00","article_modified_time":"2019-05-24T20:13:06+00:00","og_image":[{"width":755,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a","datePublished":"2019-05-23T18:00:17+00:00","dateModified":"2019-05-24T20:13:06+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/"},"wordCount":583,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png","keywords":["aten\u00e7\u00e3o psicossocial","esquizofrenia","sa\u00fade mental"],"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/","name":"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png","datePublished":"2019-05-23T18:00:17+00:00","dateModified":"2019-05-24T20:13:06+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/05\/banner_CB_dia_esquisofrenia-1.png","width":755,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/05\/23\/dia-mundial-da-pessoa-com-esquizofrenia-alerta-sobre-sintomas-e-tratamento-da-doenca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Dia Mundial da Pessoa com Esquizofrenia alerta sobre sintomas e tratamento da doen\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/79220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=79220"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/79220\/revisions"}],"predecessor-version":[{"id":79260,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/79220\/revisions\/79260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/79223"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=79220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=79220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=79220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}