{"id":7835,"date":"2016-05-30T18:27:52","date_gmt":"2016-05-30T21:27:52","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/"},"modified":"2019-01-14T11:18:29","modified_gmt":"2019-01-14T14:18:29","slug":"dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/","title":{"rendered":"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro"},"content":{"rendered":"<p>De acordo com o Minist\u00e9rio da Sa\u00fade, o tabagismo \u00e9 respons\u00e1vel por 200 mil mortes todos os anos no Brasil \u2013 25% delas por angina e infarto do mioc\u00e1rdio, 45% por infarto agudo do mioc\u00e1rdio (abaixo de 65 anos) e 85% das mortes por bronquite e enfisema pulmonar. O h\u00e1bito tamb\u00e9m responde por 90% dos casos de c\u00e2ncer de pulm\u00e3o no pa\u00eds. Entre os 10% restantes, um ter\u00e7o dos casos ocorre em fumantes passivos. Esse tipo de tumor \u00e9 considerado o mais letal e umas das principais causas de morte no Brasil.<\/p>\n<p>Ter\u00e7a-feira, 31 de maio, \u00e9 o Dia Mundial sem Tabaco, data em que todos os anos a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) convida os pa\u00edses a mobilizar e a esclarecer a popula\u00e7\u00e3o sobre os riscos \u00e0 sa\u00fade associados com o tabagismo e a adotar pol\u00edticas p\u00fablicas eficazes para reduzir o consumo. O tratamento do tabagismo no Brasil \u00e9 desenvolvido com base nas diretrizes do Programa Nacional de Controle do Tabagismo. O Instituto Nacional de C\u00e2ncer (Inca) \u00e9 o \u00f3rg\u00e3o do Minist\u00e9rio da Sa\u00fade respons\u00e1vel pelo PNCT. As orienta\u00e7\u00f5es do programa seguem as principais diretrizes internacionais relacionadas ao tratamento do tabagismo. Assim, a rede p\u00fablica oferece aos fumantes que desejam parar de fumar tratamento adequado, com metologia baseada em evid\u00eancias cient\u00edficas.<\/p>\n<p>Para quem quer deixar de fumar, na rede p\u00fablica do Governo do Estado, h\u00e1 duas unidades refer\u00eancias no tratamento do tabagismo. Uma \u00e9 o Hospital de Messejana Dr. Carlos Alberto Studart, que disp\u00f5e do Programa de Controle do Tabagismo. H\u00e1 13 anos ajuda pessoas que querem vencer o v\u00edcio de fumar. Os pacientes s\u00e3o atendidos por uma equipe de profissionais especializados como m\u00e9dicos, enfermeiras e assistente social. O programa j\u00e1 atendeu a 3 mil pacientes. O Programa de Controle do Tabagismo do Hospital de Messejana iniciou as atividades em 2002, sendo o primeiro tratamento p\u00fablico com distribui\u00e7\u00e3o gratuita de medica\u00e7\u00e3o para aliviar os sintomas de abstin\u00eancia. O telefone do programa \u00e9 o (85) 3101-4062.<\/p>\n<p>A outra op\u00e7\u00e3o na rede p\u00fablica do Governo do Estado para fumantes que querem fazer o tratamento gratuito contra o tabagismo \u00e9 o Centro de Sa\u00fade do Meireles, da Secretaria da Sa\u00fade do Estado. Fica na Avenida Ant\u00f4nio Justa, 3113. L\u00e1 e no HM funcionam o Programa de Controle do tabagismo, que trata os fumantes com avalia\u00e7\u00e3o cl\u00ednica, realiza abordagem m\u00ednima ou intensiva individual ou em grupo e, se preciso, com terapia medicamentosa.<\/p>\n<p>O sucesso terap\u00eautico do tratamento \u00e9 elevado, com taxa de abstin\u00eancia tab\u00e1gica de 48% em pelo menos um ano. Uma vez inscrito no Programa de Controle do Tabagismo, o paciente passa por uma triagem m\u00e9dica para coleta de informa\u00e7\u00f5es pessoais relativas ao estado psicol\u00f3gico e quanto \u00e0 motiva\u00e7\u00e3o para deixar o cigarro. Exames importantes s\u00e3o realizados para avaliar a sa\u00fade do paciente e seu grau de depend\u00eancia \u00e0 nicotina. Ap\u00f3s a avalia\u00e7\u00e3o inicial, o paciente passa a fazer parte do grupo de apoio, no qual \u00e9 realizado o tratamento padr\u00e3o, baseado na abordagem comportamental e terapia medicamentosa.<\/p>\n<p>O Dia Mundial Sem Fumo foi criado pela OMS em 1987 com o objetivo de sensibilizar e mobilizar a sociedade sobre os riscos do tabagismo e busca de vida mais saud\u00e1vel sem o fumo. O tabagismo mata anualmente cerca de 6 milh\u00f5es de pessoas no mundo, destes 600.000 s\u00e3o fumantes passivos e 200.000 s\u00e3o brasileiros. Esta taxa de mortalidade poder\u00e1 alcan\u00e7ar 8 milh\u00f5es de pessoas at\u00e9 2030, em caso de falha ou falta de implementa\u00e7\u00e3o de medidas de impacto de redu\u00e7\u00e3o da preval\u00eancia tab\u00e1gica. Mais de 80% destas mortes preven\u00edveis ocorrer\u00e3o em pessoas de pa\u00edses de baixo poder aquisitivo.<\/p>\n<p>Para o Dia Mundial Sem Tabaco de 2016, a OMS apela a todos os pa\u00edses para que se prepararem para adotar embalagens padronizadas de produtos do tabaco. Isso significa instituir regulamenta\u00e7\u00f5es que restrinjam ou pro\u00edbam o uso de logotipos, cores, imagens de marca ou informa\u00e7\u00f5es promocionais em ma\u00e7os e embalagens de produtos de tabaco. Segundo a OMS, essa \u00e9 uma importante medida de redu\u00e7\u00e3o da demanda, que diminui a atratividade dos produtos do tabaco, restringe o uso de embalagens como uma forma de publicidade e promo\u00e7\u00e3o e aumenta a efic\u00e1cia das advert\u00eancias sanit\u00e1rias.<\/p>\n<p><strong>Assessoria de Comunica\u00e7\u00e3o da Sesa<\/strong><br \/>\nSelma Oliveira \/ Marcus S\u00e1 \/ Helga Rackel ( <a href=\"mailto:selma.oliveira@saude.ce.gov.br\">selma.oliveira@saude.ce.gov.br<\/a> \/ 85 3101.5221 \/ 3101.5220)<br \/>\nTwitter: @SaudeCeara<br \/>\nwww.facebook.com\/SaudeCeara<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o Minist\u00e9rio da Sa\u00fade, o tabagismo \u00e9 respons\u00e1vel por 200 mil mortes todos os anos no Brasil \u2013 25% delas por angina e infarto do mioc\u00e1rdio, 45% por infarto agudo do mioc\u00e1rdio (abaixo de 65 anos) e 85% das mortes por bronquite e enfisema pulmonar. O h\u00e1bito tamb\u00e9m responde por 90% dos [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":7834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sesa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia mundial sem tabaco: o alerta sobre os perigos do cigarro - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"De acordo com o Minist\u00e9rio da Sa\u00fade, o tabagismo \u00e9 respons\u00e1vel por 200 mil mortes todos os anos no Brasil \u2013 25% delas por angina e infarto do mioc\u00e1rdio, 45% por infarto agudo do mioc\u00e1rdio (abaixo de 65 anos) e 85% das mortes por bronquite e enfisema pulmonar. O h\u00e1bito tamb\u00e9m responde por 90% dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-30T21:27:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-14T14:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"273\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro\",\"datePublished\":\"2016-05-30T21:27:52+00:00\",\"dateModified\":\"2019-01-14T14:18:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\"},\"wordCount\":768,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png\",\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\",\"name\":\"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png\",\"datePublished\":\"2016-05-30T21:27:52+00:00\",\"dateModified\":\"2019-01-14T14:18:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png\",\"width\":555,\"height\":273,\"caption\":\"alt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"De acordo com o Minist\u00e9rio da Sa\u00fade, o tabagismo \u00e9 respons\u00e1vel por 200 mil mortes todos os anos no Brasil \u2013 25% delas por angina e infarto do mioc\u00e1rdio, 45% por infarto agudo do mioc\u00e1rdio (abaixo de 65 anos) e 85% das mortes por bronquite e enfisema pulmonar. O h\u00e1bito tamb\u00e9m responde por 90% dos [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-05-30T21:27:52+00:00","article_modified_time":"2019-01-14T14:18:29+00:00","og_image":[{"width":555,"height":273,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro","datePublished":"2016-05-30T21:27:52+00:00","dateModified":"2019-01-14T14:18:29+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/"},"wordCount":768,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png","articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/","name":"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png","datePublished":"2016-05-30T21:27:52+00:00","dateModified":"2019-01-14T14:18:29+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_dia_mundial_sem_tabaco.png","width":555,"height":273,"caption":"alt"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/30\/dia-mundial-sem-tabaco-o-alerta-sobre-os-perigos-do-cigarro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Dia mundial sem tabaco: o alerta sobre os perigos do cigarro"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=7835"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7835\/revisions"}],"predecessor-version":[{"id":76836,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7835\/revisions\/76836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/7834"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=7835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=7835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=7835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}