{"id":78273,"date":"2019-04-05T17:09:55","date_gmt":"2019-04-05T20:09:55","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=78273"},"modified":"2019-04-05T17:10:35","modified_gmt":"2019-04-05T20:10:35","slug":"ter-uma-refeicao-equilibrada-previne-doencas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/","title":{"rendered":"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78275\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Alimentar-se bem cotidianamente \u00e9 uma forma de cuidar da pr\u00f3pria sa\u00fade. Pensar no corpo como uma m\u00e1quina que precisa de combust\u00edvel de qualidade facilita o entendimento de que n\u00e3o basta matar a fome para estar bem alimentado. A base nutricional de um indiv\u00edduo deve ser composta por alimentos naturais ou minimamente processados, que sofreram poucas altera\u00e7\u00f5es na composi\u00e7\u00e3o.<\/p>\n<p>A orienta\u00e7\u00e3o de nutricionistas \u00e9 desembalar menos e descascar mais. Frutas, legumes, verduras, tub\u00e9rculos (mandioca, batata doce, inhame etc.), ovos, castanhas, frutas secas, carnes resfriadas ou congeladas est\u00e3o entre os itens que podem ser inclu\u00eddos para uma refei\u00e7\u00e3o saud\u00e1vel e equilibrada.<\/p>\n<p>Entre os produtos processados, h\u00e1 os que contam com adi\u00e7\u00e3o de sal, a\u00e7\u00facar ou alguma outra subst\u00e2ncia culin\u00e1ria, como queijos, frutas em calda, p\u00e3es com farinha de trigo, extrato concentrado de tomate. Outros s\u00e3o formula\u00e7\u00f5es industriais que t\u00eam somente uma pequena propor\u00e7\u00e3o de alimentos naturais e grande quantidade de aditivos qu\u00edmicos, como os embutidos (presunto, lingui\u00e7a, mortadela, salsicha etc.), sucos em p\u00f3, salgadinhos em pacote e refrigerantes.<\/p>\n<p>A nutricionista da Secretaria da Sa\u00fade do Cear\u00e1, Vilma Oliveira, explica que o alimento tem potencial de gerar sa\u00fade no organismo. \u201cNa hora que voc\u00ea vai escolher, pode estar determinando ali a sua sa\u00fade. Quando voc\u00ea opta por alimentos saud\u00e1veis, como frutas, legumes, verduras, eles s\u00e3o protetores do nosso organismo contra as doen\u00e7as cr\u00f4nicas. Tem os alimentos que voc\u00ea pode usar de forma moderada, como as prote\u00ednas (carne, ovos, leite, peixe)\u201d, explica a profissional.<\/p>\n<p>Por outro lado, optar pela ingest\u00e3o frequente e em grande quantidade dos alimentos ultraprocessados pode gerar doen\u00e7as. \u201cEnt\u00e3o a alimenta\u00e7\u00e3o \u00e9 uma forma de se proteger das doen\u00e7as cr\u00f4nicas. Se a fam\u00edlia j\u00e1 tem uma tend\u00eancia a determinada doen\u00e7a, com a escolha adequada dos alimentos, voc\u00ea pode estar se protegendo ou atrasando esse tipo de problema\u201d, ressalta Vilma. Alimentos semi-prontos, com excesso de sal, a\u00e7\u00facar, gordura e condimentos contribuem para algumas doen\u00e7as.<\/p>\n<h4>Como montar o prato ideal<\/h4>\n<p>O prato ideal \u00e9 o que equilibra os tipos de alimentos dos grupos verde, amarelo e azul, segundo a cartilha <a href=\"https:\/\/189.28.128.100\/dab\/docs\/portaldab\/publicacoes\/alimentacao_cardioprotetora.pdf\" target=\"_blank\" rel=\"noopener\">Alimenta\u00e7\u00e3o Cardioprotetora<\/a>. O material foi elaborado pelo Minist\u00e9rio da Sa\u00fade em parceria com o Hospital do Cora\u00e7\u00e3o (HCor). A cartilha segue as orienta\u00e7\u00f5es do Guia Alimentar para a Popula\u00e7\u00e3o Brasileira e o Manual de orienta\u00e7\u00f5es para profissionais de Sa\u00fade da Aten\u00e7\u00e3o B\u00e1sica &#8211; Alimenta\u00e7\u00e3o Cardioprotetora.<\/p>\n<p>No grupo verde, composto por alimentos cardioprotetores, est\u00e3o os que mais cont\u00eam vitaminas, minerais, fibras e antioxidantes (verduras, frutas, legumes, leite e iogurte desnatados ou semidesnatados etc.). N\u00e3o fazem parte desse grupo nutrientes como gordura saturada, colesterol e s\u00f3dio, que podem prejudicar o cora\u00e7\u00e3o. Eles fornecem vitaminas, minerais, fibras e antioxidantes.<\/p>\n<p>Alimentos do grupo amarelo podem ser consumidos moderadamente, como p\u00e3es, cereais, \u00f3leos vegetais e farinhas. Como fornecem energia para as atividades do dia a dia, devem ser mantidos na dieta em menor quantidade, uma vez que garantem minerais, vitaminas, calorias, sal e gorduras. Carnes, queijos brancos e amarelos e manteiga s\u00e3o itens do grupo azul. Fontes de gordura saturada, sal e colesterol, esses alimentos podem ser prejudiciais ao cora\u00e7\u00e3o.<\/p>\n<p>No grupo vermelho, n\u00e3o recomendado para uma alimenta\u00e7\u00e3o saud\u00e1vel, est\u00e3o itens como macarr\u00e3o instant\u00e2neo, salgadinhos de pacote, sucos industrializados, refrigerantes, achocolatado em p\u00f3, sorvete, molhos industrializados, nuggets e achocalatados em p\u00f3, por exemplo. Esses alimentos devem ser evitados, pois contam com aditivos qu\u00edmicos como conservantes, estabilizantes, corantes, edulcorantes e aromatizantes.<\/p>\n<p>\u201c\u00c9 preciso evitar o saleiro na mesa e aqueles alimentos que sabidamente t\u00eam excesso de sal, como os embutidos e os enlatados. Quando a alimenta\u00e7\u00e3o traz mais os ultraprocessados, isso \u00e9 prejudicial\u201d, orienta Vilma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alimentar-se bem cotidianamente \u00e9 uma forma de cuidar da pr\u00f3pria sa\u00fade. Pensar no corpo como uma m\u00e1quina que precisa de combust\u00edvel de qualidade facilita o entendimento de que n\u00e3o basta matar a fome para estar bem alimentado. A base nutricional de um indiv\u00edduo deve ser composta por alimentos naturais ou minimamente processados, que sofreram poucas [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":78275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[85,697,236],"class_list":["post-78273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sesa","tag-alimentacao-saudavel","tag-cuidados","tag-prevencao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Alimentar-se bem cotidianamente \u00e9 uma forma de cuidar da pr\u00f3pria sa\u00fade. Pensar no corpo como uma m\u00e1quina que precisa de combust\u00edvel de qualidade facilita o entendimento de que n\u00e3o basta matar a fome para estar bem alimentado. A base nutricional de um indiv\u00edduo deve ser composta por alimentos naturais ou minimamente processados, que sofreram poucas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-05T20:09:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-05T20:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as\",\"datePublished\":\"2019-04-05T20:09:55+00:00\",\"dateModified\":\"2019-04-05T20:10:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\"},\"wordCount\":660,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg\",\"keywords\":[\"alimenta\u00e7\u00e3o saud\u00e1vel\",\"cuidados\",\"preven\u00e7\u00e3o\"],\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\",\"name\":\"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg\",\"datePublished\":\"2019-04-05T20:09:55+00:00\",\"dateModified\":\"2019-04-05T20:10:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/","og_locale":"pt_BR","og_type":"article","og_title":"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Alimentar-se bem cotidianamente \u00e9 uma forma de cuidar da pr\u00f3pria sa\u00fade. Pensar no corpo como uma m\u00e1quina que precisa de combust\u00edvel de qualidade facilita o entendimento de que n\u00e3o basta matar a fome para estar bem alimentado. A base nutricional de um indiv\u00edduo deve ser composta por alimentos naturais ou minimamente processados, que sofreram poucas [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2019-04-05T20:09:55+00:00","article_modified_time":"2019-04-05T20:10:35+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as","datePublished":"2019-04-05T20:09:55+00:00","dateModified":"2019-04-05T20:10:35+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/"},"wordCount":660,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg","keywords":["alimenta\u00e7\u00e3o saud\u00e1vel","cuidados","preven\u00e7\u00e3o"],"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/","name":"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg","datePublished":"2019-04-05T20:09:55+00:00","dateModified":"2019-04-05T20:10:35+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_no_prato_cb.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/05\/ter-uma-refeicao-equilibrada-previne-doencas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Ter uma refei\u00e7\u00e3o equilibrada previne doen\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/78273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=78273"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/78273\/revisions"}],"predecessor-version":[{"id":78278,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/78273\/revisions\/78278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/78275"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=78273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=78273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=78273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}