{"id":78211,"date":"2019-04-01T17:06:33","date_gmt":"2019-04-01T20:06:33","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=78211"},"modified":"2019-04-01T17:12:50","modified_gmt":"2019-04-01T20:12:50","slug":"atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/","title":{"rendered":"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-78212\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>Os cuidados di\u00e1rios com o corpo e a mente s\u00e3o necess\u00e1rios para uma melhor qualidade de vida. Para orientar sobre a import\u00e2ncia da mudan\u00e7a de h\u00e1bitos e como manter a sa\u00fade protegida, a Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) realizar\u00e1 entre os dias 5 e 11 de abril diferentes a\u00e7\u00f5es de promo\u00e7\u00e3o \u00e0 sa\u00fade. O Dia D ser\u00e1 no domingo, 7 de abril, Dia Mundial da Sa\u00fade, das 8 \u00e0s 11h30, no Parque Estadual do Coc\u00f3. A a\u00e7\u00e3o ser\u00e1 aberta ao p\u00fablico.<\/p>\n<p>A campanha da Sesa para o Dia Mundial da Sa\u00fade neste ano tem o tema \u201cPreven\u00e7\u00e3o hoje, sa\u00fade todo dia\u201d. Ser\u00e3o realizadas a\u00e7\u00f5es com o apoio da Secretaria do Meio Ambiente do Cear\u00e1 (Sema), Prefeitura Municipal de Fortaleza e Conselho Regional de Fisioterapia e Terapia Ocupacional da 6\u00aa Regi\u00e3o Cear\u00e1 (Crefito-CE).<\/p>\n<p>Na sexta-feira, 5, as atividades ser\u00e3o para os funcion\u00e1rios que atuam na Secretaria. J\u00e1 no domingo, 7, quem for ao Parque do Coc\u00f3 poder\u00e1 participar de sess\u00f5es de alongamento, acupuntura, terapia ocupacional, gin\u00e1stica laboral, al\u00e9m de outras atividades de sa\u00fade e bem-estar para toda a fam\u00edlia.<\/p>\n<p>No dia 9 de abril, uma equipe do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU 192 Cear\u00e1) realizar\u00e1 atividades educativas sobre doen\u00e7as cardiovasculares no Shopping Iguatemi. Os profissionais do N\u00facleo de Educa\u00e7\u00e3o Permanente do SAMU 192 Cear\u00e1 atender\u00e3o o p\u00fablico na pra\u00e7a central do t\u00e9rreo, pr\u00f3ximo \u00e0 pra\u00e7a de alimenta\u00e7\u00e3o, das 10 \u00e0s 22 horas.<\/p>\n<p>Na quinta-feira seguinte, 11 de abril, ocorrer\u00e1 o F\u00f3rum da Linha de Cuidado do Infarto Agudo do Mioc\u00e1rdio \u2013 Da preven\u00e7\u00e3o \u00e0 interven\u00e7\u00e3o. O evento ser\u00e1 no Hospital de Messejana Dr. Carlos Alberto Studart Gomes, das 8 \u00e0s 17 horas, para m\u00e9dicos e enfermeiros da rede p\u00fablica estadual inscritos.<\/p>\n<h4 class=\"destacado\"><a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/programacao_dia_mundial_saude_2019.pdf\" target=\"_blank\" rel=\"noopener\">Programa\u00e7\u00e3o<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Os cuidados di\u00e1rios com o corpo e a mente s\u00e3o necess\u00e1rios para uma melhor qualidade de vida. Para orientar sobre a import\u00e2ncia da mudan\u00e7a de h\u00e1bitos e como manter a sa\u00fade protegida, a Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) realizar\u00e1 entre os dias 5 e 11 de abril diferentes a\u00e7\u00f5es de promo\u00e7\u00e3o \u00e0 sa\u00fade. O [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":78212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[236,310,833],"class_list":["post-78211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sesa","tag-prevencao","tag-promocaodasaude","tag-qualidade-de-vida"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Os cuidados di\u00e1rios com o corpo e a mente s\u00e3o necess\u00e1rios para uma melhor qualidade de vida. Para orientar sobre a import\u00e2ncia da mudan\u00e7a de h\u00e1bitos e como manter a sa\u00fade protegida, a Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) realizar\u00e1 entre os dias 5 e 11 de abril diferentes a\u00e7\u00f5es de promo\u00e7\u00e3o \u00e0 sa\u00fade. O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-01T20:06:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-01T20:12:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade\",\"datePublished\":\"2019-04-01T20:06:33+00:00\",\"dateModified\":\"2019-04-01T20:12:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg\",\"keywords\":[\"preven\u00e7\u00e3o\",\"Promo\u00e7\u00e3o da Sa\u00fade\",\"qualidade de vida\"],\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\",\"name\":\"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg\",\"datePublished\":\"2019-04-01T20:06:33+00:00\",\"dateModified\":\"2019-04-01T20:12:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/","og_locale":"pt_BR","og_type":"article","og_title":"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Os cuidados di\u00e1rios com o corpo e a mente s\u00e3o necess\u00e1rios para uma melhor qualidade de vida. Para orientar sobre a import\u00e2ncia da mudan\u00e7a de h\u00e1bitos e como manter a sa\u00fade protegida, a Secretaria da Sa\u00fade do Cear\u00e1 (Sesa) realizar\u00e1 entre os dias 5 e 11 de abril diferentes a\u00e7\u00f5es de promo\u00e7\u00e3o \u00e0 sa\u00fade. O [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2019-04-01T20:06:33+00:00","article_modified_time":"2019-04-01T20:12:50+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade","datePublished":"2019-04-01T20:06:33+00:00","dateModified":"2019-04-01T20:12:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/"},"wordCount":328,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg","keywords":["preven\u00e7\u00e3o","Promo\u00e7\u00e3o da Sa\u00fade","qualidade de vida"],"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/","name":"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg","datePublished":"2019-04-01T20:06:33+00:00","dateModified":"2019-04-01T20:12:50+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2019\/04\/banner_dia_mundial_saude2019_cb.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2019\/04\/01\/atividades-de-educacao-e-prevencao-marcam-programacao-do-dia-mundial-da-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Atividades de educa\u00e7\u00e3o e preven\u00e7\u00e3o marcam programa\u00e7\u00e3o do Dia Mundial da Sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/78211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=78211"}],"version-history":[{"count":7,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/78211\/revisions"}],"predecessor-version":[{"id":78220,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/78211\/revisions\/78220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/78212"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=78211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=78211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=78211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}