{"id":7775,"date":"2016-05-17T21:41:54","date_gmt":"2016-05-18T00:41:54","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/"},"modified":"2019-01-14T11:08:57","modified_gmt":"2019-01-14T14:08:57","slug":"hgf-comemora-47-anos-com-posse-do-novo-diretor","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/","title":{"rendered":"HGF comemora 47 anos com posse do novo diretor"},"content":{"rendered":"<p><em><span style=\"font-size: 10px\"><strong>Fotos:<\/strong> Assessoria de Imprensa do HGF<\/span><\/em><\/p>\n<p>Nesta quarta-feira, 18 de maio, \u00e0s 9 horas, o Secret\u00e1rio da Sa\u00fade do Estado, Henrique Javi, dar\u00e1 posse ao novo diretor geral do Hospital Geral de Fortaleza, Jo\u00e3o Batista Silva. A solenidade de posse abre a programa\u00e7\u00e3o das comemora\u00e7\u00f5es dos 47 anos do HGF. Mais de 300 participantes, entre servidores \u2013 m\u00e9dicos, enfermeiros, pesquisadores, estudantes, t\u00e9cnicos, e os parceiros da \u00e1rea de sa\u00fade no Cear\u00e1, estar\u00e3o presentes no evento, que ir\u00e1 acontecer juntamente com a comemora\u00e7\u00e3o da 47\u00aa Reuni\u00e3o Anual do HGF.<\/p>\n<p>A programa\u00e7\u00e3o come\u00e7a com a posse do diretor geral. Logo em seguida, sob a tem\u00e1tica &#8220;O v\u00ednculo humanizado e o avan\u00e7o tecnol\u00f3gico na sa\u00fade&#8221;, profissionais debater\u00e3o sobre a tecnologia em cuidados paliativos e terapia intensiva, a import\u00e2ncia de manter o v\u00ednculo humanizado diante do avan\u00e7o tecnol\u00f3gico na sa\u00fade e o avan\u00e7o da telemedicina, contribuindo para um tratamento humanizado. Al\u00e9m dos debates, os participantes conhecer\u00e3o os novos projetos selecionados entre os 46 inscritos por estudiosos das mais diversas \u00e1reas de sa\u00fade, que estar\u00e3o apresentando seus trabalhos no audit\u00f3rio do hospital.<\/p>\n<p>Criado em 23 de maio de 1969, o HGF tem a miss\u00e3o de ser refer\u00eancia em atendimento de alta complexidade, ofertando servi\u00e7os humanizados, seguros e de boa qualidade.\u00a0 Atualmente o HGF ocupa 64 mil metros quadrados de \u00e1rea, possui 563 leitos e realiza atendimento em 63 especialidades e sub-especialidades. Al\u00e9m de um hospital com perfil terci\u00e1rio, atendendo pacientes com patologias de alta complexidade, o HGF tem tamb\u00e9m a importante miss\u00e3o de ensino.<\/p>\n<p>Ao longo de sua hist\u00f3ria, o HGF tem alcan\u00e7ado grandes conquistas, destacando-se o recorde em transplantes de rim, f\u00edgado, p\u00e2ncreas e c\u00f3rnea. \u00c9 a maior Unidade de AVC do pa\u00eds, com vinte leitos e capacidade para atender at\u00e9 150 pacientes por m\u00eas. Refer\u00eancia nas especialidades de Cirurgia Geral, Neurologia, Neurocirurgia, Reumatologia, Nefrologia, Transplante Renal, de F\u00edgado e de P\u00e2ncreas, Gineneco-obstetr\u00edcia, Traumato-ortopedia, Oftalmologia, entre outras.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-7774\" style=\"width: 555px;height: 274px\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_diretor_hgf_joabatista.jpg\" alt=\"alt\" width=\"555\" height=\"274\" \/><\/p>\n<p><strong>Perfil do novo diretor<\/strong><\/p>\n<p>Com gradua\u00e7\u00e3o em Medicina pela Universidade Federal do Cear\u00e1 (1988) e mestrado em Obstetr\u00edcia e Ginecologia pela Universidade de S\u00e3o Paulo (1994), Jo\u00e3o Batista tem especializa\u00e7\u00e3o em Gest\u00e3o Hospitalar, Sistemas de Sa\u00fade e Acredita\u00e7\u00e3o Hospitalar pela UFC e desenvolve consultoria e pesquisa na \u00e1rea de gest\u00e3o de servi\u00e7os de sa\u00fade. Na \u00e1rea cl\u00ednica tem atua\u00e7\u00e3o relacionada \u00e0s doen\u00e7as sexualmente transmiss\u00edveis, HPV, preven\u00e7\u00e3o do c\u00e2ncer e, ainda, \u00e0 medicina do trabalho. Atualmente \u00e9 professor-assistente da UFC. H\u00e1 mais de uma semana Jo\u00e3o Batista j\u00e1 est\u00e1 dentro do Hospital Geral de Fortaleza, tomando p\u00e9 de toda a complexidade da gest\u00e3o. Ele antecipa, na entrevista feita pela Assessoria de Comunica\u00e7\u00e3o do HGF,\u00a0 suas aspira\u00e7\u00f5es na gest\u00e3o do maior hospital p\u00fablico do Estado.<\/p>\n<p><strong>Quais s\u00e3o os principais planos para HGF?<\/strong><br \/>\nEu pretendo criar um modelo de gerenciamento para cada unidade do hospital. Esse \u00e9 o maior hospital do Estado, grande em tamanho e em n\u00famero de atendimentos. \u00c9 um hospital que recebe muita demanda que necessita de tecnologia mais avan\u00e7ada. Por conta de ser um hospital de grande porte, com emerg\u00eancia de portas abertas, 24 horas, precisa adequar a estrutura a essa alta demanda.<\/p>\n<p><strong>Quais as estrat\u00e9gias que ser\u00e3o utilizadas para o alcance dos resultados?<\/strong><br \/>\nA nossa proposta s\u00e3o estabelecer acordos de coopera\u00e7\u00e3o, que possamos ser mais \u00fateis para os hospitais e os hospitais possam ser mais \u00fateis para o HGF. Vamos fortalecer o sistema de rede na assist\u00eancia \u00e0 sa\u00fade da popula\u00e7\u00e3o. \u00c9 uma ideia de coopera\u00e7\u00e3o e n\u00e3o de competitividade. Tem que ser o Estado quem mais coopera, com o Cear\u00e1 atingindo melhores n\u00edveis de qualidade na aten\u00e7\u00e3o aos pacientes\u00a0 e\u00a0 n\u00e3o um hospital isoladamente.\u00a0 \u00c9 importante que a gente eleve a qualidade de todos os hospitais da rede, juntos. Eu venho para trabalhar a vis\u00e3o do coletivo para o individual, o hospital \u00e9 de excel\u00eancia, se ele \u00e9 de excel\u00eancia os servi\u00e7os e os profissionais s\u00e3o de excel\u00eancia. A institui\u00e7\u00e3o \u00e9 que tem que ser excelente.<\/p>\n<p><strong>Que marca quer implantar no HGF?<\/strong><br \/>\nUm modelo de gest\u00e3o profissional para que possamos trabalhar utilizando as ferramentas mais avan\u00e7adas de gest\u00e3o e ter um alinhamento estrat\u00e9gico, com mais satisfa\u00e7\u00e3o para os profissionais e melhores resultados para os pacientes. Estamos determinados em construir a boa pr\u00e1tica de buscar sempre o melhor resultado na assist\u00eancia do paciente.<\/p>\n<p><strong>Assessoria de Imprensa do HGF<\/strong><br \/>\nD\u00e9bora Morais\/Thiago Vidal<br \/>\n(85) 3101.7086 \/ 9.8726.1212<br \/>\n<a href=\"mailto:debora.morais@hgf.ce.gov.br\">debora.morais@hgf.ce.gov.br<\/a><br \/>\nTwitter: @Hospital_HGF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotos: Assessoria de Imprensa do HGF Nesta quarta-feira, 18 de maio, \u00e0s 9 horas, o Secret\u00e1rio da Sa\u00fade do Estado, Henrique Javi, dar\u00e1 posse ao novo diretor geral do Hospital Geral de Fortaleza, Jo\u00e3o Batista Silva. A solenidade de posse abre a programa\u00e7\u00e3o das comemora\u00e7\u00f5es dos 47 anos do HGF. Mais de 300 participantes, entre [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":7773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[496],"tags":[],"class_list":["post-7775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hgf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HGF comemora 47 anos com posse do novo diretor - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HGF comemora 47 anos com posse do novo diretor - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Fotos: Assessoria de Imprensa do HGF Nesta quarta-feira, 18 de maio, \u00e0s 9 horas, o Secret\u00e1rio da Sa\u00fade do Estado, Henrique Javi, dar\u00e1 posse ao novo diretor geral do Hospital Geral de Fortaleza, Jo\u00e3o Batista Silva. A solenidade de posse abre a programa\u00e7\u00e3o das comemora\u00e7\u00f5es dos 47 anos do HGF. Mais de 300 participantes, entre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-18T00:41:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-14T14:08:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"HGF comemora 47 anos com posse do novo diretor\",\"datePublished\":\"2016-05-18T00:41:54+00:00\",\"dateModified\":\"2019-01-14T14:08:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\"},\"wordCount\":799,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png\",\"articleSection\":[\"Hospital Geral de Fortaleza (HGF)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\",\"name\":\"HGF comemora 47 anos com posse do novo diretor - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png\",\"datePublished\":\"2016-05-18T00:41:54+00:00\",\"dateModified\":\"2019-01-14T14:08:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png\",\"width\":555,\"height\":274,\"caption\":\"alt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HGF comemora 47 anos com posse do novo diretor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HGF comemora 47 anos com posse do novo diretor - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/","og_locale":"pt_BR","og_type":"article","og_title":"HGF comemora 47 anos com posse do novo diretor - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Fotos: Assessoria de Imprensa do HGF Nesta quarta-feira, 18 de maio, \u00e0s 9 horas, o Secret\u00e1rio da Sa\u00fade do Estado, Henrique Javi, dar\u00e1 posse ao novo diretor geral do Hospital Geral de Fortaleza, Jo\u00e3o Batista Silva. A solenidade de posse abre a programa\u00e7\u00e3o das comemora\u00e7\u00f5es dos 47 anos do HGF. Mais de 300 participantes, entre [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-05-18T00:41:54+00:00","article_modified_time":"2019-01-14T14:08:57+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"HGF comemora 47 anos com posse do novo diretor","datePublished":"2016-05-18T00:41:54+00:00","dateModified":"2019-01-14T14:08:57+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/"},"wordCount":799,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png","articleSection":["Hospital Geral de Fortaleza (HGF)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/","name":"HGF comemora 47 anos com posse do novo diretor - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png","datePublished":"2016-05-18T00:41:54+00:00","dateModified":"2019-01-14T14:08:57+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_novo_diretor_hgf.png","width":555,"height":274,"caption":"alt"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/17\/hgf-comemora-47-anos-com-posse-do-novo-diretor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"HGF comemora 47 anos com posse do novo diretor"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=7775"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7775\/revisions"}],"predecessor-version":[{"id":76824,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7775\/revisions\/76824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/7773"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=7775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=7775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=7775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}