{"id":7723,"date":"2016-05-06T14:15:34","date_gmt":"2016-05-06T17:15:34","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/"},"modified":"2019-01-14T10:57:13","modified_gmt":"2019-01-14T13:57:13","slug":"dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/","title":{"rendered":"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos"},"content":{"rendered":"<p>Luis Gustavo e Luis Guilherme passaram pela primeira consulta de retorno ap\u00f3s a alta do M\u00e9todo Canguru do Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, na manh\u00e3 dessa quinta-feira, 5 de maio. Sabe qual foi a not\u00edcia? \u201cEles est\u00e3o \u00f3timos. Passaram a primeira semana muito bem, em casa\u201d, conta Francisca Deizivane dos Santos, m\u00e3es dos g\u00eameos. O pai, Sttefano Luis de Almeida Auad, est\u00e1 animado. Ele faz quest\u00e3o de ajudar com os filhos. Segundo ele, todos precisam estar envolvidos no cuidado.<\/p>\n<p>Os filhos de Deizivane nasceram prematuros na maternidade do HGCC, depois de um descolamento de placenta, no dia seis de abril. Ap\u00f3s um tempo no ber\u00e7\u00e1rio de m\u00e9dio risco, ela resolveu continuar o tratamento com o M\u00e9todo Canguru. \u201cEu tinha muita dificuldade. Quis vir para me sentir mais segura, para poder amamentar e cuidar dos meus filhos.\u201d, revela. O Dia das M\u00e3es para a fam\u00edlia ser\u00e1 bem mais feliz ap\u00f3s a confirma\u00e7\u00e3o do bom estado de sa\u00fade dos beb\u00eas.<\/p>\n<p>Nat\u00e9rcia Bruno, enfermeira do Canguru, assegura que a fam\u00edlia deve ser envolvida em todo o processo de cuidados do rec\u00e9m-nascido. No Hospital C\u00e9sar Cals, isso j\u00e1 acontece desde o pr\u00e9-natal de alto risco. Ela conta que as visitas \u00e0s m\u00e3es no ambiente do m\u00e9todo n\u00e3o s\u00e3o limitadas. Pais, av\u00f3s, irm\u00e3os, tias, primos, todos podem passar um momento com os beb\u00eas. \u201cA fam\u00edlia faz parte do tratamento. N\u00f3s trabalhamos a desospitaliza\u00e7\u00e3o e as orienta\u00e7\u00f5es que passamos s\u00e3o para o futuro\u201d, esclarece a enfermeira.<\/p>\n<p>Para participar do m\u00e9todo, que \u00e9 uma maneira de cuidar de beb\u00eas prematuros, a m\u00e3e \u00e9 convidada. Ela recebe todas as informa\u00e7\u00f5es e orienta\u00e7\u00f5es para o cuidado com o filho. O rec\u00e9m-nascido s\u00f3 \u00e9 admitido quando ele n\u00e3o precisa mais de aparelhos, n\u00e3o faz mais uso de antibi\u00f3ticos, est\u00e1 clinicamente est\u00e1vel, e a m\u00e3e aceita o convite.<\/p>\n<p>Quando o beb\u00ea j\u00e1 passa pelos cuidados do Canguru, muitas s\u00e3o as vantagens comprovadas, como o controle da temperatura corporal da crian\u00e7a, que \u00e9 aquecida pela temperatura da pele da m\u00e3e; o aleitamento materno, a partir do fortalecimento do v\u00ednculo, o aumento da afetividade entre m\u00e3e e beb\u00ea; e a m\u00e3e passa a acreditar e a confiar na recupera\u00e7\u00e3o do pr\u00f3prio filho. Tudo isso por conta do envolvimento total da m\u00e3e, do contato pele a pele e da presen\u00e7a da fam\u00edlia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-7722\" style=\"width: 555px;height: 274px\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc1.png\" alt=\"alt\" width=\"555\" height=\"274\" \/><\/p>\n<p>\u00c9 dessa forma que William Gomes da Silva, pai de Jo\u00e3o Emanuel, ajuda a esposa, Diana de Souza Nascimento, nos cuidados com o primeiro filho do casal. Ele vem ao Hospital C\u00e9sar Cals todos os dias. Enquanto ela toma banho, ele aproveita para sentir o filho bem mais pr\u00f3ximo. Quando Jo\u00e3o nasceu, ele foi encaminhado para a Unidade de Terapia Intensiva Neonatal. O pai dele n\u00e3o podia segur\u00e1-lo, mas agora \u00e9 diferente. \u201c\u00c9 uma maravilha poder segurar o meu filho\u201d, conta feliz com a sensa\u00e7\u00e3o.<\/p>\n<p>Atualmente, quatro m\u00e3es est\u00e3o no M\u00e9todo Canguru. Somente nos quatro primeiros meses de 2016, 40 beb\u00eas j\u00e1 receberam os cuidados intensivos das m\u00e3es e profissionais envolvidos. A estrutura conta com jardim, sala de jantar, sala de estar, cozinha, quartos e banheiros. Nada lembra a estrutura hospitalar. A aten\u00e7\u00e3o passa por uma equipe multiprofissional formada por enfermeiros, m\u00e9dicos, psic\u00f3logos, assistentes sociais, fisioterapeutas, t\u00e9cnicos e auxiliares de enfermagem.<\/p>\n<p><strong>Assessoria de Comunica\u00e7\u00e3o do HGCC<\/strong><br \/>\nWescley Jorge<br \/>\n<a href=\"mailto:ascom@hgcc.ce.gov.br\">ascom@hgcc.ce.gov.br<\/a> \/ 85 3101.5323<br \/>\nFacebook.com\/HospitalGeralCesarCals<br \/>\nTwitter: @Hosp_CesarCals<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Gustavo e Luis Guilherme passaram pela primeira consulta de retorno ap\u00f3s a alta do M\u00e9todo Canguru do Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, na manh\u00e3 dessa quinta-feira, 5 de maio. Sabe qual foi a not\u00edcia? \u201cEles est\u00e3o \u00f3timos. Passaram a primeira semana muito bem, em casa\u201d, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":7721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[501],"tags":[],"class_list":["post-7723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hgcc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Luis Gustavo e Luis Guilherme passaram pela primeira consulta de retorno ap\u00f3s a alta do M\u00e9todo Canguru do Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, na manh\u00e3 dessa quinta-feira, 5 de maio. Sabe qual foi a not\u00edcia? \u201cEles est\u00e3o \u00f3timos. Passaram a primeira semana muito bem, em casa\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-06T17:15:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-14T13:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos\",\"datePublished\":\"2016-05-06T17:15:34+00:00\",\"dateModified\":\"2019-01-14T13:57:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\"},\"wordCount\":638,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png\",\"articleSection\":[\"Hospital Geral Dr. C\u00e9sar Cals (HGCC)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\",\"name\":\"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png\",\"datePublished\":\"2016-05-06T17:15:34+00:00\",\"dateModified\":\"2019-01-14T13:57:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png\",\"width\":555,\"height\":274,\"caption\":\"alt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Luis Gustavo e Luis Guilherme passaram pela primeira consulta de retorno ap\u00f3s a alta do M\u00e9todo Canguru do Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado do Cear\u00e1, na manh\u00e3 dessa quinta-feira, 5 de maio. Sabe qual foi a not\u00edcia? \u201cEles est\u00e3o \u00f3timos. Passaram a primeira semana muito bem, em casa\u201d, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-05-06T17:15:34+00:00","article_modified_time":"2019-01-14T13:57:13+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos","datePublished":"2016-05-06T17:15:34+00:00","dateModified":"2019-01-14T13:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/"},"wordCount":638,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png","articleSection":["Hospital Geral Dr. C\u00e9sar Cals (HGCC)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/","name":"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png","datePublished":"2016-05-06T17:15:34+00:00","dateModified":"2019-01-14T13:57:13+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/05\/banner_metodo_canguru_hgcc0.png","width":555,"height":274,"caption":"alt"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/05\/06\/dia-das-maes-feliz-com-a-saude-dos-gemeos-para-a-familia-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Dia das m\u00e3es feliz com a sa\u00fade dos g\u00eameos para a fam\u00edlia Santos"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=7723"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7723\/revisions"}],"predecessor-version":[{"id":76808,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7723\/revisions\/76808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/7721"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=7723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=7723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=7723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}