{"id":75262,"date":"2018-12-20T13:53:28","date_gmt":"2018-12-20T16:53:28","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=75262"},"modified":"2018-12-20T16:11:44","modified_gmt":"2018-12-20T19:11:44","slug":"governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/","title":{"rendered":"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-81623\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg\" alt=\"\" width=\"961\" height=\"637\" \/><\/p>\n<p><em>Os primeiros profissionais devem iniciar atendimento a partir de mar\u00e7o de 2019<\/em><\/p>\n<p>O governador do Cear\u00e1, Camilo Santana, sancionou na manh\u00e3 desta quinta-feira (20) a lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1. A assinatura foi realizada em coletiva de imprensa, que contou com a participa\u00e7\u00e3o do prefeito de Fortaleza, Roberto Cl\u00e1udio, do secret\u00e1rio da Sa\u00fade do Estado, Henrique Javi, da secret\u00e1ria da Sa\u00fade de Fortaleza, Joana Maciel, do superintendente da Escola de Sa\u00fade P\u00fablica, Salustiano Pessoa, e do presidente da Aprece, Gadiel Gon\u00e7alves.<\/p>\n<p>O Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 \u00e9 uma iniciativa do governo estadual para preencher as vagas abertas no Programa Mais M\u00e9dicos com a sa\u00edda dos profissionais cubanos. \u201cA demanda surgiu a partir da necessidade de preencher as vagas com a sa\u00edda desses profissionais, por\u00e9m nosso intuito n\u00e3o \u00e9 apenas substituir mas ampliar o Programa Mais M\u00e9dicos e garantir a cobertura de 100% de atendimento m\u00e9dico na aten\u00e7\u00e3o prim\u00e1ria\u201d, disse o governador Camilo Santana.<\/p>\n<p>A lei de iniciativa do Poder Executivo visa estimular a qualifica\u00e7\u00e3o e valoriza\u00e7\u00e3o dos profissionais de sa\u00fade do Estado, com o pagamento da bolsa de R$ 11.865,60, mesmo valor pago no Programa Mais M\u00e9dicos, al\u00e9m de oferecer curso de p\u00f3s-gradua\u00e7\u00e3o em \u201cAten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade\u201d, com dura\u00e7\u00e3o de um ano, sob responsabilidade da ESP\/CE. A gradua\u00e7\u00e3o tamb\u00e9m somar\u00e1 pontos em sele\u00e7\u00f5es nas resid\u00eancias nos hospitais estaduais.<\/p>\n<p>\u201cO Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 vai fortalecer a aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade, na perspectiva de formar profissionais m\u00e9dicos que se sintam atra\u00eddos para vivenciar a experi\u00eancia e forma\u00e7\u00e3o em sa\u00fade da fam\u00edlia, bem como estimular e apoiar a promo\u00e7\u00e3o da sa\u00fade nos munic\u00edpios\u201d, avalia o secret\u00e1rio da Sa\u00fade do Cear\u00e1, Henrique Javi.<\/p>\n<p>Com atua\u00e7\u00e3o nos eixos de ensino, pesquisa e extens\u00e3o, o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 buscar\u00e1 criar mecanismos que reduzam situa\u00e7\u00f5es de vulnerabilidade e os riscos \u00e0 sa\u00fade da popula\u00e7\u00e3o. A estrat\u00e9gia educacional ser\u00e1 baseada em ambientes de trabalho, favorecendo a integra\u00e7\u00e3o ensino-servi\u00e7o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-81627\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02867.jpg\" alt=\"\" width=\"860\" height=\"548\" \/><\/p>\n<h3>Implementa\u00e7\u00e3o<\/h3>\n<p>Para a implementa\u00e7\u00e3o do M\u00e9dicos da Fam\u00edlia Cear\u00e1, a Secretaria da Sa\u00fade realizar\u00e1 uma convoca\u00e7\u00e3o para ades\u00e3o dos munic\u00edpios ao Programa. \u201cA Sesa est\u00e1 realizando um levantamento com a demanda dos munic\u00edpios do interior do estado. A partir da ades\u00e3o, o Governo do Cear\u00e1 far\u00e1 um aporte de recursos de acordo com o tamanho e as condi\u00e7\u00f5es do munic\u00edpio\u201d, esclareceu Camilo Santana.<\/p>\n<h3>Fortaleza<\/h3>\n<p>Primeiro munic\u00edpio cearense a receber o programa, em Fortaleza ser\u00e3o contratados 140 m\u00e9dicos a partir de edital que ser\u00e1 lan\u00e7ado no come\u00e7o de 2019, com previs\u00e3o de in\u00edcio da capacita\u00e7\u00e3o para o m\u00eas de mar\u00e7o. \u201cEm Fortaleza, a Prefeitura Municipal ficar\u00e1 respons\u00e1vel pelo pagamento da bolsa integral, com previs\u00e3o de investimento de cerca de R$ 20 milh\u00f5es anuais, ficando o Estado encarregado pela sele\u00e7\u00e3o, qualifica\u00e7\u00e3o e coordena\u00e7\u00e3o a cargo da Escola de Sa\u00fade P\u00fablica\u201d, pontuou o prefeito Roberto Cl\u00e1udio.<\/p>\n<p>O prefeito defendeu que, somando-se aos profissionais vindos do programa federal, o M\u00e9dico da Fam\u00edlia Fortaleza busca a integralidade da aten\u00e7\u00e3o b\u00e1sica. \u201cBuscamos, com o preenchimento dessas vagas, beneficiar especialmente as fam\u00edlias das \u00e1reas mais vulner\u00e1veis de Fortaleza\u201d, afirmou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-81624\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02824.jpg\" alt=\"\" width=\"837\" height=\"697\" \/><\/p>\n<h3>Interioriza\u00e7\u00e3o<\/h3>\n<p>O prefeito de S\u00e3o Benedito e presidente da Associa\u00e7\u00e3o dos Prefeitos do Cear\u00e1 (Aprece), Gadyel Gon\u00e7alves, relata a dificuldade encontrada pelos gestores municipais em preencher as vagas. S\u00e3o Benedito perdeu 7 dos 12 profissionais que atuavam no munic\u00edpio.<\/p>\n<p>\u201cEm contato com os prefeitos municipais, a preocupa\u00e7\u00e3o \u00e9 uma s\u00f3. Dos mais de 200 m\u00e9dicos homologados no Programa Mais M\u00e9dicos, muitos profissionais chegavam nos munic\u00edpios e diziam que n\u00e3o dava para ficar na cidade. Acreditamos que a ferramenta vai ajudar muito para que a sa\u00fade chegue na ponta, nos munic\u00edpios menores e mais distantes da capital\u201d, disse.<\/p>\n<h3>IJF<\/h3>\n<p>Na ocasi\u00e3o tamb\u00e9m foi anunciada a abertura de mais 71 leitos no segundo andar do IJF 2 at\u00e9 o final do ano. Com os 59 leitos liberados no primeiro andar, em outubro deste ano, o hospital somar\u00e1 130 novas vagas para receber pacientes. A constru\u00e7\u00e3o est\u00e1 sendo realiza dentro do Programa Juntos Por Fortaleza, uma parceria entre o Governo do Cear\u00e1 e a Prefeitura da Capital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os primeiros profissionais devem iniciar atendimento a partir de mar\u00e7o de 2019 O governador do Cear\u00e1, Camilo Santana, sancionou na manh\u00e3 desta quinta-feira (20) a lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1. A assinatura foi realizada em coletiva de imprensa, que contou com a participa\u00e7\u00e3o do prefeito de Fortaleza, Roberto Cl\u00e1udio, do secret\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[328,847,848],"class_list":["post-75262","post","type-post","status-publish","format-standard","hentry","category-sesa","tag-lei","tag-mais-medicos","tag-programamedicodafamiliaceara"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Os primeiros profissionais devem iniciar atendimento a partir de mar\u00e7o de 2019 O governador do Cear\u00e1, Camilo Santana, sancionou na manh\u00e3 desta quinta-feira (20) a lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1. A assinatura foi realizada em coletiva de imprensa, que contou com a participa\u00e7\u00e3o do prefeito de Fortaleza, Roberto Cl\u00e1udio, do secret\u00e1rio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-20T16:53:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T19:11:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1\",\"datePublished\":\"2018-12-20T16:53:28+00:00\",\"dateModified\":\"2018-12-20T19:11:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\"},\"wordCount\":779,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg\",\"keywords\":[\"Lei\",\"mais m\u00e9dicos\",\"programam\u00e9dicodafam\u00edliacear\u00e1\"],\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\",\"name\":\"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg\",\"datePublished\":\"2018-12-20T16:53:28+00:00\",\"dateModified\":\"2018-12-20T19:11:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage\",\"url\":\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg\",\"contentUrl\":\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/","og_locale":"pt_BR","og_type":"article","og_title":"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Os primeiros profissionais devem iniciar atendimento a partir de mar\u00e7o de 2019 O governador do Cear\u00e1, Camilo Santana, sancionou na manh\u00e3 desta quinta-feira (20) a lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1. A assinatura foi realizada em coletiva de imprensa, que contou com a participa\u00e7\u00e3o do prefeito de Fortaleza, Roberto Cl\u00e1udio, do secret\u00e1rio [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2018-12-20T16:53:28+00:00","article_modified_time":"2018-12-20T19:11:44+00:00","og_image":[{"url":"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1","datePublished":"2018-12-20T16:53:28+00:00","dateModified":"2018-12-20T19:11:44+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/"},"wordCount":779,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg","keywords":["Lei","mais m\u00e9dicos","programam\u00e9dicodafam\u00edliacear\u00e1"],"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/","name":"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg","datePublished":"2018-12-20T16:53:28+00:00","dateModified":"2018-12-20T19:11:44+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#primaryimage","url":"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg","contentUrl":"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2018\/12\/181220_COLETIVA-MEDICO-DA-FAMILIA-CE_TM02581.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/12\/20\/governador-camilo-santana-sanciona-lei-que-cria-o-programa-medico-da-familia-ceara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Governador Camilo Santana sanciona lei que cria o Programa M\u00e9dico da Fam\u00edlia Cear\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/75262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=75262"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/75262\/revisions"}],"predecessor-version":[{"id":75277,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/75262\/revisions\/75277"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=75262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=75262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=75262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}