{"id":7405,"date":"2016-02-25T17:51:23","date_gmt":"2016-02-25T20:51:23","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/"},"modified":"2019-01-10T14:54:15","modified_gmt":"2019-01-10T17:54:15","slug":"hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/","title":{"rendered":"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10px\"><strong>Foto: <\/strong>Assessoria de Comunica\u00e7\u00e3o do HGCC<\/span><\/p>\n<p>Todo paciente que chega ao Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado, tem seus dados, como nome, idade, data de nascimento, entre outros, inseridos no prontu\u00e1rio, na ficha de interna\u00e7\u00e3o, no sistema informatizado e agora na pulseira de identifica\u00e7\u00e3o. Na segunda-feira, 22, quando foi implantado o novo modelo de identifica\u00e7\u00e3o, os pacientes internados passaram a receber a pulseira, onde s\u00e3o informados dados como o nome do paciente, a data de nascimento, o n\u00famero do prontu\u00e1rio e o nome da m\u00e3e do paciente.<\/p>\n<p>A pulseira de identifica\u00e7\u00e3o ir\u00e1 refor\u00e7ar ainda mais os mecanismos j\u00e1 adotados para garantir toda seguran\u00e7a poss\u00edvel ao paciente internado, no ato de confer\u00eancia dos dados. As informa\u00e7\u00f5es s\u00e3o essenciais para que os profissionais de sa\u00fade possam confirmar e assegurar que o paciente receba a condu\u00e7\u00e3o correta do seu tratamento em todos os est\u00e1gios da interna\u00e7\u00e3o.<\/p>\n<p>O agricultor Joseane Silveira de Moraes recebeu a pulseira assim que foi internado na ter\u00e7a-feira, 23. Ele sofreu um derrame pleural e est\u00e1 em tratamento no Bloco 500, destinado \u00e0s doen\u00e7as respirat\u00f3rias. Segundo Joseane, \u00e9 a primeira vez que ele utiliza esse tipo de identifica\u00e7\u00e3o. \u201cToda inova\u00e7\u00e3o \u00e9 muito v\u00e1lida, desde que venha melhorar o atendimento\u201d, ressalta. Para N\u00facleo de Assist\u00eancia \u00e0 Seguran\u00e7a do Paciente (NASP) e a Ger\u00eancia de Risco, o uso da pulseira \u00e9 mais um instrumento voltado para evitar a ocorr\u00eancia de eventos adversos, garantindo mais seguran\u00e7a aos pacientes internados.<\/p>\n<p>A partir de agora, os profissionais de sa\u00fade respons\u00e1veis pelos cuidados dos pacientes, al\u00e9m de conferir as informa\u00e7\u00f5es no prontu\u00e1rio, na ficha de identifica\u00e7\u00e3o e na placa informativa de cada leito, dever\u00e3o checar os dados nas pulseiras. A confer\u00eancia ocorre antes da realiza\u00e7\u00e3o de qualquer exame, administra\u00e7\u00e3o de medica\u00e7\u00e3o, verifica\u00e7\u00e3o de sinais vitais e procedimentos, transfer\u00eancias, entrega de exames, carta de alta, antes da alimenta\u00e7\u00e3o e, com especial aten\u00e7\u00e3o, antes do paciente ser encaminhado para procedimentos cir\u00fargicos.<\/p>\n<p>No Hospital C\u00e9sar Cals, a identifica\u00e7\u00e3o dos pacientes est\u00e1 de acordo com as diretrizes da Portaria GM\/ MS n\u00ba 529\/ 2013 e a RDC\/ Anvisa n\u00ba 36\/ 2013, que institui o Programa Nacional de Seguran\u00e7a do Paciente, no qual devem ser observadas a cria\u00e7\u00e3o do N\u00facleo de Seguran\u00e7a do Paciente, notifica\u00e7\u00e3o de eventos adversos e ado\u00e7\u00e3o de medidas para evitar riscos no cuidado em sa\u00fade. O paciente, identificado no ato da admiss\u00e3o, possui um prontu\u00e1rio com todas as informa\u00e7\u00f5es relevantes, como exames, diagn\u00f3stico, medica\u00e7\u00e3o, anamnese, evolu\u00e7\u00e3o do quadro cl\u00ednico, condutas, entre outras. A pulseira de identifica\u00e7\u00e3o \u00e9 mais um instrumento voltado para fortalecer a pol\u00edtica de seguran\u00e7a.<\/p>\n<p><strong>Assessoria de Comunica\u00e7\u00e3o do HGCC<\/strong><br \/>\nWescley Jorge<br \/>\n<a href=\"mailto:ascom@hgcc.ce.gov.br\">ascom@hgcc.ce.gov.br<\/a> \/ 85 3101.5323<br \/>\nFacebook.com\/HospitalGeralCesarCals<br \/>\nTwitter: @Hosp_CesarCals<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Foto: Assessoria de Comunica\u00e7\u00e3o do HGCC Todo paciente que chega ao Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado, tem seus dados, como nome, idade, data de nascimento, entre outros, inseridos no prontu\u00e1rio, na ficha de interna\u00e7\u00e3o, no sistema informatizado e agora na pulseira de identifica\u00e7\u00e3o. Na segunda-feira, 22, quando [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[501],"tags":[],"class_list":["post-7405","post","type-post","status-publish","format-standard","hentry","category-hgcc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Foto: Assessoria de Comunica\u00e7\u00e3o do HGCC Todo paciente que chega ao Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado, tem seus dados, como nome, idade, data de nascimento, entre outros, inseridos no prontu\u00e1rio, na ficha de interna\u00e7\u00e3o, no sistema informatizado e agora na pulseira de identifica\u00e7\u00e3o. Na segunda-feira, 22, quando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-25T20:51:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-10T17:54:15+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC\",\"datePublished\":\"2016-02-25T20:51:23+00:00\",\"dateModified\":\"2019-01-10T17:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Hospital Geral Dr. C\u00e9sar Cals (HGCC)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\",\"name\":\"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2016-02-25T20:51:23+00:00\",\"dateModified\":\"2019-01-10T17:54:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&nbsp; Foto: Assessoria de Comunica\u00e7\u00e3o do HGCC Todo paciente que chega ao Hospital Geral Dr. C\u00e9sar Cals, da rede p\u00fablica do Governo do Estado, tem seus dados, como nome, idade, data de nascimento, entre outros, inseridos no prontu\u00e1rio, na ficha de interna\u00e7\u00e3o, no sistema informatizado e agora na pulseira de identifica\u00e7\u00e3o. Na segunda-feira, 22, quando [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-02-25T20:51:23+00:00","article_modified_time":"2019-01-10T17:54:15+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC","datePublished":"2016-02-25T20:51:23+00:00","dateModified":"2019-01-10T17:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/"},"wordCount":513,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Hospital Geral Dr. C\u00e9sar Cals (HGCC)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/","name":"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2016-02-25T20:51:23+00:00","dateModified":"2019-01-10T17:54:15+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/02\/25\/hospital-cesar-cals-implanta-novo-modelo-de-identificacao-dos-pacientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Novo modelo de identifica\u00e7\u00e3o de pacientes \u00e9 implantado no HGCC"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=7405"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7405\/revisions"}],"predecessor-version":[{"id":76650,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7405\/revisions\/76650"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=7405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=7405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=7405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}