{"id":73103,"date":"2018-06-29T15:40:55","date_gmt":"2018-06-29T18:40:55","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=73103"},"modified":"2018-10-11T09:28:21","modified_gmt":"2018-10-11T12:28:21","slug":"aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/","title":{"rendered":"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota"},"content":{"rendered":"<p>O governador Camilo Santana e o secret\u00e1rio da Sa\u00fade do Cear\u00e1, Henrique Javi, entregam neste s\u00e1bado (30), \u00e0s 8 horas, no bairro Moura Brasil, 28 ambul\u00e2ncias para a renova\u00e7\u00e3o da frota do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU 192 Cear\u00e1). As novas Unidades de Suporte B\u00e1sico (USB) contemplar\u00e3o 25 munic\u00edpios: Capistrano, Eus\u00e9bio (2), Guaiuba, Itapipoca (2), Maracana\u00fa (2), Maranguape, Paracuru, Pentecoste, Reden\u00e7\u00e3o, S\u00e3o Gon\u00e7alo, Cascavel, General Sampaio, Icapu\u00ed, Itapaj\u00e9, Ocara, Pacatuba, Paraipaba, Horizonte, Pacajus, Aracati, Aracoiaba, Baturit\u00e9, Beberibe, Caucaia, Chorozinho.<\/p>\n<p>Atualmente, o SAMU 192 Cear\u00e1 d\u00e1 cobertura a 136 munic\u00edpios de 18 regi\u00f5es de Sa\u00fade, com 13 bases regionais e 52 bases descentralizadas. A frota atual \u00e9 de 100 ve\u00edculos: 19 Unidades de Suporte Avan\u00e7ado (USA, UTI m\u00f3vel), duas Unidades de Suporte Intermedi\u00e1rio (USI), 54 Unidades de Suporte B\u00e1sico (USB), 21 USB 4\u00d74, duas motol\u00e2ncias e dois aerom\u00e9dicos. O servi\u00e7o funciona 24 horas por dia com equipes multiprofissionais de sa\u00fade, formada por m\u00e9dicos, enfermeiros, auxiliares de enfermagem e socorristas, que prestam o socorro em qualquer lugar, seja ele privado (resid\u00eancias, locais de trabalho etc.) ou p\u00fablico (vias p\u00fablicas), ap\u00f3s chamada gratuita, feita atrav\u00e9s do 192.<\/p>\n<h3>Servi\u00e7o<\/h3>\n<p><strong>SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota<\/strong><\/p>\n<p>Data: s\u00e1bado, 30 de junho de 2018<\/p>\n<p>Hor\u00e1rio: 8h<\/p>\n<p>Local: Avenida Presidente Castelo Branco (Avenida Leste Oeste), n\u00famero 600, Bairro Moura Brasil, Fortaleza\/CE (ao lado da Igreja de Santa Edwiges).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Camilo Santana e o secret\u00e1rio da Sa\u00fade do Cear\u00e1, Henrique Javi, entregam neste s\u00e1bado (30), \u00e0s 8 horas, no bairro Moura Brasil, 28 ambul\u00e2ncias para a renova\u00e7\u00e3o da frota do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU 192 Cear\u00e1). As novas Unidades de Suporte B\u00e1sico (USB) contemplar\u00e3o 25 munic\u00edpios: Capistrano, Eus\u00e9bio (2), Guaiuba, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[673,674],"class_list":["post-73103","post","type-post","status-publish","format-standard","hentry","category-sesa","tag-ambulancias","tag-frota"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O governador Camilo Santana e o secret\u00e1rio da Sa\u00fade do Cear\u00e1, Henrique Javi, entregam neste s\u00e1bado (30), \u00e0s 8 horas, no bairro Moura Brasil, 28 ambul\u00e2ncias para a renova\u00e7\u00e3o da frota do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU 192 Cear\u00e1). As novas Unidades de Suporte B\u00e1sico (USB) contemplar\u00e3o 25 munic\u00edpios: Capistrano, Eus\u00e9bio (2), Guaiuba, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-29T18:40:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-11T12:28:21+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota\",\"datePublished\":\"2018-06-29T18:40:55+00:00\",\"dateModified\":\"2018-10-11T12:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\"},\"wordCount\":254,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"keywords\":[\"ambul\u00e2ncias\",\"frota\"],\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\",\"name\":\"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2018-06-29T18:40:55+00:00\",\"dateModified\":\"2018-10-11T12:28:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/","og_locale":"pt_BR","og_type":"article","og_title":"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O governador Camilo Santana e o secret\u00e1rio da Sa\u00fade do Cear\u00e1, Henrique Javi, entregam neste s\u00e1bado (30), \u00e0s 8 horas, no bairro Moura Brasil, 28 ambul\u00e2ncias para a renova\u00e7\u00e3o da frota do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU 192 Cear\u00e1). As novas Unidades de Suporte B\u00e1sico (USB) contemplar\u00e3o 25 munic\u00edpios: Capistrano, Eus\u00e9bio (2), Guaiuba, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2018-06-29T18:40:55+00:00","article_modified_time":"2018-10-11T12:28:21+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota","datePublished":"2018-06-29T18:40:55+00:00","dateModified":"2018-10-11T12:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/"},"wordCount":254,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"keywords":["ambul\u00e2ncias","frota"],"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/","name":"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2018-06-29T18:40:55+00:00","dateModified":"2018-10-11T12:28:21+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/06\/29\/aviso-de-pauta-samu-192-ceara-recebe-28-ambulancias-para-renovacao-da-frota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Aviso de pauta: SAMU 192 Cear\u00e1 recebe 28 ambul\u00e2ncias para renova\u00e7\u00e3o da frota"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/73103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=73103"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/73103\/revisions"}],"predecessor-version":[{"id":73104,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/73103\/revisions\/73104"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=73103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=73103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=73103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}