{"id":7297,"date":"2016-01-26T20:06:30","date_gmt":"2016-01-26T23:06:30","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/"},"modified":"2019-01-10T11:47:16","modified_gmt":"2019-01-10T14:47:16","slug":"hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/","title":{"rendered":"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es"},"content":{"rendered":"<p>Com o objetivo de aprimorar o atendimento ao p\u00fablico, o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Estado, realiza ao longo deste ano de 2016 um programa permanente de capacita\u00e7\u00e3o dos profissionais que lidam diretamente com a popula\u00e7\u00e3o, seja presencialmente ou pelo telefone. O programa \u00e9 focado no desenvolvimento de compet\u00eancias pessoais e t\u00e9cnicas para a presta\u00e7\u00e3o de um servi\u00e7o mais humanizado, com efici\u00eancia e efetividade.<\/p>\n<p>O programa \u00e9 fruto de uma experi\u00eancia realizada entre os meses de setembro e outubro do ano passado que treinou 70% dos atendentes das recep\u00e7\u00f5es do hospital e do call center, a central de atendimento por telefone. O bom aproveitamento dos cursos mostrou a import\u00e2ncia de continuar os treinamentos de forma a motivar os atendentes e mant\u00ea-los alerta de seu papel para a satisfa\u00e7\u00e3o dos pacientes, segundo o coordenador do N\u00facleo de Atendimento ao Cliente (NAC), Elvis de Almeida.<\/p>\n<p>\u201cDesde 2014 busc\u00e1vamos desenvolver esse treinamento com a equipe. A nossa ideia \u00e9 motivar os colaboradores, promovendo uma reciclagem de conhecimentos, e estimular o trabalho em equipe, buscando uma mudan\u00e7a de comportamento a fim de solucionar as quest\u00f5es dos pacientes\u201d, afirmou. \u201cNeste ano teremos essas capacita\u00e7\u00f5es de forma sistem\u00e1tica, sempre na pen\u00faltima sexta-feira de cada m\u00eas\u201d, completou.<\/p>\n<p>A psic\u00f3loga dos Recursos Humanos do HGF, S\u00f4nia Paranagu\u00e1 de Santana, explica que os atendentes s\u00e3o os primeiros a terem contato com o usu\u00e1rio e a suas necessidades, num ambiente muito ativo e por vezes estressante. Para S\u00f4nia Paranagu\u00e1, que tamb\u00e9m \u00e9 facilitadora dos cursos, os participantes foram receptivos \u00e0s atividades propostas, com exposi\u00e7\u00e3o de problemas, sugest\u00e3o de solu\u00e7\u00f5es e de melhorias no servi\u00e7o.<\/p>\n<p>Para a assessora de atendimento ao p\u00fablico, Sara Freire, o curso instigou a reflex\u00e3o sobre as suas atividades di\u00e1rias. \u201cConsegui rever conceitos como prestatividade e rendimento, al\u00e9m de fatores importantes como o trato com a carga emotiva natural da minha fun\u00e7\u00e3o\u201d, declarou.<\/p>\n<p>Outro participante foi Gutemberg Oliveira, que trabalha na recep\u00e7\u00e3o do ambulat\u00f3rio. Ele disse que a capacita\u00e7\u00e3o contribuiu para que ele compreendesse melhor a situa\u00e7\u00e3o dos pacientes, muitos deles vindos do interior, tornando-se mais sens\u00edvel \u00e0s suas demandas. \u201cAchei interessante tamb\u00e9m a integra\u00e7\u00e3o com os colegas que tamb\u00e9m trabalham no atendimento. Ficamos mais cientes do que cada um faz e onde trabalha\u201d.<\/p>\n<p>A dona de casa Francisca Oliveira Barbosa, moradora de Caucaia, veio ao HGF marcar uma consulta de retorno ao endocrinologista para a sobrinha e elogiou o atendimento. \u201cA recepcionista foi bem prestativa e me explicou tudo direitinho. N\u00e3o tenho do que reclamar\u201d, disse. O eletricista Ant\u00f4nio Gumercindo da Silva Santos precisava agendar uma tomografia solicitada pelo m\u00e9dico e tamb\u00e9m fez um coment\u00e1rio positivo. \u201cQuem n\u00e3o gosta de ser bem atendido n\u00e3o \u00e9? Aqui foi tudo bem, resolveram meu problema\u201d, frisou.<\/p>\n<p><strong>Assessoria de Imprensa do HGF<\/strong><br \/>\nB\u00e1rbara Holanda\/ Thiago Vidal<br \/>\n(85) 3101.7086<br \/>\nTwitter: @Hospital_HGF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de aprimorar o atendimento ao p\u00fablico, o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Estado, realiza ao longo deste ano de 2016 um programa permanente de capacita\u00e7\u00e3o dos profissionais que lidam diretamente com a popula\u00e7\u00e3o, seja presencialmente ou pelo telefone. O programa \u00e9 focado no desenvolvimento de compet\u00eancias [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[496],"tags":[],"class_list":["post-7297","post","type-post","status-publish","format-standard","hentry","category-hgf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Com o objetivo de aprimorar o atendimento ao p\u00fablico, o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Estado, realiza ao longo deste ano de 2016 um programa permanente de capacita\u00e7\u00e3o dos profissionais que lidam diretamente com a popula\u00e7\u00e3o, seja presencialmente ou pelo telefone. O programa \u00e9 focado no desenvolvimento de compet\u00eancias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-26T23:06:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-10T14:47:16+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es\",\"datePublished\":\"2016-01-26T23:06:30+00:00\",\"dateModified\":\"2019-01-10T14:47:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Hospital Geral de Fortaleza (HGF)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\",\"name\":\"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2016-01-26T23:06:30+00:00\",\"dateModified\":\"2019-01-10T14:47:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/","og_locale":"pt_BR","og_type":"article","og_title":"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Com o objetivo de aprimorar o atendimento ao p\u00fablico, o Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Estado, realiza ao longo deste ano de 2016 um programa permanente de capacita\u00e7\u00e3o dos profissionais que lidam diretamente com a popula\u00e7\u00e3o, seja presencialmente ou pelo telefone. O programa \u00e9 focado no desenvolvimento de compet\u00eancias [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-01-26T23:06:30+00:00","article_modified_time":"2019-01-10T14:47:16+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es","datePublished":"2016-01-26T23:06:30+00:00","dateModified":"2019-01-10T14:47:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/"},"wordCount":519,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Hospital Geral de Fortaleza (HGF)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/","name":"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2016-01-26T23:06:30+00:00","dateModified":"2019-01-10T14:47:16+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/26\/hgf-prepara-atendentes-para-melhorar-acolhimento-nas-recepcoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"HGF prepara atendentes para melhorar acolhimento nas recep\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=7297"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7297\/revisions"}],"predecessor-version":[{"id":76609,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/7297\/revisions\/76609"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=7297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=7297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=7297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}