{"id":728,"date":"2010-03-22T17:32:57","date_gmt":"2010-03-22T20:32:57","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/"},"modified":"2010-03-22T17:32:57","modified_gmt":"2010-03-22T20:32:57","slug":"governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/","title":{"rendered":"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas"},"content":{"rendered":"<p>A popula\u00e7\u00e3o de 190 mil habitantes da microrregi\u00e3o de Russas ter\u00e1 acesso a servi\u00e7os especializados de sa\u00fade bucal a partir de agora, com a inaugura\u00e7\u00e3o do Centro de Especialidades Odontol\u00f3gicas nesta ter\u00e7a-feira, 23, \u00e0s 9 horas. Como unidade regional, o CEO de Russas atender\u00e1, al\u00e9m dos moradores de Russas, a popula\u00e7\u00e3o dos munic\u00edpios que integram a nona microrregi\u00e3o de sa\u00fade. Assim, no CEO de Russas ser\u00e3o oferecidos servi\u00e7os de ortodontia, pr\u00f3tese, cirurgias, periodontia, diagn\u00f3stico de c\u00e2ncer de boca \u00e0 popula\u00e7\u00e3o tamb\u00e9m de Jaguaretama, Jaguaruana, Morada Nova e Palhano. Na nova unidade de sa\u00fade bucal ser\u00e3o realizados 136 atendimentos por dia.\u00a0\u00a0 <\/p>\n<p>O CEO Regional, em Russas, tem uma \u00e1rea coberta de 496 metros quadrados. Foi constru\u00eddo com recursos do Tesouro do Estado. Nas obras, um investimento de R$1.309.198,41.\u00a0 Na aquisi\u00e7\u00e3o de equipamentos, o Governo do Estado investiu mais R$890 mil. O novo CEO faz parte do Programa de Expans\u00e3o e Melhoria da Assist\u00eancia Especializada no Interior do Estado, desenvolvido pelo Governo do Estado, atrav\u00e9s da Secretaria da Sa\u00fade, para ampliar e melhorar a assist\u00eancia na pr\u00f3pria regi\u00e3o onde as pessoas moram, sem necessidade de transfer\u00eancia para a capital. No total, s\u00e3o 16 CEOs. <\/p>\n<p>O Programa de Expans\u00e3o e Melhoria da Assist\u00eancia Especializada inclui ainda o Hospital Regional Norte e o Hospital Regional do Cariri. Os dois j\u00e1 est\u00e3o em constru\u00e7\u00e3o e 21 policl\u00ednicas. Das 21 policl\u00ednicas, 17 est\u00e3o sendo constru\u00eddas.\u00a0\u00a0 <\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A popula\u00e7\u00e3o de 190 mil habitantes da microrregi\u00e3o de Russas ter\u00e1 acesso a servi\u00e7os especializados de sa\u00fade bucal a partir de agora, com a inaugura\u00e7\u00e3o do Centro de Especialidades Odontol\u00f3gicas nesta ter\u00e7a-feira, 23, \u00e0s 9 horas. Como unidade regional, o CEO de Russas atender\u00e1, al\u00e9m dos moradores de Russas, a popula\u00e7\u00e3o dos munic\u00edpios que integram [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-728","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A popula\u00e7\u00e3o de 190 mil habitantes da microrregi\u00e3o de Russas ter\u00e1 acesso a servi\u00e7os especializados de sa\u00fade bucal a partir de agora, com a inaugura\u00e7\u00e3o do Centro de Especialidades Odontol\u00f3gicas nesta ter\u00e7a-feira, 23, \u00e0s 9 horas. Como unidade regional, o CEO de Russas atender\u00e1, al\u00e9m dos moradores de Russas, a popula\u00e7\u00e3o dos munic\u00edpios que integram [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-22T20:32:57+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas\",\"datePublished\":\"2010-03-22T20:32:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\"},\"wordCount\":274,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\",\"name\":\"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-03-22T20:32:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A popula\u00e7\u00e3o de 190 mil habitantes da microrregi\u00e3o de Russas ter\u00e1 acesso a servi\u00e7os especializados de sa\u00fade bucal a partir de agora, com a inaugura\u00e7\u00e3o do Centro de Especialidades Odontol\u00f3gicas nesta ter\u00e7a-feira, 23, \u00e0s 9 horas. Como unidade regional, o CEO de Russas atender\u00e1, al\u00e9m dos moradores de Russas, a popula\u00e7\u00e3o dos munic\u00edpios que integram [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-03-22T20:32:57+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas","datePublished":"2010-03-22T20:32:57+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/"},"wordCount":274,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/","name":"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-03-22T20:32:57+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/22\/governo-do-estado-investe-mais-de-r2-milhoes-no-ceo-de-russas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Governo do Estado investe mais de R$2 milh\u00f5es no CEO de Russas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=728"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/728\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}