{"id":708,"date":"2011-03-22T20:15:48","date_gmt":"2011-03-22T23:15:48","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/"},"modified":"2017-11-29T18:34:39","modified_gmt":"2017-11-29T21:34:39","slug":"gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/","title":{"rendered":"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue"},"content":{"rendered":"<p>\u201cSer\u00e1 se estamos lavando bem e vedando, mesmo, as caixas d\u2019\u00e1gua? Estamos, de fato, evitando jogar lixo nas ruas?\u201d Com esse exerc\u00edcio de consci\u00eancia coletiva em favor da sa\u00fade p\u00fablica e para reduzir o n\u00famero de casos de dengue, o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, fez uma mobiliza\u00e7\u00e3o contra a doen\u00e7a, na tarde desta ter\u00e7a-feira, em Caucaia. Ele disse para o prefeito, Washington G\u00f3is, a secret\u00e1ria de sa\u00fade do munic\u00edpio, Luiza de Marilac, grupos de agentes comunit\u00e1rios de sa\u00fade e de endemias, estudantes, vereadores e lideran\u00e7as comunit\u00e1rias que \u201cembora sabendo dos riscos de adoecer e de morte, ainda n\u00e3o fazemos tudo que \u00e9 para ser feito\u201d. Lembrou da constata\u00e7\u00e3o de que 72% dos focos do mosquito nos munic\u00edpios cearenses e na regi\u00e3o Nordeste s\u00e3o encontrados nas caixas d\u2019\u00e1gua por falta de telamento.<\/p>\n<p>O secret\u00e1rio insistiu na a\u00e7\u00e3o preventiva como a grande estrat\u00e9gia de combate \u00e0 dengue j\u00e1 a partir de atitudes dentro de casa: \u201co carro fumac\u00ea n\u00e3o faz milagre. O inseticida s\u00f3 mata uma parte dos mosquitos adultos, sem trazer nenhum efeito sobre a larva que est\u00e1 na grande maioria dos casos dentro dos im\u00f3veis\u201d. O efeito do inseticida tem pequena dura\u00e7\u00e3o. Depois de 40 minutos que o fumac\u00ea passa nas ruas o inseticida n\u00e3o faz mais efeito. Com o \u00edndice de infesta\u00e7\u00e3o do mosquito chegando a 10% (de cada 100 im\u00f3veis visitados pelos agentes de endemias h\u00e1 focos do mosquito em 10), a Sesa liberou para Caucaia quatro ve\u00edculos para opera\u00e7\u00e3o do fumac\u00ea.<\/p>\n<p>Em Caucaia foram confirmados 81 casos de dengue este ano. Tr\u00eas pessoas morreram por dengue com complica\u00e7\u00e3o. O prefeito apelou \u00e0s 150 pessoas presentes a mobiliza\u00e7\u00e3o feita na tarde desta ter\u00e7a-feira, na sede do gr\u00eamio, no centro de Caucaia, que \u201cdeixem o agente de endemia entrar nas suas casas. Precisamos botar na cabe\u00e7a que a dengue \u00e9 uma doen\u00e7a grave, que mata, mas que pode ser evitada com a vigil\u00e2ncia feita dentro de casa, na escola, na empresa, na igreja\u201d. Antes de Caucaia, a equipe de gestores e t\u00e9cnicos da Sesa estiveram fazendo a mesma a\u00e7\u00e3o de mobiliza\u00e7\u00e3o nos munic\u00edpios de Itapipoca, Ic\u00f3, S\u00e3o Gon\u00e7alo do Amarante e Granja na semana passada.<\/p>\n<p>Este ano est\u00e3o confirmados 5.534 casos em 144 munic\u00edpios cearenses e 15 \u00f3bitos em 11 munic\u00edpios. <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/05\/10\/arrastao-do-fumace-percorre-107-bairros-da-capital-ate-sexta-feira\/\"><span style=\"text-decoration: underline;\">Ver boletim epidemiol\u00f3gico atualizado<\/span><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSer\u00e1 se estamos lavando bem e vedando, mesmo, as caixas d\u2019\u00e1gua? Estamos, de fato, evitando jogar lixo nas ruas?\u201d Com esse exerc\u00edcio de consci\u00eancia coletiva em favor da sa\u00fade p\u00fablica e para reduzir o n\u00famero de casos de dengue, o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, fez uma mobiliza\u00e7\u00e3o contra a doen\u00e7a, na tarde [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-708","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"\u201cSer\u00e1 se estamos lavando bem e vedando, mesmo, as caixas d\u2019\u00e1gua? Estamos, de fato, evitando jogar lixo nas ruas?\u201d Com esse exerc\u00edcio de consci\u00eancia coletiva em favor da sa\u00fade p\u00fablica e para reduzir o n\u00famero de casos de dengue, o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, fez uma mobiliza\u00e7\u00e3o contra a doen\u00e7a, na tarde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-22T23:15:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-29T21:34:39+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue\",\"datePublished\":\"2011-03-22T23:15:48+00:00\",\"dateModified\":\"2017-11-29T21:34:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\",\"name\":\"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2011-03-22T23:15:48+00:00\",\"dateModified\":\"2017-11-29T21:34:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/","og_locale":"pt_BR","og_type":"article","og_title":"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"\u201cSer\u00e1 se estamos lavando bem e vedando, mesmo, as caixas d\u2019\u00e1gua? Estamos, de fato, evitando jogar lixo nas ruas?\u201d Com esse exerc\u00edcio de consci\u00eancia coletiva em favor da sa\u00fade p\u00fablica e para reduzir o n\u00famero de casos de dengue, o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, fez uma mobiliza\u00e7\u00e3o contra a doen\u00e7a, na tarde [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-03-22T23:15:48+00:00","article_modified_time":"2017-11-29T21:34:39+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue","datePublished":"2011-03-22T23:15:48+00:00","dateModified":"2017-11-29T21:34:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/"},"wordCount":434,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/","name":"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2011-03-22T23:15:48+00:00","dateModified":"2017-11-29T21:34:39+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/22\/gestores-e-populacao-de-caucaia-sao-mobilizados-para-agir-mais-contra-a-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Gestores e popula\u00e7\u00e3o de Caucaia s\u00e3o mobilizados para agir mais contra a dengue"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=708"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/708\/revisions"}],"predecessor-version":[{"id":9905,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/708\/revisions\/9905"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}