{"id":682,"date":"2010-10-26T18:18:53","date_gmt":"2010-10-26T21:18:53","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/"},"modified":"2010-10-26T18:18:53","modified_gmt":"2010-10-26T21:18:53","slug":"fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/","title":{"rendered":"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme"},"content":{"rendered":"<p>O VI Simp\u00f3sio Brasileiro de Doen\u00e7a Falciforme acontece em setembro do ano que vem. Fortaleza foi a escolhida para sediar o evento em 2011, que \u00e9 realizado a cada dois anos no Brasil. O Simp\u00f3sio ser\u00e1 lan\u00e7ado amanh\u00e3, dia 27 de outubro, \u00e0s 10h, no Audit\u00f3rio&nbsp; Waldir Arcoverde, na sede da Secretaria da Sa\u00fade do Estado, marcando o Dia Nacional de Luta pelos Direitos das Pessoas Com Doen\u00e7a Falciforme. Na ocasi\u00e3o, ser\u00e3o apresentados tamb\u00e9m os primeiros resultados da realiza\u00e7\u00e3o da fase II do teste do pezinho, inmplantado em julho no Cear\u00e1, e que serve para identificar o tra\u00e7o falciforme nos rec\u00e9m-nascidos.<\/p>\n<p>Estar\u00e3o presentes representantes de todos as unidades de sa\u00fade envolvidas no processo de diagn\u00f3stico e tratamento da doen\u00e7a no estado: Dra. Luciana Carlos, diretora geral do Hemoce; Dra. Andrea Alc\u00e2ntara, coordenadora do Programa Estadual de Aten\u00e7\u00e3o Integral \u00e0s Pessoas com Doen\u00e7as Falciformes e Outras Hemoglobinopatias e respons\u00e1vel pelo ambulat\u00f3rio em Fortaleza; Dra. Diva Fernandes, coordenadora do N\u00facleo de Aten\u00e7\u00e3o \u00e0 S\u00e1ude da Crian\u00e7a; Dra. M\u00e1rcia Limaverde, respons\u00e1vel pelo ambulat\u00f3rio do Hospital Infantil Albert Sabin; Dra. Nilza Frota, respons\u00e1vel pelo teste do pezinho no Albert Sabin; Dr. Ricardo Carvalho, diretor do Laborat\u00f3rio Central do Estado; Lu\u00eds Bernardo, \u00c1lvaro Bezerra e Moema Braga, do Movimento Negro de Fortaleza; e pacientes.<\/p>\n<p>A doen\u00e7a falciforme \u00e9 o tipo de patologia gen\u00e9tica com maior incid\u00eancia na popula\u00e7\u00e3o brasileira e tem diagn\u00f3stico e tratamento acess\u00edveis. Em 2010, dois passos important\u00edssimos foram dados para evoluir esse processo aqui no Cear\u00e1. Primeiramente, em maio, a Secretaria da Sa\u00fade do Estado&nbsp; instituiu oficialmente o Programa Estadual de Aten\u00e7\u00e3o Integral \u00e0s Pessoas com Doen\u00e7as Falciformes e Outras Hemoglobinopatias, coordenado pelo Hemoce e com parceria do Hospital Albert Sabin para diagn\u00f3stico e tratamento de crian\u00e7as e adolescentes at\u00e9 os 18 anos. A coordenadora do programa, Dra. Andrea Alc\u00e2ntara, contabiliza tamb\u00e9m, em todo o estado, 226 pacientes adultos fazendo este acompanhamento nos ambulat\u00f3rios das unidades da hemorrede.<\/p>\n<p>Depois, em julho de 2010, o Minist\u00e9rio da Sa\u00fade autorizou e iniciou o repasse de recursos para a rede p\u00fablica de sa\u00fade do Cear\u00e1 realizar a fase II do teste do pezinho, exame que identifica logo no rec\u00e9m-nascido o tra\u00e7o falciforme e possibilita o in\u00edcio precoce do tratamento da doen\u00e7a na crian\u00e7a. A fase I do teste do pezinho serve a investiga\u00e7\u00e3o de outras duas doen\u00e7as: a fenilceton\u00faria e o hipotireoidismo. O sangue coletado dos beb\u00eas para a realiza\u00e7\u00e3o dos dois exames \u00e9 encaminhado para o Laborat\u00f3rio Central do Estado (Lacen). Segundo o diretor da unidade, Dr. Ricardo Carvalho, j\u00e1 est\u00e3o sendo analisadas cerca de 10 mil amostras por m\u00eas.<\/p>\n<p><strong>A Doen\u00e7a Falciforme<\/strong><\/p>\n<p>A doen\u00e7a falciforme \u00e9 uma das doen\u00e7as gen\u00e9ticas mais comuns no mundo, causada pela muta\u00e7\u00e3o no gene que produz a hemoglobina. Essa muta\u00e7\u00e3o teve origem no continente africano e pode ser encontrada nas popula\u00e7\u00f5es de v\u00e1rias partes do mundo. No Brasil, devido ao grande contingente de popula\u00e7\u00e3o com ascend\u00eancia africana, a doen\u00e7a falciforme faz parte de um grupo de doen\u00e7as e agravos relevantes que afetam a popula\u00e7\u00e3o negra. H\u00e1 100 anos, foi conhecido o primeiro relato cient\u00edfico da doen\u00e7a falciforme e, h\u00e1 cinco anos, o Minist\u00e9rio da Sa\u00fade, atendendo a uma antiga reivindica\u00e7\u00e3o do movimento de homens e mulheres negras, iniciou um trabalho de implementa\u00e7\u00e3o das a\u00e7\u00f5es da Pol\u00edtica Nacional de Aten\u00e7\u00e3o Integral \u00e0s Pessoas com Doen\u00e7a Falciforme.<\/p>\n<p><strong>O Simp\u00f3sio<\/strong><\/p>\n<p>A parceria entre os Governos Federal e Estadual, atrav\u00e9s do Minist\u00e9rio da Sa\u00fade, da Secretaria da Sa\u00fade do Estado e do Centro de Hematologia e Hemoterapia do Cear\u00e1 \u2013 Hemoce, para a realiza\u00e7\u00e3o do VI Simp\u00f3sio Brasileiro de Doen\u00e7a Falciforme e Outras Hemoglobinopatias evidencia a dimens\u00e3o de interesses que a quest\u00e3o da doen\u00e7a falciforme tem alcan\u00e7ado tanto no Brasil quanto na comunidade internacional. S\u00e3o esperadas cerca de 1.000 pessoas para participar do evento no ano que vem em Fortaleza, entre profissionais de servi\u00e7os de sa\u00fade do Brasil e de outros pa\u00edses, pesquisadores, acad\u00eamicos da \u00e1rea representantes do controle social e gestores estaduais e municipais. A partir das discuss\u00f5es realizadas aqui, espera-se dar continuidade ao processo de formula\u00e7\u00e3o de pol\u00edticas p\u00fablicas \u2013 n\u00e3o apenas no Brasil, mas tamb\u00e9m em n\u00edvel intercontinental \u2013 na aten\u00e7\u00e3o a esse tipo de paciente. Na oportunidade, o nosso pa\u00eds pode se consolidar ainda mais como centro de excel\u00eancia em investiga\u00e7\u00e3o cient\u00edfica e na aten\u00e7\u00e3o a pessoas com doen\u00e7a falciforme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O VI Simp\u00f3sio Brasileiro de Doen\u00e7a Falciforme acontece em setembro do ano que vem. Fortaleza foi a escolhida para sediar o evento em 2011, que \u00e9 realizado a cada dois anos no Brasil. O Simp\u00f3sio ser\u00e1 lan\u00e7ado amanh\u00e3, dia 27 de outubro, \u00e0s 10h, no Audit\u00f3rio&nbsp; Waldir Arcoverde, na sede da Secretaria da Sa\u00fade do [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-682","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O VI Simp\u00f3sio Brasileiro de Doen\u00e7a Falciforme acontece em setembro do ano que vem. Fortaleza foi a escolhida para sediar o evento em 2011, que \u00e9 realizado a cada dois anos no Brasil. O Simp\u00f3sio ser\u00e1 lan\u00e7ado amanh\u00e3, dia 27 de outubro, \u00e0s 10h, no Audit\u00f3rio&nbsp; Waldir Arcoverde, na sede da Secretaria da Sa\u00fade do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-26T21:18:53+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme\",\"datePublished\":\"2010-10-26T21:18:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\"},\"wordCount\":830,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\",\"name\":\"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-10-26T21:18:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/","og_locale":"pt_BR","og_type":"article","og_title":"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O VI Simp\u00f3sio Brasileiro de Doen\u00e7a Falciforme acontece em setembro do ano que vem. Fortaleza foi a escolhida para sediar o evento em 2011, que \u00e9 realizado a cada dois anos no Brasil. O Simp\u00f3sio ser\u00e1 lan\u00e7ado amanh\u00e3, dia 27 de outubro, \u00e0s 10h, no Audit\u00f3rio&nbsp; Waldir Arcoverde, na sede da Secretaria da Sa\u00fade do [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-10-26T21:18:53+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme","datePublished":"2010-10-26T21:18:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/"},"wordCount":830,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/","name":"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-10-26T21:18:53+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/10\/26\/fase-ii-do-teste-do-pezinho-e-simposio-brasileiro-de-doenca-falciforme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Hemoce avalia fase II do teste do pezinho e lan\u00e7a Simp\u00f3sio de Falciforme"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=682"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/682\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}