{"id":67989,"date":"2018-05-28T17:01:21","date_gmt":"2018-05-28T20:01:21","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=67989"},"modified":"2023-07-04T11:16:43","modified_gmt":"2023-07-04T14:16:43","slug":"hospitais-e-unidades","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/","title":{"rendered":"Hospitais e unidades da Sesa"},"content":{"rendered":"<p>A aten\u00e7\u00e3o prim\u00e1ria \u00e9 a porta de entrada do sistema de sa\u00fade. Fazem parte da aten\u00e7\u00e3o prim\u00e1ria, por exemplo, os postos de sa\u00fade, centros de sa\u00fade e unidades de Sa\u00fade da Fam\u00edlia. A partir desse primeiro atendimento, o cidad\u00e3o \u00e9 encaminhado para outros servi\u00e7os de maior complexidade da sa\u00fade p\u00fablica, como hospitais e cl\u00ednicas especializadas, que s\u00e3o da aten\u00e7\u00e3o secund\u00e1ria e terci\u00e1ria.<\/p>\n<p>A rede da Secretaria da Sa\u00fade do Estado do Cear\u00e1 tem 11 hospitais, sendo oito na capital e tr\u00eas no interior. Em Fortaleza, s\u00e3o dois de n\u00edvel secund\u00e1rio, com atendimento especializado e de m\u00e9dia complexidade: Hospital e Maternidade Jos\u00e9 Martiniano de Alencar (HMJMA) e Hospital Geral Dr. Waldemar Alc\u00e2ntara (HGWA), e seis a n\u00edvel terci\u00e1rio, que atendem casos de alta complexidade. S\u00e3o eles: Hospital Geral de Fortaleza (HGF), Hospital Geral Dr. C\u00e9sar Cals (HGCC), Hospital Infantil Albert Sabin (Hias), Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas (HSJ), Hospital de Messejana Dr. Alberto Studart Gomes (HM) e Hospital de Sa\u00fade Mental Professor Frota Pinto (HSMM). No interior, os tr\u00eas hospitais s\u00e3o terci\u00e1rios, com atendimento regionalizado: Hospital Regional Norte, em Sobral, Hospital Regional do Cariri, em Juazeiro do Norte, e Hospital Regional Sert\u00e3o Central, em Quixeramobim.<\/p>\n<p><strong><br \/>\nHospital Geral de Fortaleza<\/strong><br \/>\nRua \u00c1vila Goulart, 900, Papicu, Fortaleza<br \/>\nTelefone: (85) 3101-7086 | 3101-3180<\/p>\n<p><strong>Hospital de Messejana Dr. Carlos Alberto Studart Gomes<\/strong><br \/>\nAvenida Frei Cirilo, 3480, Messejana, Fortaleza<br \/>\nTelefone: (85) 3101-4076<\/p>\n<p><strong>Hospital Infantil Albert Sabin\u00a0<\/strong><br \/>\nRua Tertuliano Sales, 544, Vila Uni\u00e3o, Fortaleza<br \/>\nTelefone: (85) 3101-4200<\/p>\n<p><strong>Hospital Geral C\u00e9sar Cals\u00a0<\/strong><br \/>\nAv. Imperador, 545, Centro, Fortaleza<br \/>\nTelefone: (85) 3101-5404\/ 5412<\/p>\n<p><strong>Hospital S\u00e3o Jos\u00e9 de Doen\u00e7as Infecciosas\u00a0<\/strong><br \/>\nRua Nestor Barbosa, 315, Parquel\u00e2ndia, Fortaleza<br \/>\nTelefone: (85) 3101-2321 | 3101-2322<\/p>\n<p><strong>Hospital de Sa\u00fade Mental Professor Frota Pinto\u00a0<\/strong><br \/>\nRua Vicente Nobre Macedo, s\/n, Messejana, Fortaleza<br \/>\nTelefone: (85) 3101-4332<\/p>\n<p><strong>Hospital Geral Waldemar Alc\u00e2ntara<\/strong><br \/>\nRua Dr. Pergentino Maia, 1559, Messejana, Fortaleza<br \/>\nTelefone: (85) 3216-8300<\/p>\n<p><strong>Hospital e Maternidade Jos\u00e9 Martiniano de Alencar <\/strong><br \/>\nRua Princesa Isabel, 1526, Centro, Fortaleza<br \/>\nTelefone: (85)\u00a03101-4976<\/p>\n<p><strong>Hospital Regional Norte<br \/>\n<\/strong>Rua John Sanford, 1500, bairro Junco, Sobral<br \/>\nTelefone: (88) 3677-9300<\/p>\n<p><strong>Hospital Regional do Cariri<br \/>\n<\/strong>Rua Catulo da Paix\u00e3o Cearense, s\/n, no tri\u00e2ngulo Crajubar, Juazeiro do Norte<\/p>\n<p><strong>Hospital Regional do Sert\u00e3o Central<\/strong><br \/>\nRodovia CE 060, quil\u00f4metro 198 (Estrada do Algod\u00e3o), Quixeramobim<br \/>\nTelefone: (88) 3406-1300<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"larajan\"><strong>Servi\u00e7os especiais<\/strong><\/h2>\n<p>A Sesa mant\u00e9m unidades servi\u00e7os de sa\u00fade espec\u00edficos para o atendimento da pessoa que em raz\u00e3o do agravo necessita de atendimento especial.<\/p>\n<p><strong>Centro de Refer\u00eancia Nacional em Dermatologia Sanit\u00e1ria Dona Lib\u00e2nia<\/strong><br \/>\nRua Pedro I, 1033, Centro, Fortaleza<br \/>\nTelefone: 3101-5452<\/p>\n<p>O atendimento no Centro Dona Lib\u00e2nia \u00e9 de segunda a sexta-feira, das 7 \u00e0s 17 horas. A primeira consulta \u00e9 por meio da central de regula\u00e7\u00e3o ou quando o paciente \u00e9 encaminhado de um posto de sa\u00fade. Para pacientes com hansen\u00edase, a demanda \u00e9 espont\u00e2nea; ou seja, a primeira consulta n\u00e3o precisa de encaminhamento. Na assist\u00eancia, al\u00e9m de atendimentos a pacientes com hansen\u00edase, o Centro Dona Lib\u00e2nia realiza tamb\u00e9m atendimentos em dermatologia geral, dermatologia pedi\u00e1trica, DST\/Aids, oncologia cut\u00e2nea, alergia, dermatoses ocupacionais, cirurgia dermatol\u00f3gica, entre outros.<\/p>\n<p><strong>Centro Integrado de Diabetes e Hipertens\u00e3o (CIDH)<\/strong><br \/>\nAv. Silva Paulet, 2406, Aldeota, Fortaleza<br \/>\nTelefone: (85) 3101-1530 \/ 3101-1536<\/p>\n<p>O Centro Integrado de Diabetes e Hipertens\u00e3o \u00e9 refer\u00eancia de n\u00edvel secund\u00e1rio no atendimento a pessoas com diabetes e hipertens\u00e3o arterial no Estado. Para a primeira consulta na unidade, o paciente \u00e9 encaminhado pelas Unidades B\u00e1sicas de Sa\u00fade dos munic\u00edpios. Inicialmente, \u00e9 atendido pelo setor de enfermagem, onde tem o hist\u00f3rico, al\u00e9m da aferi\u00e7\u00e3o da press\u00e3o arterial, medi\u00e7\u00e3o de altura e peso, verifica\u00e7\u00e3o da glicemia capilar e logo \u00e9 encaminhado para o m\u00e9dico.<\/p>\n<p>A depender da complica\u00e7\u00e3o que o paciente apresenta, ele poder\u00e1 ser visto pelo cl\u00ednico ou pelo especialista (cardiologista, nefrologista, vascular, neurologista, oftalmologista). Tamb\u00e9m ser\u00e1 encaminhado ao nutricionista, para orienta\u00e7\u00f5es sobre os h\u00e1bitos alimentares, e ao fisioterapeuta, caso haja necessidade. Os pacientes tamb\u00e9m s\u00e3o atendidos na aten\u00e7\u00e3o prim\u00e1ria, j\u00e1 que a consulta no CIDH \u00e9 complementar ao tratamento na aten\u00e7\u00e3o prim\u00e1ria em sa\u00fade. O atendimento ocorre de segunda a sexta-feira, de 7 \u00e0s 16 horas<\/p>\n<p><strong>Instituto de Preven\u00e7\u00e3o do C\u00e2ncer do Cear\u00e1 (IPC)<\/strong><br \/>\nAv. Assis Chateaubriand, 58, Rodolfo Te\u00f3filo, Fortaleza<br \/>\nTelefone: 3101-1450\/ 3101-1451<\/p>\n<p>O Instituto de Preven\u00e7\u00e3o do C\u00e2ncer do Cear\u00e1 \u00e9 uma unidade de aten\u00e7\u00e3o secund\u00e1ria. Para ter acesso aos servi\u00e7os o usu\u00e1rio geralmente \u00e9 encaminhado de uma unidade de aten\u00e7\u00e3o prim\u00e1ria, como um posto de sa\u00fade, por exemplo. As vagas para atendimento na unidade s\u00e3o disponibilizadas na Central de Regula\u00e7\u00e3o do Estado (CRESUS). Toda unidade prim\u00e1ria tem acesso ao n\u00famero de vagas dispon\u00edveis no CRESUS. O IPC disponibiliza vagas em tr\u00eas agendas: prefeitura, munic\u00edpios e uma agenda restrita da unidade, esta \u00faltima \u00e9 para atendimento \u00e0s pacientes que j\u00e1 est\u00e3o em tratamento na unidade.<\/p>\n<p>O IPC possui catorze ambulat\u00f3rios, divididos em servi\u00e7os de enfermagem, mastologia e ginecologia, al\u00e9m dos setores de mamografia, ultrassonografia e centro cir\u00fargico, onde ocorrem cirurgias para retirada de n\u00f3dulo na mama, coniza\u00e7\u00e3o do colo do \u00fatero (um peda\u00e7o em formato de cone \u00e9 retirado do \u00f3rg\u00e3o para a realiza\u00e7\u00e3o de uma bi\u00f3psia) e pele para as pacientes atendidos no Instituto. Conta tamb\u00e9m com uma equipe multidisciplinar, formada por ginecologistas, mastologistas, enfermeiros, radiologistas e dermatologistas.<\/p>\n<p>Na aten\u00e7\u00e3o \u00e0s pacientes com c\u00e2ncer, \u00e9 preciso destacar o servi\u00e7o de apoio e humaniza\u00e7\u00e3o, com assistentes sociais, psic\u00f3loga e fisioterapeutas. Atrav\u00e9s do servi\u00e7o social, a paciente pode tirar d\u00favidas sobre a doen\u00e7a e a legisla\u00e7\u00e3o. Na fisioterapia, h\u00e1 um preparo para as mulheres que ir\u00e3o se operar, com o intuito de evitar complica\u00e7\u00f5es no p\u00f3s-operat\u00f3rio. Toda paciente atendida que ir\u00e1 se opera ou \u00e9 diagnosticada com c\u00e2ncer passa pelo setor de psicologia.<\/p>\n<p><strong>Centro de Sa\u00fade Meireles (CSM)<\/strong><br \/>\nAv. Ant\u00f4nio Justa, 3113, Meireles, Fortaleza<br \/>\nTelefone: (85) 3101-1440 \/ 3101-1442 \/ 3101-1446 \/ 3101-1447<\/p>\n<p class=\"destacado\">Programa de Aten\u00e7\u00e3o \u00e0 Sa\u00fade da Pessoa Ostomizada<\/p>\n<p>O servi\u00e7o de ostomizados atende a pacientes ostomizados (que utilizam bolsas coletoras) intestinais e urin\u00e1rios da capital e do interior, no Centro de Sa\u00fade Meireles, de segunda a sexta-feira, das 7h30min \u00e0s 16 horas. Com o atendimento integral realizado pelo programa, os pacientes t\u00eam o fornecimento de bolsas coletoras, consulta e o acompanhamento por uma equipe multiprofissional e especializada, que inclui m\u00e9dico proctologista, enfermeira, nutricionista, assistente social e psic\u00f3logo. Este ano, at\u00e9 o m\u00eas de abril, o Programa atendeu a 7.962 pacientes e forneceu 69.613 bolsas e acess\u00f3rios de ostomia.<\/p>\n<p>Para agendar a primeira consulta no Programa de Aten\u00e7\u00e3o \u00e0 Pessoa Ostomizada, basta ligar para o Centro de Sa\u00fade Meireles, telefone (85) 3486-6274. O agendamento pode ser feito de segunda a sexta-feira, das 8 \u00e0s 16 horas.<\/p>\n<p class=\"destacado\">Programa de Alergia \u00e0 Prote\u00edna do Leite de Vaca<\/p>\n<p>O Programa do APLV atende a crian\u00e7as de zero a tr\u00eas anos de idade com suspeita ou diagn\u00f3stico de alergia alimentar \u00e0 prote\u00edna do leite de vaca e de soja. A primeira consulta \u00e9 agendada pela Central de Regula\u00e7\u00e3o. Quem mora no interior do Estado vai ao posto de sa\u00fade do munic\u00edpio e ap\u00f3s a avalia\u00e7\u00e3o cl\u00ednica, o m\u00e9dico do posto encaminha o paciente para a Coordenadoria Regional de Sa\u00fade, onde os pais ou respons\u00e1veis da crian\u00e7a solicitam o agendamento da primeira consulta para o atendimento no Centro de Sa\u00fade Meireles, em Fortaleza.<\/p>\n<p>Quem reside em Fortaleza tamb\u00e9m procura um posto de sa\u00fade, onde no pr\u00f3prio local \u00e9 feito o agendamento com a Central de Regula\u00e7\u00e3o, logo depois da consulta com o m\u00e9dico. O atendimento do Programa do APLV no Centro de Sa\u00fade Meireles ocorre de segunda a sexta-feira, das 8 \u00e0s 12 horas e das 13 \u00e0s 17 horas, por uma equipe de sete m\u00e9dicas gastropediatras e alergologistas e quatro nutricionistas. Ap\u00f3s a consulta com os especialistas, o beb\u00ea \u00e9 encaminhado para avalia\u00e7\u00e3o com a nutricionista, que indica o card\u00e1pio e prescreve a receita do lactente. Logo em seguida, no cadastramento, \u00e9 marcada a data para o recebimento de uma das f\u00f3rmulas infantis fornecidas pela Secretaria da Sa\u00fade do Estado que, este ano, distribuiu 60.315 latas at\u00e9 o m\u00eas de abril. Mais informa\u00e7\u00f5es pelo (85) 3486-6288.<\/p>\n<p class=\"destacado\">Programa de Controle do Tabagismo<\/p>\n<p>Para quem quer deixar de fumar, na rede p\u00fablica do Governo do Estado, h\u00e1 duas unidades refer\u00eancias no tratamento do tabagismo: Hospital de Messejana Dr. Carlos Alberto Studart e Centro de Sa\u00fade do Meireles, onde fumantes t\u00eam avalia\u00e7\u00e3o cl\u00ednica e participam de abordagem m\u00ednima ou intensiva individual ou em grupo, al\u00e9m de acesso gratuito a terapia medicamentosa, quando necess\u00e1ria. Os pacientes s\u00e3o atendidos por uma equipe de profissionais especializados como m\u00e9dicos, enfermeiras e assistente social. Mais informa\u00e7\u00f5es: (85) 3101-1440.<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"larajan\"><strong>Servi\u00e7os de apoio<\/strong><\/h2>\n<p><strong>Centro de Hematologia e Hemoterapia do Cear\u00e1 (Hemoce)<\/strong><br \/>\nAv. Jos\u00e9 Bastos, 3390, Rodolfo Te\u00f3filo, Fortaleza<br \/>\nTelefone: (85) 3101-2296 | Fax: (85) 3101-2307<\/p>\n<p><strong>Laborat\u00f3rio Central de Sa\u00fade P\u00fablica (Lacen)<\/strong><br \/>\nAv. Bar\u00e3o de Studart, 2405, Aldeota, Fortaleza<br \/>\nTelefone: (85) 3101-1491 \/ 3101-1485<\/p>\n<p><strong>Servi\u00e7o de Verifica\u00e7\u00e3o de \u00d3bito (SVO)<\/strong><br \/>\nBR 116, s\/n, Messejana, atr\u00e1s do Hospital do Cora\u00e7\u00e3o<br \/>\nTelefone: (85) 3101-2150\/ 3101-2149\/ 3101-2147<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A aten\u00e7\u00e3o prim\u00e1ria \u00e9 a porta de entrada do sistema de sa\u00fade. Fazem parte da aten\u00e7\u00e3o prim\u00e1ria, por exemplo, os postos de sa\u00fade, centros de sa\u00fade e unidades de Sa\u00fade da Fam\u00edlia. A partir desse primeiro atendimento, o cidad\u00e3o \u00e9 encaminhado para outros servi\u00e7os de maior complexidade da sa\u00fade p\u00fablica, como hospitais e cl\u00ednicas especializadas, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-67989","post","type-post","status-publish","format-standard","hentry","category-sesa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospitais e unidades da Sesa - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospitais e unidades da Sesa - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A aten\u00e7\u00e3o prim\u00e1ria \u00e9 a porta de entrada do sistema de sa\u00fade. Fazem parte da aten\u00e7\u00e3o prim\u00e1ria, por exemplo, os postos de sa\u00fade, centros de sa\u00fade e unidades de Sa\u00fade da Fam\u00edlia. A partir desse primeiro atendimento, o cidad\u00e3o \u00e9 encaminhado para outros servi\u00e7os de maior complexidade da sa\u00fade p\u00fablica, como hospitais e cl\u00ednicas especializadas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-28T20:01:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T14:16:43+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Hospitais e unidades da Sesa\",\"datePublished\":\"2018-05-28T20:01:21+00:00\",\"dateModified\":\"2023-07-04T14:16:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\"},\"wordCount\":1589,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\",\"name\":\"Hospitais e unidades da Sesa - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2018-05-28T20:01:21+00:00\",\"dateModified\":\"2023-07-04T14:16:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospitais e unidades da Sesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospitais e unidades da Sesa - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospitais e unidades da Sesa - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A aten\u00e7\u00e3o prim\u00e1ria \u00e9 a porta de entrada do sistema de sa\u00fade. Fazem parte da aten\u00e7\u00e3o prim\u00e1ria, por exemplo, os postos de sa\u00fade, centros de sa\u00fade e unidades de Sa\u00fade da Fam\u00edlia. A partir desse primeiro atendimento, o cidad\u00e3o \u00e9 encaminhado para outros servi\u00e7os de maior complexidade da sa\u00fade p\u00fablica, como hospitais e cl\u00ednicas especializadas, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2018-05-28T20:01:21+00:00","article_modified_time":"2023-07-04T14:16:43+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Hospitais e unidades da Sesa","datePublished":"2018-05-28T20:01:21+00:00","dateModified":"2023-07-04T14:16:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/"},"wordCount":1589,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/","name":"Hospitais e unidades da Sesa - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2018-05-28T20:01:21+00:00","dateModified":"2023-07-04T14:16:43+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/28\/hospitais-e-unidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Hospitais e unidades da Sesa"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/67989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=67989"}],"version-history":[{"count":14,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/67989\/revisions"}],"predecessor-version":[{"id":119865,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/67989\/revisions\/119865"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=67989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=67989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=67989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}