{"id":67844,"date":"2018-05-18T16:13:36","date_gmt":"2018-05-18T19:13:36","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=67844"},"modified":"2018-05-25T08:20:39","modified_gmt":"2018-05-25T11:20:39","slug":"hgf-celebra-49-anos-com-tres-dias-de-programacao","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/","title":{"rendered":"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-67845\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg\" alt=\"\" width=\"555\" height=\"274\" \/><\/p>\n<p>O Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Cear\u00e1, inicia nesta segunda-feira, 21, a 49\u00aa Reuni\u00e3o Anual, que ocorrer\u00e1 no audit\u00f3rio principal, \u00e0s 8h30. At\u00e9 quarta-feira, 23, profissionais de s\u00e1ude participar\u00e3o do encontro comemorativo aos 49 anos do HGF. O tema deste ano \u00e9 \u201cQuem ama cuidar do outro, cuida primeiro de si\u201d. A abertura da programa\u00e7\u00e3o ter\u00e1 apresenta\u00e7\u00e3o da orquestra da Universidade Estadual do Cear\u00e1 (Uece) e cerim\u00f4nia ecum\u00eanica para servidores, colaboradores, pacientes e acompanhantes.<\/p>\n<p>Na ter\u00e7a-feira, 22, os profissionais participar\u00e3o de confer\u00eancia magna com a coordenadora de gest\u00e3o de pessoas da Secretaria do Planejamento e Gest\u00e3o do Estado (Seplag), Silvana Dourado, que falar\u00e1 sobre &#8220;Promo\u00e7\u00e3o da sa\u00fade e qualidade de vida nas organiza\u00e7\u00f5es da sa\u00fade&#8221;. A programa\u00e7\u00e3o da 49\u00aa Reuni\u00e3o Anual ter\u00e1 minicursos, palestras, mesas redondas, homenagens aos funcion\u00e1rios aposentados do HGF e sess\u00e3o de cinema com debate, no qual especialistas discutir\u00e3o sobre o trabalho da equipe de sa\u00fade representada no filme. Haver\u00e1 tamb\u00e9m servi\u00e7os de odontologia; expedi\u00e7\u00e3o de documentos, atrav\u00e9s do Balc\u00e3o Cidad\u00e3o, e cadastro de estacionamento para idosos e pessoas com defici\u00eancia, com a Autarquia Municipal de Tr\u00e2nsito e Cidadania (AMC).<\/p>\n<p><strong>O HGF<\/strong><\/p>\n<p>O Hospital Geral de Fortaleza foi inaugurado em 23 de maio de 1969, como unidade pertencente ao extinto Instituto Nacional de Assist\u00eancia M\u00e9dica da Previd\u00eancia e Social (Inamps), idealizado para ser Centro de Refer\u00eancia para a regi\u00e3o Norte e Nordeste no tocante \u00e0 assist\u00eancia de alta complexidade. Desde o ano de 1990, quando de sua estadualiza\u00e7\u00e3o, o hospital passou a integrar o Sistema \u00danico de Sa\u00fade (SUS), na rede da Secretaria da Sa\u00fade do Estado do Cear\u00e1 (Sesa), \u00f3rg\u00e3o do Poder Executivo.<\/p>\n<p>Atualmente, o HGF \u00e9 o maior hospital p\u00fablico da rede estadual, refer\u00eancia em procedimentos de alta complexidade, realizando transplantes, neurocirurgias, e prestando assist\u00eancia em Acidente Vascular Cerebral (AVC) e outras patologias neurol\u00f3gicas, ortopedia, obstetr\u00edcia de alto risco, tratamentos cl\u00ednicos especializados dentre outros. Integra a rede de Hospitais Sentinelas, Hospital Amigo da Crian\u00e7a, Rede Cegonha e o Programa SOS Emerg\u00eancia, do Minist\u00e9rio da Sa\u00fade. \u00c9 refer\u00eancia em 33 especialidades e 64 subespecialidades e conta com 528 leitos.<\/p>\n<p>Tem sido marcante o desenvolvimento das tecnologias de sa\u00fade adotadas pelo hospital, proporcionando uma melhor qualidade \u00e0s pr\u00e1ticas do cuidado. Atualmente, h\u00e1 4.542 trabalhadores em diversas \u00e1reas da sa\u00fade, administrativas, t\u00e9cnicas e de apoio, que fazem do HGF refer\u00eancia em atendimento de alta complexidade para a popula\u00e7\u00e3o do Cear\u00e1 e tamb\u00e9m de outros estados do pa\u00eds.<\/p>\n<p>S\u00e3o esses profissionais que continuam diariamente a contar a hist\u00f3ria do hospital que, h\u00e1 49 anos, existe para cuidar, salvar vidas, melhorar qualidade de vida dos pacientes. Anualmente, o HGF realiza a m\u00e9ida de 301 mil consultas, 38 mil atendimentos na emerg\u00eancia e 1,8 milh\u00e3o de exames laboratoriais e de imagens.<\/p>\n<p><strong>Servi\u00e7o<\/strong><br \/>\n49\u00aa Reuni\u00e3o Anual do HGF<br \/>\nLocal: Audit\u00f3rio principal do Hospital Geral de Fortaleza<br \/>\nEndere\u00e7o:\u00a0<a href=\"https:\/\/maps.google.com\/?q=Rua+Riachuelo,+900+-+Papicu&amp;entry=gmail&amp;source=g\">Rua Riachuelo, 900 &#8211; Papicu<\/a><br \/>\nData: 21, 22 e 23 de maio<br \/>\nHor\u00e1rio: 8h \u00e0s 17h<\/p>\n<p><strong>Mais informa\u00e7\u00f5es: <\/strong>Se\u00e7\u00e3o de Ensino, Aperfei\u00e7oamento e Pesquisa do HGF, (85) 3101-3183.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Cear\u00e1, inicia nesta segunda-feira, 21, a 49\u00aa Reuni\u00e3o Anual, que ocorrer\u00e1 no audit\u00f3rio principal, \u00e0s 8h30. At\u00e9 quarta-feira, 23, profissionais de s\u00e1ude participar\u00e3o do encontro comemorativo aos 49 anos do HGF. O tema deste ano \u00e9 \u201cQuem ama cuidar do outro, cuida primeiro [&hellip;]<\/p>\n","protected":false},"author":127,"featured_media":67845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[496],"tags":[342,490,209],"class_list":["post-67844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hgf","tag-altacomplexidade","tag-anual","tag-reuniao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Cear\u00e1, inicia nesta segunda-feira, 21, a 49\u00aa Reuni\u00e3o Anual, que ocorrer\u00e1 no audit\u00f3rio principal, \u00e0s 8h30. At\u00e9 quarta-feira, 23, profissionais de s\u00e1ude participar\u00e3o do encontro comemorativo aos 49 anos do HGF. O tema deste ano \u00e9 \u201cQuem ama cuidar do outro, cuida primeiro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-18T19:13:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-25T11:20:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cgeadrianaaguiar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cgeadrianaaguiar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\"},\"author\":{\"name\":\"cgeadrianaaguiar\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/feac53c52b21b5f6bddc5db8a0af7a21\"},\"headline\":\"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o\",\"datePublished\":\"2018-05-18T19:13:36+00:00\",\"dateModified\":\"2018-05-25T11:20:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\"},\"wordCount\":556,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg\",\"keywords\":[\"AltaComplexidade\",\"anual\",\"Reuni\u00e3o\"],\"articleSection\":[\"Hospital Geral de Fortaleza (HGF)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\",\"name\":\"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg\",\"datePublished\":\"2018-05-18T19:13:36+00:00\",\"dateModified\":\"2018-05-25T11:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg\",\"width\":555,\"height\":274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/feac53c52b21b5f6bddc5db8a0af7a21\",\"name\":\"cgeadrianaaguiar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5b2b8be4e9a6246ee9256941c5d2614b759a4aedeac64cedeae78c57a01ff35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5b2b8be4e9a6246ee9256941c5d2614b759a4aedeac64cedeae78c57a01ff35?s=96&d=mm&r=g\",\"caption\":\"cgeadrianaaguiar\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/cgeadrianaaguiar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/","og_locale":"pt_BR","og_type":"article","og_title":"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O Hospital Geral de Fortaleza (HGF), da rede p\u00fablica do Governo do Cear\u00e1, inicia nesta segunda-feira, 21, a 49\u00aa Reuni\u00e3o Anual, que ocorrer\u00e1 no audit\u00f3rio principal, \u00e0s 8h30. At\u00e9 quarta-feira, 23, profissionais de s\u00e1ude participar\u00e3o do encontro comemorativo aos 49 anos do HGF. O tema deste ano \u00e9 \u201cQuem ama cuidar do outro, cuida primeiro [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2018-05-18T19:13:36+00:00","article_modified_time":"2018-05-25T11:20:39+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg","type":"image\/jpeg"}],"author":"cgeadrianaaguiar","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cgeadrianaaguiar","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/"},"author":{"name":"cgeadrianaaguiar","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/feac53c52b21b5f6bddc5db8a0af7a21"},"headline":"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o","datePublished":"2018-05-18T19:13:36+00:00","dateModified":"2018-05-25T11:20:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/"},"wordCount":556,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg","keywords":["AltaComplexidade","anual","Reuni\u00e3o"],"articleSection":["Hospital Geral de Fortaleza (HGF)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/","name":"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg","datePublished":"2018-05-18T19:13:36+00:00","dateModified":"2018-05-25T11:20:39+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/05\/banner_49_anos_hgf_site-.jpg","width":555,"height":274},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/05\/18\/hgf-celebra-49-anos-com-tres-dias-de-programacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"HGF celebra 49 anos com tr\u00eas dias de programa\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/feac53c52b21b5f6bddc5db8a0af7a21","name":"cgeadrianaaguiar","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f5b2b8be4e9a6246ee9256941c5d2614b759a4aedeac64cedeae78c57a01ff35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5b2b8be4e9a6246ee9256941c5d2614b759a4aedeac64cedeae78c57a01ff35?s=96&d=mm&r=g","caption":"cgeadrianaaguiar"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/cgeadrianaaguiar\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/67844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=67844"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/67844\/revisions"}],"predecessor-version":[{"id":67846,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/67844\/revisions\/67846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/67845"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=67844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=67844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=67844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}