{"id":655,"date":"2009-11-12T12:30:37","date_gmt":"2009-11-12T15:30:37","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/"},"modified":"2009-11-12T12:30:37","modified_gmt":"2009-11-12T15:30:37","slug":"equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/","title":{"rendered":"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue"},"content":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <br \/>Nos \u00faltimos 40 dias foram registrados 13 mil casos de dengue e seis mortes por dengue hemorr\u00e1gica em Cabo Verde, na \u00c1frica. O governo cabo-verdiano solicitou ajuda internacional para combater a epidemia da doen\u00e7a no Pa\u00eds. O Cear\u00e1 aceitou o convite da embaixadora do Brasil,\u00a0 Maria Dulce Barros, feita \u00e0 Secretaria da Sa\u00fade do Estado. O Coordenador de Promo\u00e7\u00e3o e Prote\u00e7\u00e3o \u00e0 Sa\u00fade da Sesa, Manoel Fons\u00eaca,\u00a0 est\u00e1 em Cabo Verde desde a \u00faltima segunda-feira, integrando a opera\u00e7\u00e3o de ajuda internacional, formada tamb\u00e9m por profissionais de Portugal, Espanha, Fran\u00e7a e Cuba. Ele est\u00e1 colaborando no hospital p\u00fablico Agostinho Neto, em Praia, Capital. \u201cO m\u00ednimo que podemos dizer sobre a ajuda do Dr. Fons\u00eaca \u00e9 que de \u00e9 uma ben\u00e7\u00e3o para o povo cabo-verdiano, ajudando no diagn\u00f3stico e tratamento de pacientes e implantando o servi\u00e7o de informa\u00e7\u00f5es para organizar e facilitar o controle da situa\u00e7\u00e3o\u201d, afirmou por telefone a embaixadora.\u00a0 Neste domingo ele retorna e \u00e0 noite dois t\u00e9cnicos da Sesa e dois consultores do Minist\u00e9rio da Sa\u00fade no Cear\u00e1 viajam para Praia, onde realizar\u00e3o treinamentos com profissionais de endemias cabo-verdianos para o controle dos focos do mosquito Aedes aegypti.\u00a0\u00a0\u00a0 <\/p>\n<p>O Secret\u00e1rio da Sa\u00fade do Estado, Jo\u00e3o Ananias,\u00a0 afirma que colaborar com os cabo-verdianos, que pela primeira vez enfrentam uma epidemia, \u00e9 uma a\u00e7\u00e3o humanit\u00e1ria e de solidariedade. Para ele, \u201co Cear\u00e1, com a experi\u00eancia que tem\u00a0 na preven\u00e7\u00e3o e controle da doen\u00e7a desde 1986, n\u00e3o poderia\u00a0 se negar em colaborar\u201d. Ele lembra que a dengue no Estado ainda \u00e9 um desafio, mas h\u00e1 avan\u00e7os que os n\u00fameros mostram, reconhecidos pelo Minist\u00e9rio da Sa\u00fade. Enquanto em 2008 foram confirmados 44.508 casos de dengue este ano, at\u00e9 o dia 6 de novembro, o n\u00famero de casos confirmados n\u00e3o chega a cinco mil. \u00c9 exatamente 4.516 casos, com cinco \u00f3bitos por dengue hemorr\u00e1gica. <\/p>\n<p>A Sesa, al\u00e9m das a\u00e7\u00f5es de vigil\u00e2ncia epidemiol\u00f3gica e de controle do mosquito, com treinamentos de profissionais do Programa Sa\u00fade da Fam\u00edlia, Hospitais-p\u00f3lo no Interior\u00a0 e hospitais da rede estadual na Capital, ap\u00f3ia os munic\u00edpios nas atividades de mobiliza\u00e7\u00e3o social, envolvendo a comunidade no compromisso de combater os focos do mosquito. Est\u00e1 levando a pe\u00e7a de teatro Romeu e Julieta no tempo da\u00a0 dengue para diferentes munic\u00edpios. Nesta sexta-feira, 13, a pe\u00e7a ser\u00e1 apresentada em Tamboril, munic\u00edpio dos Inhamuns. No dia 25 deste m\u00eas, a pe\u00e7a ir\u00e1 para Crate\u00fas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nos \u00faltimos 40 dias foram registrados 13 mil casos de dengue e seis mortes por dengue hemorr\u00e1gica em Cabo Verde, na \u00c1frica. O governo cabo-verdiano solicitou ajuda internacional para combater a epidemia da doen\u00e7a no Pa\u00eds. O Cear\u00e1 aceitou o convite da embaixadora do Brasil,\u00a0 Maria Dulce Barros, feita \u00e0 Secretaria da Sa\u00fade do [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-655","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nos \u00faltimos 40 dias foram registrados 13 mil casos de dengue e seis mortes por dengue hemorr\u00e1gica em Cabo Verde, na \u00c1frica. O governo cabo-verdiano solicitou ajuda internacional para combater a epidemia da doen\u00e7a no Pa\u00eds. O Cear\u00e1 aceitou o convite da embaixadora do Brasil,\u00a0 Maria Dulce Barros, feita \u00e0 Secretaria da Sa\u00fade do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-12T15:30:37+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue\",\"datePublished\":\"2009-11-12T15:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\"},\"wordCount\":442,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\",\"name\":\"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-11-12T15:30:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/","og_locale":"pt_BR","og_type":"article","og_title":"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nos \u00faltimos 40 dias foram registrados 13 mil casos de dengue e seis mortes por dengue hemorr\u00e1gica em Cabo Verde, na \u00c1frica. O governo cabo-verdiano solicitou ajuda internacional para combater a epidemia da doen\u00e7a no Pa\u00eds. O Cear\u00e1 aceitou o convite da embaixadora do Brasil,\u00a0 Maria Dulce Barros, feita \u00e0 Secretaria da Sa\u00fade do [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-11-12T15:30:37+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue","datePublished":"2009-11-12T15:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/"},"wordCount":442,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/","name":"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-11-12T15:30:37+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/11\/12\/equipe-do-ceara-viaja-a-cabo-verde-para-ajudar-no-combate-a-epidemia-de-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Equipe do Cear\u00e1 viaja a Cabo Verde para ajudar no combate \u00e0 epidemia de dengue"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/655\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}