{"id":576,"date":"2009-09-08T12:06:47","date_gmt":"2009-09-08T15:06:47","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/"},"modified":"2009-09-08T12:06:47","modified_gmt":"2009-09-08T15:06:47","slug":"curso-quer-melhorar-a-gestao-da-atencao-primaria","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/","title":{"rendered":"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria"},"content":{"rendered":"<p>Come\u00e7a nesta quarta-feira, 9, o segundo m\u00f3dulo do Curso de Aperfei\u00e7oamento de Gest\u00e3o em Aten\u00e7\u00e3o Prim\u00e1ria, voltado para gestores de sa\u00fade.\u00a0 O treinamento de tr\u00eas dias \u00e9 ministrado por consultores brasileiros e canadenses e trata de tem\u00e1ticas de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS). Enfatiza aspectos de g\u00eanero e etnia. Os 52 participantes do curso est\u00e3o elaborando projetos baseados em evid\u00eancias a fim de intervir positivamente em uma s\u00e9rie de problemas de sa\u00fade. Tuberculose, hansen\u00edase, mortalidade materna, s\u00edfilis cong\u00eanita, preven\u00e7\u00e3o do c\u00e2ncer de colo de \u00fatero, doen\u00e7as do aparelho circulat\u00f3rio e mortalidade infantil foram os temas selecionados.<\/p>\n<p>O curso, composto de quatro m\u00f3dulos, faz parte de um projeto patrocinado pela Ag\u00eancia Canadense de Desenvolvimento Internacional (CIDA), Universidade de Toronto, Minist\u00e9rio da Sa\u00fade e Conass (Conselho Nacional dos Secret\u00e1rios de Sa\u00fade), em parceria com a Secretaria de Sa\u00fade do Cear\u00e1. As aulas ser\u00e3o ministradas no hotel Mareiro, at\u00e9 a sexta-feira. Al\u00e9m do Cear\u00e1, os estados do Piau\u00ed, Alagoas e Para\u00edba tamb\u00e9m foram contemplados com o projeto que visa melhorar os indicadores de sa\u00fade nestes estados. <\/p>\n<p>Entre participantes do curso est\u00e3o nutricionistas, enfermeiros, pedagogos, m\u00e9dicos, dentistas e assistentes sociais. S\u00e1o profissionais vinculados ao estado, outros provenientes dos munic\u00edpios, professores das Universidades Federal e Estadual, um membro do Cossems (Conselho de Secret\u00e1rios e Secretarias Municipais de Sa\u00fade) e ainda um representante da Sociedade Brasileira de Medicina de Fam\u00edlia e Comunidade.<\/p>\n<p>De acordo com Yves Talbot, m\u00e9dico e professor da Universidade de Toronto, o objetivo principal do curso \u00e9 o aperfei\u00e7oamento das pr\u00e1ticas de gest\u00e3o de servi\u00e7os de Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade (APS) no contexto do Sistema \u00danico de Sa\u00fade (SUS). O curso oportuniza a apropria\u00e7\u00e3o de uma metodologia de enfrentamento de problemas de sa\u00fade e disponibiliza ferramentas para que os participantes desenvolvam habilidades gerenciais. Al\u00e9m disso,\u00a0 o curso enfatiza que as quest\u00f5es de g\u00eanero e etnia devem ser consideradas a fim de que pessoas de ambos os sexos e todas as ra\u00e7as sejam tratadas com equidade, explica Talbot.<\/p>\n<p>Adriana Gaertner \u2013 Universidade de Toronto<br \/>adriana.gaertner@utoronto.ca<br \/>(85) 9621-5154 <\/p>\n<p><strong>Informa\u00e7\u00f5es complementares<\/strong><\/p>\n<p><strong>A aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS), tamb\u00e9m denominada aten\u00e7\u00e3o b\u00e1sica (governo do Brasil), foi definida pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade em 1978 como:<\/strong><br \/>Aten\u00e7\u00e3o essencial \u00e0 sa\u00fade baseada em tecnologia e m\u00e9todos pr\u00e1ticos, cientificamente comprovados e socialmente aceit\u00e1veis, tornados universalmente acess\u00edveis a indiv\u00edduos e fam\u00edlias na comunidade por meios aceit\u00e1veis para eles e a um custo que tanto a comunidade como o pa\u00eds possa arcar em cada est\u00e1gio de seu desenvolvimento, um esp\u00edrito de autoconfian\u00e7a e autodetermina\u00e7\u00e3o. \u00c9 parte integral do sistema de sa\u00fade do pa\u00eds, do qual \u00e9 fun\u00e7\u00e3o central, sendo o enfoque principal do desenvolvimento social e econ\u00f4mico global da comunidade. \u00c9 o primeiro n\u00edvel de contato dos indiv\u00edduos, da fam\u00edlia e da comunidade com o sistema nacional de sa\u00fade, levando a aten\u00e7\u00e3o \u00e0 sa\u00fade o mais pr\u00f3ximo poss\u00edvel do local onde as pessoas vivem e trabalham, constituindo o primeiro elemento de um processo de aten\u00e7\u00e3o continuada \u00e0 sa\u00fade. (Declara\u00e7\u00e3o de Alma-Ata) <br \/><strong><br \/>De acordo com Barbara Starfield, as principais caracter\u00edsticas da aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS) s\u00e3o:<\/strong><br \/>&gt; Constituir a porta de entrada do servi\u00e7o \u2014 espera-se da APS que seja mais acess\u00edvel \u00e0 popula\u00e7\u00e3o, em todos os sentidos, e que com isso seja o primeiro recurso a ser buscado. Dessa forma, a autora fala que a APS \u00e9 o Primeiro Contato da medicina com o paciente. <\/p>\n<p>&gt; Continuidade do cuidado \u2014 a pessoa atendida mant\u00e9m seu v\u00ednculo com o servi\u00e7o ao longo do tempo, de forma que quando uma nova demanda surge esta seja atendida de forma mais eficiente; essa caracter\u00edstica tamb\u00e9m \u00e9 chamada de longitudinalidade. <\/p>\n<p>&gt; Integralidade \u2014 o n\u00edvel prim\u00e1rio \u00e9 respons\u00e1vel por todos os problemas de sa\u00fade; ainda que parte deles seja encaminhado a equipes de n\u00edvel secund\u00e1rio ou terci\u00e1rio, o servi\u00e7o de Aten\u00e7\u00e3o Prim\u00e1ria continua co-respons\u00e1vel. Al\u00e9m do v\u00ednculo com outros servi\u00e7os de sa\u00fade, os servi\u00e7os do n\u00edvel prim\u00e1rio podem lan\u00e7ar m\u00e3o de visitas domiciliares, reuni\u00f5es com a comunidade e a\u00e7\u00f5es intersetoriais. Nessa caracter\u00edstica, a Integralidade tamb\u00e9m significa a abrang\u00eancia ou amplia\u00e7\u00e3o do conceito de sa\u00fade, n\u00e3o se limitando ao corpo puramente biol\u00f3gico. <\/p>\n<p>&gt; Coordena\u00e7\u00e3o do cuidado \u2014 mesmo quando parte substancial do cuidado \u00e0 sa\u00fade de uma pessoa for realizado em outros n\u00edveis de atendimento, o n\u00edvel prim\u00e1rio tem a incumb\u00eancia de organizar, coordenar e\/ou integrar esses cuidados, j\u00e1 que freq\u00fcentemente s\u00e3o realizados por profissionais de \u00e1reas diferentes ou terceiros, e que portanto t\u00eam pouco di\u00e1logo entre si. [1] <\/p>\n<p>paul.cantin@utoronto.ca<br \/>jennifer.little@utoronto.ca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7a nesta quarta-feira, 9, o segundo m\u00f3dulo do Curso de Aperfei\u00e7oamento de Gest\u00e3o em Aten\u00e7\u00e3o Prim\u00e1ria, voltado para gestores de sa\u00fade.\u00a0 O treinamento de tr\u00eas dias \u00e9 ministrado por consultores brasileiros e canadenses e trata de tem\u00e1ticas de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS). Enfatiza aspectos de g\u00eanero e etnia. Os 52 participantes do curso est\u00e3o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-576","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Come\u00e7a nesta quarta-feira, 9, o segundo m\u00f3dulo do Curso de Aperfei\u00e7oamento de Gest\u00e3o em Aten\u00e7\u00e3o Prim\u00e1ria, voltado para gestores de sa\u00fade.\u00a0 O treinamento de tr\u00eas dias \u00e9 ministrado por consultores brasileiros e canadenses e trata de tem\u00e1ticas de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS). Enfatiza aspectos de g\u00eanero e etnia. Os 52 participantes do curso est\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-08T15:06:47+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria\",\"datePublished\":\"2009-09-08T15:06:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\"},\"wordCount\":874,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\",\"name\":\"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-09-08T15:06:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Come\u00e7a nesta quarta-feira, 9, o segundo m\u00f3dulo do Curso de Aperfei\u00e7oamento de Gest\u00e3o em Aten\u00e7\u00e3o Prim\u00e1ria, voltado para gestores de sa\u00fade.\u00a0 O treinamento de tr\u00eas dias \u00e9 ministrado por consultores brasileiros e canadenses e trata de tem\u00e1ticas de aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade (APS). Enfatiza aspectos de g\u00eanero e etnia. Os 52 participantes do curso est\u00e3o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-09-08T15:06:47+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria","datePublished":"2009-09-08T15:06:47+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/"},"wordCount":874,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/","name":"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-09-08T15:06:47+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/08\/curso-quer-melhorar-a-gestao-da-atencao-primaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Curso quer melhorar a gest\u00e3o da aten\u00e7\u00e3o prim\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}