{"id":550,"date":"2009-10-14T19:30:59","date_gmt":"2009-10-14T22:30:59","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/"},"modified":"2009-10-14T19:30:59","modified_gmt":"2009-10-14T22:30:59","slug":"consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/","title":{"rendered":"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o"},"content":{"rendered":"<p>Amanh\u00e3, 15, e sexta-feira, 16, a Secretaria da Sa\u00fade do Estado dar\u00e1 orienta\u00e7\u00f5es e informa\u00e7\u00f5es sobre a diferen\u00e7a entre diet e light, os cuidados com os alimentos na hora de preparar, higienizar, armazenar e transportar e sobre o uso da \u00e1gua sanit\u00e1ria na desinfec\u00e7\u00e3o dos alimentos em duas pra\u00e7as da capital. Na quinta-feira, das 15 \u00e0s 21 horas, ser\u00e1 na Pra\u00e7a da Gentil\u00e2ndia, na II Feira da Agricultura Familiar e Economia Solid\u00e1ria, na programa\u00e7\u00e3o da\u00a0 Semana Mundial da Alimenta\u00e7\u00e3o. No Dia Mundial da Alimenta\u00e7\u00e3o, sexta-feira, 16, a Sesa em duas tendas, na Pra\u00e7a do Ferreira, al\u00e9m de orienta\u00e7\u00f5es sobre cozinha segura, alimentos org\u00e2nicos e saud\u00e1veis, ser\u00e3o realizados servi\u00e7os de verifica\u00e7\u00e3o de press\u00e3o arterial e do \u00edndice de massa corp\u00f3rea.\u00a0 A Secretaria da Sa\u00fade realizar\u00e1 tamb\u00e9m atividades internas para os funcion\u00e1rios. No dia 15, das 8 \u00e0s 12 horas e, no dia 16, das 14 \u00e0s 17 horas, ser\u00e1 realizada avalia\u00e7\u00e3o de \u00edndice de massa corporal (IMC) e demonstra\u00e7\u00e3o do valor das frutas na sa\u00fade e na qualidade de vida. <\/p>\n<p>Durante as atividades da Semana Mundial da Alimenta\u00e7\u00e3o, a Secretaria da Sa\u00fade far\u00e1 a distribui\u00e7\u00e3o do folder \u201cEduca\u00e7\u00e3o para o Consumo de Alimento Saud\u00e1vel\u201d, que d\u00e1 dicas de consumo para a aquisi\u00e7\u00e3o, transporte, armazenamento, higieniza\u00e7\u00e3o e prepara\u00e7\u00e3o de alimentos. Para esclarecimento da popula\u00e7\u00e3o, a Sesa vai demonstrar que produtos \u201cdiet\u201d s\u00e3o aqueles que, na composi\u00e7\u00e3o, n\u00e3o t\u00eam adi\u00e7\u00e3o de um ou mais nutrientes (a\u00e7\u00facar, gordura e sal), enquanto que os produtos \u201clight\u201d apresentam redu\u00e7\u00e3o m\u00ednima de 25% em determinado nutriente ou calorias, comparados com o alimento convencional.<\/p>\n<p>No dia 16 de outubro, 150 pa\u00edses celebram o Dia Mundial da Alimenta\u00e7\u00e3o. Para este ano, o tema escolhido pela Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para Agricultura e Alimenta\u00e7\u00e3o (FAO) \u00e9 \u201cAlcan\u00e7ar a Seguran\u00e7a Alimentar em \u00c9poca de Crise\u201d. Com esse tema, pretende estimular uma reflex\u00e3o a respeito do quadro da atual inseguran\u00e7a alimentar mundial. Segundo relat\u00f3rio da FAO, a fome afeta atualmente 1,02 bilh\u00e3o de pessoas, quase um sexto da popula\u00e7\u00e3o mundial.<\/p>\n<p>Durante esta semana, 300 especialistas se re\u00fanem em Roma, sede da FAO, para debater o tema &#8220;Como alimentar o mundo em 2050&#8221;. A popula\u00e7\u00e3o mundial passar\u00e1 de 6,8 bilh\u00f5es de pessoas atualmente a 9,1 bilh\u00f5es em 2050, segundo as proje\u00e7\u00f5es mais recentes da ONU. De 16 a 18 de novembro, Roma receber\u00e1 uma reuni\u00e3o mundial sobre a seguran\u00e7a alimentar.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amanh\u00e3, 15, e sexta-feira, 16, a Secretaria da Sa\u00fade do Estado dar\u00e1 orienta\u00e7\u00f5es e informa\u00e7\u00f5es sobre a diferen\u00e7a entre diet e light, os cuidados com os alimentos na hora de preparar, higienizar, armazenar e transportar e sobre o uso da \u00e1gua sanit\u00e1ria na desinfec\u00e7\u00e3o dos alimentos em duas pra\u00e7as da capital. Na quinta-feira, das 15 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-550","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Amanh\u00e3, 15, e sexta-feira, 16, a Secretaria da Sa\u00fade do Estado dar\u00e1 orienta\u00e7\u00f5es e informa\u00e7\u00f5es sobre a diferen\u00e7a entre diet e light, os cuidados com os alimentos na hora de preparar, higienizar, armazenar e transportar e sobre o uso da \u00e1gua sanit\u00e1ria na desinfec\u00e7\u00e3o dos alimentos em duas pra\u00e7as da capital. Na quinta-feira, das 15 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-14T22:30:59+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o\",\"datePublished\":\"2009-10-14T22:30:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\"},\"wordCount\":439,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\",\"name\":\"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-10-14T22:30:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Amanh\u00e3, 15, e sexta-feira, 16, a Secretaria da Sa\u00fade do Estado dar\u00e1 orienta\u00e7\u00f5es e informa\u00e7\u00f5es sobre a diferen\u00e7a entre diet e light, os cuidados com os alimentos na hora de preparar, higienizar, armazenar e transportar e sobre o uso da \u00e1gua sanit\u00e1ria na desinfec\u00e7\u00e3o dos alimentos em duas pra\u00e7as da capital. Na quinta-feira, das 15 [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-10-14T22:30:59+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o","datePublished":"2009-10-14T22:30:59+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/"},"wordCount":439,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/","name":"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-10-14T22:30:59+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/10\/14\/consumidores-recebem-nas-pracas-orientacoes-sobre-alimentacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Consumidores recebem, nas pra\u00e7as, orienta\u00e7\u00f5es sobre alimenta\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=550"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/550\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}